{"id":1452406,"date":"2024-09-03T21:03:52","date_gmt":"2024-09-04T04:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/"},"modified":"2024-09-03T21:03:52","modified_gmt":"2024-09-04T04:03:52","slug":"sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","title":{"rendered":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense.<\/p>\n<p>El secretario de Justicia de Estados Unidos, Merrick Garland, aleg\u00f3 que la aeronave fue \u201ccomprada ilegalmente\u201d a trav\u00e9s de una empresa fantasma y \u201csacada de contrabando de Estados Unidos para ser utilizada por Nicol\u00e1s Maduro y sus compinches\u201d. Anthony Salisbury, agente especial a cargo de investigaciones del Departamento Seguridad Nacional, dijo a CNN que \u201cel avi\u00f3n fue incautado en violaci\u00f3n de las sanciones de EE.UU. a Venezuela y otros asuntos penales que todav\u00eda estamos investigando en relaci\u00f3n con este avi\u00f3n\u201d.<\/p>\n<p>Exclusivo: Estados Unidos incauta el avi\u00f3n utilizado por el presidente de Venezuela, Nicol\u00e1s Maduro, en Rep\u00fablica Dominicana<\/p>\n<p>Las sanciones son medidas que publica el Departamento del Tesoro de EE.UU. como una herramienta para su pol\u00edtica exterior y seguridad nacional.<\/p>\n<p>En abril, Washington reinstaur\u00f3 algunas de las sanciones sobre el sector de petr\u00f3leo y gas de Venezuela (que estuvieron suspendidas por seis meses), debido a preocupaciones relacionadas con la democracia en el pa\u00eds sudamericano. En respuesta, el canciller de Venezuela, Yv\u00e1n Gil, dijo en ese momento que EE.UU., con su decisi\u00f3n, &#171;le hace da\u00f1o a cualquier intento de normalizaci\u00f3n de las relaciones bilaterales (&#8230;) y sobre todo le hace da\u00f1o a sus propias inversiones e intereses en la industria petrolera venezolana&#187;.<\/p>\n<p>Adem\u00e1s, luego de las elecciones del 28 de julio, en las que las autoridades electorales de Venezuela declararon ganador a Maduro sin divulgar los resultados desglosados, un funcionario estadounidense le dijo a CNN que evaluar\u00eda la pol\u00edtica de sanciones \u201ca la luz de los intereses generales de la pol\u00edtica exterior nacional de EE.UU.\u201d y \u201clas acciones que toman o no toman Maduro y sus representantes\u201d.<\/p>\n<p>\u00bfQu\u00e9 podr\u00eda pasar con las sanciones de EE.UU. a Venezuela tras las elecciones?<\/p>\n<p>Este martes, Estados Unidos conden\u00f3 la orden de arresto girada por un tribunal venezolano el lunes contra el candidato presidencial de la mayor\u00eda opositora venezolana, Edmundo Gonz\u00e1lez, y la Casa Blanca est\u00e1 &#171;considerando una serie de opciones para demostrar al Sr. Maduro y sus representantes que sus acciones en Venezuela tendr\u00e1n consecuencias&#187;, dijo a periodistas el portavoz del Consejo de Seguridad Nacional, John Kirby.<\/p>\n<p>Las sanciones contra el sector energ\u00e9tico (petr\u00f3leo y gas) de Venezuela<\/p>\n<p>En agosto de 2017, el Gobierno estadounidense del entonces presidente Donald Trump impuso\u00a0sanciones sectoriales que prohib\u00edan a los bancos de EE.UU. comprar bonos del Gobierno venezolano y su compa\u00f1\u00eda estatal petrolera PDVSA. La orden tambi\u00e9n limitaba las transacciones con bonos existentes propiedad del sector p\u00fablico venezolano.<\/p>\n<p>En enero de 2019, cuando Washington reconoci\u00f3 a Juan Guaid\u00f3 como presidente interino de Venezuela, el Gobierno de Trump anunci\u00f3 sanciones contra PDVSA, por lo cual cualquier compra de petr\u00f3leo venezolano por parte de entidades de EE.UU. har\u00eda que todo el dinero se depositara en cuentas bloqueadas.<\/p>\n<p>En octubre de 2023, el Departamento del Tesoro anunci\u00f3 la suspensi\u00f3n de algunas sanciones, entre ellas las petroleras, luego de que el Gobierno de Maduro y la oposici\u00f3n venezolana alcanzaran un acuerdo en Barbados para celebrar elecciones libres y justas en 2024. Esto se conoci\u00f3 como licencia 44 y permit\u00eda a la mayor\u00eda de las compa\u00f1\u00edas petroleras de EE.UU. hacer negocios en Venezuela. Tambi\u00e9n autorizaba a PDVSA a vender su petr\u00f3leo en Estados Unidos y utilizar su sistema financiero para pagar a acreedores y cobrar deudas.<\/p>\n<p>El 17 de abril de 2024 la licencia 44 expir\u00f3 y las sanciones fueron \u00a0reinstauradas, pero se dej\u00f3 en vigor la licencia 41, concedida en noviembre de 2022, que permite a Chevron exportar crudo venezolano gracias a una asociaci\u00f3n que mantiene con PDVSA.<\/p>\n<p>\u00bfQu\u00e9 tipo de sanciones aplica el Departamento del Tesoro?<\/p>\n<p>Los pa\u00edses con medidas m\u00e1s restrictivas est\u00e1n considerados dentro de las sanciones generales o selectivas, que son geogr\u00e1ficas y de amplio alcance, y que proh\u00edben cualquier importaci\u00f3n, exportaci\u00f3n, financiaci\u00f3n o transacci\u00f3n, por lo que se suele decir que aplica un embargo. Bajo esa figura est\u00e1n actualmente pa\u00edses como Cuba, Corea del Norte o Ir\u00e1n.<\/p>\n<p>En cambio, los pa\u00edses a los que se aplican medidas contra sectores puntuales, como es el caso de Venezuela, entran en la categor\u00eda de sanciones espec\u00edficas o selectivas, con el objetivo de minimizar el impacto en \u00e1reas no relacionadas al sector que castiga el Departamento del Tesoro.<\/p>\n<p>Adem\u00e1s, Washington tambi\u00e9n ha aplicado sanciones a decenas de individuos y compa\u00f1\u00edas de Venezuela. Maduro fue sancionado en 2017\u00a0y se prohibi\u00f3 a los ciudadanos estadounidenses hacer tratos con \u00e9l, luego de las elecciones para la Asamblea Constituyente que, seg\u00fan denunci\u00f3 el Tesoro, aspiraba &#171;ileg\u00edtimamente a usurpar el papel constitucional de la Asamblea Nacional elegida democr\u00e1ticamente&#187;.<\/p>\n<p>En respuesta, Maduro dijo en aquel entonces: \u201c\u00bfPor qu\u00e9 se me sanciona? Porque soy capaz de decir las verdades de las persecuciones contra los pueblos mexicano y latinoamericanos por parte del gobierno de Donald Trump, y la deportaci\u00f3n, expulsi\u00f3n y abuso y tortura de miles de latinoamericanos&#187;.<\/p>\n<p>Posteriormente, el Tesoro ha emitido sanciones contra la esposa de Maduro, Cilia Flores, y otros miembros de su c\u00edrculo cercano,\u00a0en\u00a0un intento de debilitar su control sobre el poder.<\/p>\n<p>\u00bfQu\u00e9 implica una sanci\u00f3n?<\/p>\n<p>Ante una sanci\u00f3n de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), todos los bienes y participaciones en bienes de estas personas que se encuentren en EE.UU. o que est\u00e9n en poder o bajo el control de personas estadounidenses quedan bloqueados, as\u00ed como las entidades en las que el 50% o m\u00e1s pertenezca a una o m\u00e1s personas designadas, a menos que lo autorice una licencia de la OFAC, informa el Tesoro.<\/p>\n<p>Adem\u00e1s, las reglamentaciones de la OFAC proh\u00edben de manera general todas las operaciones por parte de personas estadounidenses o personas dentro de EE.UU. (o que transiten por ese territorio) que involucren bienes o participaciones en bienes de personas designadas o bloqueadas.<\/p>\n<p>Si un individuo o empresa elude una sanci\u00f3n, la OFAC puede imponer penalidades civiles o criminales.<\/p>\n<p>Con informaci\u00f3n de Priscilla Alvarez, Gonzalo Zegarra, Osmary Hern\u00e1ndez, Michael R\u00edos, Jennifer Hansler, Stefano Pozzebon, Mary Triny Mena, Ivana Kottasov\u00e1, Jessie Yeung y Jos\u00e9 \u00c1lvarez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense. El secretario de Justicia de Estados Unidos, Merrick Garland, aleg\u00f3 que la aeronave [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452406","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense. El secretario de Justicia de Estados Unidos, Merrick Garland, aleg\u00f3 que la aeronave [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-04T04:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os\",\"datePublished\":\"2024-09-04T04:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\"},\"wordCount\":1136,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\",\"name\":\"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-04T04:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0El Gobierno de Estados Unidos mantiene sanciones sectoriales e individuales sobre Venezuela y contin\u00faa evaluando su pol\u00edtica hacia el pa\u00eds sudamericano, al que incaut\u00f3 un avi\u00f3n utilizado por el presidente Nicol\u00e1s Maduro, seg\u00fan anunci\u00f3\u00a0este lunes el Departamento de Estado estadounidense. El secretario de Justicia de Estados Unidos, Merrick Garland, aleg\u00f3 que la aeronave [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","og_site_name":"Noticias","article_published_time":"2024-09-04T04:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/"},"author":{"name":"","@id":""},"headline":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os","datePublished":"2024-09-04T04:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/"},"wordCount":1136,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","url":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","name":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-04T04:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qu\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \u00faltimos a\u00f1os","url":"http:\/\/noticiasya.com\/tampa\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/09\/03\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-04T04:03:52Z","datePublished":"2024-09-04T04:03:52Z","dateModified":"2024-09-04T04:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qu\\u00e9 sanciones ha impuesto EE.UU. a Venezuela en los \\u00faltimos a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/09\\\/03\\\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/09\\\/03\\\/sanciones-impuesto-ee-uu-venezuela-en-los-ultimos-anios-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-04T04:03:52Z\",\"datePublished\":\"2024-09-04T04:03:52Z\",\"dateModified\":\"2024-09-04T04:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452410,"url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/03\/segundo-avion-maduro-republica-domincana-trax\/","url_meta":{"origin":1452406,"position":0},"title":"Un segundo avi\u00f3n vinculado a Maduro est\u00e1 vigilado 24 horas en Rep\u00fablica Dominicana","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) -- Un segundo avi\u00f3n vinculado al r\u00e9gimen de Nicol\u00e1s Maduro en Venezuela est\u00e1 bajo vigilancia las 24 horas del d\u00eda por las autoridades en Rep\u00fablica Dominicana, dijo a CNN una fuente con conocimiento del asunto.La fuente no especific\u00f3 detalles sobre el modelo o la marca del avi\u00f3n o si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452381,"url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/03\/asi-avion-nicolas-maduro-incauto-estados-unidos-orix\/","url_meta":{"origin":1452406,"position":1},"title":"As\u00ed es el avi\u00f3n utilizado por Nicol\u00e1s Maduro que incaut\u00f3 Estados Unidos","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Este lunes, Estados Unidos incaut\u00f3 el avi\u00f3n que utilizaba el presidente de Venezuela, Nicol\u00e1s Maduro, tras considerar que su adquisici\u00f3n violaba las sanciones estadounidenses, entre otros asuntos criminales, seg\u00fan dos funcionarios.Se trata del m\u00e1s reciente episodio de una relaci\u00f3n fr\u00eda de larga data entre Washington y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451501,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/30\/sanciones-eeuu-venezuela-elecciones-orix\/","url_meta":{"origin":1452406,"position":2},"title":"\u00bfQu\u00e9 podr\u00eda pasar con las sanciones de EE.UU. a Venezuela tras las elecciones?","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La situaci\u00f3n en Venezuela tras las elecciones de este domingo se vuelve cada vez m\u00e1s compleja, mientras siguen sin difundirse datos oficiales adicionales de los resultados y tanto el oficialismo como la oposici\u00f3n se adjudican el triunfo. \u00bfC\u00f3mo puede afectar esto al pa\u00eds en cuanto a sanciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448209,"url":"https:\/\/noticiasya.com\/tampa\/2024\/04\/17\/estados-unidos-reinstaura-sanciones-petroleo-gas-venezuela-orix\/","url_meta":{"origin":1452406,"position":3},"title":"Estados Unidos reinstaura las sanciones contra el sector de petr\u00f3leo y gas de Venezuela","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Estados Unidos decidi\u00f3 este mi\u00e9rcoles reinstaurar algunas de las sanciones sobre el sector de petr\u00f3leo y gas de Venezuela, seg\u00fan public\u00f3 el Departamento del Tesoro de EE.UU. en un documento. Este, adem\u00e1s, se\u00f1ala la prohibici\u00f3n de realizar transacciones con cualquier entidad con sede en Rusia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444679,"url":"https:\/\/noticiasya.com\/tampa\/2024\/01\/30\/estados-unidos-reactiva-sanciones-al-sector-de-petroleo-y-gas-de-venezuela-en-reaccion-a-la-inhabilitacion-de-la-candidatura-de-maria-corina-machado\/","url_meta":{"origin":1452406,"position":4},"title":"Estados Unidos reactiva sanciones al sector de petr\u00f3leo y gas de Venezuela en reacci\u00f3n a la inhabilitaci\u00f3n de la candidatura de Mar\u00eda Corina Machado","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos anunci\u00f3 este martes que reactivar\u00e1 las sanciones al sector de petr\u00f3leo y gas de Venezuela, en respuesta a la decisi\u00f3n del Tribunal Supremo de Justicia venezolano (TSJ) de inhabilitar la candidatura de la opositora Mar\u00eda Corina Machado.Tribunal Supremo de Venezuela inhabilita la candidatura presidencial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444726,"url":"https:\/\/noticiasya.com\/tampa\/2024\/01\/31\/estados-unidos-reactiva-sanciones-al-sector-de-petroleo-y-gas-de-venezuela-en-reaccion-a-la-inhabilitacion-de-la-candidatura-de-maria-corina-machado-2\/","url_meta":{"origin":1452406,"position":5},"title":"Estados Unidos reactiva sanciones al sector de petr\u00f3leo y gas de Venezuela en reacci\u00f3n a la inhabilitaci\u00f3n de la candidatura de Mar\u00eda Corina Machado","author":"","date":"enero 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Estados Unidos anunci\u00f3 este martes que reactivar\u00e1 las sanciones al sector de petr\u00f3leo y gas de Venezuela, en respuesta a la decisi\u00f3n del Tribunal Supremo de Justicia venezolano (TSJ) de inhabilitar la candidatura de la opositora Mar\u00eda Corina Machado.Tribunal Supremo de Venezuela inhabilita la candidatura presidencial de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452406"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452406\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}