{"id":1468013,"date":"2025-11-04T04:03:38","date_gmt":"2025-11-04T12:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/"},"modified":"2025-11-04T04:03:38","modified_gmt":"2025-11-04T12:03:38","slug":"muere-dick-cheney-vicepresidente-republicano-bush-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","title":{"rendered":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush"},"content":{"rendered":"<p>Dick Cheney, el vicepresidente m\u00e1s poderoso de la era moderna estadounidense y principal art\u00edfice de la \u201cguerra contra el terrorismo\u201d \u2014quien contribuy\u00f3 a que el pa\u00eds se involucrara en la desastrosa invasi\u00f3n de Iraq bas\u00e1ndose en premisas err\u00f3neas\u2014 muri\u00f3, seg\u00fan un comunicado de su familia. Ten\u00eda 84 a\u00f1os.<\/p>\n<p>El cuadrag\u00e9simo sexto vicepresidente, quien sirvi\u00f3 junto al presidente republicano George W. Bush durante dos mandatos entre 2001 y 2009, fue durante d\u00e9cadas una figura influyente y controvertida en Washington.<\/p>\n<p>Sin embargo, en sus \u00faltimos a\u00f1os, Cheney, a\u00fan un conservador de l\u00ednea dura, fue pr\u00e1cticamente marginado de su partido debido a sus intensas <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2022%2F08%2F09%2Fmedia%2Fliz-cheney-fox-news-ad-spots%2Findex.html%23%3A~%3Atext%3DThe%2520ad%2520shows%2520Dick%2520Cheney%2Cattack%2520on%2520the%2520US%2520Capitol.&#038;data=05%7C02%7Clauren.chadwick%40cnn.com%7Cf2ec01bb518c4eb9314808de05c9c5a6%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638954561325672952%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=O6gFsyrfGCzhfTc45rasKSPQNp0caoYdhSBJSA7xMX4%3D&#038;reserved=0\" rel=\"noopener noreferrer\" target=\"_blank\">cr\u00edticas al presidente Donald Trump,<\/a> a quien tild\u00f3 de \u201ccobarde\u201d y la mayor amenaza que jam\u00e1s haya enfrentado la rep\u00fablica.<\/p>\n<p>En un ir\u00f3nico ep\u00edlogo a una brillante carrera pol\u00edtica, emiti\u00f3 su \u00faltimo voto en las elecciones presidenciales de 2024 por una dem\u00f3crata liberal, y tambi\u00e9n miembro del club de los vicepresidentes, Kamala Harris, reflejando as\u00ed c\u00f3mo el Partido Republicano populista se hab\u00eda vuelto en contra de su conservadurismo tradicional.<\/p>\n<p>Cheney padeci\u00f3 enfermedades cardiovasculares durante la mayor parte de su vida adulta, sobreviviendo a una serie de ataques card\u00edacos, para luego llevar una vida plena y vigorosa, y vivi\u00f3 muchos a\u00f1os jubilado despu\u00e9s de un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2012%2F03%2F24%2Fpolitics%2Fcheney-transplant-surgery%2Findex.html&#038;data=05%7C02%7Clauren.chadwick%40cnn.com%7Cf2ec01bb518c4eb9314808de05c9c5a6%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638954561325699344%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=zNUbftCBwViF57tdlvAHN4GTad1QNTi98uoxJzbxpk4%3D&#038;reserved=0\">trasplante de coraz\u00f3n en 2012<\/a> que \u00e9l mismo calific\u00f3 en una entrevista de 2014 como \u201cel regalo de la vida misma\u201d.<\/p>\n<p>Cheney, un sarc\u00e1stico exrepresentante de Wyoming, ex secretario general de la Casa Blanca y exsecretario de Defensa, disfrutaba de una lucrativa carrera en el mundo empresarial cuando George W. Bush le encomend\u00f3 la tarea de evaluar a los posibles candidatos a la vicepresidencia.<\/p>\n<p> La misi\u00f3n culmin\u00f3 con el propio Cheney jurando el cargo como un experimentado n\u00famero dos de un inexperto presidente que lleg\u00f3 al Despacho Oval tras unas elecciones disputadas.<\/p>\n<p>Si bien las caricaturas de Cheney como el verdadero presidente no reflejan con exactitud la verdadera din\u00e1mica del c\u00edrculo \u00edntimo de Bush, \u00e9l disfrutaba de la enorme influencia que ejerc\u00eda entre bastidores.<\/p>\n<p>Cheney se encontraba en la Casa Blanca, con el presidente fuera de la ciudad, en la fresca y despejada ma\u00f1ana del 11 de septiembre de 2001.<\/p>\n<p>En la fracci\u00f3n de segundo de horror en que un segundo avi\u00f3n secuestrado impact\u00f3 contra el World Trade Center en Nueva York, dijo que se convirti\u00f3 en un hombre nuevo, decidido a vengar los ataques orquestados por Al Qaeda e imponer el poder estadounidense en todo Medio Oriente con una doctrina neoconservadora de cambio de r\u00e9gimen y guerra preventiva.<\/p>\n<p>\u201cEn ese momento, supe que se trataba de un acto deliberado. Era un acto terrorista\u201d, record\u00f3 sobre aquel d\u00eda en una entrevista con John King de CNN en 2002.<\/p>\n<p>A\u00f1os despu\u00e9s, Cheney reflexion\u00f3 sobre c\u00f3mo los ataques le dejaron una enorme sensaci\u00f3n de responsabilidad para garantizar que un atentado similar contra la patria jam\u00e1s se repitiera.<\/p>\n<p>Sin embargo, la percepci\u00f3n de que fue el \u00fanico impulsor de la guerra contra el terrorismo y las intervenciones estadounidenses en Iraq y Afganist\u00e1n es err\u00f3nea.<\/p>\n<p>Los relatos contempor\u00e1neos e hist\u00f3ricos de la administraci\u00f3n demuestran que Bush se autodenominaba \u201c<a href=\"https:\/\/www.nytimes.com\/2006\/12\/24\/weekinreview\/the-decider.html\" rel=\"noopener noreferrer\" target=\"_blank\">El Decisor<\/a>\u201d.<\/p>\n<p>Desde un b\u00fanker en las profundidades de la Casa Blanca, Cheney asumi\u00f3 el control de la crisis, dirigiendo la respuesta de una naci\u00f3n afligida y repentinamente en guerra.<\/p>\n<p>Dio la orden extraordinaria de autorizar el derribo de cualquier otro avi\u00f3n secuestrado que se dirigiera a la Casa Blanca o al Capitolio.<\/p>\n<p>Para muchos, sus frecuentes viajes a lugares \u201csecretos\u201d fuera de Washington para preservar la cadena de sucesi\u00f3n presidencial reforzaron su imagen de figura omnipotente que libraba una guerra encubierta desde las sombras.<\/p>\n<p>Su belicismo y su visi\u00f3n alarmista de una naci\u00f3n que enfrentaba graves amenazas no eran una excepci\u00f3n en aquel entonces, especialmente durante un per\u00edodo traum\u00e1tico que incluy\u00f3 ataques con \u00e1ntrax y tiroteos de francotiradores en los alrededores de Washington que exacerbaron el temor p\u00fablico a pesar de no estar relacionados con el 11-S.<\/p>\n<p>Los atentados del 11 de septiembre desencadenaron la guerra de Estados Unidos en Afganist\u00e1n para derrocar a los talibanes, que daban refugio a Al Qaeda, aunque el l\u00edder del grupo terrorista, Osama bin Laden, logr\u00f3 escapar.<\/p>\n<p>Poco despu\u00e9s, Cheney comenz\u00f3 a presionar para ampliar la ofensiva estadounidense a Iraq y a su l\u00edder, Saddam Hussein, cuyas fuerzas hab\u00eda ayudado a expulsar de Kuwait en la primera Guerra del Golfo cuando era jefe del Pent\u00e1gono durante la presidencia de George H.W. Bush.<\/p>\n<p>Las agresivas advertencias del vicepresidente sobre los supuestos programas de armas de destrucci\u00f3n masiva de Iraq, sus presuntos v\u00ednculos con Al Qaeda y su intenci\u00f3n de suministrar armas letales a terroristas para atacar Estados Unidos, desempe\u00f1aron un papel fundamental en la preparaci\u00f3n del terreno para la invasi\u00f3n estadounidense de Iraq en 2003.<\/p>\n<p>Informes del Congreso y otras investigaciones posteriores a la guerra demostraron que Cheney y otros funcionarios de la administraci\u00f3n exageraron, tergiversaron o no presentaron adecuadamente informaci\u00f3n de inteligencia err\u00f3nea sobre programas de armas de destrucci\u00f3n masiva que Iraq, en definitiva, no pose\u00eda.<\/p>\n<p>Una de las afirmaciones m\u00e1s infames de Cheney, que el principal secuestrador del 11-S, Mohamed Atta, se reuni\u00f3 con funcionarios de inteligencia iraqu\u00edes en Praga, nunca fue corroborada, ni siquiera por la comisi\u00f3n independiente que investig\u00f3 los atentados del 11 de septiembre.<\/p>\n<p>Pero Cheney insisti\u00f3 en 2005 en que \u00e9l y otros altos funcionarios actuaban con base en \u201cla mejor informaci\u00f3n de inteligencia disponible\u201d en ese momento.<\/p>\n<p>Si bien admiti\u00f3 que, a posteriori, las deficiencias de la informaci\u00f3n eran evidentes, insisti\u00f3 en que cualquier afirmaci\u00f3n de que los datos estaban \u201cdistorsionados, exagerados o fabricados\u201d era \u201ccompletamente falsa\u201d.<\/p>\n<p>Los conflictos en Iraq y Afganist\u00e1n tambi\u00e9n condujeron a Estados Unidos por un oscuro camino legal y moral, incluyendo los \u201cinterrogatorios intensificados\u201d a sospechosos de terrorismo, que los cr\u00edticos denunciaron como tortura.<\/p>\n<p>Pero Cheney, quien estuvo en el centro de todas las facetas de la guerra global contra el terrorismo, insisti\u00f3 en que m\u00e9todos como el ahogamiento simulado eran perfectamente aceptables.<em> <\/em><\/p>\n<p>Cheney tambi\u00e9n fue un defensor declarado de la detenci\u00f3n de sospechosos de terrorismo sin juicio en la Bah\u00eda de Guant\u00e1namo, Cuba, una pr\u00e1ctica que los cr\u00edticos nacionales e internacionales calificaron de afrenta a los valores fundamentales estadounidenses.<\/p>\n<p>Cheney se convirti\u00f3 en un s\u00edmbolo de los excesos de las campa\u00f1as antiterroristas y de las premisas fatalmente falsas y la mala planificaci\u00f3n que transformaron la invasi\u00f3n de Iraq, inicialmente exitosa, en un sangriento atolladero.<\/p>\n<p>Abandon\u00f3 el cargo repudiado por los dem\u00f3cratas y con un \u00edndice de aprobaci\u00f3n del 31 %, <a href=\"https:\/\/www.pewresearch.org\/politics\/2009\/01\/15\/section-4-favorability-of-political-figures-and-parties\/\" rel=\"noopener noreferrer\" target=\"_blank\">seg\u00fan el Centro de Investigaci\u00f3n Pew.<\/a><\/p>\n<p>Hasta el final de su vida, Cheney no expres\u00f3 arrepentimiento alguno, seguro de que simplemente hab\u00eda hecho lo necesario para responder a un ataque sin precedentes contra el territorio continental estadounidense que mat\u00f3 a casi 2.800 personas y condujo a casi dos d\u00e9cadas de guerras en el extranjero que dividieron a la naci\u00f3n y transformaron su pol\u00edtica.<\/p>\n<p>\u201cLo volver\u00eda a hacer sin pensarlo dos veces\u201d, <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2014%2F12%2F14%2Fpolitics%2Fdick-cheney-torture-report-meet-the-press%2Findex.html&#038;data=05%7C02%7Clauren.chadwick%40cnn.com%7Cf2ec01bb518c4eb9314808de05c9c5a6%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638954561325767976%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=Y3J%2Bi0BW%2Becv5%2BN6FNZUDxrNeyePgT%2Bw%2BPpwhMZu8U4%3D&#038;reserved=0\">dijo Cheney<\/a> cuando se le present\u00f3 un informe del Comit\u00e9 de Inteligencia del Senado en 2014 que <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2015%2F01%2F29%2Fus%2Fcia-torture-report-fast-facts%2Findex.html&#038;data=05%7C02%7Clauren.chadwick%40cnn.com%7Cf2ec01bb518c4eb9314808de05c9c5a6%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638954561325781648%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=%2FnHtipujwTjJDFtqyVHk1uXnZQtZGrVPt4RAC4WKbRg%3D&#038;reserved=0\">conclu\u00eda<\/a> que los m\u00e9todos de interrogatorio reforzados eran brutales e ineficaces y responsables de da\u00f1ar la posici\u00f3n de Estados Unidos ante el mundo.<\/p>\n<p>Sobre la guerra de Iraq, declar\u00f3 a CNN en 2015: \u201cEra lo correcto entonces. Lo cre\u00eda entonces y lo creo ahora\u201d.<\/p>\n<p>Las agresivas pol\u00edticas antiterroristas de Cheney se enmarcaban en una doctrina personal que justificaba poderes presidenciales extraordinarios con una supervisi\u00f3n limitada del Congreso.<\/p>\n<p>Esto concordaba con su creencia de que la autoridad del poder ejecutivo se hab\u00eda erosionado err\u00f3neamente tras la guerra de Vietnam y el esc\u00e1ndalo Watergate, que provoc\u00f3 la dimisi\u00f3n de su primer jefe presidencial, el presidente Richard Nixon.<\/p>\n<p>Sin embargo, en sus \u00faltimos a\u00f1os, Cheney se convirti\u00f3 en un cr\u00edtico ac\u00e9rrimo de un hombre que ten\u00eda una visi\u00f3n a\u00fan m\u00e1s amplia de los poderes presidenciales que \u00e9l: Trump. Cheney hab\u00eda apoyado a Trump en 2016 a pesar de sus cr\u00edticas a las pol\u00edticas exteriores de Bush y Cheney y a la transformaci\u00f3n del partido de Reagan en un Partido Republicano populista y nacionalista.<\/p>\n<p>Pero el fin del primer mandato del presidente, cuando su negativa a aceptar la derrota electoral de 2020 desencaden\u00f3 la insurrecci\u00f3n del 6 de enero, impuls\u00f3 a Cheney a pronunciarse, de una manera inusualmente p\u00fablica.<\/p>\n<p>La hija del exvicepresidente, la entonces representante de Wyoming, Liz Cheney, sacrific\u00f3 una prometedora carrera en el Partido Republicano para oponerse a Trump tras su intento de anular las elecciones presidenciales de 2020 y la revuelta en el Capitolio de Estados Unidos el 6 de enero de 2021.<\/p>\n<p>En un <a href=\"https:\/\/www.cnn.com\/2022\/08\/04\/politics\/dick-cheney-donald-trump-coward-wyoming-primary\/index.html\" rel=\"noopener noreferrer\" target=\"_blank\">anuncio de la fallida campa\u00f1a de su hija<\/a> para derrotar a un candidato pro-Trump en las primarias de 2022, Dick Cheney \u2014a quien, para entonces, rara vez se ve\u00eda en p\u00fablico\u2014 mir\u00f3 directamente a la c\u00e1mara desde debajo de un sombrero de vaquero de ala ancha y transmiti\u00f3 un mensaje contundente.<\/p>\n<p>\u201cEn los 246 a\u00f1os de historia de nuestra naci\u00f3n, nunca ha habido un individuo que represente una mayor amenaza para nuestra rep\u00fablica que Donald Trump\u201d, dijo Cheney.<\/p>\n<p>\u201cEs un cobarde. Un hombre de verdad no mentir\u00eda a sus seguidores. Perdi\u00f3 las elecciones, y perdi\u00f3 por mucho. Lo s\u00e9. \u00c9l lo sabe, y en el fondo, creo que la mayor\u00eda de los republicanos lo saben\u201d, indic\u00f3.<\/p>\n<p>Richard Bruce Cheney naci\u00f3 el 30 de enero de 1941 en Lincoln, Nebraska.<\/p>\n<p>Mientras viv\u00eda en el peque\u00f1o pueblo de monta\u00f1a de Casper, Wyoming, conoci\u00f3 a Lynne Vincent, su novia del instituto y futura esposa.<\/p>\n<p>Cheney fue <a href=\"https:\/\/www.cnn.com\/2013\/03\/15\/politics\/cheney-documentary\/index.html\">admitido<\/a> en la Universidad de Yale con una beca, pero tuvo dificultades para integrarse y mantener sus calificaciones. Seg\u00fan \u00e9l mismo admiti\u00f3, <a href=\"https:\/\/millercenter.org\/the-presidency\/presidential-oral-histories\/richard-b-cheney-oral-history\">fue expulsado<\/a>.<\/p>\n<p>Regres\u00f3 al oeste para trabajar en las l\u00edneas el\u00e9ctricas y fue arrestado dos veces por conducir bajo los efectos del alcohol.<\/p>\n<p>En un punto de inflexi\u00f3n para Cheney, Lynne le dio un ultim\u00e1tum; seg\u00fan cont\u00f3 a <a href=\"https:\/\/www.newyorker.com\/magazine\/2001\/05\/07\/the-quiet-man-nicholas-lemann\">The New Yorker<\/a>, ella le hab\u00eda dejado claro que no estaba interesada en casarse con un liniero del condado. \u201cMe puse las pilas y me esforc\u00e9. Decid\u00ed que era hora de labrarme un futuro\u201d, declar\u00f3 a la revista.<\/p>\n<p>Cheney regres\u00f3 a la universidad y obtuvo una licenciatura y una maestr\u00eda en ciencias pol\u00edticas por la Universidad de Wyoming. La pareja se cas\u00f3 en 1964.<\/p>\n<p>A Cheney le sobreviven Lynne, sus hijas Liz y Mary Cheney y siete nietos.<\/p>\n<p>Cheney comenz\u00f3 a perfeccionar su juego de poder interno \u2014en el que se convirti\u00f3 en un maestro\u2014 como ayudante de Nixon.<\/p>\n<p>Posteriormente, Donald Rumsfeld lo eligi\u00f3 como su subsecretario de la Casa Blanca durante la presidencia de Gerald Ford, y en 1975 sucedi\u00f3 a su mentor y amigo cercano en el cargo cuando Rumsfeld se convirti\u00f3 en secretario de Defensa.<\/p>\n<p>Cheney desempe\u00f1\u00f3 un papel fundamental en el resurgimiento de su colaboraci\u00f3n en 2001, cuando convenci\u00f3 a Rumsfeld para que regresara al Pent\u00e1gono tras haber estado apartado de la pol\u00edtica.<\/p>\n<p>Ambos forjaron una extraordinaria alianza en los despachos de la administraci\u00f3n Bush durante la guerra contra el terrorismo y la guerra de Iraq, para gran frustraci\u00f3n de los miembros m\u00e1s moderados del Gobierno, como el entonces secretario de Estado Colin Powell y la asesora de Seguridad Nacional Condoleezza Rice, quien sucedi\u00f3 a Powell en el segundo mandato.<\/p>\n<p>Mientras el presidente dem\u00f3crata Jimmy Carter estaba en la Casa Blanca, Cheney decidi\u00f3 postularse para el Congreso y fue elegido para el \u00fanico esca\u00f1o de Wyoming en la C\u00e1mara de Representantes de Estados Unidos en 1978.<\/p>\n<p>Cheney cumpli\u00f3 seis mandatos, llegando a ser jefe de la minor\u00eda en la C\u00e1mara, y acumul\u00f3 un <a href=\"http:\/\/www.cnn.com\/TRANSCRIPTS\/0007\/25\/wt.08.html\" rel=\"noopener noreferrer\" target=\"_blank\">historial de votaci\u00f3n muy conservador<\/a>.<\/p>\n<p>En 1989, el presidente George H.W. Bush, quien hab\u00eda trabajado con Cheney en la administraci\u00f3n Ford, lo design\u00f3 como su secretario de Defensa, calific\u00e1ndolo de \u201camigo y asesor de confianza\u201d. Fue confirmado por el Senado con una votaci\u00f3n de 92-0.<\/p>\n<p>Como jefe del Pent\u00e1gono, Cheney demostr\u00f3 una gran habilidad al dirigir la invasi\u00f3n estadounidense de Panam\u00e1 en 1989 y la Operaci\u00f3n Tormenta del Desierto en 1991 para expulsar a las tropas iraqu\u00edes de Kuwait.<\/p>\n<p>Tras su etapa como secretario de Defensa, Cheney consider\u00f3 brevemente presentarse a las elecciones presidenciales de 1996, pero finalmente desisti\u00f3.<\/p>\n<p>Durante la presidencia del dem\u00f3crata Bill Clinton, Cheney se uni\u00f3 a Halliburton Co., con sede en Dallas, donde desempe\u00f1\u00f3 el cargo de CEO.<\/p>\n<p>No fue hasta que el joven Bush decidi\u00f3 presentarse a las elecciones que Cheney fue elegido para dirigir la b\u00fasqueda del compa\u00f1ero de f\u00f3rmula del candidato republicano y, despu\u00e9s de rechazar inicialmente el puesto, acab\u00f3 siendo a\u00f1adido a la candidatura del Partido Republicano.<\/p>\n<p>\u201cDurante el proceso, llegu\u00e9 a la conclusi\u00f3n de que el selector era la mejor persona para ser seleccionada\u201d, dijo Bush en el documental de CNN de 2020 \u201cPresidente en espera\u201d.<\/p>\n<p>Cheney aport\u00f3 una gran cantidad de conocimientos y experiencia a \u00e1reas donde los cr\u00edticos se\u00f1alaban la debilidad de Bush. Como exgobernador de Texas, Bush carec\u00eda de experiencia pol\u00edtica en Washington y ten\u00eda poca trayectoria militar y en pol\u00edtica exterior en comparaci\u00f3n con Cheney.<\/p>\n<p>Al comienzo de la presidencia de Bush, Cheney lider\u00f3 un grupo de trabajo para desarrollar la pol\u00edtica energ\u00e9tica del Gobierno y trat\u00f3 de mantener sus registros en secreto en una lucha que dur\u00f3 el primer mandato de Bush y lleg\u00f3 hasta la Corte Suprema de Estados Unidos.<\/p>\n<p>Sin embargo, discrepaba con Bush sobre el tema del matrimonio entre personas del mismo sexo, afirmando que la decisi\u00f3n deb\u00eda dejarse en manos de los estados.<\/p>\n<p>En un encuentro con la comunidad en 2004, mencion\u00f3 p\u00fablicamente, por primera vez, la orientaci\u00f3n sexual de su hija Mary, seg\u00fan <a href=\"https:\/\/www.washingtonpost.com\/wp-dyn\/articles\/A29862-2004Aug24.html?itid=lk_inline_manual_5\" rel=\"noopener noreferrer\" target=\"_blank\">The Washington Post<\/a>. \u201cCon respecto a las relaciones, mi opini\u00f3n general es que la libertad significa libertad para todos.<br \/>Las personas\u2026 deber\u00edan ser libres de entablar cualquier tipo de relaci\u00f3n que deseen\u201d, declar\u00f3, seg\u00fan inform\u00f3 el Post.<\/p>\n<p>Su relaci\u00f3n con Bush se complic\u00f3 en a\u00f1os posteriores, incluso por la negativa de Bush a indultar al jefe de gabinete de Cheney, Scooter Libby, quien hab\u00eda sido condenado por perjurio y obstrucci\u00f3n de la justicia en 2007 tras una investigaci\u00f3n sobre qui\u00e9n filtr\u00f3 la identidad de un agente de la CIA.<\/p>\n<p>En uno de los momentos m\u00e1s notorios de su vida personal, que contribuy\u00f3 a su leyenda en 2006, Cheney <a href=\"https:\/\/www.cnn.com\/2006\/POLITICS\/02\/12\/cheney\/\">dispar\u00f3 accidentalmente a un compa\u00f1ero de caza<\/a> en la cara con perdigones, caus\u00e1ndole heridas relativamente leves.<\/p>\n<p>Los problemas de salud de Cheney comenzaron en 1978, cuando sufri\u00f3 su primer infarto a los 37 a\u00f1os mientras hac\u00eda campa\u00f1a para el Congreso.<\/p>\n<p>Le siguieron otros tres en 1984, 1988 y noviembre de 2000, pocos d\u00edas despu\u00e9s de que comenzara el recuento de votos en Florida para las elecciones presidenciales, que dio como resultado la victoria de Bush y Cheney.<\/p>\n<p>En aquel momento, Cheney declar\u00f3 que ser\u00eda el primero en dimitir si supiera que no podr\u00eda desempe\u00f1ar el cargo y ten\u00eda una carta de renuncia preparada por si se le consideraba incapacitado.<\/p>\n<p>Cheney complet\u00f3 los dos mandatos de Bush y asisti\u00f3 a la investidura de Barack Obama en enero de 2009 en silla de ruedas.<\/p>\n<p>Un a\u00f1o despu\u00e9s de sufrir su quinto ataque card\u00edaco en 2010, Cheney recibi\u00f3 una bomba card\u00edaca que mantuvo el \u00f3rgano funcionando hasta su trasplante en 2012.<\/p>\n<p>Tras dejar el cargo, Cheney regres\u00f3 a la vida privada, escribiendo dos libros de memorias: uno sobre su trayectoria personal y pol\u00edtica y otro sobre su lucha contra la enfermedad card\u00edaca, adem\u00e1s de un libro con su hija, Liz.<\/p>\n<p>Se convirti\u00f3 en uno de los cr\u00edticos m\u00e1s ac\u00e9rrimos del presidente Barack Obama dentro del Partido Republicano, quien hab\u00eda basado su campa\u00f1a electoral en promesas de poner fin a las guerras y otros cambios respecto a lo que \u00e9l consideraba pol\u00edticas fallidas de la administraci\u00f3n Bush-Cheney.<\/p>\n<p>A\u00f1os m\u00e1s tarde, Cheney criticaba duramente a su propio partido \u2014especialmente la respuesta de sus l\u00edderes al ataque al Capitolio\u2014 cuando regres\u00f3 al Congreso de Estados Unidos con la entonces representante Liz Cheney<strong> <\/strong>en el primer aniversario del 6 de enero de 2021.<\/p>\n<p>\u201cEstoy profundamente decepcionado por la falta de reconocimiento, por parte de muchos miembros de mi partido, de la gravedad de los ataques del 6 de enero y de la continua amenaza que se cierne sobre nuestra naci\u00f3n\u201d, dijo en un comunicado.<\/p>\n<p>En un momento memorable, <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/january-6-capitol-insurrection-anniversary\/h_70f9c3ae3b478fa7b2115bfc9f89f22b\">los dem\u00f3cratas hicieron fila<\/a> para saludar al exvicepresidente republicano y estrecharle la mano.<\/p>\n<p>La expresidenta dem\u00f3crata de la C\u00e1mara de Representantes, Nancy Pelosi, <a href=\"https:\/\/www.cnn.com\/2023\/11\/28\/politics\/liz-cheney-trump-mccarthy-book\/index.html\" rel=\"noopener noreferrer\" target=\"_blank\">abraz\u00f3 a Cheney<\/a>. El exvicepresidente critic\u00f3 duramente a los l\u00edderes republicanos en el Congreso, afirmando que no se parecen en nada a los l\u00edderes que recordaba de su \u00e9poca en la c\u00e1mara.<\/p>\n<p>Fue una escena que habr\u00eda sido impensable dos d\u00e9cadas antes y una ilustraci\u00f3n de c\u00f3mo los extraordinarios cambios en la pol\u00edtica estadounidense provocados por Trump hab\u00edan hecho que antiguos rivales pol\u00edticos encontraran una causa com\u00fan en la lucha por la democracia.<\/p>\n<p>\u201cEste liderazgo no se parece en nada al de las personas que conoc\u00ed cuando estuve aqu\u00ed durante 10 a\u00f1os\u201d, manifest\u00f3 Cheney en el Capitolio en 2022.<\/p>\n<p>Cheney continu\u00f3 criticando a Trump en los a\u00f1os siguientes e incluso lleg\u00f3 a <a href=\"https:\/\/www.cnn.com\/2024\/09\/06\/politics\/dick-cheney-kamala-harris-president\/index.html\">respaldar a la entonces vicepresidenta Kamala Harris<\/a>, dem\u00f3crata y rival de Trump en las elecciones presidenciales de 2024.<\/p>\n<p>Declar\u00f3 que votar\u00eda por Harris debido al \u201cdeber de anteponer el pa\u00eds al partidismo para defender nuestra Constituci\u00f3n\u201d.<\/p>\n<p>Cheney enfatiz\u00f3 su desd\u00e9n por Trump en aquel momento y advirti\u00f3 que \u201cnunca m\u00e1s se le podr\u00eda confiar el poder\u201d, aunque Trump ganar\u00eda la presidencia un par de meses despu\u00e9s.<\/p>\n<p><em>Jamie Gangel y Shania Shelton, de CNN, contribuyeron a este informe.<\/em><\/p>\n<p><em>Noticia en desarrollo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dick Cheney, el vicepresidente m\u00e1s poderoso de la era moderna estadounidense y principal art\u00edfice de la \u201cguerra contra el terrorismo\u201d \u2014quien contribuy\u00f3 a que el pa\u00eds se involucrara en la desastrosa invasi\u00f3n de Iraq bas\u00e1ndose en premisas err\u00f3neas\u2014 muri\u00f3, seg\u00fan un comunicado de su familia. Ten\u00eda 84 a\u00f1os. El cuadrag\u00e9simo sexto vicepresidente, quien sirvi\u00f3 junto [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468013","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dick Cheney, el vicepresidente m\u00e1s poderoso de la era moderna estadounidense y principal art\u00edfice de la \u201cguerra contra el terrorismo\u201d \u2014quien contribuy\u00f3 a que el pa\u00eds se involucrara en la desastrosa invasi\u00f3n de Iraq bas\u00e1ndose en premisas err\u00f3neas\u2014 muri\u00f3, seg\u00fan un comunicado de su familia. Ten\u00eda 84 a\u00f1os. El cuadrag\u00e9simo sexto vicepresidente, quien sirvi\u00f3 junto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-04T12:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush\",\"datePublished\":\"2025-11-04T12:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\"},\"wordCount\":3120,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\",\"name\":\"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-04T12:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias","og_description":"Dick Cheney, el vicepresidente m\u00e1s poderoso de la era moderna estadounidense y principal art\u00edfice de la \u201cguerra contra el terrorismo\u201d \u2014quien contribuy\u00f3 a que el pa\u00eds se involucrara en la desastrosa invasi\u00f3n de Iraq bas\u00e1ndose en premisas err\u00f3neas\u2014 muri\u00f3, seg\u00fan un comunicado de su familia. Ten\u00eda 84 a\u00f1os. El cuadrag\u00e9simo sexto vicepresidente, quien sirvi\u00f3 junto [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-04T12:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/"},"author":{"name":"","@id":""},"headline":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush","datePublished":"2025-11-04T12:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/"},"wordCount":3120,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","name":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-04T12:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/04\/muere-dick-cheney-vicepresidente-republicano-bush-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-04T12:03:38Z","datePublished":"2025-11-04T12:03:38Z","dateModified":"2025-11-04T12:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere Dick Cheney, el influyente vicepresidente republicano de George W. Bush\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/04\\\/muere-dick-cheney-vicepresidente-republicano-bush-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/04\\\/muere-dick-cheney-vicepresidente-republicano-bush-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-04T12:03:38Z\",\"datePublished\":\"2025-11-04T12:03:38Z\",\"dateModified\":\"2025-11-04T12:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468016,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/quien-fue-dick-cheney-guerra-terrorismo-trax\/","url_meta":{"origin":1468013,"position":0},"title":"\u00bfQui\u00e9n fue Dick Cheney, el llamado art\u00edfice de la &#171;guerra contra el terrorismo&#187; y poderoso exvicepresidente de EE.UU.?","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Dick Cheney deja un legado de poder, controversias y pol\u00edticas de guerra que marcaron y definieron al Estados Unidos contempor\u00e1neo. Fue el cuadrag\u00e9simo sexto vicepresidente del pa\u00eds, sirvi\u00f3 junto al presidente republicano George W. Bush durante dos mandatos entre 2001 y 2009. Cheney fue durante d\u00e9cadas una figura influyente y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468528,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/20\/trump-vance-funeral-dick-cheney-trax\/","url_meta":{"origin":1468013,"position":1},"title":"Ni Trump ni Vance fueron invitados al funeral de Dick Cheney, pero s\u00ed asistir\u00e1n los cuatro exvicepresidentes que a\u00fan viven","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Expresidentes y pol\u00edticos de ambos partidos se re\u00fanen este jueves en Washington, para el funeral del exvicepresidente Dick Cheney, despidiendo as\u00ed a una figura clave de la pol\u00edtica republicana anterior al movimiento MAGA.Pero ni el presidente Donald Trump ni el vicepresidente J.D. Vance fueron invitados al funeral de Cheney, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468017,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/vice-pelicula-dick-cheney-christian-bale-orix\/","url_meta":{"origin":1468013,"position":2},"title":"&#171;Vice&#187;, la pel\u00edcula que cont\u00f3 la vida del exvicepresidente de EE.UU. Dick Cheney","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Hollywood, cuando apunta al poder en Washington, suele fijarse en los presidentes: \u201cLincoln\u201d, \u201cJFK\u201d, \u201cNixon\u201d, por solo citar algunos ejemplos. Lo que confirma lo influyente que fue el expresidente Dick Cheney, fallecido este martes 4 de noviembre a los 84 a\u00f1os, cuya vida fue objeto de una pel\u00edcula, \u201cVice\u201d, en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468043,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/05\/5-cosas-5-de-noviembre-orix\/","url_meta":{"origin":1468013,"position":3},"title":"Las 5 cosas que debes saber este 5 de noviembre: elecciones en EE.UU., accidente de avi\u00f3n en Louisville y presidente de Per\u00fa","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"CNN entrevista al presidente de Per\u00fa, Jos\u00e9 Jer\u00ed, tras la decisi\u00f3n de su Gobierno de cortar relaciones diplom\u00e1ticas con M\u00e9xico. Un accidente de avi\u00f3n cerca del aeropuerto de Louisville deja al menos siete muertos. Las disputas detr\u00e1s del aplazamiento de la Cumbre de las Am\u00e9ricas. Esto es lo que debes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459686,"url":"https:\/\/noticiasya.com\/tampa\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","url_meta":{"origin":1468013,"position":4},"title":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?","author":"","date":"marzo 9, 2025","format":false,"excerpt":"J. D. Vance es un tipo diferente de vicepresidente.No es el amo maquiav\u00e9lico de Washington que trabaja en las sombras, como Dick Cheney, ni el hombre de confianza en pol\u00edtica exterior, como George H. W. Bush o Joe Biden.En cambio, el joven Vance parece haberse convertido en la personificaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451154,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/15\/trump-vance-vicepresidente-heredero-politico-maga-analisis-trax\/","url_meta":{"origin":1468013,"position":5},"title":"AN\u00c1LISIS | Dos d\u00edas despu\u00e9s de sobrevivir a un intento de magnicidio, Trump elige a su heredero MAGA","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) -- J.D. Vance es la encarnaci\u00f3n de la transformaci\u00f3n populista, nacionalista y obrera del viejo Partido Republicano del establishment.Por eso el expresidente Donald Trump \u2013que nunca olvida los entusiasmos de su base\u2013 eligi\u00f3 al senador de Ohio como compa\u00f1ero de f\u00f3rmula para la vicepresidencia y lo nombr\u00f3 de hecho\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468013"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468013\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}