{"id":1468032,"date":"2025-11-04T17:03:39","date_gmt":"2025-11-05T01:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/"},"modified":"2025-11-04T17:03:39","modified_gmt":"2025-11-05T01:03:39","slug":"peru-jeri-mexico-crisis-diplomatica-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","title":{"rendered":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas"},"content":{"rendered":"<p>El presidente interino de Per\u00fa, Jos\u00e9 Jer\u00ed, dijo este martes que Per\u00fa \u201cmantuvo la cordialidad hasta donde se pudo\u201d con M\u00e9xico, al referirse a la decisi\u00f3n de su Gobierno de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/03\/latinoamerica\/peru-rompe-relaciones-mexico-asilo-betssy-chavez-orix\">romper relaciones diplom\u00e1ticas<\/a> con el pa\u00eds por la decisi\u00f3n de dar asilo a la expresidenta del Consejo de Ministros, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/04\/latinoamerica\/quien-es-betssy-chavez-exministra-peru-mexico-orix\">Betssy Ch\u00e1vez<\/a>.<\/p>\n<p>\u201cCreo que hemos demostrado que la ruptura de relaciones diplom\u00e1ticas responde justamente a un criterio que hemos tenido\u201d, asegur\u00f3 Jer\u00ed en una entrevista exclusiva con CNN desde Lima.<\/p>\n<p>El presidente interino dijo que eval\u00faa con Canciller\u00eda la decisi\u00f3n de otorgar el salvoconducto a la exfuncionaria del Gobierno de Pedro Castillo, <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/06\/20\/peru-capturan-expresidenta-consejo-ministros-orix\">investigada en Per\u00fa<\/a> por los presuntos delitos de rebeli\u00f3n y conspiraci\u00f3n en agravio del Estado, se\u00f1alamientos que Ch\u00e1vez rechaza.<\/p>\n<p>La posibilidad de ofrecer un salvoconducto a Ch\u00e1vez, agreg\u00f3, la definir\u00e1n \u201cestrictamente\u201d con la recomendaci\u00f3n de Canciller\u00eda. Y adelant\u00f3 que probablemente el viernes se conozca \u201cla postura definitiva\u201d de Per\u00fa al respecto.<\/p>\n<p>Jer\u00ed asegur\u00f3 que aceptar\u00e1 la recomendaci\u00f3n de la Canciller\u00eda en los t\u00e9rminos que as\u00ed lo plantee, y dijo que ser\u00e1 en base a \u201cinformaci\u00f3n t\u00e9cnica y acuerdos internacionales\u201d.<\/p>\n<p>Tambi\u00e9n dej\u00f3 en claro que existe una tensi\u00f3n con el Gobierno de la presidenta Claudia Sheinbaum por lo que consideran una intromisi\u00f3n en asuntos de su pa\u00eds. M\u00e9xico por su parte <a href=\"https:\/\/www.gob.mx\/sre\/prensa\/comunicado-relaciones-exteriores\">plante\u00f3 su desacuerdo<\/a> con la decisi\u00f3n de Per\u00fa. \u201cNosotros tampoco est\u00e1bamos de acuerdo cuando ella se expresaba respecto a asuntos internos de nuestro pa\u00eds, y creo que hemos mantenido la cordialidad hasta donde se pudo\u201d.<\/p>\n<p>Pese a ese conflicto en curso, Jer\u00ed no prev\u00e9 que esto afecte a las relaciones comerciales. \u201cTodav\u00eda hay un principio de realidad entre ambos pa\u00edses. Canciller\u00eda y los sectores son los que continuar\u00e1n. Y adem\u00e1s, a nivel consular todav\u00eda mantendremos las iniciativas que siempre se han sostenido en el tiempo\u201d.<\/p>\n<p>La tensi\u00f3n en las relaciones entre ambos pa\u00edses se remonta a a\u00f1os atr\u00e1s, cuando el Gobierno del entonces presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, respald\u00f3 a Pedro Castillo, raz\u00f3n por la que el Congreso peruano declar\u00f3 <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/05\/22\/comision-relaciones-exteriores-congreso-peru-declara-persona-non-grata-presidente-mexico-orix\">persona non grata<\/a> al entonces presidente en mayo de 2023.<\/p>\n<p>En las \u00faltimas horas, la situaci\u00f3n se profundiz\u00f3 tras la decisi\u00f3n de M\u00e9xico de otorgar asilo a Ch\u00e1vez, investigada por su presunta participaci\u00f3n en el supuesto intento de golpe de Estado que habr\u00eda sido perpetrado por Castillo en 2022. La defensa de Ch\u00e1vez <a href=\"https:\/\/x.com\/raul_olaechea\/status\/1985551605651865831\">sostiene<\/a> que la excongresista es objeto de \u201cpersecuci\u00f3n pol\u00edtica\u201d en Per\u00fa.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente interino de Per\u00fa, Jos\u00e9 Jer\u00ed, dijo este martes que Per\u00fa \u201cmantuvo la cordialidad hasta donde se pudo\u201d con M\u00e9xico, al referirse a la decisi\u00f3n de su Gobierno de romper relaciones diplom\u00e1ticas con el pa\u00eds por la decisi\u00f3n de dar asilo a la expresidenta del Consejo de Ministros, Betssy Ch\u00e1vez. \u201cCreo que hemos demostrado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468032","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &quot;hasta donde se pudo&quot; antes de cortar relaciones diplom\u00e1ticas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &quot;hasta donde se pudo&quot; antes de cortar relaciones diplom\u00e1ticas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente interino de Per\u00fa, Jos\u00e9 Jer\u00ed, dijo este martes que Per\u00fa \u201cmantuvo la cordialidad hasta donde se pudo\u201d con M\u00e9xico, al referirse a la decisi\u00f3n de su Gobierno de romper relaciones diplom\u00e1ticas con el pa\u00eds por la decisi\u00f3n de dar asilo a la expresidenta del Consejo de Ministros, Betssy Ch\u00e1vez. \u201cCreo que hemos demostrado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T01:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas\",\"datePublished\":\"2025-11-05T01:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\"},\"wordCount\":486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\",\"name\":\"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico \\\"hasta donde se pudo\\\" antes de cortar relaciones diplom\u00e1ticas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-05T01:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico \"hasta donde se pudo\" antes de cortar relaciones diplom\u00e1ticas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico \"hasta donde se pudo\" antes de cortar relaciones diplom\u00e1ticas - Noticias","og_description":"El presidente interino de Per\u00fa, Jos\u00e9 Jer\u00ed, dijo este martes que Per\u00fa \u201cmantuvo la cordialidad hasta donde se pudo\u201d con M\u00e9xico, al referirse a la decisi\u00f3n de su Gobierno de romper relaciones diplom\u00e1ticas con el pa\u00eds por la decisi\u00f3n de dar asilo a la expresidenta del Consejo de Ministros, Betssy Ch\u00e1vez. \u201cCreo que hemos demostrado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-05T01:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/"},"author":{"name":"","@id":""},"headline":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas","datePublished":"2025-11-05T01:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/"},"wordCount":486,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","name":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico \"hasta donde se pudo\" antes de cortar relaciones diplom\u00e1ticas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-05T01:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Presidente de Per\u00fa dice que mantuvo la cordialidad con M\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\u00e1ticas","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/04\/peru-jeri-mexico-crisis-diplomatica-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-05T01:03:39Z","datePublished":"2025-11-05T01:03:39Z","dateModified":"2025-11-05T01:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Presidente de Per\\u00fa dice que mantuvo la cordialidad con M\\u00e9xico &#171;hasta donde se pudo&#187; antes de cortar relaciones diplom\\u00e1ticas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/04\\\/peru-jeri-mexico-crisis-diplomatica-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/04\\\/peru-jeri-mexico-crisis-diplomatica-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-05T01:03:39Z\",\"datePublished\":\"2025-11-05T01:03:39Z\",\"dateModified\":\"2025-11-05T01:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468174,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/09\/encargada-embajada-mexico-peru-abandona-pais-efe\/","url_meta":{"origin":1468032,"position":0},"title":"La encargada de la Embajada de M\u00e9xico en Per\u00fa abandona el pa\u00eds tras ruptura de relaciones diplom\u00e1ticas","author":"","date":"noviembre 9, 2025","format":false,"excerpt":"La encargada de la Embajada de M\u00e9xico en Per\u00fa, Karla Ornelas, abandon\u00f3 el pa\u00eds andino en cumplimiento de una orden \u201cperentoria\u201d que le dio el Gobierno peruano tras romper relaciones diplom\u00e1ticas con su pa\u00eds por el asilo otorgado a Betssy Ch\u00e1vez, ex primera ministra de Per\u00fa, informaron fuentes oficiales.\u201cEn la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468043,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/05\/5-cosas-5-de-noviembre-orix\/","url_meta":{"origin":1468032,"position":1},"title":"Las 5 cosas que debes saber este 5 de noviembre: elecciones en EE.UU., accidente de avi\u00f3n en Louisville y presidente de Per\u00fa","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"CNN entrevista al presidente de Per\u00fa, Jos\u00e9 Jer\u00ed, tras la decisi\u00f3n de su Gobierno de cortar relaciones diplom\u00e1ticas con M\u00e9xico. Un accidente de avi\u00f3n cerca del aeropuerto de Louisville deja al menos siete muertos. Las disputas detr\u00e1s del aplazamiento de la Cumbre de las Am\u00e9ricas. Esto es lo que debes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468650,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/24\/jeri-peru-bettsy-chavez-no-descarta-embajada-mexico-efe\/","url_meta":{"origin":1468032,"position":2},"title":"Jer\u00ed no descarta ingresar a Embajada de M\u00e9xico para detener ex primera ministra de Per\u00fa","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"El presidente interino de Per\u00fa, Jos\u00e9 Jer\u00ed, afirm\u00f3 que si se tiene que entrar a la Embajada de M\u00e9xico de Lima para detener a la ex primera ministra Betssy Ch\u00e1vez, quien est\u00e1 procesada por el intento fallido de golpe del Estado del expresidente Pedro Castillo, se har\u00e1.\u201cSi se tiene que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467999,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/03\/peru-rompe-relaciones-mexico-asilo-betssy-chavez-orix\/","url_meta":{"origin":1468032,"position":3},"title":"Per\u00fa rompe relaciones diplom\u00e1ticas con M\u00e9xico por otorgar asilo a quien fuera la primera ministra de Pedro Castillo","author":"","date":"noviembre 3, 2025","format":false,"excerpt":"El Gobierno de Per\u00fa anunci\u00f3 este lunes que rompi\u00f3 relaciones diplom\u00e1ticas con M\u00e9xico, luego de que este pa\u00eds otorgara asilo a la ex primera ministra Betssy Ch\u00e1vez.\u201cEl Gobierno peruano ha decidido romper relaciones diplom\u00e1ticas con M\u00e9xico\u201d, dijo en una rueda de prensa el ministro de Relaciones Exteriores de Per\u00fa, Hugo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470818,"url":"https:\/\/noticiasya.com\/tampa\/2026\/02\/03\/peru-nuevo-embajador-eeuu-china-orix\/","url_meta":{"origin":1468032,"position":4},"title":"China desplaz\u00f3 a EE.UU. como primer socio comercial de Per\u00fa. El nuevo embajador de Washington busca revertir esa tendencia","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Bernie Navarro, un empresario estrechamente ligado a Per\u00fa, es el nuevo embajador de Estados Unidos en el pa\u00eds sudamericano y este martes present\u00f3 sus credenciales al presidente Jos\u00e9 Jer\u00ed en el Palacio de Gobierno, seg\u00fan inform\u00f3 el propio diplom\u00e1tico en X.Navarro est\u00e1 casado con una peruana y a\u00f1os atr\u00e1s celebr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471413,"url":"https:\/\/noticiasya.com\/tampa\/2026\/02\/18\/jose-balcazar-presidente-congreso-peru-orix\/","url_meta":{"origin":1468032,"position":5},"title":"Jos\u00e9 Mar\u00eda Balc\u00e1zar es elegido presidente interino de Per\u00fa tras la destituci\u00f3n de Jos\u00e9 Jer\u00ed","author":"","date":"febrero 18, 2026","format":false,"excerpt":"Jos\u00e9 Mar\u00eda Balc\u00e1zar, del partido Per\u00fa Libre, fue elegido este mi\u00e9rcoles presidente interino de Per\u00fa un d\u00eda despu\u00e9s de la destituci\u00f3n de Jos\u00e9 Jer\u00ed, convirti\u00e9ndose en el octavo mandatario desde la presidencia de Pedro Pablo Kuczynski, en medio de una d\u00e9cada de inestabilidad pol\u00edtica en el pa\u00eds.Con un total de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468032"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468032\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}