{"id":1468058,"date":"2025-11-05T10:03:47","date_gmt":"2025-11-05T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/"},"modified":"2025-11-05T10:03:47","modified_gmt":"2025-11-05T18:03:47","slug":"sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","title":{"rendered":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta"},"content":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, habl\u00f3 este mi\u00e9rcoles sobre el acoso sexual que sufri\u00f3 cuando se dirig\u00eda a una reuni\u00f3n a pie desde su residencia en Palacio Nacional el martes, cuando un hombre se le acerc\u00f3 al tiempo que la mandataria saludaba a otras personas.<\/p>\n<p>\u201cDecidimos irnos caminando (de Palacio Nacional a la Secretar\u00eda de Educaci\u00f3n P\u00fablica para la reuni\u00f3n), mucha gente nos salud\u00f3 en el camino, sin problema, hasta que se acerc\u00f3 esta persona totalmente alcoholizada y vivo este episodio de acoso\u201d, indic\u00f3 Sheinbaum en su conferencia matutina.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/04\/mexico\/video\/acosan-presidenta-claudia-sheinbaum-panorama-mundial-tv\">En videos<\/a> se puede ver a la presidenta de M\u00e9xico caminando cerca de Palacio Nacional para dirigirse a la reuni\u00f3n. Mientras algunas personas saludan a Sheinbaum, un hombre se acerca para intentar besarla y abrazarla sin su consentimiento.<\/p>\n<p>Por estos hechos, Sheinbaum coment\u00f3 que levant\u00f3 una denuncia ante la Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico (FGJCDMX) y confirm\u00f3 que el hombre involucrado se encuentra ahora detenido.<\/p>\n<p>\u201cSi no presento yo denuncia, \u00bfen qu\u00e9 condici\u00f3n se quedan todas las mujeres mexicanas?. Si esto le hacen a la presidenta, \u00bfqu\u00e9 va a pasar con todas las j\u00f3venes mujeres de nuestro pa\u00eds?\u201d, dijo la mandataria nacional.<\/p>\n<p>El acoso sexual es un delito que est\u00e1 tipificado en el <a href=\"https:\/\/data.consejeria.cdmx.gob.mx\/images\/leyes\/codigos\/2025\/CODIGO_PENAL_PARA_EL_DF_12.3.2.pdf\">art\u00edculo 179<\/a> del C\u00f3digo Penal de la Ciudad de M\u00e9xico. Cualquier persona que \u201crealice una conducta de naturaleza sexual indeseable para quien la recibe, que le cause un da\u00f1o o sufrimiento psicoemocional que lesione su dignidad\u201d puede alcanzar una pena de 1 a 3 a\u00f1os de prisi\u00f3n.<\/p>\n<p>Despu\u00e9s de acosarla, agreg\u00f3 Sheinbaum, el hombre acos\u00f3 a otras mujeres en la misma calle, \u201centonces est\u00e1 detenida esta persona\u201d.<\/p>\n<p>El hombre fue arrestado el martes a las 9 pm hora local y se encuentra a disposici\u00f3n de la Fiscal\u00eda de Investigaci\u00f3n de Delitos Sexuales de la Ciudad de M\u00e9xico, se\u00f1ala el Registro Nacional de Detenciones.<\/p>\n<p>La Secretar\u00eda de Seguridad Ciudadana (SSC) de la capital mexicana inform\u00f3 este mi\u00e9rcoles que un hombre fue detenido en calles de la colonia Centro Hist\u00f3rico \u201ccomo probable responsable de acosar a diversas mujeres en la zona\u201d.<\/p>\n<p>La SSC dijo que, seg\u00fan las primera investigaciones, el hombre est\u00e1 relacionado con el acoso contra Sheinbaum y otras dos mujeres ese mismo d\u00eda.<\/p>\n<p>CNN consult\u00f3 a la Fiscal\u00eda de Delitos Sexuales para saber los pr\u00f3ximos pasos a seguir y espera respuesta.<\/p>\n<p>A pesar del suceso, la presidenta de M\u00e9xico dijo que no va a reforzar su seguridad.<\/p>\n<p>\u201cNosotros no podemos estar lejos de la gente, eso ser\u00eda negar de d\u00f3nde venimos y c\u00f3mo somos (\u2026) Nuestros compa\u00f1eros de Ayudant\u00eda nos van a seguir apoyando, pero tenemos que estar cerca de la gente, no tenemos ning\u00fan riesgo conocido, si hay alg\u00fan riesgo nos lo informa el Gabinete de Seguridad, pero no hay ning\u00fan riesgo contra nosotros, entonces vamos a seguir como hemos venido hasta ahora\u201d, aclar\u00f3 Sheinbaum.<\/p>\n<p>La Ayudant\u00eda es el equipo de seguridad y acompa\u00f1amiento con el que cuenta Sheinbaum para giras y otras actividades. Fue <a href=\"https:\/\/x.com\/GobiernoMX\/status\/1715498291683537038\">establecido<\/a> por el expresidente Andr\u00e9s Manuel L\u00f3pez Obrador luego de desaparecer al Estado Mayor Presidencial, que en otros gobiernos se encargaba de la seguridad del presidente.<\/p>\n<p>Si bien existe este equipo de Ayudant\u00eda, qued\u00f3 un vac\u00edo en la seguridad presidencial desde la extinci\u00f3n del Estado Mayor Presidencial, de acuerdo con Ra\u00fal Ben\u00edtez-Manaut, profesor de la Universidad Nacional Aut\u00f3noma de M\u00e9xico.<\/p>\n<p>\u201cMuchos de los integrantes del Estado Mayor Presidencial estaban entrenados en Estados Unidos, en Espa\u00f1a, en Israel, en Francia, y ten\u00edan un gran entrenamiento de protecci\u00f3n de personas. Y entonces, al disolverse este cuerpo, qued\u00f3 como un vac\u00edo en lo que se llama la protecci\u00f3n de la figura presidencial y L\u00f3pez Obrador nunca lo subsan\u00f3\u201d, explic\u00f3 Ben\u00edtez-Manaut a CNN. \u201cY Claudia Sheinbaum no ha logrado construir un cuerpo presidencial de protecci\u00f3n profesional, lo que hace es contratar ciertos militares que participaron del Estado Mayor Presidencial que tienen entrenamiento de protecci\u00f3n de personas, pero no tienen sistemas de seguridad muy perfeccionados, ni seguridad perif\u00e9rica ni seguridad personal\u201d.<\/p>\n<p>El experto de la UNAM agreg\u00f3 que la protecci\u00f3n de la presidenta se basa en c\u00edrculos de seguridad, con situaciones de mayor atenci\u00f3n como el salir a caminar a las calles, que es el caso de Sheinbaum.<\/p>\n<p>\u201cTienen que tener mucho cuidado cuando salen a la calle a interactuar con la gente corriente porque se arriesgan a lo que le pas\u00f3 a Claudia Sheinbaum, nadie pudo evitar que se le acercara esta persona. Supuestamente las personas que se le acercan, en el concepto de ellos, de Sheinbaum, del partido Morena, es que son ciudadanos que los apoyan incondicionalmente, pero no sab\u00edan hasta d\u00f3nde pod\u00eda llegar una persona, a intentar acercarse a ella, no la agredi\u00f3 con armas ni con cuchillos ni con pistolas, pero s\u00ed la toc\u00f3 y en teor\u00eda le intent\u00f3 dar un beso y esto es grav\u00edsimo\u201d, dijo Ben\u00edtez-Manaut.<\/p>\n<p>Por tanto, el experto indic\u00f3 que es necesario que el cuerpo de seguridad presidencial se profesionalice para no permitir ese contacto tan cercano, sobre todo a la luz de otros cr\u00edmenes de corte pol\u00edtico, como el reciente asesinato del alcalde de Uruapan, Carlos Manzo.<\/p>\n<p>\u201cTienen que tener cierto cuidado y proteger alrededor de ella para que no sucedan estas cosas. Y m\u00e1s a\u00fan cuando sucedi\u00f3 lo del asesinato del alcalde de Uruapan, el asesino se le acerc\u00f3 mucho al alcalde y le dispar\u00f3 siete balas y las siete balas tocaron al alcalde. Entonces, quiere decir que nadie tampoco le pudo impedir que se acercara a esta persona. Es muy peligroso que se acerquen personas comunes y corrientes\u201d, recalc\u00f3.<\/p>\n<p>La Secretar\u00eda de las Mujeres <a href=\"https:\/\/www.gob.mx\/mujeres\/prensa\/pronunciamiento-por-una-vida-libre-de-violencias-para-todas-las-mujeres?idiom=es\">se pronunci\u00f3<\/a> el mi\u00e9rcoles sobre el acoso sexual sufrido por Sheinbaum y dijo que la cercan\u00eda con las personas no puede utilizarse para invadir su espacio personal \u201cni para cometer ning\u00fan tipo de contacto f\u00edsico sin consentimiento\u201d.<\/p>\n<p>\u201cLamentablemente ninguna mujer est\u00e1 exenta de vivir acoso sexual en nuestro pa\u00eds, por eso diario trabajamos para combatirlo (\u2026) Es fundamental que los hombres comprendan que este tipo de hechos no solo violentan a las mujeres, sino que adem\u00e1s son un delito\u201d, indic\u00f3 la dependencia federal en un comunicado.<\/p>\n<p>En el primer semestre de 2025, el 22,6 % de las mujeres de 18 a\u00f1os o m\u00e1s en M\u00e9xico enfrent\u00f3 alguna situaci\u00f3n de acoso o violencia sexual en lugares p\u00fablicos, <a href=\"https:\/\/www.inegi.org.mx\/contenidos\/programas\/ensu\/doc\/ensu2025_junio_presentacion_ejecutiva.pdf\">seg\u00fan<\/a> la Encuesta Nacional de Seguridad P\u00fablica Urbana (ENSU) del Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi). En cambio, apenas el 7,6 % de los hombres de esta edad pas\u00f3 por una situaci\u00f3n de acoso o violencia sexual en los primeros seis meses del a\u00f1o.<\/p>\n<p>En tanto, el 22,2 % de las mujeres que uso internet en M\u00e9xico fue v\u00edctima de ciberacoso, en comparaci\u00f3n con el 19,6 % de los hombres, <a href=\"https:\/\/www.inegi.org.mx\/contenidos\/saladeprensa\/boletines\/2025\/mociba\/MOCIBA2024_CP.pdf\">seg\u00fan<\/a> el Inegi. \u201cDe la poblaci\u00f3n de mujeres que fueron v\u00edctimas de ciberacoso y que pudieron identificar el sexo de las personas agresoras, 52,1 % manifest\u00f3 haber sido agredida solo por hombres\u201d, a\u00f1ade.<\/p>\n<p>\u201cEste tipo de violencias no deben ser trivializadas; por el contrario, denunciarlas es fundamental para alcanzar la justicia y abonar a un cambio cultural\u201d, agreg\u00f3 la Secretar\u00eda de las Mujeres.<\/p>\n<p>Para reforzar el enfoque en estos temas, Sheinbaum dijo este mi\u00e9rcoles que platicar\u00e1 con esta dependencia federal para revisar si el acoso sexual es delito penal en todos los estados del pa\u00eds, \u201cporque debe ser delito penal sancionable\u201d.<\/p>\n<p>Adem\u00e1s, Sheinbaum se\u00f1al\u00f3 que har\u00e1n una campa\u00f1a relacionada con \u201ctodas las mujeres mexicanas\u201d. \u201cTiene que haber respeto por la mujer en todos los sentidos. Y el acoso es un delito\u201d, insisti\u00f3 la mandataria.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, habl\u00f3 este mi\u00e9rcoles sobre el acoso sexual que sufri\u00f3 cuando se dirig\u00eda a una reuni\u00f3n a pie desde su residencia en Palacio Nacional el martes, cuando un hombre se le acerc\u00f3 al tiempo que la mandataria saludaba a otras personas. \u201cDecidimos irnos caminando (de Palacio Nacional a la Secretar\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468058","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias\" \/>\n<meta property=\"og:description\" content=\"La presidenta de M\u00e9xico, Claudia Sheinbaum, habl\u00f3 este mi\u00e9rcoles sobre el acoso sexual que sufri\u00f3 cuando se dirig\u00eda a una reuni\u00f3n a pie desde su residencia en Palacio Nacional el martes, cuando un hombre se le acerc\u00f3 al tiempo que la mandataria saludaba a otras personas. \u201cDecidimos irnos caminando (de Palacio Nacional a la Secretar\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-05T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta\",\"datePublished\":\"2025-11-05T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\"},\"wordCount\":1368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\",\"name\":\"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-05T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias","og_description":"La presidenta de M\u00e9xico, Claudia Sheinbaum, habl\u00f3 este mi\u00e9rcoles sobre el acoso sexual que sufri\u00f3 cuando se dirig\u00eda a una reuni\u00f3n a pie desde su residencia en Palacio Nacional el martes, cuando un hombre se le acerc\u00f3 al tiempo que la mandataria saludaba a otras personas. \u201cDecidimos irnos caminando (de Palacio Nacional a la Secretar\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-05T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/"},"author":{"name":"","@id":""},"headline":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta","datePublished":"2025-11-05T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/"},"wordCount":1368,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","name":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-05T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Sheinbaum denunci\u00f3 al hombre que la acos\u00f3. Esto dijo un experto sobre la seguridad de la presidenta","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/05\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-05T18:03:47Z","datePublished":"2025-11-05T18:03:47Z","dateModified":"2025-11-05T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Sheinbaum denunci\\u00f3 al hombre que la acos\\u00f3. Esto dijo un experto sobre la seguridad de la presidenta\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/05\\\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/05\\\/sheinbaum-denuncio-hombre-acoso-experto-seguridad-presidenta-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-05T18:03:47Z\",\"datePublished\":\"2025-11-05T18:03:47Z\",\"dateModified\":\"2025-11-05T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468138,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/acoso-sheinbaum-expone-violencia-mujeres-orix\/","url_meta":{"origin":1468058,"position":0},"title":"El acoso que denunci\u00f3 Sheinbaum saca a la luz la violencia a la que est\u00e1n expuestas muchas mujeres en M\u00e9xico","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"Las im\u00e1genes son muy claras: muestran c\u00f3mo un hombre se acerca a una mujer, parece tocarle el pecho e intenta darle un beso. Esa mujer es nada menos que la presidenta de M\u00e9xico, Claudia Sheinbaum. Pero lo que le ocurri\u00f3 a ella vuelve a poner sobre la mesa la violencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463444,"url":"https:\/\/noticiasya.com\/tampa\/2025\/06\/11\/sheinbaum-niega-incitado-protestas-redadas-noem-orix\/","url_meta":{"origin":1468058,"position":1},"title":"Sheinbaum niega haber incitado protestas en EE.UU. y defiende una postura pac\u00edfica ante las redadas","author":"","date":"junio 11, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, rechaz\u00f3 este mi\u00e9rcoles las acusaciones de la secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, quien la responsabiliz\u00f3 de incentivar las recientes protestas en Los \u00c1ngeles tras operativos migratorios.En su conferencia de prensa matutina, Sheinbaum afirm\u00f3 que su postura ha sido siempre en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469011,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/05\/sheinbaum-trump-sonrien-primera-pequena-reunion-fue-excelente-orix\/","url_meta":{"origin":1468058,"position":2},"title":"Sheinbaum y Trump sonr\u00eden en su primera &#171;peque\u00f1a&#187; reuni\u00f3n: la presidenta de M\u00e9xico dijo que fue &#171;excelente&#187;","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, y el presidente de Estados Unidos, Donald Trump, tuvieron este viernes su primer encuentro cara a cara en Washington, seguido por una reuni\u00f3n en la que tambi\u00e9n particip\u00f3 el primer ministro de Canad\u00e1, Mark Carney.\u201cTuvimos una excelente reuni\u00f3n\u201d, dijo Sheinbaum en X sobre su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459087,"url":"https:\/\/noticiasya.com\/tampa\/2025\/02\/22\/peru-protesta-contra-mexico-por-apoyo-pedro-castillo-orix\/","url_meta":{"origin":1468058,"position":3},"title":"Per\u00fa protesta contra M\u00e9xico por apoyo de Sheinbaum al expresidente Pedro Castillo","author":"","date":"febrero 22, 2025","format":false,"excerpt":"El Gobierno de Per\u00fa protest\u00f3 este viernes contra M\u00e9xico luego de que la presidenta de M\u00e9xico, Claudia Sheinbaum, expresara apoyo al expresidente peruano Pedro Castillo y calificara de \u201cinjusticia\u201d el proceso penal al que est\u00e1 sujeto en su pa\u00eds, donde est\u00e1 detenido desde hace m\u00e1s de dos a\u00f1os.\u201cLas declaraciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473338,"url":"https:\/\/noticiasya.com\/tampa\/2026\/04\/20\/presion-sheinbaum-desapariciones-visita-turk-orix\/","url_meta":{"origin":1468058,"position":4},"title":"M\u00e1s presi\u00f3n sobre Sheinbaum por la crisis de desapariciones: llega a M\u00e9xico el comisionado de Derechos Humanos de la ONU","author":"","date":"abril 20, 2026","format":false,"excerpt":"El alto comisionado de la ONU para los derechos humanos, Volker T\u00fcrk, lleg\u00f3 este fin de semana a M\u00e9xico, donde comenz\u00f3 una serie de reuniones sobre una problem\u00e1tica sensible para el Gobierno de la presidenta Claudia Sheinbaum: las personas desaparecidas, crisis ligada a los altos niveles de violencia que persisten\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456288,"url":"https:\/\/noticiasya.com\/tampa\/2024\/12\/05\/sheinbaum-ayotzinapa-investigacion-padres-43-orix\/","url_meta":{"origin":1468058,"position":5},"title":"Sheinbaum ofrece nueva ruta en la investigaci\u00f3n del caso Ayotzinapa","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Los padres de los 43 estudiantes de Ayotzinapa, desaparecidos en 2014, sostuvieron este mi\u00e9rcoles su primer encuentro con la presidenta de M\u00e9xico, Claudia Sheinbaum, desde que asumi\u00f3 el cargo el 1 de octubre, ocasi\u00f3n en la que les ofreci\u00f3 reconstruir el di\u00e1logo y la implementaci\u00f3n de una nueva ruta en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468058"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468058\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}