{"id":1468127,"date":"2025-11-07T12:03:39","date_gmt":"2025-11-07T20:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/"},"modified":"2025-11-07T12:03:39","modified_gmt":"2025-11-07T20:03:39","slug":"matan-disparo-mujer-guatemalteca-indiana-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","title":{"rendered":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU."},"content":{"rendered":"<p>Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, una mujer guatemalteca de 32 a\u00f1os, falleci\u00f3 despu\u00e9s de recibir un disparo fatal en la cabeza al presentarse a trabajar en el domicilio equivocado en Whitestown, Indiana, seg\u00fan autoridades locales.<\/p>\n<p>El mi\u00e9rcoles por la ma\u00f1ana, R\u00edos P\u00e9rez y su esposo, que forman parte de un equipo de limpieza, llegaron al domicilio e intentaron entrar, pero la mujer recibi\u00f3 un disparo, dijo en un <a href=\"https:\/\/www.facebook.com\/WhitestownPolice\/posts\/pfbid06T4SeV3J11hUMfaMGmVBfLK9UnaVvB6DMzkbkDFwBrgKc9opmSZ3sCVXYKNukjFPl\">comunicado<\/a> el Departamento de Polic\u00eda Metropolitana de Whitestown. Cuando la polic\u00eda lleg\u00f3, R\u00edos P\u00e9rez ya hab\u00eda fallecido.<\/p>\n<p>La Polic\u00eda de Whitestown, que lleg\u00f3 a la escena por una llamada al 911 que alert\u00f3 sobre una \u201cposible\u201d entrada en una vivienda, agreg\u00f3 que R\u00edos P\u00e9rez y su esposo \u201cllegaron por error a la direcci\u00f3n equivocada\u201d. Esta informaci\u00f3n es preliminar y la investigaci\u00f3n contin\u00faa, dijo la autoridad policial.<\/p>\n<p>La Oficina del Forense del condado de Boone <a href=\"https:\/\/www.facebook.com\/boonecountycoroner\/posts\/pfbid0BDgxj5RXQEW4HhtxJ3w49yaWqexupPMDtfuoy3mWQCk1rnzxirMChL3DSgvuWAAUl\">identific\u00f3<\/a> el jueves a la v\u00edctima mortal como Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, de 32 a\u00f1os y residente de la ciudad de Indian\u00e1polis.<\/p>\n<p>Tras realizar una autopsia, la Oficina del Forense \u201cdetermin\u00f3 que la causa de la muerte es homicidio y que la muerte fue resultado de una herida de bala en la cabeza\u201d.<\/p>\n<p>Las autoridades no han informado qui\u00e9n dispar\u00f3 o si hubo arrestos por este hecho. CNN contact\u00f3 a la Oficina del Sheriff y a la Fiscal\u00eda del condado de Boone para saber si hay alguna persona detenida, y espera respuesta.<\/p>\n<p>Por su parte, el Ministerio de Relaciones Exteriores de Guatemala dijo que est\u00e1n dando seguimiento al caso y acompa\u00f1amiento a la familia de R\u00edos P\u00e9rez.<\/p>\n<p>\u201cLa guatemalteca, de 32 a\u00f1os y originaria de Quetzaltenango, falleci\u00f3 en un acto violento cuando se presentaba a cumplir sus labores en la ciudad de Whitestown, en el estado de Indiana, el pasado 5 de noviembre. Le sobreviven su esposo y cuatro hijos\u201d, indic\u00f3 el Ministerio este viernes en un <a href=\"https:\/\/prensa.gob.gt\/comunicado\/el-minex-por-medio-del-consulado-en-chicago-da-seguimiento-al-caso-de-una-connacional\">comunicado<\/a>.<\/p>\n<p>A\u00f1adi\u00f3 que est\u00e1n \u201cbrindando asistencia consular, legal y migratoria, as\u00ed como en servicios de documentaci\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, una mujer guatemalteca de 32 a\u00f1os, falleci\u00f3 despu\u00e9s de recibir un disparo fatal en la cabeza al presentarse a trabajar en el domicilio equivocado en Whitestown, Indiana, seg\u00fan autoridades locales. El mi\u00e9rcoles por la ma\u00f1ana, R\u00edos P\u00e9rez y su esposo, que forman parte de un equipo de limpieza, llegaron [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468127","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, una mujer guatemalteca de 32 a\u00f1os, falleci\u00f3 despu\u00e9s de recibir un disparo fatal en la cabeza al presentarse a trabajar en el domicilio equivocado en Whitestown, Indiana, seg\u00fan autoridades locales. El mi\u00e9rcoles por la ma\u00f1ana, R\u00edos P\u00e9rez y su esposo, que forman parte de un equipo de limpieza, llegaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T20:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU.\",\"datePublished\":\"2025-11-07T20:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\"},\"wordCount\":398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\",\"name\":\"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-07T20:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias","og_description":"Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, una mujer guatemalteca de 32 a\u00f1os, falleci\u00f3 despu\u00e9s de recibir un disparo fatal en la cabeza al presentarse a trabajar en el domicilio equivocado en Whitestown, Indiana, seg\u00fan autoridades locales. El mi\u00e9rcoles por la ma\u00f1ana, R\u00edos P\u00e9rez y su esposo, que forman parte de un equipo de limpieza, llegaron [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-07T20:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/"},"author":{"name":"","@id":""},"headline":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU.","datePublished":"2025-11-07T20:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/"},"wordCount":398,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","name":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-07T20:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Matan de un disparo a mujer guatemalteca que se present\u00f3 a trabajar en la casa equivocada en EE.UU.","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/matan-disparo-mujer-guatemalteca-indiana-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-07T20:03:39Z","datePublished":"2025-11-07T20:03:39Z","dateModified":"2025-11-07T20:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Matan de un disparo a mujer guatemalteca que se present\\u00f3 a trabajar en la casa equivocada en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/matan-disparo-mujer-guatemalteca-indiana-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/matan-disparo-mujer-guatemalteca-indiana-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-07T20:03:39Z\",\"datePublished\":\"2025-11-07T20:03:39Z\",\"dateModified\":\"2025-11-07T20:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468542,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/20\/acusan-hombre-estadounidense-muerte-mujer-guatemala-casa-equivocada-orix\/","url_meta":{"origin":1468127,"position":0},"title":"Acusan a hombre estadounidense de matar a una mujer de Guatemala que se present\u00f3 a trabajar en la casa equivocada","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Un estadounidense fue acusado formalmente por las autoridades locales del estado de Indiana de matar a Mar\u00eda Florinda R\u00edos P\u00e9rez de Vel\u00e1squez, una guatemalteca de 32 a\u00f1os, quien recibi\u00f3 un disparo mortal en la cabeza al presentarse a trabajar en el domicilio equivocado en Whitestown, inform\u00f3 el lunes la Fiscal\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446906,"url":"https:\/\/noticiasya.com\/tampa\/2024\/03\/12\/nino-palestino-fuegos-artificiales-murio-heridas-bala-policia-israel-trax\/","url_meta":{"origin":1468127,"position":1},"title":"Un menor palestino de 12 a\u00f1os con fuegos artificiales muere tras disparos de la polic\u00eda fronteriza de Israel en un campo de refugiados en Jerusal\u00e9n","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN) -- Un agente de la polic\u00eda fronteriza israel\u00ed dispar\u00f3 mortalmente contra un menor palestino de 12 a\u00f1os en el campo de refugiados de Shuafat, en la Jerusal\u00e9n oriental ocupada, seg\u00fan funcionarios del hospital y un portavoz de la polic\u00eda de Israel.En un video obtenido por CNN, se puede ver\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461944,"url":"https:\/\/noticiasya.com\/tampa\/2025\/05\/03\/policia-cincinnati-disparo-joven-padre-mato-ayudante-sheriff-trax\/","url_meta":{"origin":1468127,"position":2},"title":"Polic\u00eda de Cincinnati dio un disparo mortal a joven armado; luego su padre mat\u00f3 a un agente del sheriff, dicen autoridades","author":"","date":"mayo 3, 2025","format":false,"excerpt":"Un agente del sheriff de Cincinnati fue atropellado mortalmente por un autom\u00f3vil conducido por el padre de un hombre armado de 18 a\u00f1os que muri\u00f3 por un disparo de la Polic\u00eda un d\u00eda antes, dicen las autoridades.El conductor, \u201cde una manera que fue calculada y premeditada, aline\u00f3 su autom\u00f3vil, aceler\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462677,"url":"https:\/\/noticiasya.com\/tampa\/2025\/05\/22\/seguridad-cia-disparo-mujer-frente-puertas-sede-agencia-trax\/","url_meta":{"origin":1468127,"position":3},"title":"La seguridad de la CIA le dispar\u00f3 a una mujer frente a las puertas de la sede de la agencia","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Agentes de seguridad de la CIA dispararon e hirieron a una mujer que se acerc\u00f3 a las puertas principales de la agencia en un autom\u00f3vil alrededor de las 4 a.m. hora de Miami del jueves, seg\u00fan una fuente policial y otra persona familiarizada con el asunto.Esa persona ahora est\u00e1 bajo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1436230,"url":"https:\/\/noticiasya.com\/tampa\/2022\/12\/19\/hombre-armado-con-un-cuchillo-muere-baleado-por-un-oficial-de-chula-vista\/","url_meta":{"origin":1468127,"position":4},"title":"Hombre armado con un cuchillo muere baleado por un oficial de Chula Vista","author":"agomez","date":"diciembre 19, 2022","format":false,"excerpt":"La polic\u00eda de Chula Vista recibi\u00f3 varias llamadas donde reportaban que una mujer gritaba pidiendo ayuda y que era golpeada por un hombre.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/tampa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448239,"url":"https:\/\/noticiasya.com\/tampa\/2024\/04\/18\/muerte-valentina-orellana-peralta-policia-no-enfrentara-cargos-penales-trax\/","url_meta":{"origin":1468127,"position":5},"title":"Agente de Polic\u00eda de Los \u00c1ngeles no enfrentar\u00e1 a cargos penales por la muerte de una joven de 14 a\u00f1os en una tienda durante un enfrentamiento policial con un sospechoso","author":"agomez","date":"abril 18, 2024","format":false,"excerpt":"(CNN) -- Un agente del Departamento de Polic\u00eda de Los \u00c1ngeles no enfrentar\u00e1 a cargos penales por el tiroteo mortal en 2021 de una adolescente de 14 a\u00f1os que muri\u00f3 en el interior de una tienda por departamentos cuando la Polic\u00eda dispar\u00f3 contra un hombre sospechoso de atacar a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468127"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468127\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}