{"id":1468131,"date":"2025-11-07T15:03:47","date_gmt":"2025-11-07T23:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/"},"modified":"2025-11-07T15:03:47","modified_gmt":"2025-11-07T23:03:47","slug":"muere-james-watson-genetista-nobel-adn-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","title":{"rendered":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os"},"content":{"rendered":"<p>James Watson, un renombrado bi\u00f3logo molecular y uno de los ganadores del Premio Nobel por descubrir la estructura del ADN, muri\u00f3 el jueves despu\u00e9s de una breve enfermedad, seg\u00fan una declaraci\u00f3n de su antiguo empleador.<\/p>\n<p>Ten\u00eda 97 a\u00f1os.<\/p>\n<p>Su muerte fue confirmada por un portavoz del Cold Spring Harbor Laboratory, donde pas\u00f3 la mayor parte de su carrera, quien se\u00f1al\u00f3 que falleci\u00f3 tras una breve enfermedad.<\/p>\n<p>Watson, cuya misi\u00f3n era descubrir c\u00f3mo es la mol\u00e9cula de la vida, gan\u00f3 un<a href=\"https:\/\/www.nobelprize.org\/prizes\/medicine\/1962\/watson\/biographical\/\"> Premio Nobel por ello en 1962. <\/a>M\u00e1s tarde se convirti\u00f3 en el primer director del innovador Proyecto Genoma Humano y en el primer galardonado vivo en <a href=\"https:\/\/www.nobelprize.org\/prizes\/medicine\/1962\/watson\/biographical\/\">vender un Premio Nobel<\/a>, parte de lo cual se destin\u00f3 a recaudar fondos para la investigaci\u00f3n cient\u00edfica.<\/p>\n<p>\u201cCreo que desde temprano, quise hacer algo importante con mi vida. Todav\u00eda quiero pensar en la ciencia y en realidad en nada m\u00e1s\u201d, dijo Watson a CNN en 2013. \u201cEstar impulsado por el <a href=\"https:\/\/www.cnn.com\/2013\/06\/28\/health\/james-watson-dna\/index.html\">deseo de encontrar la verdad,<\/a> esa es realmente mi herencia. La verdad, a veces no la encuentras y es complicado, pero siempre tienes que si puedes comenzar con la verdad, eso es \u00fatil\u201d.<\/p>\n<p>Su legado se vio empa\u00f1ado en a\u00f1os posteriores despu\u00e9s de que fuera noticia por <a href=\"https:\/\/www.cnn.com\/2019\/01\/13\/health\/james-watson-honors-stripped-intl\/index.html\">pol\u00e9micos comentarios<\/a> racistas, sexistas y hom\u00f3fobos que menospreciaban a varios grupos de personas, afirmando que ten\u00edan diferencias gen\u00e9ticas. Los comentarios le llevaron a perder algunos de sus t\u00edtulos honorarios.<\/p>\n<p>Watson, junto a Francis Crick y Maurice Wilkins, es m\u00e1s conocido por descubrir la estructura en doble h\u00e9lice del ADN en 1953.<\/p>\n<p>\u201cCuando ten\u00eda 25 a\u00f1os, mi colega Francis Crick y yo publicamos un art\u00edculo muy corto describiendo la estructura del ADN\u201d, dijo a CNN en 2013. \u201cPensamos que era una bomba y afortunadamente, lo fue\u201d.<\/p>\n<p>Ese descubrimiento revolucionario, <a href=\"https:\/\/www.nature.com\/articles\/171737a0.epdf\">publicado en la revista Nature, <\/a>fue un gran avance cient\u00edfico que dio lugar al campo de la biolog\u00eda molecular. Descifraron el c\u00f3digo de c\u00f3mo el ADN almacena informaci\u00f3n y de c\u00f3mo su estructura especial permite a la mol\u00e9cula replicarse.<\/p>\n<p>Watson naci\u00f3 el 6 de abril de 1928 en Chicago. Su caracter\u00edstica curiosidad se evidenciaba desde ni\u00f1o.<\/p>\n<p>Cuando ten\u00eda 8 a\u00f1os, se pregunt\u00f3 por qu\u00e9 migran las aves. La pregunta le parec\u00eda un rompecabezas que quer\u00eda resolver, lo que le inspir\u00f3 a dedicarse a la ciencia para poder entender c\u00f3mo funcionaba el mundo natural.<\/p>\n<p>Despu\u00e9s de solo dos a\u00f1os en la secundaria, Watson recibi\u00f3 una beca para la Universidad de Chicago, a solo unos kil\u00f3metros de distancia. En 1947, se gradu\u00f3 con un t\u00edtulo en zoolog\u00eda.<\/p>\n<p>Continu\u00f3 aprendiendo m\u00e1s sobre el campo, obteniendo un doctorado en zoolog\u00eda en la Universidad de Indiana en Bloomington. Fue all\u00ed donde su inter\u00e9s infantil por la observaci\u00f3n de aves dio paso a su pasi\u00f3n por aprender sobre gen\u00e9tica.<\/p>\n<p>Watson qued\u00f3 fascinado con las estructuras tridimensionales de las mol\u00e9culas durante su investigaci\u00f3n sobre virus bacterianos en la universidad. Se enter\u00f3 del trabajo que los cient\u00edficos realizaban en el Laboratorio Cavendish de Cambridge, Inglaterra, y unos a\u00f1os despu\u00e9s, se uni\u00f3 a ellos para trabajar all\u00ed en 1951.<\/p>\n<p>Watson conoci\u00f3 a dos personas importantes en 1951: Wilkins y Crick, los hombres con quienes m\u00e1s tarde compartir\u00eda el<a href=\"https:\/\/www.nobelprize.org\/prizes\/medicine\/1962\/watson\/biographical\/\"> Premio Nobel de Fisiolog\u00eda o Medicina en 1962<\/a>. Wilkins mostr\u00f3 a Watson fotograf\u00edas del patr\u00f3n de difracci\u00f3n de rayos X de la estructura del ADN, y m\u00e1s tarde ese a\u00f1o, Watson se enter\u00f3 de que tanto \u00e9l como Crick quer\u00edan descubrir la estructura del ADN.<\/p>\n<p>\u201cEn ese momento, sab\u00edamos que se hab\u00eda abierto un nuevo mundo y que un mundo antiguo, que parec\u00eda m\u00e1s bien m\u00edstico, hab\u00eda desaparecido\u201d, dijo Watson sobre el descubrimiento durante su discurso en el banquete Nobel en 1962.<\/p>\n<p>\u201cLo \u00fanico que pudimos decir cuando lo conseguimos: \u00a1Es tan hermoso!\u201d, <a href=\"https:\/\/www.cnn.com\/2013\/06\/28\/health\/james-watson-dna\/index.html\">record\u00f3 Watson <\/a>sobre acertar con la estructura, lo que tom\u00f3 m\u00e1s de un a\u00f1o.<\/p>\n<p>Watson y Crick tambi\u00e9n utilizaron el trabajo de la qu\u00edmica brit\u00e1nica Rosalind Franklin para ayudarse en su descubrimiento, pero su contribuci\u00f3n fue en gran medida pasada por alto hasta despu\u00e9s de su muerte. Las memorias de Watson, \u201cLa doble h\u00e9lice: un relato personal sobre el descubrimiento de la estructura del ADN\u201d, generaron controversia por su versi\u00f3n del descubrimiento del ADN y los roles de quienes participaron.<\/p>\n<p>El trabajo de Franklin no fue reconocido, y muri\u00f3 de c\u00e1ncer de ovario en 1958 antes de que se otorgara el Premio Nobel por el descubrimiento de la estructura del ADN. Si bien el premio nunca se otorga p\u00f3stumamente y <a href=\"https:\/\/educationalgames.nobelprize.org\/educational\/medicine\/dna_double_helix\/readmore.php\">Franklin nunca fue nominada<\/a>, algunos en la comunidad cient\u00edfica dicen que fue ignorada.<\/p>\n<p>Tres a\u00f1os despu\u00e9s de ganar el Premio Nobel, Watson public\u00f3 el libro de texto \u201cBiolog\u00eda Molecular del Gen\u201d, que es uno de los textos de biolog\u00eda moderna m\u00e1s utilizados.<\/p>\n<p>\u201cProbablemente pas\u00e9 m\u00e1s de mi carrera como escritor que como cient\u00edfico\u201d, dijo Watson en una <a href=\"https:\/\/www.youtube.com\/watch?v=P0AoopD5fLs\">entrevista de 2012 con NobelPrize.org.<\/a> A\u00f1adi\u00f3 que su popular libro de texto duplic\u00f3 sus ingresos y le abri\u00f3 nuevos mundos.<\/p>\n<p>En 1968, Watson comenz\u00f3 a dirigir el Laboratorio Cold Spring Harbor, una instituci\u00f3n de investigaci\u00f3n en Long Island, Nueva York, durante 25 a\u00f1os, transform\u00e1ndolo en un centro de investigaci\u00f3n en biolog\u00eda molecular. Fue un gran a\u00f1o, ya que <a href=\"https:\/\/www.biography.com\/scientists\/james-d-watson\">Watson se cas\u00f3 con Elizabeth Lewis<\/a> y luego tuvieron dos hijos, Rufus y Duncan.<\/p>\n<p>M\u00e1s adelante en su carrera, Watson fue el primer director del Proyecto Genoma Humano, un esfuerzo internacional de investigaci\u00f3n cuyo objetivo era mapear el genoma humano, hasta 1992, cuando dimiti\u00f3. En 2007, Watson se convirti\u00f3 en la segunda persona en tener su genoma secuenciado en su totalidad y lo public\u00f3 en l\u00ednea.<\/p>\n<p>Watson tambi\u00e9n fue noticia cuando vendi\u00f3 su Premio Nobel en 2014 <a href=\"https:\/\/www.npr.org\/sections\/thetwo-way\/2014\/12\/09\/369690594\/after-4-75-million-auction-watson-will-get-nobel-medal-back\">por $US 4,76 millones<\/a> en una subasta, incluida la prima del comprador, y el manuscrito de su discurso de aceptaci\u00f3n del premio por otros US$ 356.000, lo cual recaud\u00f3 fondos para la investigaci\u00f3n cient\u00edfica. Un multimillonario ruso compr\u00f3 la medalla y luego se la devolvi\u00f3 a Watson.<\/p>\n<p>Watson gener\u00f3 controversia en la \u00faltima parte de su vida, empa\u00f1ando su reputaci\u00f3n como cient\u00edfico en una serie de comentarios racistas. En 2007, hizo declaraciones sobre la inteligencia de las personas negras en el Sunday Times del Reino Unido. Se le retir\u00f3 su t\u00edtulo de canciller en el Laboratorio Cold Spring Harbor, donde hab\u00eda trabajado durante m\u00e1s de cuatro d\u00e9cadas.<\/p>\n<p>Tambi\u00e9n hizo otros comentarios controvertidos sin respaldo cient\u00edfico a lo largo de los a\u00f1os. Esto incluy\u00f3 repetir comentarios racistas en 2019, insinuando que los negros son menos inteligentes que los blancos debido a la gen\u00e9tica. Esas declaraciones le costaron el resto de sus t\u00edtulos honorarios en el Laboratorio Cold Spring Harbor.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>James Watson, un renombrado bi\u00f3logo molecular y uno de los ganadores del Premio Nobel por descubrir la estructura del ADN, muri\u00f3 el jueves despu\u00e9s de una breve enfermedad, seg\u00fan una declaraci\u00f3n de su antiguo empleador. Ten\u00eda 97 a\u00f1os. Su muerte fue confirmada por un portavoz del Cold Spring Harbor Laboratory, donde pas\u00f3 la mayor parte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468131","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"James Watson, un renombrado bi\u00f3logo molecular y uno de los ganadores del Premio Nobel por descubrir la estructura del ADN, muri\u00f3 el jueves despu\u00e9s de una breve enfermedad, seg\u00fan una declaraci\u00f3n de su antiguo empleador. Ten\u00eda 97 a\u00f1os. Su muerte fue confirmada por un portavoz del Cold Spring Harbor Laboratory, donde pas\u00f3 la mayor parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T23:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os\",\"datePublished\":\"2025-11-07T23:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\"},\"wordCount\":1213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\",\"name\":\"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-07T23:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias","og_description":"James Watson, un renombrado bi\u00f3logo molecular y uno de los ganadores del Premio Nobel por descubrir la estructura del ADN, muri\u00f3 el jueves despu\u00e9s de una breve enfermedad, seg\u00fan una declaraci\u00f3n de su antiguo empleador. Ten\u00eda 97 a\u00f1os. Su muerte fue confirmada por un portavoz del Cold Spring Harbor Laboratory, donde pas\u00f3 la mayor parte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-07T23:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/"},"author":{"name":"","@id":""},"headline":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os","datePublished":"2025-11-07T23:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/"},"wordCount":1213,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","name":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-07T23:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\u00f1os","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/muere-james-watson-genetista-nobel-adn-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-07T23:03:47Z","datePublished":"2025-11-07T23:03:47Z","dateModified":"2025-11-07T23:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere James Watson, famoso genetista y coganador del Premio Nobel por la estructura del ADN, a los 97 a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/muere-james-watson-genetista-nobel-adn-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/muere-james-watson-genetista-nobel-adn-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-07T23:03:47Z\",\"datePublished\":\"2025-11-07T23:03:47Z\",\"dateModified\":\"2025-11-07T23:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467203,"url":"https:\/\/noticiasya.com\/tampa\/2025\/10\/08\/premio-nobel-quimica-metalorganicas-trax\/","url_meta":{"origin":1468131,"position":0},"title":"Tres cient\u00edficos ganan el Premio Nobel de Qu\u00edmica por su trabajo en arquitectura molecular, al estilo de Harry Potter","author":"","date":"octubre 8, 2025","format":false,"excerpt":"El Premio Nobel de Qu\u00edmica 2025 ha sido otorgado a un tr\u00edo de investigadores \u2014un japon\u00e9s, un brit\u00e1nico y un jordano\u2014 por el desarrollo de \u201cestructuras metalorg\u00e1nicas\u201d, una forma de arquitectura molecular que concentra grandes cantidades de espacio en estructuras diminutas, que el Comit\u00e9 Nobel compar\u00f3 con el bolso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469133,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/10\/maria-corina-machado-no-estara-ceremonia-entrega-nobel-paz-efe\/","url_meta":{"origin":1468131,"position":1},"title":"Mar\u00eda Corina Machado no estar\u00e1 en la ceremonia de entrega del Nobel de la Paz en Oslo, afirma director del Instituto Nobel","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Mar\u00eda Corina Machado no estar\u00e1 este mi\u00e9rcoles en Oslo para recoger el premio de la Paz de este a\u00f1o, confirm\u00f3 a la televisi\u00f3n p\u00fablica noruega NRK el director del Instituto Nobel, Kristian Berg Harpviken.\u201cDesgraciadamente todav\u00eda no est\u00e1 en Noruega y tampoco estar\u00e1 en el escenario del Ayuntamiento de Oslo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467143,"url":"https:\/\/noticiasya.com\/tampa\/2025\/10\/06\/premio-nobel-medicina-cientificos-sistema-inmunologico-trax\/","url_meta":{"origin":1468131,"position":2},"title":"Otorgan el Premio Nobel de Medicina a tres cient\u00edficos por descubrir c\u00f3mo se mantiene bajo control el sistema inmunol\u00f3gico","author":"","date":"octubre 6, 2025","format":false,"excerpt":"El Premio Nobel de Fisiolog\u00eda o Medicina de 2025 fue otorgado a un tr\u00edo de cient\u00edficos, dos de ellos estadounidenses y uno japon\u00e9s, por descubrir c\u00f3mo el sistema inmunol\u00f3gico nos protege de miles de microbios diferentes que intentan invadir nuestros cuerpos.Mary E. Brunkow, Fred Ramsdell y Shimon Sakaguchi compartir\u00e1n el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455076,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/14\/premio-nobel-economia-2024-trio-por-su-trabajo-sobre-las-diferencias-de-prosperidad-entre-naciones\/","url_meta":{"origin":1468131,"position":3},"title":"Se entrega el Premio Nobel de Econom\u00eda 2024 a un tr\u00edo por su trabajo sobre las diferencias de prosperidad entre naciones","author":"","date":"octubre 14, 2024","format":false,"excerpt":"(CNN) -- Un tr\u00edo de economistas recibi\u00f3 este lunes con el Premio Nobel de Econom\u00edapor sus \"estudios sobre c\u00f3mo se forman las instituciones y afectan a la prosperidad\".Daron Acemoglu, Simon Johnson y James Robinson compartir\u00e1n el premio, dotado con 11 millones de coronas suecas (1 mill\u00f3n de d\u00f3lares).El Comit\u00e9 Nobel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470152,"url":"https:\/\/noticiasya.com\/tampa\/2026\/01\/16\/revocar-nobel-paz-machado-trump-orix\/","url_meta":{"origin":1468131,"position":4},"title":"\u00bfSe puede revocar el Premio Nobel de Paz? El gesto de Machado y Trump desata pol\u00e9mica","author":"","date":"enero 16, 2026","format":false,"excerpt":"Mar\u00eda Corina Machado llev\u00f3 la medalla del Nobel de Paz que le otorgaron a la Casa Blanca. Se la entreg\u00f3 a Donald Trump. Se tomaron una foto. Trump public\u00f3 en su red social: \u201cMar\u00eda me present\u00f3 su Premio Nobel de la Paz\u201d. El Centro Nobel de la Paz hab\u00eda tuiteado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467278,"url":"https:\/\/noticiasya.com\/tampa\/2025\/10\/10\/premio-nobel-paz-latinoamericanos-orix\/","url_meta":{"origin":1468131,"position":5},"title":"Adem\u00e1s de Mar\u00eda Corina Machado, otros seis latinoamericanos han sido galardonados con el Premio Nobel de la Paz","author":"","date":"octubre 10, 2025","format":false,"excerpt":"Mar\u00eda Corina Machado se ha convertido en la s\u00e9ptima persona en Am\u00e9rica Latina en recibir el Premio Nobel de la Paz. La l\u00edder opositora de Venezuela recibi\u00f3 un reconocimiento que en la historia de los premios recibieron en total 112 personas.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Machado hab\u00eda ayudado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468131"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468131\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}