{"id":1468133,"date":"2025-11-07T17:03:47","date_gmt":"2025-11-08T01:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/"},"modified":"2025-11-07T17:03:47","modified_gmt":"2025-11-08T01:03:47","slug":"trump-pide-corte-suprema-cupones-snap-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","title":{"rendered":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP"},"content":{"rendered":"<p>El presidente Donald Trump pidi\u00f3 este viernes por la noche a la Corte Suprema que bloquee una decisi\u00f3n de un tribunal inferior que requer\u00eda que el Gobierno cubriera completamente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre.<\/p>\n<p>La solicitud de emergencia a los jueces lleg\u00f3 horas despu\u00e9s de que un funcionario del Gobierno anunciara que estaban <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/07\/eeuu\/gobierno-apela-orden-beneficios-snap-trax\">trabajando para cumplir con la decisi\u00f3n de financiar completamente el programa<\/a>, que fue emitida un d\u00eda antes por el juez federal John McConnell en Rhode Island.<\/p>\n<p>El Gobierno hab\u00eda presentado una apelaci\u00f3n de emergencia similar ante un tribunal federal de apelaciones con sede en Boston este viernes por la ma\u00f1ana, pero el tribunal a\u00fan no se hab\u00eda pronunciado cuando el Departamento de Agricultura de EE.UU. envi\u00f3 una gu\u00eda a los estados diciendo que estaban trabajando para cumplir con la orden de McConnell. El tribunal de apelaciones, en una breve orden este viernes por la noche, se neg\u00f3 a suspender temporalmente los pagos mientras revisaba el caso \u201clo m\u00e1s r\u00e1pido posible\u201d.<\/p>\n<p>El Gobierno pidi\u00f3 a la Corte Suprema que emitiera una suspensi\u00f3n administrativa inmediata del caso antes de las 9:30 p.m., hora de Miami.<\/p>\n<p>\u201cTal interrupci\u00f3n de fondos es una crisis\u201d, dijo el Gobierno a la Corte Suprema en su apelaci\u00f3n de emergencia. \u201cPero es una crisis provocada por el fracaso del Congreso y que solo puede resolverse mediante la acci\u00f3n del Congreso\u201d.<\/p>\n<p>\u201cLa decisi\u00f3n del tribunal de distrito\u201d, dijo el procurador general de EE.UU. D. John Sauer a la Corte Suprema, \u201ces insostenible en todos los aspectos\u201d.<\/p>\n<p>La disputa legal sobre los cupones de alimentos ha surgido como un punto de presi\u00f3n central entre los tres poderes durante el hist\u00f3ricamente largo cierre del Gobierno, porque es uno de los impactos m\u00e1s f\u00e1ciles de entender y tangibles de ese estancamiento hasta ahora. Lo que est\u00e1 en juego son los beneficios alimentarios de los que dependen millones de estadounidenses.<\/p>\n<p>No est\u00e1 claro c\u00f3mo la solicitud a la Corte Suprema podr\u00eda afectar los miles de millones de d\u00f3lares en fondos federales para el Programa de Asistencia Nutricional Suplementaria, o SNAP, por sus siglas en ingl\u00e9s, como se conocen formalmente los cupones de alimentos. Varios estados confirmaron este viernes que las personas que dependen del programa deber\u00edan comenzar a recibir pronto sus pagos completos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump pidi\u00f3 este viernes por la noche a la Corte Suprema que bloquee una decisi\u00f3n de un tribunal inferior que requer\u00eda que el Gobierno cubriera completamente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre. La solicitud de emergencia a los jueces lleg\u00f3 horas despu\u00e9s de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468133","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump pidi\u00f3 este viernes por la noche a la Corte Suprema que bloquee una decisi\u00f3n de un tribunal inferior que requer\u00eda que el Gobierno cubriera completamente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre. La solicitud de emergencia a los jueces lleg\u00f3 horas despu\u00e9s de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-08T01:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP\",\"datePublished\":\"2025-11-08T01:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\"},\"wordCount\":445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\",\"name\":\"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-08T01:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias","og_description":"El presidente Donald Trump pidi\u00f3 este viernes por la noche a la Corte Suprema que bloquee una decisi\u00f3n de un tribunal inferior que requer\u00eda que el Gobierno cubriera completamente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre. La solicitud de emergencia a los jueces lleg\u00f3 horas despu\u00e9s de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-08T01:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/"},"author":{"name":"","@id":""},"headline":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP","datePublished":"2025-11-08T01:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/"},"wordCount":445,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","name":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-08T01:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/07\/trump-pide-corte-suprema-cupones-snap-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-08T01:03:47Z","datePublished":"2025-11-08T01:03:47Z","dateModified":"2025-11-08T01:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump pide a la Corte Suprema intervenir en la disputa sobre financiamiento de cupones de alimentos de SNAP\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/trump-pide-corte-suprema-cupones-snap-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/07\\\/trump-pide-corte-suprema-cupones-snap-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-08T01:03:47Z\",\"datePublished\":\"2025-11-08T01:03:47Z\",\"dateModified\":\"2025-11-08T01:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468244,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/11\/corte-orden-pagos-snap-trax\/","url_meta":{"origin":1468133,"position":0},"title":"La Corte Suprema emite una orden temporal que mantiene en suspenso los pagos completos de SNAP","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"La Corte Suprema extendi\u00f3 este martes una orden temporal que permite al Gobierno Trump retener el pago completo de los cupones de alimentos en noviembre, una medida que parece dise\u00f1ada para posponer el caso unos d\u00edas con la esperanza de que el Congreso apruebe un acuerdo pendiente para reabrir el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468194,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/10\/cupones-alimenticios-snap-corte-suprema-cierre-gobierno-trax\/","url_meta":{"origin":1468133,"position":1},"title":"Cupones alimenticios del SNAP: Gobierno de Trump dice que continuar\u00e1 su caso ante la Corte Suprema","author":"","date":"noviembre 10, 2025","format":false,"excerpt":"La administraci\u00f3n Trump inform\u00f3 este lunes a la Corte Suprema de EE.UU. que continuar\u00e1 luchando para retener la totalidad de los beneficios del Programa de Asistencia Nutricional Suplementaria (SNAP, por sus siglas en ingl\u00e9s) a los estados durante el cierre parcial del Gobierno, manteniendo as\u00ed en curso un caso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468121,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/07\/gobierno-apela-orden-beneficios-snap-trax\/","url_meta":{"origin":1468133,"position":2},"title":"Gobierno de Trump pide que se suspenda la orden judicial que le exige realizar los pagos completos de los cupones del SNAP","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"El Gobierno de Donald Trump solicit\u00f3 a un tribunal federal de apelaciones que suspenda la orden de un juez que le obliga a cubrir \u00edntegramente los beneficios del programa de cupones de alimentos del SNAP para decenas de millones de estadounidenses en noviembre.La solicitud de emergencia, presentada el viernes por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466625,"url":"https:\/\/noticiasya.com\/tampa\/2025\/09\/19\/trump-corte-suprema-deportar-venezolanos-trax\/","url_meta":{"origin":1468133,"position":3},"title":"Trump pide a la Corte Suprema que le permita deportar a 300.000 venezolanos","author":"","date":"septiembre 19, 2025","format":false,"excerpt":"Este viernes, el Gobierno de Trump inst\u00f3 a la Corte Suprema a retirar las protecciones contra la deportaci\u00f3n que se hab\u00edan concedido a unos 300.000 venezolanos que viven en Estados Unidos, y acus\u00f3 a un tribunal inferior de cometer una \u201cafrenta innecesaria\u201d al fallar en sentido contrario.El caso se refiere\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468104,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/06\/juez-ordena-trump-pagos-snap-trax\/","url_meta":{"origin":1468133,"position":4},"title":"Juez federal ordena al Gobierno de Trump que realice los pagos completos de noviembre para cupones de alimentos del SNAP","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"Un juez federal en Rhode Island dijo este jueves que el Gobierno de Trump debe cubrir completamente los beneficios de cupones de alimentos para decenas de millones de estadounidenses en noviembre.\u201cLa gente ha pasado necesidades durante demasiado tiempo\u201d, dijo McConnell desde el estrado. \u201cNo hacer pagos a ellos ni siquiera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463899,"url":"https:\/\/noticiasya.com\/tampa\/2025\/06\/24\/trump-juez-corte-suprema-migrantes-yibuti-trax\/","url_meta":{"origin":1468133,"position":5},"title":"El Gobierno de Trump acusa a un juez de desafiar a la Corte Suprema en el caso de los migrantes detenidos en Djibouti","author":"","date":"junio 24, 2025","format":false,"excerpt":"El Gobierno del presidente Donald Trump inst\u00f3 este martes a la Corte Suprema a permitir la deportaci\u00f3n inmediata a Sud\u00e1n del Sur de un grupo de migrantes que se encuentran actualmente detenidos en una base militar estadounidense en Djibouti, alegando que el juez a cargo del caso desafi\u00f3 al m\u00e1ximo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468133"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468133\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}