{"id":1468160,"date":"2025-11-08T18:03:53","date_gmt":"2025-11-09T02:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/"},"modified":"2025-11-08T18:03:53","modified_gmt":"2025-11-09T02:03:53","slug":"cientificos-gen-reducir-colesterol-alto-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","title":{"rendered":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente"},"content":{"rendered":"<p>Con la modificaci\u00f3n de un gen, los m\u00e9dicos podr\u00edan alg\u00fan d\u00eda reducir permanentemente los niveles peligrosamente altos de colesterol, eliminando posiblemente la necesidad de medicamentos, seg\u00fan un nuevo estudio piloto publicado este s\u00e1bado en el <a href=\"https:\/\/www.nejm.org\/doi\/full\/10.1056\/NEJMoa2511778\">New England Journal of Medicine<\/a>.<\/p>\n<p>El estudio fue extremadamente peque\u00f1o \u2014solo 15 pacientes con enfermedad grave\u2014 y su objetivo era probar la seguridad de un nuevo medicamento administrado mediante CRISPR-Cas9, una especie de tijera biol\u00f3gica que corta un gen espec\u00edfico para modificarlo, activarlo o desactivarlo.<\/p>\n<p>Sin embargo, los resultados preliminares mostraron una reducci\u00f3n de casi el 50 % en la lipoprote\u00edna de baja densidad, o LDL, el \u201ccolesterol malo\u201d que juega un papel importante en las enfermedades card\u00edacas, la principal causa de muerte de adultos en Estados Unidos y en todo el mundo.<\/p>\n<p>El estudio, que ser\u00e1 presentado este s\u00e1bado en las Sesiones Cient\u00edficas de la Asociaci\u00f3n Estadounidense del Coraz\u00f3n en Nueva Orleans, tambi\u00e9n encontr\u00f3 una reducci\u00f3n promedio del 55 % en los <a href=\"https:\/\/cnnespanol.cnn.com\/video\/omega3-recetado-pacientes-cardiacos-triglicerios-oraa-montoya-cafe-cnnee\">triglic\u00e9ridos<\/a>, otro tipo de grasa en la sangre que tambi\u00e9n se relaciona con un mayor riesgo de enfermedad cardiovascular.<\/p>\n<p>\u201cEsperamos que esta sea una soluci\u00f3n permanente, donde personas j\u00f3venes con enfermedad grave puedan someterse a una terapia g\u00e9nica \u00fanica y tengan niveles reducidos de LDL y triglic\u00e9ridos por el resto de sus vidas\u201d, dijo el autor principal del estudio, el doctor Steven Nissen, jefe acad\u00e9mico del Instituto Cardiovascular y Tor\u00e1cico Sydell y Arnold Miller Family en la Cl\u00ednica Cleveland, Ohio.<\/p>\n<p>\u201cEs un sue\u00f1o hecho realidad\u201d, concluy\u00f3 Nissen. \u201cSi me hubieran preguntado hace 15 a\u00f1os si podr\u00edamos haber hecho algo as\u00ed, habr\u00eda pensado que estaban locos\u201d, dijo el Dr. Pradeep Natarajan, director de cardiolog\u00eda preventiva del Hospital General de Massachusetts y profesor asociado de medicina en la Facultad de Medicina de Harvard en Boston.<\/p>\n<p>Actualmente, los cardi\u00f3logos quieren que las personas con enfermedad card\u00edaca existente o aquellas nacidas con una predisposici\u00f3n a un colesterol dif\u00edcil de controlar bajen su LDL muy por debajo de 100, que es el promedio en Estados Unidos, dijo el doctor Pradeep Natarajan, director de cardiolog\u00eda preventiva en el Hospital General de Massachusetts y profesor asociado de medicina en la Facultad de Medicina de Harvard en Boston.<\/p>\n<p>\u201cHay evidencia que sugiere que el nivel \u00f3ptimo de colesterol es de 40 a 50, lo cual es muy dif\u00edcil de lograr solo con la dieta y el estilo de vida\u201d, coment\u00f3 Natarajan, quien no particip\u00f3 en el estudio.<\/p>\n<p>\u201cAhora, los medicamentos actuales ya pueden reducir el colesterol LDL a los niveles encontrados en el estudio; de hecho, algunos medicamentos son un poco m\u00e1s potentes\u201d, dijo. \u201cAs\u00ed que tendremos que esperar y ver si este tratamiento funciona tan bien como sugiere este primer estudio\u201d.<\/p>\n<p>Aunque preliminares, los hallazgos son prometedores debido a la dificultad de recordar tomar un medicamento diario \u2014y a veces tres o cuatro\u2014 para controlar los niveles altos de colesterol, afirm\u00f3 la Dra. Ann Marie Navar, cardi\u00f3loga preventiva y profesora asociada de cardiolog\u00eda en el Centro M\u00e9dico UT Southwestern de Dallas, Texas.<\/p>\n<p>\u201cA pesar de tener muchas terapias disponibles, la mayor\u00eda de las personas no tiene su LDL bajo control\u201d, dijo Navar, quien no particip\u00f3 en el estudio.<\/p>\n<p>\u201cSi tienes 20 a\u00f1os y colesterol muy alto, podr\u00eda ser mucho m\u00e1s conveniente un tratamiento \u00fanico que no requiera tomar una pastilla todos los d\u00edas o una inyecci\u00f3n cada dos semanas durante los pr\u00f3ximos 60 a\u00f1os\u201d, agreg\u00f3. \u201cEl potencial es enorme\u201d.<\/p>\n<p>La idea de un tratamiento de edici\u00f3n gen\u00e9tica provino de una fuente inusual: una mutaci\u00f3n gen\u00e9tica. En ese escenario, el gen ANGPTL3, o prote\u00edna angiopoyetina similar 3, que es responsable de regular el LDL y los triglic\u00e9ridos, est\u00e1 desactivado.<\/p>\n<p>Las personas con un gen ANGPTL3 no funcional \u2014lo que seg\u00fan Natarajan aplica a aproximadamente 1 de cada 250 personas en Estados Unidos\u2014 tienen niveles bajos de por vida de colesterol LDL y triglic\u00e9ridos sin consecuencias negativas aparentes. Tambi\u00e9n tienen un riesgo extremadamente bajo o nulo de enfermedad cardiovascular.<\/p>\n<p>\u201cEs una mutaci\u00f3n natural que protege contra las enfermedades cardiovasculares\u201d, dijo Nissen, quien ocupa la C\u00e1tedra Lewis y Patricia Dickey en Medicina Cardiovascular en Cleveland Clinic. \u201cY ahora que existe CRISPR, tenemos la capacidad de cambiar los genes de otras personas para que tambi\u00e9n puedan tener esta protecci\u00f3n\u201d.<\/p>\n<p>A los participantes del estudio se les administraron varias dosis del medicamento basado en CRISPR mediante infusi\u00f3n: un grupo de personas recibi\u00f3 una dosis muy peque\u00f1a de 0,1 miligramos por kilo, mientras que otros recibieron niveles de 0,3 a 0,8 miligramos por kilo, dijo el autor principal del estudio, el doctor Luke Laffin, cardi\u00f3logo preventivo en el Instituto Cardiovascular y Tor\u00e1cico de la Cl\u00ednica Cleveland.<\/p>\n<p>\u201cEl promedio de disminuci\u00f3n fue del 55 % en triglic\u00e9ridos y casi del 50 % en colesterol LDL con la dosis m\u00e1s alta\u201d, dijo Laffin. \u201cEso es emocionante porque actualmente no existen terapias que reduzcan simult\u00e1neamente el colesterol LDL y los triglic\u00e9ridos\u201d.<\/p>\n<p>Hubo una peque\u00f1a disminuci\u00f3n en HDL (lipoprote\u00edna de alta densidad), conocido como colesterol \u201cbueno\u201d. No obstante, la ca\u00edda en HDL tambi\u00e9n se encuentra en personas con la mutaci\u00f3n ANGPTL3 y no parece ser da\u00f1ina, dijo Laffin.<\/p>\n<p>\u201cEl trastorno m\u00e1s com\u00fan que vemos en nuestra cl\u00ednica de prevenci\u00f3n es la hiperlipidemia mixta: personas que tienen problemas para controlar tanto el LDL como los triglic\u00e9ridos\u201d, dijo Nissen. \u201cAs\u00ed que poder hacer esto simult\u00e1neamente es realmente un avance importante\u201d.<\/p>\n<p>En personas con la mutaci\u00f3n natural, el gen ANGPTL3 est\u00e1 desactivado en todas las c\u00e9lulas del cuerpo: m\u00fasculos, coraz\u00f3n, pulmones, etc. Sin embargo, el nuevo medicamento apunta \u00fanicamente al h\u00edgado, el \u00f3rgano responsable de sintetizar triglic\u00e9ridos y producir colesterol, adem\u00e1s de eliminar el exceso de colesterol de la sangre.<\/p>\n<p>Eso es tranquilizador para la seguridad a largo plazo del impacto del medicamento, dijo Nissen, ya que hace menos probable que se editen genes en otras partes del cuerpo.<\/p>\n<p>De acuerdo con el estudio, los efectos secundarios del tratamiento inicial fueron m\u00ednimos, principalmente irritaci\u00f3n en los puntos de infusi\u00f3n. Una persona sufri\u00f3 una hernia de disco espinal y otra present\u00f3 un aumento de enzimas que podr\u00edan indicar da\u00f1o hep\u00e1tico, pero estos niveles se normalizaron en dos semanas.<\/p>\n<p>Sin embargo, una persona muri\u00f3 seis meses despu\u00e9s de la infusi\u00f3n: \u201cTen\u00eda una enfermedad cardiovascular extensa y avanzada, y recibi\u00f3 la dosis m\u00e1s peque\u00f1a de 0,1, una dosis que no tiene ning\u00fan efecto\u201d, dijo Nissen.<\/p>\n<p>\u201cNo creemos que su muerte tenga ninguna implicaci\u00f3n para el estudio\u201d, dijo.<br \/>\u201cAdem\u00e1s, la FDA ha recomendado que estas personas sean seguidas despu\u00e9s de que terminen los ensayos durante 15 a\u00f1os para ver si hay efectos adversos a largo plazo. Eso se har\u00e1, y es lo correcto\u201d.<\/p>\n<p>Los ensayos cl\u00ednicos de fase 2 comenzar\u00e1n pronto, seguidos r\u00e1pidamente por los de fase 3, que est\u00e1n dise\u00f1ados para mostrar el efecto del medicamento en una poblaci\u00f3n m\u00e1s grande, indic\u00f3 Nissen.<\/p>\n<p>\u201cEsperamos hacer todo esto para finales del pr\u00f3ximo a\u00f1o\u201d, dijo Nissen. \u201cNos estamos moviendo muy r\u00e1pido porque hay una gran necesidad m\u00e9dica insatisfecha: millones de personas tienen estos trastornos y muchas de ellas no est\u00e1n en tratamiento o lo han interrumpido por diversos motivos. Ese es un gran problema de subtratamiento aqu\u00ed en Estados Unidos\u201d.<\/p>\n<p>Aun as\u00ed, esto es solo el comienzo, y ha habido medicamentos similares que parec\u00edan prometedores al principio pero luego fueron rechazados por preocupaciones de seguridad, dijo Nadar.<\/p>\n<p>\u201cEl mensaje m\u00e1s importante para llevar a casa es que si est\u00e1s tomando un medicamento para reducir el colesterol, sigue tom\u00e1ndolo\u201d, dijo. \u201cTodos los datos muestran que cuanto m\u00e1s tiempo reduzcas tu colesterol LDL, mejor ser\u00e1 tu resultado. Alguien que baja su LDL de 100 a 30 solo por un a\u00f1o estar\u00e1 mucho menos protegido que alguien que lo baja de 100 a 50 durante toda la vida\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la modificaci\u00f3n de un gen, los m\u00e9dicos podr\u00edan alg\u00fan d\u00eda reducir permanentemente los niveles peligrosamente altos de colesterol, eliminando posiblemente la necesidad de medicamentos, seg\u00fan un nuevo estudio piloto publicado este s\u00e1bado en el New England Journal of Medicine. El estudio fue extremadamente peque\u00f1o \u2014solo 15 pacientes con enfermedad grave\u2014 y su objetivo era [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468160","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Con la modificaci\u00f3n de un gen, los m\u00e9dicos podr\u00edan alg\u00fan d\u00eda reducir permanentemente los niveles peligrosamente altos de colesterol, eliminando posiblemente la necesidad de medicamentos, seg\u00fan un nuevo estudio piloto publicado este s\u00e1bado en el New England Journal of Medicine. El estudio fue extremadamente peque\u00f1o \u2014solo 15 pacientes con enfermedad grave\u2014 y su objetivo era [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T02:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente\",\"datePublished\":\"2025-11-09T02:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\"},\"wordCount\":1398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\",\"name\":\"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-09T02:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias","og_description":"Con la modificaci\u00f3n de un gen, los m\u00e9dicos podr\u00edan alg\u00fan d\u00eda reducir permanentemente los niveles peligrosamente altos de colesterol, eliminando posiblemente la necesidad de medicamentos, seg\u00fan un nuevo estudio piloto publicado este s\u00e1bado en el New England Journal of Medicine. El estudio fue extremadamente peque\u00f1o \u2014solo 15 pacientes con enfermedad grave\u2014 y su objetivo era [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","og_site_name":"Noticias","article_published_time":"2025-11-09T02:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/"},"author":{"name":"","@id":""},"headline":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente","datePublished":"2025-11-09T02:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/"},"wordCount":1398,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","url":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","name":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-09T02:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cient\u00edficos editaron un gen que podr\u00eda reducir el colesterol alto de forma permanente","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/08\/cientificos-gen-reducir-colesterol-alto-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-09T02:03:53Z","datePublished":"2025-11-09T02:03:53Z","dateModified":"2025-11-09T02:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cient\\u00edficos editaron un gen que podr\\u00eda reducir el colesterol alto de forma permanente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/08\\\/cientificos-gen-reducir-colesterol-alto-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/08\\\/cientificos-gen-reducir-colesterol-alto-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-09T02:03:53Z\",\"datePublished\":\"2025-11-09T02:03:53Z\",\"dateModified\":\"2025-11-09T02:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468164,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/09\/pildora-podria-reducir-colesterol-estatinas-trax\/","url_meta":{"origin":1468160,"position":0},"title":"Una p\u00edldora podr\u00eda reducir el colesterol en pacientes que no obtienen suficiente beneficio solo con estatinas, seg\u00fan estudio","author":"","date":"noviembre 9, 2025","format":false,"excerpt":"Para algunas personas con colesterol alto, hacer cambios en el estilo de vida y tomar medicamentos con estatinas de forma rutinaria puede no ser suficiente para alcanzar sus niveles objetivo de colesterol. Para estos pacientes, una nueva p\u00edldora experimental podr\u00eda ofrecer algo de esperanza.Datos de un ensayo de fase 3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442719,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/27\/enfrenta-estos-problemas-de-salud-para-reducir-el-riesgo-de-demencia-temprana-segun-un-estudio\/","url_meta":{"origin":1468160,"position":1},"title":"Enfrenta estos problemas de salud para reducir el riesgo de demencia temprana, seg\u00fan un estudio","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) \u2014 El deterioro cognitivo puede comenzar a\u00f1os antes de que aparezcan los primeros signos de demencia, que para algunos puede ocurrir tan r\u00e1pido como a los 30 a\u00f1os, una condici\u00f3n conocida como demencia de inicio temprano o de aparici\u00f3n precoz. Se estima que casi 4 millones de personas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442875,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/29\/las-10-preguntas-sobre-salud-mas-frecuentes-que-le-hicieron-al-dr-google-en-2023\/","url_meta":{"origin":1468160,"position":2},"title":"Las 10 preguntas sobre salud m\u00e1s frecuentes que le hicieron al Dr. Google en 2023","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN) -- Este a\u00f1o, los usuarios de Google en Estados Unidos quisieron saber m\u00e1s sobre la faringitis estreptoc\u00f3cica, c\u00f3mo reducir el colesterol y qu\u00e9 ayuda contra la hinchaz\u00f3n.Estas fueron algunas de las preguntas relacionadas con la salud m\u00e1s buscadas en Google en Estados Unidos entre el 1 de enero y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451364,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/23\/brain-care-score-herramienta-predecir-riesgo-demencia-depresion-trax\/","url_meta":{"origin":1468160,"position":3},"title":"Una sencilla herramienta puede predecir el riesgo de demencia y depresi\u00f3n, seg\u00fan un estudio","author":"","date":"julio 23, 2024","format":false,"excerpt":"(CNN) -- Cient\u00edficos anunciaron en diciembre la creaci\u00f3n con \u00e9xito del Brain Care Score, una herramienta para evaluar el riesgo de demencia o ictus sin necesidad de procedimientos m\u00e9dicos.Seg\u00fan un nuevo estudio, esta puntuaci\u00f3n, que tambi\u00e9n ayuda a pacientes y m\u00e9dicos a identificar cambios beneficiosos en el estilo de vida,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450564,"url":"https:\/\/noticiasya.com\/tampa\/2024\/06\/20\/cientificos-gen-obesidad-nuevo-estudio-trax\/","url_meta":{"origin":1468160,"position":4},"title":"Cient\u00edficos identifican un gen relacionado con la obesidad, seg\u00fan un nuevo estudio","author":"","date":"junio 20, 2024","format":false,"excerpt":"(CNN) -- La obesidad no es simplemente una cuesti\u00f3n de comida y ejercicio: puede estar en tu c\u00f3digo gen\u00e9tico, seg\u00fan una nueva investigaci\u00f3n.\"Las causas de la obesidad son muy complejas y, en la mayor\u00eda de los casos, la combinaci\u00f3n de muchos factores. En este estudio, sin embargo, hemos hallado un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465112,"url":"https:\/\/noticiasya.com\/tampa\/2025\/08\/04\/alimentos-ultraprocesados-perdida-peso-trax\/","url_meta":{"origin":1468160,"position":5},"title":"Comer alimentos m\u00ednimamente procesados duplica p\u00e9rdida de peso incluso con  ultraprocesados que son saludables, dice estudio","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Las personas en el Reino Unido perdieron el doble de peso comiendo comidas t\u00edpicamente hechas en casa que cuando com\u00edan alimentos ultraprocesados comprados en tiendas considerados saludables, seg\u00fan ha descubierto la investigaci\u00f3n m\u00e1s reciente.\u201cEste nuevo estudio muestra que incluso cuando una dieta ultraprocesada cumple con las pautas nutricionales, las personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468160"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468160\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}