{"id":1468184,"date":"2025-11-09T20:03:52","date_gmt":"2025-11-10T04:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/"},"modified":"2025-11-09T20:03:52","modified_gmt":"2025-11-10T04:03:52","slug":"27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","title":{"rendered":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria"},"content":{"rendered":"<p>Al menos 27 presos murieron este domingo por asfixia en el Centro de Privaci\u00f3n de Libertad de Machala, ubicado en la provincia de El Oro, en el sur de Ecuador, inform\u00f3 el Servicio Nacional de Atenci\u00f3n Integral a Personas Privadas de la Libertad y Adolescentes Infractores (SNAI).<\/p>\n<p>En un <a href=\"https:\/\/x.com\/SNAI_Ec\/status\/1987691125222830588\">comunicado<\/a> publicado en su cuenta oficial de X, el SNAI dijo que \u201centre ellos cometieron asfixia, lo que produjo muerte inmediata por suspensi\u00f3n\u201d. Las autoridades no ofrecieron de inmediato m\u00e1s detalles sobre las circunstancias del hecho, que ocurre en medio de una prolongada crisis carcelaria en el pa\u00eds.<\/p>\n<p>En respuesta a la prensa, incluido CNN, el organismo se\u00f1al\u00f3 que \u201clas autoridades, equipos operativos y personal m\u00e9dico forense contin\u00faan trabajando en el lugar, verificando la informaci\u00f3n y atendiendo las emergencias registradas\u201d. El SNAI a\u00f1adi\u00f3 que \u201ceste hecho corresponde a un suceso distinto al ocurrido en horas de la ma\u00f1ana\u201d en el mismo centro penitenciario, y hasta el momento no ha proporcionado ning\u00fan motivo de las muertes.<\/p>\n<p>Durante la madrugada de este domingo en la misma c\u00e1rcel otro incidente dej\u00f3 cuatro reclusos muertos y varios heridos, <a href=\"https:\/\/x.com\/SNAI_Ec\/status\/1987504717031674300\">seg\u00fan el SNAI.<\/a> La instituci\u00f3n atribuy\u00f3 esos hechos a un proceso de \u201creorganizaci\u00f3n de los privados de libertad en la nueva c\u00e1rcel de m\u00e1xima seguridad\u201d.<\/p>\n<p>El incidente en Machala ocurre semanas despu\u00e9s de una serie de enfrentamientos mortales en otros penales del pa\u00eds. En septiembre de 2025, <a href=\"https:\/\/www.cnn.com\/2025\/09\/25\/americas\/ecuador-esmeraldas-prison-clash-intl-latam\">un violento choque entre bandas rivales<\/a> en una prisi\u00f3n de la ciudad costera de Esmeraldas dej\u00f3 al menos 17 muertos, seg\u00fan la Polic\u00eda Nacional. Tres d\u00edas antes, en la misma c\u00e1rcel de Machala, otros 14 reclusos fueron asesinados.<\/p>\n<p>El coronel William Fabi\u00e1n Calle inform\u00f3 entonces que, al ingresar las fuerzas de seguridad al penal de Machala, hallaron 14 presos muertos, 14 heridos y un guardia penitenciario que hab\u00eda sido baleado dentro de una de las celdas.<\/p>\n<p>\u201cUstedes saben que hay conflicto entre bandas en esta prisi\u00f3n. Dos pabellones est\u00e1n controlados por un grupo de delincuencia organizada, y es all\u00ed donde se est\u00e1n produciendo los asesinatos. La pregunta es c\u00f3mo lograron pasar al otro pabell\u00f3n, cuando hay varios filtros\u201d, se\u00f1al\u00f3 el funcionario.<\/p>\n<p>Desde 2021, m\u00e1s de 500 internos han muerto en los penales de Ecuador, de acuerdo con cifras oficiales. La ola de violencia carcelaria ocurre en el contexto de un estado de conflicto armado interno que rige en todo el pa\u00eds desde enero de 2024, pese al despliegue de fuerzas militares y policiales en varios centros penitenciarios.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 27 presos murieron este domingo por asfixia en el Centro de Privaci\u00f3n de Libertad de Machala, ubicado en la provincia de El Oro, en el sur de Ecuador, inform\u00f3 el Servicio Nacional de Atenci\u00f3n Integral a Personas Privadas de la Libertad y Adolescentes Infractores (SNAI). En un comunicado publicado en su cuenta oficial [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1468184","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos 27 presos murieron este domingo por asfixia en el Centro de Privaci\u00f3n de Libertad de Machala, ubicado en la provincia de El Oro, en el sur de Ecuador, inform\u00f3 el Servicio Nacional de Atenci\u00f3n Integral a Personas Privadas de la Libertad y Adolescentes Infractores (SNAI). En un comunicado publicado en su cuenta oficial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T04:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria\",\"datePublished\":\"2025-11-10T04:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\",\"name\":\"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-11-10T04:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias","og_description":"Al menos 27 presos murieron este domingo por asfixia en el Centro de Privaci\u00f3n de Libertad de Machala, ubicado en la provincia de El Oro, en el sur de Ecuador, inform\u00f3 el Servicio Nacional de Atenci\u00f3n Integral a Personas Privadas de la Libertad y Adolescentes Infractores (SNAI). En un comunicado publicado en su cuenta oficial [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","og_site_name":"Noticias","article_published_time":"2025-11-10T04:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/"},"author":{"name":"","@id":""},"headline":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria","datePublished":"2025-11-10T04:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","url":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","name":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-11-10T04:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 27 presos mueren por asfixia en una c\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria","url":"http:\/\/noticiasya.com\/tampa\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2025\/11\/09\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-11-10T04:03:52Z","datePublished":"2025-11-10T04:03:52Z","dateModified":"2025-11-10T04:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 27 presos mueren por asfixia en una c\\u00e1rcel del sur de Ecuador, en medio de una nueva ola de violencia carcelaria\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/09\\\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2025\\\/11\\\/09\\\/27-presos-mueren-asfixia-carcel-ecuador-ola-violencia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-11-10T04:03:52Z\",\"datePublished\":\"2025-11-10T04:03:52Z\",\"dateModified\":\"2025-11-10T04:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469069,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/08\/muertos-carcel-machala-ecuador-explosion-orix\/","url_meta":{"origin":1468184,"position":0},"title":"Mueren 13 presos en la c\u00e1rcel de Machala en Ecuador tras una explosi\u00f3n","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"El Servicio de Atenci\u00f3n a Personas Privadas de la Libertad de Ecuador (SNAI) confirm\u00f3 este lunes que 13 reclusos murieron este domingo luego de que se registr\u00f3 la detonaci\u00f3n de un artefacto explosivo en los exteriores de la c\u00e1rcel de Machala, centro de privaci\u00f3n de libertad de la provincia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468188,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/10\/5-cosas-10-noviembre-orix\/","url_meta":{"origin":1468184,"position":1},"title":"Las 5 cosas que debes saber este 10 de noviembre: cierre del Gobierno, plan Michoac\u00e1n, violencia carcelaria en Ecuador, CELAC","author":"","date":"noviembre 10, 2025","format":false,"excerpt":"Nueva ola de violencia carcelaria en Ecuador. La presidenta de M\u00e9xico revela plan millonario contra la violencia en Michoac\u00e1n. \u00bfC\u00f3mo han cambiado los roles de las agencias federales en la batalla migratoria de Trump? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465054,"url":"https:\/\/noticiasya.com\/tampa\/2025\/08\/01\/trasladan-prision-401-presos-tuberculosis-ecuador-orix\/","url_meta":{"origin":1468184,"position":2},"title":"Trasladan de una prisi\u00f3n a otra a 401 presos con tuberculosis en Ecuador","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Autoridades de seguridad y sanitarias de Ecuador reubicaron de una prisi\u00f3n a otra a 401 presos diagnosticados con tuberculosis, inform\u00f3 este viernes el Servicio Nacional de Atenci\u00f3n Integral a Personas Adultas Privadas de la Libertad y a Adolescentes Infractores (SNAI).Entre el 28 y el 31 de julio, los internos fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469354,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/17\/hacinamiento-tuberculosis-carceles-ecuador-orix\/","url_meta":{"origin":1468184,"position":3},"title":"Hacinamiento, tuberculosis y violencia: el peligroso combo que afecta a las c\u00e1rceles de Ecuador y provoca decenas de muertes","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Al menos 30 presos murieron en una c\u00e1rcel del sur de Ecuador el pasado 9 de noviembre por presunta asfixia. Apenas un mes despu\u00e9s, en la misma prisi\u00f3n se registraron 13 muertes luego de la explosi\u00f3n de un artefacto en los exteriores del centro sin que se aclare su conexi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466822,"url":"https:\/\/noticiasya.com\/tampa\/2025\/09\/25\/muertos-enfrentamiento-carcel-ecuador-orix\/","url_meta":{"origin":1468184,"position":4},"title":"Al menos 17 muertos tras enfrentamiento en una c\u00e1rcel de Ecuador","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Un enfrentamiento entre bandas rivales en la c\u00e1rcel de la ciudad costera de Esmeraldas en Ecuador dej\u00f3 al menos 17 muertos, seg\u00fan inform\u00f3 la Polic\u00eda Nacional a trav\u00e9s de un comunicado compartido a la prensa.\u201cLa situaci\u00f3n se da por una orden externa del grupo de delincuencia organizada Tiguerones para que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450594,"url":"https:\/\/noticiasya.com\/tampa\/2024\/06\/21\/construccion-carcel-maxima-seguridad-ecuador-violencia-orix\/","url_meta":{"origin":1468184,"position":5},"title":"Comienza la construcci\u00f3n de una c\u00e1rcel de m\u00e1xima seguridad en la costa de Ecuador, en medio de la lucha contra la violencia","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El presidente de Ecuador, Daniel Noboa, y varios funcionarios de su Gobierno anunciaron en un acto oficial el inicio de la construcci\u00f3n de una c\u00e1rcel de m\u00e1xima seguridad en la provincia costera de Santa Elena, con la que buscan combatir al crimen organizado y ordenar el sistema\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1468184"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1468184\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1468184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1468184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1468184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}