{"id":1472301,"date":"2026-03-18T01:03:51","date_gmt":"2026-03-18T08:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/"},"modified":"2026-03-18T01:03:51","modified_gmt":"2026-03-18T08:03:51","slug":"conclusiones-elecciones-primarias-illinois-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","title":{"rendered":"Conclusiones de las elecciones primarias de Illinois"},"content":{"rendered":"<p>Al nominar este martes a la vicegobernadora Juliana Stratton para el Senado, los dem\u00f3cratas de Illinois eligieron a una candidata cuyo mensaje inclu\u00eda un <a href=\"https:\/\/www.facebook.com\/reel\/967001489339870\">anuncio de televisi\u00f3n<\/a> en el que aparec\u00edan personas diciendo \u201cque se jo** Trump\u201d.<\/p>\n<p>Stratton fue seleccionada por encima de un rival m\u00e1s moderado y con mayor financiaci\u00f3n, el representante Raja Krishnamoorthi, as\u00ed como de la representante Robin Kelly.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/17\/politics\/juliana-stratton-illinois-senate-primary\">La victoria de Stratton<\/a>, impulsada por un amplio margen en Chicago y reforzada por resultados mejores de lo esperado en sus suburbios, se produjo en unas elecciones primarias en las que hab\u00eda un esca\u00f1o vacante en el Senado y cuatro en la C\u00e1mara de Representantes.<\/p>\n<p>Es probable que los dem\u00f3cratas ganen todos esos esca\u00f1os en noviembre. Sin embargo, las divisiones m\u00e1s profundas del partido \u2014sobre ideolog\u00eda, relevo generacional, c\u00f3mo abordar la relaci\u00f3n con Israel y otros temas\u2014 quedaron patentes en <a href=\"https:\/\/www.cnn.com\/2026\/03\/17\/politics\/juliana-stratton-illinois-senate-primary\">las primarias de este martes<\/a>.<\/p>\n<p>En definitiva, es probable que los resultados no contribuyan a zanjar los prolongados debates sobre el futuro del partido.<\/p>\n<p>Los candidatos respaldados por grupos proisrael\u00edes y pro-criptomonedas ganaron algunas contiendas clave, pero perdieron otras.<\/p>\n<p>Un candidato progresista que promet\u00eda un cambio generacional no logr\u00f3 la victoria en una contienda por un esca\u00f1o en la C\u00e1mara de Representantes en el \u00e1rea de Chicago, pero el ganador de esa elecci\u00f3n tambi\u00e9n se enfrent\u00f3 a la organizaci\u00f3n de presi\u00f3n proisrael\u00ed American Israel Public Affairs Committee (AIPAC).<\/p>\n<p>Y un exmiembro del Congreso consigui\u00f3 regresar a la pol\u00edtica, mientras que otro reconoci\u00f3 su derrota.<\/p>\n<p>Aqu\u00ed hay cinco conclusiones de las primarias de Illinois:<\/p>\n<p>El mayor ganador de las primarias podr\u00eda ser el principal impulsor de Stratton: el gobernador J.B Pritzker.<\/p>\n<p>El gobernador dem\u00f3crata, considerado por muchos como un posible candidato presidencial para 2028, no tuvo oposici\u00f3n en sus primarias para un tercer mandato.<\/p>\n<p>Sin embargo, Pritzker invirti\u00f3 millones de d\u00f3lares para impulsar la candidatura de Stratton frente a dos miembros del Congreso en la contienda para reemplazar <a href=\"https:\/\/www.cnn.com\/2025\/04\/23\/politics\/dick-durbin-senate-retirement\">al senador dem\u00f3crata saliente Dick Durbin<\/a>.<\/p>\n<p>Pritzker, el multimillonario heredero de una fortuna en el sector hotelero, celebr\u00f3 con un encendido discurso el martes por la noche, arremetiendo contra Trump y dejando claro una vez m\u00e1s cu\u00e1l es su postura mientras el partido comienza a definir qu\u00e9 busca en su pr\u00f3ximo candidato.<\/p>\n<p>Calific\u00f3 al presidente como \u201cel principal charlat\u00e1n de feria\u201d y a los republicanos que lo apoyan en el Congreso y en la Casa Blanca como \u201cestafadores corruptos y ego\u00edstas, promotores de la intolerancia y el odio\u201d.<\/p>\n<p>\u201cTodo lo que nos importa est\u00e1 bajo asedio por parte de Washington\u201d, se\u00f1al\u00f3 Pritzker.<\/p>\n<p>Si Stratton gana en noviembre \u2014y en Illinois, un estado tradicionalmente dem\u00f3crata, es la gran favorita frente al candidato republicano, el expresidente del Partido Republicano de Illinois, Don Tracy\u2014 aportar\u00eda una energ\u00eda m\u00e1s progresista al Senado, justo cuando los dem\u00f3cratas se enfrentan a lo que podr\u00eda ser un cambio de guardia.<\/p>\n<p>Durbin, de 81 a\u00f1os, es el segundo dem\u00f3crata de mayor rango en el Senado. Stratton, de 60 a\u00f1os, ha declarado que <a href=\"https:\/\/www.facebook.com\/reel\/1449178323225179\/\">no apoyar\u00e1<\/a> al l\u00edder de la minor\u00eda en el Senado, Chuck Schumer, como l\u00edder del grupo parlamentario dem\u00f3crata.<\/p>\n<p>En un discurso pronunciado el martes para celebrar su victoria, Stratton prometi\u00f3 abordar una serie de objetivos pol\u00edticos progresistas, y prometi\u00f3 a sus seguidores que \u201clucharemos por la atenci\u00f3n m\u00e9dica universal, lucharemos para abolir ICE, lucharemos por un salario digno\u201d y \u201clucharemos para defender nuestros derechos y rescatar nuestra democracia del borde del abismo\u201d.<\/p>\n<p>La candidata indic\u00f3 que \u201cel coraje llevar\u00e1 esta lucha directamente a la puerta de Donald Trump\u201d.<\/p>\n<p>Si Stratton resulta elegida este oto\u00f1o, se convertir\u00eda en la sexta mujer negra en ocupar un esca\u00f1o en el Senado.<\/p>\n<p>Dos exmiembros dem\u00f3cratas del Congreso intentaron regresar a la pol\u00edtica el martes. Solo uno lo logr\u00f3.<\/p>\n<p>La exdiputada Melissa Bean, una dem\u00f3crata moderada que fue arrasada por la ola del Tea Party en las elecciones de mitad de mandato de 2010, gan\u00f3 las primarias para el esca\u00f1o del octavo distrito que Krishnamoorthi deja vacante.<\/p>\n<p>Bean derrot\u00f3 al empresario tecnol\u00f3gico Junaid Ahmed, un progresista respaldado por los senadores Bernie Sanders, Elizabeth Warren y los Justice Democrats.<\/p>\n<p>Sin embargo, en el segundo distrito, el intento del exrepresentante Jesse Jackson Jr. de recuperar su antiguo esca\u00f1o semanas despu\u00e9s de <a href=\"https:\/\/www.cnn.com\/2026\/02\/17\/us\/reverend-jesse-jackson-death\">la muerte de su padre<\/a> fracas\u00f3.<\/p>\n<p>Jackson pas\u00f3 m\u00e1s de un a\u00f1o en prisi\u00f3n entre 2014 y 2015 tras declararse culpable de cargos federales derivados del uso de fondos de campa\u00f1a para compras personales.<\/p>\n<p>El martes fue derrotado por Donna Miller, comisionada del condado de Cook, quien cont\u00f3 con el respaldo de millones de d\u00f3lares en gastos de un super PAC vinculado a AIPAC.<\/p>\n<p>Las primarias de Illinois estuvieron plagadas de gastos externos, con grupos vinculados a la organizaci\u00f3n de presi\u00f3n proisrael\u00ed American Israel Public Affairs Committee que invirtieron millones en las contiendas dem\u00f3cratas.<\/p>\n<p>Los aliados de AIPAC respaldaron a Bean y Miller, dos ganadores de las primarias para la C\u00e1mara de Representantes. Sin embargo, se opusieron a Stratton y al representante estatal La Shawn Ford, quien gan\u00f3 las primarias para el esca\u00f1o del s\u00e9ptimo Distrito en la C\u00e1mara.<\/p>\n<p>Ford derrot\u00f3 a la tesorera municipal Melissa Conyears-Ervin, quien contaba con el respaldo de millones de d\u00f3lares en gastos vinculados a AIPAC, y a otros 11 candidatos en la contienda para reemplazar al representante saliente Danny Davis.<\/p>\n<p>En la contienda por el noveno distrito, el alcalde de Evanston, Daniel Biss, un candidato al que <a href=\"https:\/\/www.cnn.com\/2026\/03\/15\/politics\/democrats-primaries-aipac-israel\">se opon\u00edan grupos afines a AIPAC,<\/a> result\u00f3 ganador. Sin embargo, lo logr\u00f3 derrotando <a href=\"https:\/\/www.cnn.com\/2026\/03\/14\/politics\/kat-abughazaleh-illinois-primary\">a Kat Abughazaleh<\/a>, una palestina-estadounidense de 26 a\u00f1os y ferviente cr\u00edtica de Israel, que aspiraba a convertirse en la primera mujer de la Generaci\u00f3n Z en el Congreso.<\/p>\n<p>El super PAC pro-criptomonedas Fairshake obtuvo poco a cambio de los millones que gast\u00f3 en las primarias de Illinois. Dos candidatos a los que se opuso, Stratton y Ford, resultaron ganadores.<\/p>\n<p>La senadora de Massachusetts, Elizabeth Warren, una destacada cr\u00edtica de las criptomonedas, arremeti\u00f3 contra el gasto del grupo en un mitin junto a Stratton la semana pasada.<\/p>\n<p>Los resultados sugieren que podr\u00eda haber habido cierta reacci\u00f3n negativa contra los gastos de decenas de millones de d\u00f3lares de los super PAC.<\/p>\n<p>Brian Henn, residente de Chicago, declar\u00f3 el martes mientras votaba que los anuncios de campa\u00f1a eran \u201clos \u00fanicos anuncios que he visto en la televisi\u00f3n en el \u00faltimo mes. Es una locura\u201d.<\/p>\n<p>Jennifer Parks, de 54 a\u00f1os, vot\u00f3 por Stratton en un centro de votaci\u00f3n en el centro de Chicago. Declar\u00f3 que apoyaba a la vicegobernadora \u201cporque realmente est\u00e1 tratando de cambiar las cosas y oponerse a Citizens United, y necesitamos eliminar m\u00e1s dinero de las corporaciones de las elecciones\u201d.<\/p>\n<p>\u201cRealmente necesitamos encontrar maneras de contrarrestar esta tendencia y lograr que el dinero de los individuos se destine a las campa\u00f1as electorales, o retirar el dinero de las elecciones para que la gente pueda postularse y la voz individual sea la que prevalezca, y no la voz corporativa\u201d, se\u00f1al\u00f3.<\/p>\n<p>La participaci\u00f3n en las primarias dem\u00f3cratas de Illinois fue alta, con m\u00e1s de 1,1 millones de votos escrutados en las disputas para el Senado hasta la noche del martes.<\/p>\n<p>Pero no igualar\u00e1 lo ocurrido en 2018, la \u00faltima vez que el estado tuvo unas primarias dem\u00f3cratas competitivas a nivel estatal en un a\u00f1o de elecciones de mitad de mandato. En aquella ocasi\u00f3n, Pritzker derrot\u00f3 a Biss, entonces senador estatal, y a Chris Kennedy, miembro de la famosa familia dem\u00f3crata.<\/p>\n<p>Cuando se termine el recuento, es probable que se hayan emitido casi tantos votos este a\u00f1o como en 2002, cuando Rod Blagojevich gan\u00f3 unas re\u00f1idas primarias dem\u00f3cratas camino a su primer mandato como gobernador.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al nominar este martes a la vicegobernadora Juliana Stratton para el Senado, los dem\u00f3cratas de Illinois eligieron a una candidata cuyo mensaje inclu\u00eda un anuncio de televisi\u00f3n en el que aparec\u00edan personas diciendo \u201cque se jo** Trump\u201d. Stratton fue seleccionada por encima de un rival m\u00e1s moderado y con mayor financiaci\u00f3n, el representante Raja Krishnamoorthi, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472301","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conclusiones de las elecciones primarias de Illinois - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones de las elecciones primarias de Illinois - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al nominar este martes a la vicegobernadora Juliana Stratton para el Senado, los dem\u00f3cratas de Illinois eligieron a una candidata cuyo mensaje inclu\u00eda un anuncio de televisi\u00f3n en el que aparec\u00edan personas diciendo \u201cque se jo** Trump\u201d. Stratton fue seleccionada por encima de un rival m\u00e1s moderado y con mayor financiaci\u00f3n, el representante Raja Krishnamoorthi, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T08:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conclusiones de las elecciones primarias de Illinois\",\"datePublished\":\"2026-03-18T08:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\"},\"wordCount\":1365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\",\"name\":\"Conclusiones de las elecciones primarias de Illinois - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-18T08:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones de las elecciones primarias de Illinois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusiones de las elecciones primarias de Illinois - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones de las elecciones primarias de Illinois - Noticias","og_description":"Al nominar este martes a la vicegobernadora Juliana Stratton para el Senado, los dem\u00f3cratas de Illinois eligieron a una candidata cuyo mensaje inclu\u00eda un anuncio de televisi\u00f3n en el que aparec\u00edan personas diciendo \u201cque se jo** Trump\u201d. Stratton fue seleccionada por encima de un rival m\u00e1s moderado y con mayor financiaci\u00f3n, el representante Raja Krishnamoorthi, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-18T08:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/"},"author":{"name":"","@id":""},"headline":"Conclusiones de las elecciones primarias de Illinois","datePublished":"2026-03-18T08:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/"},"wordCount":1365,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","name":"Conclusiones de las elecciones primarias de Illinois - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-18T08:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conclusiones de las elecciones primarias de Illinois"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conclusiones de las elecciones primarias de Illinois","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/conclusiones-elecciones-primarias-illinois-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-18T08:03:51Z","datePublished":"2026-03-18T08:03:51Z","dateModified":"2026-03-18T08:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conclusiones de las elecciones primarias de Illinois\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/conclusiones-elecciones-primarias-illinois-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/conclusiones-elecciones-primarias-illinois-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-18T08:03:51Z\",\"datePublished\":\"2026-03-18T08:03:51Z\",\"dateModified\":\"2026-03-18T08:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470852,"url":"https:\/\/noticiasya.com\/tampa\/2026\/02\/04\/contiendas-elecciones-intermedias-senado-trax\/","url_meta":{"origin":1472301,"position":0},"title":"Las 10 contiendas electorales que decidir\u00e1n el control del Senado de EE.UU.","author":"","date":"febrero 4, 2026","format":false,"excerpt":"En la lucha por el control del Senado de Estados Unidos, la mayor\u00eda podr\u00eda depender de qu\u00e9 factor tenga m\u00e1s peso: el mapa o el entorno.Comencemos con el mapa y las matem\u00e1ticas. Los republicanos actualmente tienen 53 esca\u00f1os en la c\u00e1mara, en comparaci\u00f3n con los 47 de los dem\u00f3cratas, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471856,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/04\/james-talarico-gana-primarias-democratas-texas-trax\/","url_meta":{"origin":1472301,"position":1},"title":"James Talarico vence a Jasmine Crockett y gana las primarias dem\u00f3cratas en la contienda por el Senado de Texas","author":"","date":"marzo 4, 2026","format":false,"excerpt":"El representante estatal James Talarico gan\u00f3 las primarias dem\u00f3cratas para el Senado de Estados Unidos en Texas, lo que coloca a un legislador estatal, antes poco conocido, en la cima de la lista del partido para las elecciones generales de noviembre.Talarico, de 36 a\u00f1os, venci\u00f3 a la representante Jasmine Crockett,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471794,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/02\/primarias-texas-preguntas-trax\/","url_meta":{"origin":1472301,"position":2},"title":"Primarias en EE.UU.: qu\u00e9 se vota, por qu\u00e9 las de Texas son cruciales y las 8 grandes preguntas","author":"","date":"marzo 2, 2026","format":false,"excerpt":"Las elecciones de 2026 en EE.UU. arrancan este martes con fuerza, mientras los votantes acuden a las urnas para las primeras primarias estatales en Arkansas, Carolina del Norte y Texas.La gran apuesta es la carrera al Senado de Estados Unidos en Texas, pero hay mucho m\u00e1s que los analistas pol\u00edticos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471853,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/04\/analisis-conclusiones-primarias-ee-uu-texas-carolina-norte-trax\/","url_meta":{"origin":1472301,"position":3},"title":"Conclusiones del proceso de primarias electorales en EE.UU. en Texas y Carolina del Norte","author":"","date":"marzo 4, 2026","format":false,"excerpt":"Los votantes de tres estados de EE.UU. acudieron a las urnas este martes para el primer d\u00eda de primarias camino a las elecciones intermedias de 2026, y la gran noticia fueron un par de primarias para el Senado de Texas que parecen indicar un camino bastante favorable para las esperanzas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446520,"url":"https:\/\/noticiasya.com\/tampa\/2024\/03\/05\/a-que-estar-atento-este-supermartes-trax\/","url_meta":{"origin":1472301,"position":4},"title":"A qu\u00e9 estar atentos este supermartes","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- El comienzo del fin de las primarias presidenciales de 2024 comienza este martes, cuando se espera que el presidente Joe Biden y el expresidente Donald Trump consigan una revancha de su contienda de 2020, ocho meses antes de las elecciones generales de noviembre.Habr\u00e1 contiendas en 16 estados el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467415,"url":"https:\/\/noticiasya.com\/tampa\/2025\/10\/15\/democrata-gina-hinojosa-gobernadora-texas-trax\/","url_meta":{"origin":1472301,"position":5},"title":"La dem\u00f3crata Gina Hinojosa lanza campa\u00f1a para gobernadora en Texas","author":"","date":"octubre 15, 2025","format":false,"excerpt":"La representante estatal de Texas, Gina Hinojosa, dem\u00f3crata y originaria del sur de dicho estado, est\u00e1 lanzando su candidatura para gobernadora de Texas y se presenta a las concurridas primarias dem\u00f3cratas para desafiar al gobernador republicano Greg Abbott en 2026.\u201cNuestra lucha en este momento es contra los multimillonarios y las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472301"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472301\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}