{"id":1472308,"date":"2026-03-18T06:03:51","date_gmt":"2026-03-18T13:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/"},"modified":"2026-03-18T06:03:51","modified_gmt":"2026-03-18T13:03:51","slug":"gasolina-precio-mas-alto-septiembre-2023-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","title":{"rendered":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023"},"content":{"rendered":"<p>El precio del gal\u00f3n (3,78 litros) de gasolina regular subi\u00f3 otros 5 centavos en promedio en Estados Unidos este mi\u00e9rcoles: ahora se sit\u00faa en US$ 3,84, la cifra m\u00e1s alta desde el 25 de septiembre de 2023.<\/p>\n<p>Actualmente, el precio promedio de la gasolina es de US$ 4 o m\u00e1s en siete estados, y ha superado los US$ 5 por gal\u00f3n en California, Hawai y Washington.<\/p>\n<p>El precio promedio a nivel nacional ha aumentado 86 centavos en tan solo 18 d\u00edas \u2014un salto del 29 %\u2014, lo que constituye uno de los repuntes m\u00e1s r\u00e1pidos en los precios de la gasolina de los que se tiene registro. Este r\u00e1pido incremento es comparable, en t\u00e9rminos porcentuales, con el impacto en los precios de la gasolina provocado por el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/03\/eeuu\/precios-gasolin-ee-uu-mayor-aumento-un-dia-trax\">hurac\u00e1n Katrina<\/a>, cuando la tormenta azot\u00f3 la costa del golfo en el verano de 2005, paralizando las operaciones de refinaci\u00f3n de petr\u00f3leo de Estados Unidos.<\/p>\n<p>El vertiginoso aumento de los precios del combustible podr\u00eda repercutir negativamente en la accesibilidad, el gasto de los consumidores y la econom\u00eda en general. En caso de que los precios se mantuvieran aproximadamente en este nivel durante todo el a\u00f1o, esto a\u00f1adir\u00eda un total de US$ 100.000 millones en costos adicionales acumulados a la econom\u00eda, afirm\u00f3 Gus Faucher, economista jefe de The PNC Financial Services Group.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El precio del gal\u00f3n (3,78 litros) de gasolina regular subi\u00f3 otros 5 centavos en promedio en Estados Unidos este mi\u00e9rcoles: ahora se sit\u00faa en US$ 3,84, la cifra m\u00e1s alta desde el 25 de septiembre de 2023. Actualmente, el precio promedio de la gasolina es de US$ 4 o m\u00e1s en siete estados, y ha [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472308","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias\" \/>\n<meta property=\"og:description\" content=\"El precio del gal\u00f3n (3,78 litros) de gasolina regular subi\u00f3 otros 5 centavos en promedio en Estados Unidos este mi\u00e9rcoles: ahora se sit\u00faa en US$ 3,84, la cifra m\u00e1s alta desde el 25 de septiembre de 2023. Actualmente, el precio promedio de la gasolina es de US$ 4 o m\u00e1s en siete estados, y ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T13:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023\",\"datePublished\":\"2026-03-18T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\",\"name\":\"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-18T13:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias","og_description":"El precio del gal\u00f3n (3,78 litros) de gasolina regular subi\u00f3 otros 5 centavos en promedio en Estados Unidos este mi\u00e9rcoles: ahora se sit\u00faa en US$ 3,84, la cifra m\u00e1s alta desde el 25 de septiembre de 2023. Actualmente, el precio promedio de la gasolina es de US$ 4 o m\u00e1s en siete estados, y ha [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-18T13:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/"},"author":{"name":"","@id":""},"headline":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023","datePublished":"2026-03-18T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","name":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-18T13:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\u00f3n, el nivel m\u00e1s alto desde septiembre de 2023","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/gasolina-precio-mas-alto-septiembre-2023-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-18T13:03:51Z","datePublished":"2026-03-18T13:03:51Z","dateModified":"2026-03-18T13:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El precio de la gasolina en EE.UU. alcanza los US$ 3,84 por gal\\u00f3n, el nivel m\\u00e1s alto desde septiembre de 2023\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/gasolina-precio-mas-alto-septiembre-2023-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/gasolina-precio-mas-alto-septiembre-2023-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-18T13:03:51Z\",\"datePublished\":\"2026-03-18T13:03:51Z\",\"dateModified\":\"2026-03-18T13:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1423695,"url":"https:\/\/noticiasya.com\/tampa\/2022\/09\/01\/circulo-k-ofrece-gasolina-40%c2%a2-menos-por-galon-solo-este-1-de-septiembre-horarios-aplican\/","url_meta":{"origin":1472308,"position":0},"title":"C\u00edrculo K ofrece gasolina 40\u00a2 menos por gal\u00f3n \u00a1solo este 1 de septiembre!; horarios aplican","author":"agomez","date":"septiembre 1, 2022","format":false,"excerpt":"Esta es la oferta anunciada:\u00a0","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/tampa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468877,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/02\/precio-gasolina-eeuu-3-dolares-galon-trax\/","url_meta":{"origin":1472308,"position":1},"title":"El precio de la gasolina en EE.UU. cae por debajo de los US$ 3 el gal\u00f3n por primera vez desde mayo de 2021","author":"agomez","date":"diciembre 2, 2025","format":false,"excerpt":"El precio de la gasolina en Estados Unidos cay\u00f3 este martes por debajo de un promedio de US$ 3 por gal\u00f3n por primera vez en cuatro a\u00f1os y medio.Este hito representa una inusual noticia positiva en medio de una crisis de asequibilidad que se ha prolongado durante a\u00f1os, y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472095,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/11\/cuando-precios-gasolina-trax\/","url_meta":{"origin":1472308,"position":2},"title":"\u00bfCu\u00e1ndo empezar\u00e1n a bajar los precios en las gasolineras de EE.UU.?","author":"","date":"marzo 11, 2026","format":false,"excerpt":"Los precios mundiales del petr\u00f3leo han ca\u00eddo muy por debajo de su m\u00e1ximo reciente. Pero no esperes un alivio en las gasolineras de EE.UU. en los pr\u00f3ximos d\u00edas.La guerra en Ir\u00e1n pr\u00e1cticamente cerr\u00f3 el estrecho de Ormuz, cortando el suministro de aproximadamente una quinta parte del petr\u00f3leo mundial. Sin embargo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1420195,"url":"https:\/\/noticiasya.com\/tampa\/2022\/08\/16\/foto-asi-amanecio-el-precio-de-la-gasolina-este-martes-en-el-paso\/","url_meta":{"origin":1472308,"position":3},"title":"FOTO: As\u00ed amaneci\u00f3 el precio de la gasolina este martes en El Paso","author":"agomez","date":"agosto 16, 2022","format":false,"excerpt":"En algunos lugares se lleg\u00f3 a registrar en 3.59 d\u00f3lares por gal\u00f3n.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/tampa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472756,"url":"https:\/\/noticiasya.com\/tampa\/2026\/04\/01\/aumento-precio-gasolina-guerra-trax\/","url_meta":{"origin":1472308,"position":4},"title":"El precio de la gasolina en EE.UU. sube 5 centavos, hasta los US$ 4,06 por gal\u00f3n","author":"agomez","date":"abril 1, 2026","format":false,"excerpt":"El precio promedio del gal\u00f3n (3,78 litros) de gasolina regular en EE.UU. aument\u00f3 casi 5 centavos, hasta los US$ 4,06, seg\u00fan la \u00faltima lectura de la AAA. Este es el mayor aumento diario en los precios de la gasolina en m\u00e1s de dos semanas.El alza se produjo un d\u00eda despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468682,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/25\/descuento-trump-precio-gasolina-ha-desaparecido-trax\/","url_meta":{"origin":1472308,"position":5},"title":"El descuento de Trump al precio de la gasolina ha desaparecido","author":"","date":"noviembre 25, 2025","format":false,"excerpt":"El presidente Donald Trump y su equipo econ\u00f3mico suelen responder a las preocupaciones sobre la crisis de asequibilidad pregonando cu\u00e1nto m\u00e1s barata es la gasolina en comparaci\u00f3n con lo que costaba cuando gobernaba su predecesor.Durante la mayor parte de 2025, esto fue un motivo leg\u00edtimo de orgullo para la Casa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472308"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472308\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}