{"id":1472312,"date":"2026-03-18T08:03:42","date_gmt":"2026-03-18T15:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/"},"modified":"2026-03-18T08:03:42","modified_gmt":"2026-03-18T15:03:42","slug":"iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","title":{"rendered":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia"},"content":{"rendered":"<p>El r\u00e9gimen iran\u00ed ejecut\u00f3 este mi\u00e9rcoles a un ciudadano sueco al que acusaba de espionaje, seg\u00fan inform\u00f3 el ministro de Asuntos Exteriores de Suecia en un <a href=\"https:\/\/www.regeringen.se\/uttalanden\/2026\/03\/uttalande-av-utrikesminister-maria-malmer-stenergard-med-anledning-av-avrattning-av-svensk-medborgare-i-iran\/\">comunicado<\/a>.<\/p>\n<p>\u201cNos resulta evidente que el proceso legal que condujo a la ejecuci\u00f3n del ciudadano sueco no ha sido jur\u00eddicamente s\u00f3lido\u201d, declar\u00f3 la ministra de Asuntos Exteriores de Suecia, Maria Malmer Stenergard. \u201cSuecia seguir\u00e1 condenando las graves violaciones de los derechos humanos en Ir\u00e1n\u201d.<\/p>\n<p>Suecia no mencion\u00f3 el nombre del ciudadano en el comunicado. Sin embargo, los medios estatales iran\u00edes lo identificaron como Kourosh Keyvani, quien fue arrestado el a\u00f1o pasado y acusado de <strong>\u201c<\/strong> cooperaci\u00f3n de inteligencia y espionaje a favor del Gobierno israel\u00ed\u201d.<\/p>\n<p>\u201cSuecia ha planteado el caso repetidamente a distintos niveles con representantes iran\u00edes desde la detenci\u00f3n en junio de 2025. En estos contactos, hemos recalcado la expectativa de Suecia de que nuestro ciudadano reciba un juicio justo y no sea condenado a la pena de muerte\u201d, declar\u00f3 Stenergard en el comunicado.<\/p>\n<p>Keyvani ten\u00eda doble nacionalidad sueca e iran\u00ed. Es el tercer hombre que Ir\u00e1n ejecutar\u00e1 por espionaje en 2026. Al menos 13 personas fueron ejecutadas por cargos similares el a\u00f1o pasado, seg\u00fan el grupo de monitoreo <a href=\"https:\/\/iranhr.net\/en\/articles\/8655\/\">Iran Human Rights,<\/a> con sede en Noruega.<\/p>\n<p>Cientos de iran\u00edes permanecen en el corredor de la muerte, entre ellos muchos considerados presos pol\u00edticos. Muchos a\u00fan no han sido sentenciados y podr\u00edan enfrentarse a la pena capital.<\/p>\n<p>\u201cLa pena de muerte es un castigo inhumano, cruel e irreversible. Suecia, junto con el resto de la UE, condena su aplicaci\u00f3n bajo cualquier circunstancia\u201d, a\u00f1adi\u00f3 el ministro de Asuntos Exteriores sueco.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El r\u00e9gimen iran\u00ed ejecut\u00f3 este mi\u00e9rcoles a un ciudadano sueco al que acusaba de espionaje, seg\u00fan inform\u00f3 el ministro de Asuntos Exteriores de Suecia en un comunicado. \u201cNos resulta evidente que el proceso legal que condujo a la ejecuci\u00f3n del ciudadano sueco no ha sido jur\u00eddicamente s\u00f3lido\u201d, declar\u00f3 la ministra de Asuntos Exteriores de Suecia, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472312","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias\" \/>\n<meta property=\"og:description\" content=\"El r\u00e9gimen iran\u00ed ejecut\u00f3 este mi\u00e9rcoles a un ciudadano sueco al que acusaba de espionaje, seg\u00fan inform\u00f3 el ministro de Asuntos Exteriores de Suecia en un comunicado. \u201cNos resulta evidente que el proceso legal que condujo a la ejecuci\u00f3n del ciudadano sueco no ha sido jur\u00eddicamente s\u00f3lido\u201d, declar\u00f3 la ministra de Asuntos Exteriores de Suecia, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T15:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia\",\"datePublished\":\"2026-03-18T15:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\",\"name\":\"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-18T15:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias","og_description":"El r\u00e9gimen iran\u00ed ejecut\u00f3 este mi\u00e9rcoles a un ciudadano sueco al que acusaba de espionaje, seg\u00fan inform\u00f3 el ministro de Asuntos Exteriores de Suecia en un comunicado. \u201cNos resulta evidente que el proceso legal que condujo a la ejecuci\u00f3n del ciudadano sueco no ha sido jur\u00eddicamente s\u00f3lido\u201d, declar\u00f3 la ministra de Asuntos Exteriores de Suecia, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-18T15:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/"},"author":{"name":"","@id":""},"headline":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia","datePublished":"2026-03-18T15:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","name":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-18T15:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ir\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\u00fan el ministro de Asuntos Exteriores de Suecia","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/18\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-18T15:03:42Z","datePublished":"2026-03-18T15:03:42Z","dateModified":"2026-03-18T15:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ir\\u00e1n ejecuta a un ciudadano sueco por presunto espionaje, seg\\u00fan el ministro de Asuntos Exteriores de Suecia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/18\\\/iran-ejecuta-ciudadano-sueco-presunto-espionaje-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-18T15:03:42Z\",\"datePublished\":\"2026-03-18T15:03:42Z\",\"dateModified\":\"2026-03-18T15:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444366,"url":"https:\/\/noticiasya.com\/tampa\/2024\/01\/24\/el-parlamento-de-turquia-aprueba-el-ingreso-de-suecia-a-la-otan\/","url_meta":{"origin":1472312,"position":0},"title":"El Parlamento de Turqu\u00eda aprueba el ingreso de Suecia a la OTAN","author":"","date":"enero 24, 2024","format":false,"excerpt":"(CNN) -- El Parlamento de Turqu\u00eda vot\u00f3 el martes a favor del ingreso de Suecia en la OTAN, con lo que el pa\u00eds n\u00f3rdico da un paso m\u00e1s hacia su adhesi\u00f3n a la alianza militar tras meses de retrasos.De los 346 diputados que votaron, 287 se pronunciaron a favor de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455906,"url":"https:\/\/noticiasya.com\/tampa\/2024\/11\/18\/cables-submarinos-internet-mar-baltico-advertencias-posible-guerra-hibrida-rusia-trax\/","url_meta":{"origin":1472312,"position":1},"title":"Interrumpen dos cables submarinos de internet en el mar B\u00e1ltico, lo que genera advertencias de una posible &#171;guerra h\u00edbrida&#187;","author":"","date":"noviembre 18, 2024","format":false,"excerpt":"(CNN) \u2014 Se interrumpieron repentinamente dos cables submarinos de internet en el mar B\u00e1ltico, seg\u00fan empresas de telecomunicaciones locales, en medio de nuevas advertencias sobre la posible interferencia rusa con la infraestructura submarina global.Un cable de comunicaciones entre Lituania y Suecia fue cortado el domingo por la ma\u00f1ana alrededor de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444508,"url":"https:\/\/noticiasya.com\/tampa\/2024\/01\/27\/el-gobierno-de-biden-comunica-al-congreso-su-intencion-de-vender-f-16-a-turquia-despues-de-que-erdogan-aprobara-el-ingreso-de-suecia-en-la-otan\/","url_meta":{"origin":1472312,"position":2},"title":"El Gobierno de Biden comunica al Congreso su intenci\u00f3n de vender F-16 a Turqu\u00eda despu\u00e9s de que Erdogan aprobara el ingreso de Suecia en la OTAN","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN) -- El Gobierno de Biden comunic\u00f3 al Congreso su intenci\u00f3n de vender aviones de combate F-16 a Turqu\u00eda despu\u00e9s de que el presidente Recep Tayyip Erdogan firmara el jueves la adhesi\u00f3n de Suecia a la OTAN, un hecho que pone fin a m\u00e1s de un a\u00f1o de negociaciones silenciosas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458428,"url":"https:\/\/noticiasya.com\/tampa\/2025\/02\/07\/suecia-endurecera-leyes-armas-tiroteo-masivo-escuela-reux\/","url_meta":{"origin":1472312,"position":3},"title":"Suecia endurecer\u00e1 sus leyes sobre armas tras tiroteo masivo en escuela para adultos","author":"","date":"febrero 7, 2025","format":false,"excerpt":"El Gobierno derechista de Suecia dijo este viernes que buscar\u00e1 endurecer las leyes sobre armas tras el tiroteo masivo m\u00e1s mort\u00edfero del pa\u00eds en un centro de educaci\u00f3n para adultos, donde el atacante parece haber utilizado varios de sus propios rifles con licencia.Diez personas murieron por disparos en la escuela\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472403,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/teheran-envia-advertencia-ejecucion-hombres-protestas-analisis-trax\/","url_meta":{"origin":1472312,"position":4},"title":"Teher\u00e1n env\u00eda una clara advertencia con la ejecuci\u00f3n de hombres vinculados a las protestas, dicen analistas","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Cuando un luchador de 19 a\u00f1os y otros dos hombres fueron ahorcados en la ciudad santa de Qom el jueves, el r\u00e9gimen teocr\u00e1tico de Ir\u00e1n envi\u00f3 un mensaje tanto a los disidentes dentro del pa\u00eds como a los opositores en el extranjero, afirman analistas.Los tres hombres, todos ellos vinculados a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457221,"url":"https:\/\/noticiasya.com\/tampa\/2025\/01\/04\/suecia-reduccion-poblacion-lobos-trax\/","url_meta":{"origin":1472312,"position":5},"title":"Suecia permite que casi el 10% de la poblaci\u00f3n de lobos sea eliminada, pero el Gobierno quiere una reducci\u00f3n a\u00fan m\u00e1s dr\u00e1stica","author":"","date":"enero 4, 2025","format":false,"excerpt":"Suecia comenz\u00f3 su caza anual de lobos esta semana, permitiendo que casi el 10% de la poblaci\u00f3n de esta especie en peligro sea eliminada, mientras los conservacionistas expresan preocupaciones sobre la controvertida pol\u00edtica.Desde 2010, Suecia ha permitido la caza de lobos bajo un sistema de cuotas con licencia. Los conservacionistas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472312"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472312\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}