{"id":1472334,"date":"2026-03-19T04:03:47","date_gmt":"2026-03-19T11:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/"},"modified":"2026-03-19T04:03:47","modified_gmt":"2026-03-19T11:03:47","slug":"archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","title":{"rendered":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s"},"content":{"rendered":"<p>Una ley de transparencia aprobada por el Congreso ha obligado a publicar m\u00e1s <a href=\"https:\/\/www.cnn.com\/politics\/epstein-files\">archivos de Epstein<\/a> que nunca, pero algunos legisladores y v\u00edctimas est\u00e1n explorando formas de presionar al Departamento de Justicia para que revele a\u00fan m\u00e1s informaci\u00f3n del voluminoso material que se mantiene oculto.<\/p>\n<p>Unos 2,5 millones de documentos de los archivos de investigaci\u00f3n del Departamento de Justicia sobre el fallecido delincuente sexual convicto Jeffrey Epstein no se han hecho p\u00fablicos, y muchas de las 3,5 millones de p\u00e1ginas que s\u00ed se han publicado est\u00e1n fuertemente tachadas, lo que suscita interrogantes sobre qu\u00e9 informaci\u00f3n se est\u00e1 ocultando al p\u00fablico.<\/p>\n<p>En el Capitolio, los legisladores est\u00e1n estudiando una nueva ley y a\u00fan desean interrogar bajo juramento a la secretaria de Justicia Pam Bondi sobre su gesti\u00f3n de los archivos de Epstein, lo que podr\u00eda revelar informaci\u00f3n oculta.<\/p>\n<p>Bondi se reuni\u00f3 voluntariamente con miembros de la Comisi\u00f3n a puerta cerrada el mi\u00e9rcoles, pero la reuni\u00f3n se torn\u00f3 tensa cuando los dem\u00f3cratas abandonaron la sala visiblemente frustrados, alegando que Bondi se negaba a cumplir con la citaci\u00f3n judicial.<\/p>\n<p>La presi\u00f3n para que Bondi testifique surge en medio de la frustraci\u00f3n y la insatisfacci\u00f3n con la forma en que la administraci\u00f3n ha cumplido con la Ley de Transparencia de los Archivos Epstein, y con las limitaciones de la propia ley.<\/p>\n<p>Los representantes Thomas Massie, republicano de Kentucky, y Ro Khanna, dem\u00f3crata de California \u2014el d\u00fao que lider\u00f3 el impulso bipartidista para aprobar la legislaci\u00f3n en el Congreso a finales del a\u00f1o pasado\u2014 est\u00e1n sopesando si unirse a las v\u00edctimas de los abusos de Epstein para demandar y obtener acceso a m\u00e1s archivos.<\/p>\n<p>Massie y Khanna reconocieron a CNN en una entrevista reciente que el hecho de no incluir un mecanismo de aplicaci\u00f3n en el texto ha creado algunas limitaciones a la ley.<\/p>\n<p>\u201cSi hubiera salido que la secretaria de Justicia va a infringir la ley y que habr\u00eda que llevarla ante un tribunal para que se juzgara una ley claramente redactada, lo habr\u00eda hecho\u201d, declar\u00f3 Massie cuando se le pregunt\u00f3 por qu\u00e9 no incluyeron una secci\u00f3n en el proyecto de ley que describiera lo que se denomina una \u201ccausa de acci\u00f3n\u201d, es decir, una gu\u00eda legal sobre c\u00f3mo alguien o el propio Congreso podr\u00edan acudir a los tribunales para poner a prueba el cumplimiento del Departamento de Justicia con la ley de transparencia.<\/p>\n<p>Pero siguen argumentando que la presi\u00f3n p\u00fablica ha sido su mejor herramienta.<\/p>\n<p>El Departamento de Justicia ha accedido repetidamente a corregir errores de censura, incluida la <a href=\"https:\/\/www.cnn.com\/2026\/02\/05\/politics\/justice-department-under-scrutiny-for-revealing-victim-info-and-concealing-possible-enablers-in-epstein-files\">divulgaci\u00f3n indebida de los nombres de las v\u00edctimas<\/a>, al tiempo que insiste en que los funcionarios no ocultan nada.<\/p>\n<p>Actualmente no existe ning\u00fan mecanismo legal que permita a un juez obligar al departamento a eliminar las partes censuradas o a publicar m\u00e1s documentos.<\/p>\n<p>Un alto funcionario del Departamento de Justicia declar\u00f3 recientemente a los periodistas que esperan dar por concluida la investigaci\u00f3n sobre Epstein y que no se prev\u00e9n cargos adicionales a menos que surja nueva informaci\u00f3n.<\/p>\n<p>\u201cNos han criticado duramente los abogados, el Congreso y el p\u00fablico por cometer errores\u201d, indic\u00f3 el funcionario, argumentando que algunas de las cr\u00edticas han sido injustas dado a que los abogados trabajaron largas jornadas bajo presi\u00f3n, y algunos revisaron m\u00e1s de 1.000 documentos por semana.<\/p>\n<p>\u201cSiempre hay much\u00edsimos errores en la revisi\u00f3n de documentos\u201d, a\u00f1adi\u00f3 el funcionario, y se\u00f1al\u00f3 que el departamento implement\u00f3 nuevos procedimientos tan pronto como se dieron cuenta de que hab\u00eda problemas con la publicaci\u00f3n.<\/p>\n<p>Seg\u00fan la ley, el Departamento de Justicia estaba autorizado a retener o censurar ciertos documentos, como informaci\u00f3n clasificada y representaciones de abuso sexual infantil.<\/p>\n<p>El subsecretario de Justicia, Todd Blanche, declar\u00f3 ante el Congreso que el departamento fue m\u00e1s all\u00e1, ocultando tambi\u00e9n algunas deliberaciones internas, comunicaciones entre abogados y clientes y actas de juicios del jurado investigador.<\/p>\n<p>Seg\u00fan Blanche, el departamento tambi\u00e9n retuvo archivos de Epstein que estaban escritos en idiomas extranjeros, y algunos registros no pudieron subirse a la base de datos p\u00fablica debido a problemas t\u00e9cnicos.<\/p>\n<p>La citaci\u00f3n judicial de Bondi es el \u00faltimo quebradero de cabeza para el Departamento de Justicia y un ejemplo de c\u00f3mo el Congreso puede seguir ejerciendo presi\u00f3n incluso sin nuevas leyes ni litigios.<\/p>\n<p>A principios de este mes, la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, liderada por los republicanos, vot\u00f3 de forma bipartidista a favor de citar a Bondi como parte de su investigaci\u00f3n sobre Epstein, quien falleci\u00f3 en prisi\u00f3n en 2019.<\/p>\n<p>La presi\u00f3n sobre Bondi se centra especialmente en la gesti\u00f3n del departamento respecto a la publicaci\u00f3n de los archivos, un aspecto secundario de la investigaci\u00f3n de la C\u00e1mara sobre Epstein.<\/p>\n<p>Como parte de esa investigaci\u00f3n en curso, los legisladores y sus equipos han hablado con figuras destacadas que aparecen en los archivos, como el expresidente Bill Clinton, y con otros que formaban parte del c\u00edrculo \u00edntimo de Epstein, incluida su c\u00f3mplice Ghislaine Maxwell.<\/p>\n<p>Bondi recibi\u00f3 la citaci\u00f3n a principios de esta semana, pero se espera que consulte con la Oficina de Asesor\u00eda Legal del Departamento de Justicia antes de responder oficialmente.<\/p>\n<p>Mientras tanto, Bondi y Blanche informaron a los legisladores de la Comisi\u00f3n de Supervisi\u00f3n a puerta cerrada el mi\u00e9rcoles para responder preguntas sobre el proceso de censura del departamento y su manejo de la investigaci\u00f3n de Epstein.<\/p>\n<p>\u201cLo dej\u00e9 bien claro: cumplir\u00e9 la ley\u201d, declar\u00f3 Bondi despu\u00e9s de la reuni\u00f3n.<\/p>\n<p>Aunque el presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, indic\u00f3 que \u201cpersonalmente\u201d no ve\u00eda ninguna raz\u00f3n para que Bondi compareciera para prestar testimonio, declar\u00f3 a CNN que planea seguir adelante con la citaci\u00f3n, dado que cinco republicanos de su comisi\u00f3n la apoyaron.<\/p>\n<p>Mientras tanto, un grupo bipartidista de legisladores de la C\u00e1mara de Representantes est\u00e1 estudiando una legislaci\u00f3n que intentar\u00eda responsabilizar al Departamento de Justicia y al FBI por cualquier censura indebida y que obligar\u00eda a la publicaci\u00f3n de los documentos restantes.<\/p>\n<p>Si el Congreso redactara un nuevo proyecto de ley, tanto Khanna como Massie afirmaron que se asegurar\u00edan de que incluyera las disposiciones sobre la aplicaci\u00f3n de la ley que se omitieron en la legislaci\u00f3n actual, a pesar de que sostienen que la norma actual es aplicable y ha obligado a la divulgaci\u00f3n de m\u00e1s documentos de los que nadie cre\u00eda posibles en el momento de su promulgaci\u00f3n el a\u00f1o pasado.<\/p>\n<p>\u201cHemos logrado la liberaci\u00f3n de m\u00e1s de la mitad\u201d, declar\u00f3 Khanna. \u201c\u00bfPodr\u00eda la ley haber sido un 20 % mejor? Claro, pero la mayor parte de esto es simplemente un incumplimiento flagrante de la norma tal como est\u00e1\u201d, afirm\u00f3.<\/p>\n<p>Los miembros del Congreso pueden consultar una versi\u00f3n de los archivos sin censurar o, al menos, con menos partes tachadas.<\/p>\n<p>El Departamento de Justicia les ha recordado a los legisladores este derecho, incluso en una carta reciente, con la esperanza de que la controversia sobre el contenido censurado de los archivos desaparezca, como lo expres\u00f3 un alto funcionario.<\/p>\n<p>En cambio, tras examinar esos documentos en ordenadores dentro de un edificio del Departamento de Justicia, los legisladores han expresado quejas de que la agencia federal no est\u00e1 cumpliendo la ley de transparencia.<\/p>\n<p>Afirmaron que el Departamento de Justicia cometi\u00f3 un error al <a href=\"https:\/\/www.cnn.com\/2026\/02\/10\/politics\/epstein-files-unredacted-names\">ocultar las identidades<\/a> de los presuntos c\u00f3mplices de Epstein y al retener tres memorandos del FBI con entrevistas a una mujer que aleg\u00f3 que el presidente Donald Trump abus\u00f3 de ella cuando ten\u00eda entre 13 y 15 a\u00f1os.<\/p>\n<p>El departamento respondi\u00f3 eliminando las partes censuradas y publicando los memorandos.<\/p>\n<p>Trump ha negado sistem\u00e1ticamente haber cometido irregularidades en relaci\u00f3n con Epstein, y el hecho de que un nombre aparezca en los archivos del caso Epstein no es prueba de que se haya cometido alguna irregularidad.<\/p>\n<p>Los legisladores afirman que esperan que la indignaci\u00f3n p\u00fablica por la gesti\u00f3n de la investigaci\u00f3n de Epstein y la publicaci\u00f3n de los archivos mantenga la presi\u00f3n sobre el Departamento de Justicia.<\/p>\n<p>\u201cLa presi\u00f3n p\u00fablica est\u00e1 dando resultado ahora mismo\u201d, declar\u00f3 Massie.<\/p>\n<p>\u201cNunca antes en la historia moderna de Estados Unidos ha existido una ley que haya expuesto tanto a la \u00e9lite global\u201d, se\u00f1al\u00f3 Khanna. \u201cHa sido una ventana al c\u00edrculo de Epstein. Gente rica y poderosa que actuaba como si estuviera por encima de la ley\u201d.<\/p>\n<p>Que el Congreso est\u00e9 buscando desesperadamente nuevas herramientas para forzar la publicaci\u00f3n de documentos adicionales sobre Epstein es, en cierto modo, consecuencia de sus propias acciones.<\/p>\n<p>\u201cEl hecho de no haber incluido un mecanismo de aplicaci\u00f3n en la ley de transparencia sobre Epstein fue uno de los mayores errores del Congreso en mi vida\u201d, declar\u00f3 Bradley Moss, un abogado especializado en seguridad nacional con amplia experiencia en litigios sobre asuntos de transparencia gubernamental.<\/p>\n<p>\u201cEn efecto, la ley era poco m\u00e1s que una norma que dec\u00eda \u2018por favor, hagan lo correcto\u2019, ordenando al Departamento de Justicia que publicara registros adicionales sin crear realmente un medio legal directo para garantizar que el Departamento de Justicia hiciera precisamente eso\u201d, asegur\u00f3 Moss.<\/p>\n<p>Seg\u00fan declar\u00f3 Khanna a CNN, cuando los legisladores estaban redactando la ley, se debati\u00f3 con sus asesores legales la posibilidad de a\u00f1adir ese texto espec\u00edfico, pero finalmente decidieron que cualquier incumplimiento de la ley podr\u00eda considerarse obstrucci\u00f3n a la justicia por parte de los funcionarios del Departamento de Justicia, y que el Congreso podr\u00eda solicitar procesamientos en futuras administraciones.<\/p>\n<p>\u201cEn retrospectiva, probablemente habr\u00eda a\u00f1adido algo expl\u00edcito sobre una acci\u00f3n legal privada tambi\u00e9n\u201d, apunt\u00f3 Khanna.<\/p>\n<p>Los borradores anteriores del proyecto de ley tambi\u00e9n habr\u00edan obligado a otras agencias, como la CIA, a divulgar cualquier documento relacionado con Epstein.<\/p>\n<p>Sin embargo, esa cl\u00e1usula se elimin\u00f3 para lograr el consenso necesario que garantizara su aprobaci\u00f3n final y la firma de Trump, ya que el presidente y su equipo hab\u00edan estado presionando a los republicanos para que no respaldaran la iniciativa.<\/p>\n<p>\u201cCuando se aprueba un proyecto de ley como este, no se puede volver atr\u00e1s y decir: \u2018Oh, deber\u00edamos haber a\u00f1adido esto\u2019, porque si se hubiera a\u00f1adido aquello, probablemente no habr\u00eda salido adelante\u201d, traslad\u00f3 Massie.<\/p>\n<p>Aunque la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes <a href=\"https:\/\/www.cnn.com\/2025\/08\/05\/politics\/subpoenas-doj-epstein-files-clintons-barr-mueller-garland-congress\">cit\u00f3<\/a> al Departamento de Justicia para que entregara los archivos de Epstein en agosto de 2025, no fue hasta que <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-presidency-epstein-files-release-11-19-25?post-id=cmi650wee00003b6nfsxo1v04\">se aprob\u00f3<\/a> la ley de Massie y Khanna en noviembre de 2025 que el Departamento de Justicia comenz\u00f3 a entregar los documentos m\u00e1s importantes.<\/p>\n<p>Khanna y Massie intentaron recientemente, sin \u00e9xito, convencer a un tribunal federal de Nueva York para que designara a un abogado externo que supervisara la publicaci\u00f3n de los archivos por parte del Departamento de Justicia.<\/p>\n<p>Escribieron al juez Paul Engelmayer, quien ha estado supervisando el esfuerzo por proteger las identidades de las v\u00edctimas en el caso penal contra la c\u00f3mplice de Epstein, Ghislaine Maxwell, dici\u00e9ndole que \u201ctenemos preocupaciones urgentes y graves sobre el incumplimiento por parte del Departamento de Justicia de la Ley [de Transparencia]\u201d.<\/p>\n<p>El Departamento de Justicia argument\u00f3 que los miembros de la C\u00e1mara de Representantes no ten\u00edan derecho a acudir a los tribunales para intentar hacer cumplir la ley.<\/p>\n<p>\u201cAl carecer de legitimaci\u00f3n procesal y de causa de acci\u00f3n, los Representantes no pueden solicitar la reparaci\u00f3n que piden y, con el debido respeto, el Tribunal carece de autoridad para emitirla\u201d, escribi\u00f3 el fiscal estadounidense Jay Clayton ante el tribunal.<\/p>\n<p>Engelmayer coincidi\u00f3 en gran medida, dictaminando que el caso penal de Maxwell no era el foro adecuado para que los tribunales federales supervisaran el cumplimiento de la ley por parte del Departamento de Justicia.<\/p>\n<p>\u201cLos representantes tambi\u00e9n tienen, por supuesto, la libertad de ejercer la supervisi\u00f3n del Departamento de Justicia a trav\u00e9s de las herramientas disponibles para el Congreso\u201d, se\u00f1al\u00f3 Engelmayer a finales del mes pasado.<\/p>\n<p>Aunque los legisladores fracasaron en este intento, afirmaron que Engelmayer les brind\u00f3 a ellos y a los sobrevivientes la oportunidad de demandar a t\u00edtulo personal.<\/p>\n<p>\u201cEste problema no desaparecer\u00e1 hasta que publiquen los archivos\u201d, sentenci\u00f3 Khanna.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una ley de transparencia aprobada por el Congreso ha obligado a publicar m\u00e1s archivos de Epstein que nunca, pero algunos legisladores y v\u00edctimas est\u00e1n explorando formas de presionar al Departamento de Justicia para que revele a\u00fan m\u00e1s informaci\u00f3n del voluminoso material que se mantiene oculto. Unos 2,5 millones de documentos de los archivos de investigaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472334","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una ley de transparencia aprobada por el Congreso ha obligado a publicar m\u00e1s archivos de Epstein que nunca, pero algunos legisladores y v\u00edctimas est\u00e1n explorando formas de presionar al Departamento de Justicia para que revele a\u00fan m\u00e1s informaci\u00f3n del voluminoso material que se mantiene oculto. Unos 2,5 millones de documentos de los archivos de investigaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T11:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s\",\"datePublished\":\"2026-03-19T11:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\"},\"wordCount\":2147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\",\"name\":\"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-19T11:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias","og_description":"Una ley de transparencia aprobada por el Congreso ha obligado a publicar m\u00e1s archivos de Epstein que nunca, pero algunos legisladores y v\u00edctimas est\u00e1n explorando formas de presionar al Departamento de Justicia para que revele a\u00fan m\u00e1s informaci\u00f3n del voluminoso material que se mantiene oculto. Unos 2,5 millones de documentos de los archivos de investigaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-19T11:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s","datePublished":"2026-03-19T11:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/"},"wordCount":2147,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","name":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-19T11:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfHemos visto ya los \u00faltimos archivos de Epstein? Legisladores y v\u00edctimas exigen que se publiquen m\u00e1s","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-19T11:03:47Z","datePublished":"2026-03-19T11:03:47Z","dateModified":"2026-03-19T11:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfHemos visto ya los \\u00faltimos archivos de Epstein? Legisladores y v\\u00edctimas exigen que se publiquen m\\u00e1s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/archivos-epstein-legisladores-victimas-exigen-publiquen-mas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-19T11:03:47Z\",\"datePublished\":\"2026-03-19T11:03:47Z\",\"dateModified\":\"2026-03-19T11:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470886,"url":"https:\/\/noticiasya.com\/tampa\/2026\/02\/05\/archivos-epstein-departamento-justicia-datos-victimas-facilitadores-trax\/","url_meta":{"origin":1472334,"position":0},"title":"El Departamento de Justicia en la mira por revelar datos de v\u00edctimas y ocultar posibles facilitadores en archivos de Epstein","author":"","date":"febrero 5, 2026","format":false,"excerpt":"El Departamento de Justicia no ocult\u00f3 informaci\u00f3n que identificaba a muchas de las v\u00edctimas de Jeffrey Epstein y redact\u00f3 los detalles de individuos que podr\u00edan haber ayudado al delincuente sexual convicto, lo que provoc\u00f3 una protesta de los sobrevivientes que acusan al Departamento de Justicia de arruinar la publicaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469333,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/17\/claves-publicacion-archivos-epstein-trax\/","url_meta":{"origin":1472334,"position":1},"title":"Claves para entender la pr\u00f3xima publicaci\u00f3n de los archivos de Epstein","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Una nueva ley federal exige que el Departamento de Justicia publique antes del viernes una enorme cantidad de documentos de investigaci\u00f3n relacionados con Jeffrey Epstein.La publicaci\u00f3n de los archivos de Epstein, que detallan las investigaciones sobre el multimillonario y delincuente sexual ca\u00eddo en desgracia, fallecido en 2019, ha atra\u00eddo una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470664,"url":"https:\/\/noticiasya.com\/tampa\/2026\/01\/30\/publican-mas-archivos-caso-jeffrey-epstein-trax\/","url_meta":{"origin":1472334,"position":2},"title":"El Departamento de Justicia publica millones de p\u00e1ginas de documentos en la investigaci\u00f3n de Epstein","author":"","date":"enero 30, 2026","format":false,"excerpt":"El Departamento de Justicia ha completado la revisi\u00f3n de los registros relacionados con Jeffrey Epstein y publicar\u00e1 los documentos a lo largo del viernes, anunci\u00f3 vicesecretario de Justicia Todd Blanche.Los documentos que se publicar\u00e1n hoy incluir\u00e1n m\u00e1s de 3 millones de p\u00e1ginas, 2.000 videos y 180.000 v\u00eddeos.La publicaci\u00f3n pondr\u00e1 fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469609,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/27\/archivos-epstein-que-falta-trax\/","url_meta":{"origin":1472334,"position":3},"title":"\u00bfQu\u00e9 falta por publicar de los archivos de Epstein? Lo que podr\u00eda salir a la luz en 2026","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"La saga de los \u201carchivos Epstein\u201d se extender\u00e1 hasta 2026, a pesar de la fecha l\u00edmite impuesta la semana pasada para publicar todos los registros.El Congreso aprob\u00f3 una ley el mes pasado, con un apoyo casi un\u00e1nime, que exige al Departamento de Justicia publicar todos sus archivos sobre Jeffrey Epstein,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469844,"url":"https:\/\/noticiasya.com\/tampa\/2026\/01\/06\/justicia-archivos-epstein-2-millones-documentos-trax\/","url_meta":{"origin":1472334,"position":4},"title":"Departamento de Justicia dice que public\u00f3 menos del 1 % de archivos de Epstein y a\u00fan revisa m\u00e1s de 2 millones de documentos","author":"","date":"enero 6, 2026","format":false,"excerpt":"El Departamento de Justicia anunci\u00f3 el lunes que ha publicado 12.285 documentos \u2014menos del 1 %\u2014 de sus archivos relacionados con Jeffrey Epstein, y que a\u00fan se est\u00e1n revisando m\u00e1s de 2 millones de documentos.La secretaria de Justicia, Pam Bondi, y el vicesecretario de Justicia, Todd Blanche, dijeron a un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470547,"url":"https:\/\/noticiasya.com\/tampa\/2026\/01\/28\/departamento-justicia-archivos-epstein-publicacion-trax\/","url_meta":{"origin":1472334,"position":5},"title":"El Departamento de Justicia espera publicar pronto sus archivos de Epstein, dicen altos funcionarios","author":"","date":"enero 28, 2026","format":false,"excerpt":"Los principales l\u00edderes del Departamento de Justicia dijeron en una presentaci\u00f3n judicial el martes que esperan publicar los archivos del departamento relacionados con Jeffrey Epstein \u201cen el corto plazo\u201d.La secretaria de Justicia, Pam Bondi, el secretario de Justicia adjunto, Todd Blanche, y el fiscal federal para el Distrito Sur de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472334"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472334\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}