{"id":1472338,"date":"2026-03-19T06:03:51","date_gmt":"2026-03-19T13:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/"},"modified":"2026-03-19T06:03:51","modified_gmt":"2026-03-19T13:03:51","slug":"colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","title":{"rendered":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador"},"content":{"rendered":"<p>Una operaci\u00f3n de seguridad conjunta entre M\u00e9xico y Colombia logr\u00f3 la captura en Ciudad de M\u00e9xico de<a href=\"https:\/\/x.com\/petrogustavo\/status\/2034295026738512371?s=20\"> \u00c1ngel Esteban Aguilar Morales,<\/a> alias \u201cLobo Menor\u201d, <a href=\"https:\/\/x.com\/fiscaliaecuador\/status\/2021286422842573082?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">procesado <\/a>como uno de los presuntos autores intelectuales en el caso del asesinato del excandidato presidencial de Ecuador, <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/08\/10\/fernando-villavicencio-vida-origen-familia-carrera-politica-orix\">Fernando Villavicencio<\/a>, seg\u00fan se\u00f1alaron este mi\u00e9rcoles los gobiernos de ambos pa\u00edses.<\/p>\n<p>La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de M\u00e9xico, la Secretar\u00eda de la Marina y el Instituto de Migraci\u00f3n de M\u00e9xico, en colaboraci\u00f3n con la Polic\u00eda Nacional de Colombia, ejecutaron la detenci\u00f3n del sospechoso tras acciones de inteligencia y seguimiento en tiempo real del cabecilla de la banda delictiva ecuatoriana Los Lobos, vinculada al narcotr\u00e1fico, miner\u00eda ilegal y crimen transnacional.<\/p>\n<p>Las autoridades mexicanas informaron que alias \u201cLobo Menor\u201d se identific\u00f3 como ciudadano colombiano bajo el nombre de Juan Carlos Montero Mestre, en la colonia de Polanco en Ciudad de M\u00e9xico. Posteriormente fue ubicado en la alcald\u00eda de Miguel Hidalgo.<\/p>\n<p>\u201cSe despleg\u00f3 un operativo coordinado que permiti\u00f3 su detenci\u00f3n sin uso de la violencia y en estricto apego a los derechos humanos. Estas acciones se realizaron con el apoyo de autoridades colombianas a trav\u00e9s de los canales de cooperaci\u00f3n policial y migratoria\u201d, indic\u00f3 este mi\u00e9rcoles la Secretar\u00eda de Seguridad de M\u00e9xico <a href=\"https:\/\/x.com\/sspcmexico\/status\/2034310486515490979?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">en un comunicado.<\/a><\/p>\n<p>En febrero de este a\u00f1o, un juez <a href=\"https:\/\/x.com\/fiscaliaecuador\/status\/2021286422842573082?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">orden\u00f3 <\/a>prisi\u00f3n preventiva en contra de alias \u201cLobo Menor\u201d, quien se manten\u00eda como pr\u00f3fugo de la justicia, seg\u00fan dijo la Fiscal\u00eda de Ecuador. CNN intenta averiguar si Aguilar Morales tiene representaci\u00f3n legal.<\/p>\n<p>La oficina de Migraci\u00f3n Colombia <a href=\"https:\/\/x.com\/directorpolicia\/status\/2034307951997902972?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">inform\u00f3<\/a> que \u00c1ngel Esteban Aguilar Morales era requerido internacionalmente a trav\u00e9s de circular roja de Interpol y su detenci\u00f3n se produjo en el aeropuerto de Bogot\u00e1 tras su arribo en un vuelo procedente de M\u00e9xico.<\/p>\n<p>\u201cEl individuo intentaba evadir los controles migratorios utilizando una identidad falsa como ciudadano colombiano. Sin embargo, gracias a mecanismos de cooperaci\u00f3n internacional y a los protocolos de verificaci\u00f3n de la autoridad migratoria de Colombia, se logr\u00f3 establecer su verdadera identidad\u201d, puntualiz\u00f3.<\/p>\n<p>Migraci\u00f3n Colombia adelant\u00f3 que alias Lobo Menor fue puesto a \u00f3rdenes de las autoridades competentes para avanzar en su proceso judicial. \u201cEste resultado demuestra que Colombia es un pa\u00eds con instituciones s\u00f3lidas y con personal comprometido que trabaja de manera articulada por la seguridad nacional\u201d, dijo la directora general de Migraci\u00f3n Colombia, Gloria Arriero.<\/p>\n<p>El presidente de Colombia, Gustavo Petro, tambi\u00e9n se pronunci\u00f3 sobre esta operaci\u00f3n de Colombia y M\u00e9xico y <a href=\"https:\/\/x.com\/petrogustavo\/status\/2034295026738512371?s=46&#038;t=vWSsaMsKttiCRFRT9JR29g\">se\u00f1al\u00f3 en su cuenta de X<\/a> que \u201ccomo resultado de la operaci\u00f3n \u2018JERIC\u00d3\u2019 realizada en las \u00faltimas horas, se dio con la captura de \u00c1ngel Esteban Aguilar Morales alias LOBO MENOR en el sector de Polanco en la Ciudad de M\u00e9xico\u201d.<\/p>\n<p>\u201cEs un golpe significativo contra el crimen organizado transnacional y ratifica la efectividad de la cooperaci\u00f3n trilateral entre Colombia, Ecuador y M\u00e9xico en la lucha frontal contra las redes multicrimen\u201d, enfatiz\u00f3 Petro.<\/p>\n<p>El ministro del Interior de Ecuador, Jhon Reimberg, <a href=\"https:\/\/x.com\/johnreimberg\/status\/2034301130985893940\">se\u00f1al\u00f3 <\/a>que Angel Esteban Aguilar tiene una orden de captura por su vinculaci\u00f3n dentro del caso del asesinato del Fernando Villavicencio, que ocurri\u00f3 en agosto de 2023 cuando el entonces candidato sal\u00eda de un mitin pol\u00edtico en Quito.<\/p>\n<p>\u201cEsc\u00f3ndanse donde se escondan, los encontraremos y atraparemos\u201d, advirti\u00f3 Reimberg.<\/p>\n<p>Esta detenci\u00f3n se produce en medio de tensiones ente Ecuador y Colombia debido a los se\u00f1alamientos mutuos de falta de cooperaci\u00f3n en la lucha contra el crimen organizado y el narcotr\u00e1fico. Adem\u00e1s, Ecuador mantiene rotas sus relaciones con M\u00e9xico desde abril de 2024, tras la incursi\u00f3n armada de la polic\u00eda ecuatoriana a la embajada de M\u00e9xico para capturar al exvicepresidente Jorge Glas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una operaci\u00f3n de seguridad conjunta entre M\u00e9xico y Colombia logr\u00f3 la captura en Ciudad de M\u00e9xico de \u00c1ngel Esteban Aguilar Morales, alias \u201cLobo Menor\u201d, procesado como uno de los presuntos autores intelectuales en el caso del asesinato del excandidato presidencial de Ecuador, Fernando Villavicencio, seg\u00fan se\u00f1alaron este mi\u00e9rcoles los gobiernos de ambos pa\u00edses. La Secretar\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472338","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una operaci\u00f3n de seguridad conjunta entre M\u00e9xico y Colombia logr\u00f3 la captura en Ciudad de M\u00e9xico de \u00c1ngel Esteban Aguilar Morales, alias \u201cLobo Menor\u201d, procesado como uno de los presuntos autores intelectuales en el caso del asesinato del excandidato presidencial de Ecuador, Fernando Villavicencio, seg\u00fan se\u00f1alaron este mi\u00e9rcoles los gobiernos de ambos pa\u00edses. La Secretar\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T13:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador\",\"datePublished\":\"2026-03-19T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\"},\"wordCount\":688,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\",\"name\":\"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-19T13:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias","og_description":"Una operaci\u00f3n de seguridad conjunta entre M\u00e9xico y Colombia logr\u00f3 la captura en Ciudad de M\u00e9xico de \u00c1ngel Esteban Aguilar Morales, alias \u201cLobo Menor\u201d, procesado como uno de los presuntos autores intelectuales en el caso del asesinato del excandidato presidencial de Ecuador, Fernando Villavicencio, seg\u00fan se\u00f1alaron este mi\u00e9rcoles los gobiernos de ambos pa\u00edses. La Secretar\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-19T13:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador","datePublished":"2026-03-19T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/"},"wordCount":688,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","name":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-19T13:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo M\u00e9xico y Colombia detuvieron a un pr\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-19T13:03:51Z","datePublished":"2026-03-19T13:03:51Z","dateModified":"2026-03-19T13:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo M\\u00e9xico y Colombia detuvieron a un pr\\u00f3fugo por el crimen de Fernando Villavicencio, excandidato presidencial de Ecuador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/colombia-mexico-captura-alias-lobo-menor-asesinato-fernando-villavicencio-ecuador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-19T13:03:51Z\",\"datePublished\":\"2026-03-19T13:03:51Z\",\"dateModified\":\"2026-03-19T13:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465614,"url":"https:\/\/noticiasya.com\/tampa\/2025\/08\/18\/ecuador-cargos-autores-asesinato-fernando-villavicencio-orix\/","url_meta":{"origin":1472338,"position":0},"title":"Fiscal\u00eda de Ecuador formular\u00e1 cargos contra presuntos autores intelectuales del asesinato de Fernando Villavicencio","author":"","date":"agosto 18, 2025","format":false,"excerpt":"La Fiscal\u00eda General de Ecuador inform\u00f3 este lunes que ha solicitado a un juez que convoque al exministro del Interior, Jos\u00e9 Serrano; al condenado por delitos de corrupci\u00f3n Daniel Salcedo, quien est\u00e1 en prisi\u00f3n; al exasamble\u00edsta del corre\u00edsmo Ronny Aleaga y al empresario Xavier Jord\u00e1n a una audiencia de formulaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447742,"url":"https:\/\/noticiasya.com\/tampa\/2024\/04\/04\/ecuador-declara-persona-non-grata-embajadora-mexico-orix\/","url_meta":{"origin":1472338,"position":1},"title":"Ecuador declara persona non grata a la embajadora de M\u00e9xico por declaraciones de L\u00f3pez Obrador","author":"","date":"abril 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Ministerio de Relaciones Exteriores de Ecuador inform\u00f3 este jueves que declar\u00f3 persona non grata a la embajadora de M\u00e9xico en el pa\u00eds, Raquel Serur Smeke, debido a las declaraciones del mi\u00e9rcoles del presidente Andr\u00e9s Manuel L\u00f3pez Obrador sobre las elecciones presidenciales de Ecuador de 2023 y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446062,"url":"https:\/\/noticiasya.com\/tampa\/2024\/02\/27\/fiscalia-acusa-seis-detenidos-asesinato-fernando-villavicencio-orix\/","url_meta":{"origin":1472338,"position":2},"title":"La Fiscal\u00eda de Ecuador acusa a 6 detenidos por el asesinato de Fernando Villavicencio; se\u00f1ala que la orden sali\u00f3 de la c\u00e1rcel de Latacunga","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La fiscal ecuatoriana Ana Hidalgo present\u00f3 dictamen acusatorio contra seis detenidos que est\u00e1n procesados por el asesinato del excandidato presidencial Fernando Villavicencio, que hace m\u00e1s de seis meses despu\u00e9s conmocion\u00f3 al pa\u00eds, durante la audiencia preparatoria de juicio realizada este martes.Villavicencio fue asesinado por sicarios el 9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466157,"url":"https:\/\/noticiasya.com\/tampa\/2025\/09\/04\/prision-preventiva-presuntos-autores-intelectuales-asesinato-villavicencio-orix\/","url_meta":{"origin":1472338,"position":3},"title":"Ordenan prisi\u00f3n preventiva para dos presuntos autores intelectuales del asesinato de Villavicencio en Ecuador","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"La Fiscal\u00eda de Ecuador formul\u00f3 este mi\u00e9rcoles cargos en contra de cuatro presuntos autores intelectuales del asesinato del excandidato presidencial Fernando Villavicencio, ocurrido el 9 de agosto de 2023 tras un mitin pol\u00edtico en Quito. La audiencia \u2014que se desarroll\u00f3 en una unidad judicial en Quito\u2014 estuvo marcada por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451700,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/09\/hija-fernando-villavicencio-asesinato-entrevista-ecuador-orix\/","url_meta":{"origin":1472338,"position":4},"title":"&#171;En la narcopol\u00edtica est\u00e1n los asesinos de mi padre\u201d: hija de Fernando Villavicencio lo recuerda un a\u00f1o despu\u00e9s de su asesinato en Ecuador","author":"","date":"agosto 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La tarde del 9 de agosto de 2023, en medio de una campa\u00f1a presidencial marcada por un adelanto de elecciones, Ecuador se paraliz\u00f3 cuando se confirm\u00f3 que el entonces candidato Fernando Villavicencio recibi\u00f3 varios disparos al salir de un mitin en el norte de Quito. Un atroz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462448,"url":"https:\/\/noticiasya.com\/tampa\/2025\/05\/16\/fiscalia-ecuador-declara-jorge-glas-caso-villavicencio-orix\/","url_meta":{"origin":1472338,"position":5},"title":"Fiscal\u00eda de Ecuador cita a declarar a Jorge Glas y a otras personas dentro del caso Villavicencio, dicen sus abogados","author":"","date":"mayo 16, 2025","format":false,"excerpt":"El exvicepresidente de Ecuador Jorge Glas es una de varias personas que esta semana comenzaron a ser citadas por la Fiscal\u00eda para rendir declaraci\u00f3n como parte del caso del asesinato del entonces candidato presidencial Fernando Villavicencio, ocurrido el 9 de agosto de 2023 tras un mitin pol\u00edtico en Quito.Los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472338"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472338\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}