{"id":1472361,"date":"2026-03-19T17:03:51","date_gmt":"2026-03-20T00:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/"},"modified":"2026-03-19T17:03:51","modified_gmt":"2026-03-20T00:03:51","slug":"cesar-chavez-comunidades-reconsiderar-homenajes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","title":{"rendered":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino"},"content":{"rendered":"<p>Una figura cubierta por una s\u00e1bana permaneci\u00f3 el mi\u00e9rcoles en el Jard\u00edn de la Paz de la Universidad Estatal de Fresno, en California, como un fantasma en la penumbra. La gran s\u00e1bana negra, sostenida torpemente con clips de pl\u00e1stico, ocultaba la estatua de Cesar Chavez, quien pas\u00f3 d\u00e9cadas bajo los reflectores como un \u00edcono del poder laboral y del orgullo latino.<\/p>\n<p>El legado de esta figura emblem\u00e1tica, que falleci\u00f3 hace tres d\u00e9cadas, se vio sacudido el mi\u00e9rcoles por las impactantes acusaciones en <a href=\"https:\/\/www.nytimes.com\/2026\/03\/18\/us\/cesar-chavez-sexual-abuse-allegations-ufw.html\">un art\u00edculo del New York Times<\/a>, que afirmaba que durante d\u00e9cadas Chavez abus\u00f3 sexualmente de ni\u00f1as y mujeres, incluida una de sus colaboradoras m\u00e1s destacadas, mientras lideraba el movimiento estadounidense por los derechos de los trabajadores agr\u00edcolas.<\/p>\n<p>Admiradores y funcionarios p\u00fablicos ahora se apresuran a responder a las acusaciones sobre el hombre al que se ha honrado con d\u00edas festivos, estatuas y nombres de escuelas en comunidades de todo el pa\u00eds.<\/p>\n<p>Esto es lo que se sabe sobre las acusaciones contra Chavez y las respuestas hasta el momento.<\/p>\n<p>La r\u00e1pida decisi\u00f3n de la Universidad Estatal de Fresno de cubrir su estatua de Chavez, erigida en el campus hace 30 a\u00f1os, fue una de las se\u00f1ales m\u00e1s visibles de la rapidez con la que se est\u00e1 reconsiderando su memoria.<\/p>\n<p>Para el final del d\u00eda, la escultura fue cubierta con madera contrachapada.<\/p>\n<p>\u201cAnte la gravedad de las revelaciones actuales, como primer paso estamos cubriendo la estatua mientras determinamos los siguientes pasos apropiados para su posible retiro\u201d, <a href=\"https:\/\/today.fresnostate.edu\/a-message-from-the-president-on-the-peace-garden-and-our-community-values\/\">declar\u00f3 el mi\u00e9rcoles<\/a> el presidente de la universidad, Sa\u00fal Jim\u00e9nez-Sandoval.<\/p>\n<p>\u201cEn Fresno State, nuestros valores se basan en la dignidad, el respeto y el cuidado mutuo. Cuando tenemos conocimiento de denuncias de esta naturaleza, debemos reconocer su peso y dar espacio a quienes han sido afectados\u201d.<\/p>\n<p>La respuesta es a\u00fan m\u00e1s compleja para las decenas de escuelas nombradas en honor a Chavez, as\u00ed como para los estados que celebran el 31 de marzo como el D\u00eda de Cesar Chavez.<\/p>\n<p>En California, donde la festividad est\u00e1 escrita en la ley estatal, los dos legisladores dem\u00f3cratas <a href=\"https:\/\/speaker.asmdc.org\/press-releases\/20260319-speaker-rivas-pro-tem-limon-announce-california-state-holiday-honor\">anunciaron el jueves que impulsar\u00e1n un proyecto para cambiar su nombre<\/a>. El gobernador Gavin Newsom dijo que apoya la idea.<\/p>\n<p>\u201cLo que representaba Cesar era un movimiento: el movimiento de los trabajadores agr\u00edcolas, el movimiento laboral, y es correcto celebrar ese movimiento\u201d, dijo Newsom el jueves, al referirse a las acusaciones. \u201cApoyo avanzar en la direcci\u00f3n que muchos est\u00e1n promoviendo, incluidos miembros de la legislatura, y espero hacerlo de manera expedita\u201d, agreg\u00f3.<\/p>\n<p>La alcaldesa de Los \u00c1ngeles, Karen Bass, tambi\u00e9n dem\u00f3crata, firm\u00f3 el jueves una proclamaci\u00f3n que cambia el nombre del <a href=\"https:\/\/www.laworks.com\/cesarchavez\">D\u00eda de Cesar Chavez<\/a> a \u201cD\u00eda de los Trabajadores Agr\u00edcolas\u201d, para continuar honrando al movimiento sin mencionar a Chavez.<\/p>\n<p>\u201cHe estado en contacto con la familia Chavez, y apoyan nuestra decisi\u00f3n de renombrar este d\u00eda festivo\u201d, dijo Bass. Otros homenajes en la ciudad tambi\u00e9n ser\u00e1n revisados.<\/p>\n<p>\u201cEl sufrimiento y la lucha de los trabajadores agr\u00edcolas contin\u00faa, y lo honraremos. Pero tendremos que revisar varias cosas, incluyendo el nombre de d\u00edas festivos, edificios y calles\u201d, agreg\u00f3.<\/p>\n<p>En Texas, el gobernador republicano Greg Abbott anunci\u00f3 que este a\u00f1o el estado no celebrar\u00e1 el D\u00eda de Cesar Chavez, considerado \u201copcional\u201d bajo la ley estatal.<\/p>\n<p>\u201cLos reportes sobre los horribles y ampliamente reconocidos abusos sexuales de C\u00e9sar Ch\u00e1vez desmantelan con raz\u00f3n el mito de este h\u00e9roe progresista y socavan la narrativa que lo elev\u00f3 como una figura digna de celebraci\u00f3n oficial\u201d, <a href=\"https:\/\/gov.texas.gov\/news\/post\/governor-abbott-statement-on-cesar-chavez-allegations\">dijo Abbott<\/a>.<\/p>\n<p>En Denver, el D\u00eda de Cesar Chavez este a\u00f1o se llamar\u00e1 \u201cS\u00ed, se puede\u201d, en referencia al lema del movimiento de trabajadores agr\u00edcolas, inform\u00f3 el alcalde Mike Johnston. El nombre para a\u00f1os posteriores se decidir\u00e1 m\u00e1s adelante. El Parque Cesar Chavez de Denver ser\u00e1 renombrado, y se retirar\u00e1n un busto y una placa en su honor, agreg\u00f3 Johnston.<\/p>\n<p>En <a href=\"https:\/\/abc7news.com\/post\/former-san-francisco-supervisor-susan-leal-behind-cesar-chavez-st-name-1995-wants-change-following-abuse-allegations\/18732397\/\">San Francisco<\/a>, <a href=\"https:\/\/www.instagram.com\/p\/DWCUrsajmnl\/\">Austin <\/a>y otras comunidades, activistas que lograron renombrar calles en honor a Ch\u00e1vez ahora apoyan la idea de cambiar los nombres nuevamente.<\/p>\n<p>\u201cTenemos que ser responsables y respetuosos con las mujeres que fueron v\u00edctimas durante su vida y que no pueden estar asociadas con una persona as\u00ed\u201d, dijo el activista Gavino Fern\u00e1ndez a la estaci\u00f3n KVUE de Austin, afiliada de CNN.<\/p>\n<p>Los rumores sobre conducta sexual inapropiada de Chavez se hicieron p\u00fablicos esta semana, cuando la UFW Foundation \u2014grupo asociado con el sindicato United Farm Workers, cofundado por Chavez\u2014 reconoci\u00f3 haber recibido informaci\u00f3n sobre comportamientos \u201cimpactantes e indefendibles\u201d.<\/p>\n<p>El art\u00edculo de The New York Times detall\u00f3 que dos mujeres declararon haber sido abusadas por Chavez cuando eran adolescentes. Debra Rojas cont\u00f3 que Chavez la toc\u00f3 por primera vez a los 12 a\u00f1os y que tuvo relaciones sexuales con ella a los 15, mientras trabajaban juntas en una marcha laboral.<\/p>\n<p>\u201cSiento que ha sido una sombra sobre mi vida\u201d, dijo Rojas. \u201cQuiero que deje de seguirme. Ya es hora\u201d.<\/p>\n<p>Ana Murgu\u00eda relat\u00f3 que Chavez la acos\u00f3 por primera vez a los 13 a\u00f1os.<\/p>\n<p>El peri\u00f3dico confirm\u00f3 los detalles de sus testimonios mediante documentos del sindicato, correos electr\u00f3nicos y entrevistas con personas a quienes las mujeres hab\u00edan contado su historia previamente.<\/p>\n<p>La mayor parte de los abusos ocurri\u00f3 en un complejo conocido como La Paz, propiedad de 187 acres en California central que funcionaba como sede y hogar de Chavez, actualmente declarado <a href=\"https:\/\/www.nps.gov\/articles\/chavez.htm\">monumento nacional.<\/a><\/p>\n<p>CNN no ha verificado de manera independiente las acusaciones reportadas por The New York Times. La familia de Chavez declar\u00f3 al diario que \u201cno est\u00e1 en posici\u00f3n de juzgar\u201d las nuevas revelaciones.<\/p>\n<p>\u201cComo familia basada en los valores de equidad y justicia, honramos las voces de quienes sienten que no se les escucha y denuncian conductas sexuales inapropiadas\u201d, dijeron. \u201cEstas acusaciones son profundamente dolorosas para nuestra familia\u201d.<\/p>\n<p>Uno de los elementos m\u00e1s sorprendentes del art\u00edculo fue la declaraci\u00f3n de Dolores Huerta, aliada de Chavez y cofundadora de United Farm Workers. Ahora de 95 a\u00f1os, reconoci\u00f3 p\u00fablicamente por primera vez que tuvo encuentros sexuales no deseados con Chavez en dos ocasiones durante la d\u00e9cada de 1960.<\/p>\n<p>\u201cLa primera vez fui manipulada y presionada para tener relaciones con \u00e9l, y no sent\u00ed que pudiera decir no porque era alguien a quien admiraba, mi jefe y l\u00edder del movimiento al que ya hab\u00eda dedicado a\u00f1os de mi vida\u201d, <a href=\"https:\/\/medium.com\/@dolores_huerta\/march-18-2026-e74c20430555\">dijo Huerta en un comunicado<\/a>. \u201cLa segunda vez fui forzada, contra mi voluntad, en un ambiente donde me sent\u00ed atrapada\u201d.<\/p>\n<p>Huerta qued\u00f3 embarazada ambas veces, y los hijos no supieron qui\u00e9n era su padre hasta este a\u00f1o. Rechaz\u00f3 solicitudes de entrevista de CNN.<\/p>\n<p>Huerta se involucr\u00f3 en activismo comunitario en 1955 en Stockton, California. Como madre soltera, junto a Chavez cre\u00f3 en 1962 la Asociaci\u00f3n Nacional de Trabajadores Agr\u00edcolas, que se convirti\u00f3 en la UFW moderna.<\/p>\n<p>Aunque fueron socios en el movimiento laboral, la tensi\u00f3n entre Chavez y Huerta era conocida e incluso aparece en su biograf\u00eda oficial.<\/p>\n<p>\u201cPor mucho que fuera la mano derecha de Cesar, tambi\u00e9n pudo ser la mayor espina en su costado\u201d, dice la <a href=\"https:\/\/doloreshuerta.org\/dolores-huerta\/\">biograf\u00eda <\/a>publicada por la Fundaci\u00f3n Dolores Huerta. \u201cAmbos eran conocidos por sus acaloradas discusiones, algo que formaba parte natural de su relaci\u00f3n laboral\u201d.<\/p>\n<p>Huerta tuvo posteriormente una relaci\u00f3n con el hermano de Chavez, Richard, y tuvieron cuatro hijos.<\/p>\n<p>Adem\u00e1s de su trabajo en defensa de los trabajadores agr\u00edcolas, Huerta se convirti\u00f3 en una figura clave del movimiento feminista. Forma parte de la junta directiva de la Feminist Majority Foundation y fue copresidenta honoraria de la Marcha de las Mujeres en Washington, celebrada al d\u00eda siguiente de la primera toma de posesi\u00f3n del presidente Donald Trump en 2017.<\/p>\n<p>Huerta reconoci\u00f3 en 2015 que, al inicio de su activismo, no pensaba mucho en los derechos de las mujeres.<\/p>\n<p>\u201cEst\u00e1bamos tan concentradas en ayudar a nuestra \u2018gente\u2019, a nuestra gente, que no pens\u00e1bamos en nosotras mismas como mujeres o como feministas, \u00bfsaben?\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=PDgBPT5cEhQ&#038;t=1421s\">dijo Huerta en una entrevista en la National Portrait Gallery<\/a>. \u201cSolo quer\u00edamos asegurarnos de poner fin a esta discriminaci\u00f3n y a la opresi\u00f3n, as\u00ed que no est\u00e1bamos pensando \u2018oye, \u00bfy las mujeres?\u2019\u201d.<\/p>\n<p>Huerta recibi\u00f3 la <a href=\"https:\/\/obamawhitehouse.archives.gov\/the-press-office\/2012\/05\/29\/remarks-president-presidential-medal-freedom-ceremony\">Medalla Presidencial de la Libertad<\/a> en 2012.<\/p>\n<p>\u201cDolores fue muy amable cuando le dije que le hab\u00eda \u2018robado\u2019 su lema, \u2018S\u00ed, se puede\u2019.\u202fS\u00ed, se puede\u201d, brome\u00f3 el presidente Barack Obama durante la ceremonia en la Casa Blanca.<\/p>\n<p>En su declaraci\u00f3n explicando las acusaciones contra Chavez, Huerta dej\u00f3 claro que no deseaba que su larga vida quedara definida por haber sido v\u00edctima de abuso sexual.<\/p>\n<p>\u201cMantuve este secreto tanto tiempo porque construir el movimiento y asegurar los derechos de los trabajadores agr\u00edcolas era mi labor de vida\u201d, escribi\u00f3. \u201cLa formaci\u00f3n de un sindicato fue el \u00fanico veh\u00edculo para lograr y asegurar esos derechos, y no iba a permitir que Cesar ni nadie m\u00e1s lo impidiera\u201d.<\/p>\n<p>United Farm Workers, un d\u00eda antes de<a href=\"https:\/\/ufw.org\/statement-from-united-farm-workers-march-17-2026\/\"> la publicaci\u00f3n del art\u00edculo del Times<\/a>, calific\u00f3 las acusaciones como \u201cprofundamente preocupantes\u201d y anunci\u00f3 que no participar\u00e1 en actividades del D\u00eda de Cesar Chavez este a\u00f1o.<\/p>\n<p>La Fundaci\u00f3n Cesar Chavez dijo que est\u00e1 teniendo \u201cuna conversaci\u00f3n necesaria sobre la identidad de nuestra organizaci\u00f3n\u201d.<\/p>\n<p>\u201cA las v\u00edctimas: creemos en ustedes\u201d, <a href=\"https:\/\/chavezfoundation.org\/2026\/03\/18\/the-cesar-chavez-foundation-statement\/\">se\u00f1al\u00f3 la fundaci\u00f3n<\/a>. \u201cHonramos su valent\u00eda y lamentamos profundamente el da\u00f1o que han llevado en las sombras por tanto tiempo\u201d.<\/p>\n<ul>\n<li>L\u00ednea Nacional de Violencia Dom\u00e9stica: 1-800-799-SAFE (7233), texto START al 88788 o chat en l\u00ednea.<\/li>\n<li>L\u00ednea Nacional de Asalto Sexual: 1-800-656-HOPE (4673), texto HOPE al 64673 o chat en l\u00ednea. Proporcionado por RAINN (Red Nacional de Violaci\u00f3n, Abuso e Incesto).<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una figura cubierta por una s\u00e1bana permaneci\u00f3 el mi\u00e9rcoles en el Jard\u00edn de la Paz de la Universidad Estatal de Fresno, en California, como un fantasma en la penumbra. La gran s\u00e1bana negra, sostenida torpemente con clips de pl\u00e1stico, ocultaba la estatua de Cesar Chavez, quien pas\u00f3 d\u00e9cadas bajo los reflectores como un \u00edcono del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472361","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una figura cubierta por una s\u00e1bana permaneci\u00f3 el mi\u00e9rcoles en el Jard\u00edn de la Paz de la Universidad Estatal de Fresno, en California, como un fantasma en la penumbra. La gran s\u00e1bana negra, sostenida torpemente con clips de pl\u00e1stico, ocultaba la estatua de Cesar Chavez, quien pas\u00f3 d\u00e9cadas bajo los reflectores como un \u00edcono del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T00:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino\",\"datePublished\":\"2026-03-20T00:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\"},\"wordCount\":1702,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\",\"name\":\"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T00:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias","og_description":"Una figura cubierta por una s\u00e1bana permaneci\u00f3 el mi\u00e9rcoles en el Jard\u00edn de la Paz de la Universidad Estatal de Fresno, en California, como un fantasma en la penumbra. La gran s\u00e1bana negra, sostenida torpemente con clips de pl\u00e1stico, ocultaba la estatua de Cesar Chavez, quien pas\u00f3 d\u00e9cadas bajo los reflectores como un \u00edcono del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-20T00:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/"},"author":{"name":"","@id":""},"headline":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino","datePublished":"2026-03-20T00:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/"},"wordCount":1702,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","name":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T00:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T00:03:51Z","datePublished":"2026-03-20T00:03:51Z","dateModified":"2026-03-20T00:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\\u00edder latino\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/19\\\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T00:03:51Z\",\"datePublished\":\"2026-03-20T00:03:51Z\",\"dateModified\":\"2026-03-20T00:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472315,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/acusan-cesar-chavez-abuso-sexual-trax\/","url_meta":{"origin":1472361,"position":0},"title":"Acusan a Cesar Chavez, l\u00edder de los trabajadores agr\u00edcolas en el siglo XX, de haber cometido abusos sexuales durante d\u00e9cadas","author":"","date":"marzo 18, 2026","format":false,"excerpt":"L\u00edderes latinos y funcionarios elegidos afirman estar conmocionados por las acusaciones \u201cprofundamente perturbadoras\u201d de conducta sexual inapropiada contra Cesar Chavez, uno de los \u00edconos de los derechos civiles m\u00e1s destacados de la comunidad latina, en un momento en el que se est\u00e1n cancelando las celebraciones anuales previstas en honor al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472384,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","url_meta":{"origin":1472361,"position":1},"title":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida","author":"","date":"marzo 20, 2026","format":false,"excerpt":"La historia de Dolores Huerta es la historia de la lucha por los derechos de los hispanos a comienzos del siglo XX, en medio del controvertido programa de braceros, que por m\u00e1s de XX a\u00f1os permiti\u00f3 a trabajadores mexicanos trabajar en agricultura y en la industria ferroviaria en EE.UU de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464241,"url":"https:\/\/noticiasya.com\/tampa\/2025\/07\/04\/quien-es-julio-cesar-chavez-jr-boxeador-detenido-ice-orix\/","url_meta":{"origin":1472361,"position":2},"title":"\u00bfQui\u00e9n es Julio C\u00e9sar Ch\u00e1vez Jr., el boxeador detenido por ICE que est\u00e1 en espera de ser entregado a M\u00e9xico?","author":"","date":"julio 4, 2025","format":false,"excerpt":"El boxeador mexicano Julio C\u00e9sar Ch\u00e1vez Jr. sufri\u00f3 dos derrotas en menos de una semana, una arriba del ring y otra en su situaci\u00f3n legal.La primera ocurri\u00f3 la noche del s\u00e1bado, cuando el influencer Jake Paul lo venci\u00f3 en la pelea que sostuvieron en Anaheim, California, con lo que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472333,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/5-cosas-19-marzo-orix\/","url_meta":{"origin":1472361,"position":3},"title":"Las 5 cosas que debes saber este 19 de marzo","author":"","date":"marzo 19, 2026","format":false,"excerpt":"D\u00edaz-Canel cambia el tono contra EE.UU. La realidad alternativa de Trump sobre la guerra con Ir\u00e1n. Las acusaciones contra el l\u00edder sindical Cesar Chavez. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465820,"url":"https:\/\/noticiasya.com\/tampa\/2025\/08\/24\/julio-cesar-chavez-detencion-narcotrafico-recap-orix\/","url_meta":{"origin":1472361,"position":4},"title":"Las tres ca\u00eddas de Julio C\u00e9sar Ch\u00e1vez Jr.: del ring a su detenci\u00f3n en M\u00e9xico por supuestos v\u00ednculos con el narcotr\u00e1fico","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Hijo de una leyenda del boxeo mexicano, Julio C\u00e9sar Ch\u00e1vez Jr. parec\u00eda destinado a escribir su propia historia dentro del ring. Pero en las \u00faltimas semanas, el pugilista ha protagonizado una sucesi\u00f3n de ca\u00eddas que lo llevaron del cuadril\u00e1tero a enfrentar a la justicia por supuestos v\u00ednculos con el narcotr\u00e1fico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472296,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/17\/cesar-chavez-denuncias-trax\/","url_meta":{"origin":1472361,"position":5},"title":"Cancelan celebraciones en honor a C\u00e9sar Ch\u00e1vez por &#171;graves denuncias&#187; contra el fallecido l\u00edder sindicalista","author":"","date":"marzo 17, 2026","format":false,"excerpt":"El sindicato United Farm Workers no participar\u00e1 este mes en los eventos anuales en honor a su cofundador C\u00e9sar Ch\u00e1vez debido a lo que describe como \u201cgraves denuncias\u201d, las cuales la organizaci\u00f3n no pudo detallar.Las actividades estaban programadas para el D\u00eda de C\u00e9sar Ch\u00e1vez, una festividad estatal en California que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472361"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472361\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}