{"id":1472384,"date":"2026-03-20T10:03:52","date_gmt":"2026-03-20T17:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/"},"modified":"2026-03-20T10:03:52","modified_gmt":"2026-03-20T17:03:52","slug":"dolores-huerta-hechos-calve-vida-biografia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","title":{"rendered":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida"},"content":{"rendered":"<p>La historia de Dolores Huerta es la historia de la lucha por los derechos de los hispanos a comienzos del siglo XX, en medio del controvertido programa de braceros, que por m\u00e1s de XX a\u00f1os permiti\u00f3 a trabajadores mexicanos trabajar en agricultura y en la industria ferroviaria en EE.UU de 1945 a 1964.<\/p>\n<p>El Museo Nacional de la Historia de la Mujer (National Women\u2019s History Museum) califica a Dolores Clara Fernandez Huerta como una de las activistas laborales m\u00e1s influyentes del siglo XX. Y esa influencia continu\u00f3 en el siglo XXI.<\/p>\n<p>Huerta naci\u00f3 el 10 de abril de 1930 en Dawson, Nuevo M\u00e9xico, hija de una trabajadora agr\u00edcola y un minero. Obtuvo un t\u00edtulo de maestr\u00eda, y la biograf\u00eda de la Fundaci\u00f3n Dolores Huerta dice que fue profesora en comunidades agr\u00edcolas brevemente en los a\u00f1os 50 \u201cpero despu\u00e9s de ver muchos ni\u00f1os en el campo llegando a la escuela con hambre, pens\u00f3 que pod\u00eda hacer m\u00e1s para ayudarles, organizando a los agricultores y trabajadores del campo\u201d.<\/p>\n<p>Huerta cuenta tambi\u00e9n que fue motivada a luchar por los derechos civiles por su propia experiencia. Dice que, de estudiante, una profesora la acus\u00f3 de hacer trampa en la escuela porque una de sus tareas estaba muy bien escrita.<\/p>\n<p>En su nueva misi\u00f3n cre\u00f3 la Asociaci\u00f3n de Trabajadores Agr\u00edcolas (Agricultural Workers Association) y les ense\u00f1\u00f3 a los trabajadores a registrarse para votar a la vez que presion\u00f3 a los gobiernos locales para mejorar las comunidades en los campos de California.<\/p>\n<p>En 1955 conoci\u00f3 a Cesar Chavez, el fallecido \u00edcono de los derechos de los campesinos en EE.UU. recientemente <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/18\/eeuu\/acusan-cesar-chavez-abuso-sexual-trax\">acusado de haber cometido abuso sexual<\/a> contra Huerta y otras mujeres, y a comienzos de 1962 lanzaron National Farm Workers Association (Asociaci\u00f3n Nacional de Trabajadores del Campo), un sindicato que cambi\u00f3 las condiciones de los trabajadores agr\u00edcolas en EE.UU. R\u00e1pidamente lograron protecciones para los trabajadores del campo californiano, como asistencia para las familias de los campesinos y seguro por discapacidad.<\/p>\n<p>Es bien documentada la cercan\u00eda ideol\u00f3gica de Huerta con Cesar Chavez, tambi\u00e9n lo es la naturaleza de una din\u00e1mica marcada por acalorados argumentos sobre el rumbo de la organizaci\u00f3n y el rol de cada una de las dos fuertes personalidades que lideraron la lucha por los derechos civiles de los hispanos en la naci\u00f3n.<\/p>\n<p>La fundaci\u00f3n que ella cre\u00f3 en 2002 destaca que Dolores fue crucial en la aprobaci\u00f3n en 1975 de la Ley de Relaciones Laborales, que estableci\u00f3 el derecho de los trabajadores del campo a sindicalizarse, y cre\u00f3 la Junta de Relaciones Laborales Agr\u00edcolas de California con la que se crearon las elecciones y se asegur\u00f3 el cumplimiento de los derechos sindicales.<\/p>\n<p>La pol\u00edtica vino con su activismo. En la larga carrera de Huerta, apoy\u00f3 las campa\u00f1as presidenciales de John F. Kennedy, George McGovern, Al Gore, Howard Dean, Hillary Clinton, Joe Biden y Kamala Harris.<\/p>\n<p>Como una extensi\u00f3n de los derechos de los trabajadores inmigrantes, en a\u00f1os recientes su activismo se enfoc\u00f3 en una reforma inmigratoria, participando en incontables manifestaciones, marchas, protestas, y toda forma de presi\u00f3n pol\u00edtica en los pasillos del poder en Washington. Era dif\u00edcil no ver a Huerta en cada evento posible presionando por d\u00e9cadas en fracasados intentos de reforma migratoria. De hecho, su rol fue crucial en la aprobaci\u00f3n de la \u00faltima reforma migratoria en EE.UU., en 1986, bajo la administraci\u00f3n de Ronald Reagan, que otorg\u00f3 amnist\u00eda a unos 3 millones de personas.<\/p>\n<p>Tiene m\u00e1s de una decena de premios y reconocimientos, como el Derechos Humanos Eleaonor Roosevelt, y en 2012 Barack Obama le otorg\u00f3 el premio civil m\u00e1s alto en EE.UU.: la Medalla Presidencial de la Libertad. En 2015, el Gobierno de M\u00e9xico le entreg\u00f3 la Orden del \u00c1guila Azteca.<\/p>\n<p>Cuatro universidades le han otorgado t\u00edtulos honorarios, varias escuelas p\u00fablicas en Oklahoma y en California tienen su nombre, al igual que calles, plazas y autopistas en Texas y California.<\/p>\n<p>Desde 2018 California el 10 de abril es el d\u00eda de Dolores Huerta, para una mujer que, a punto de cumplir 96 a\u00f1os, sigue vigente y ahora forma parte de un sacud\u00f3n en la percepci\u00f3n de muchos que veneraron al ic\u00f3nico Cesar Chavez por d\u00e9cadas, al revelar un secreto de abuso y violaci\u00f3n sexual por parte de Ch\u00e1vez, que dice que guard\u00f3 por d\u00e9cadas, en parte por temor a que no se le creyera y en parte por proteger al movimiento por el que trabaj\u00f3 toda la vida. Por esa revelaci\u00f3n, los archivos hist\u00f3ricos tendr\u00e1n que hacer ajustes.<\/p>\n<p>Dolores Huerta se cas\u00f3 dos veces, y adem\u00e1s tuvo una larga relaci\u00f3n oficial con Richard Ch\u00e1vez (hermano de Cesar). Tuvo 11 hijos en total, m\u00e1s dos hijas que acaba de revelar, como producto de lo que denunci\u00f3 como dos relaciones \u00edntimas no consensuadas con Cesar Chavez. Dolores Huerta dice que, despu\u00e9s de d\u00e9cadas de silencio, ahora hace parte de la historia de mujeres v\u00edctimas y sobrevivientes de abuso sexual, que espera que ya no deban callar su tragedia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La historia de Dolores Huerta es la historia de la lucha por los derechos de los hispanos a comienzos del siglo XX, en medio del controvertido programa de braceros, que por m\u00e1s de XX a\u00f1os permiti\u00f3 a trabajadores mexicanos trabajar en agricultura y en la industria ferroviaria en EE.UU de 1945 a 1964. El Museo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472384","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias\" \/>\n<meta property=\"og:description\" content=\"La historia de Dolores Huerta es la historia de la lucha por los derechos de los hispanos a comienzos del siglo XX, en medio del controvertido programa de braceros, que por m\u00e1s de XX a\u00f1os permiti\u00f3 a trabajadores mexicanos trabajar en agricultura y en la industria ferroviaria en EE.UU de 1945 a 1964. El Museo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T17:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida\",\"datePublished\":\"2026-03-20T17:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\"},\"wordCount\":904,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\",\"name\":\"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T17:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias","og_description":"La historia de Dolores Huerta es la historia de la lucha por los derechos de los hispanos a comienzos del siglo XX, en medio del controvertido programa de braceros, que por m\u00e1s de XX a\u00f1os permiti\u00f3 a trabajadores mexicanos trabajar en agricultura y en la industria ferroviaria en EE.UU de 1945 a 1964. El Museo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-20T17:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/"},"author":{"name":"","@id":""},"headline":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida","datePublished":"2026-03-20T17:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/"},"wordCount":904,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","name":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T17:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Dolores Huerta, \u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/20\/dolores-huerta-hechos-calve-vida-biografia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T17:03:52Z","datePublished":"2026-03-20T17:03:52Z","dateModified":"2026-03-20T17:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Dolores Huerta, \\u00edcono de los derechos de los trabajadores: tres hechos que debes saber sobre su vida\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/20\\\/dolores-huerta-hechos-calve-vida-biografia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/20\\\/dolores-huerta-hechos-calve-vida-biografia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T17:03:52Z\",\"datePublished\":\"2026-03-20T17:03:52Z\",\"dateModified\":\"2026-03-20T17:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472315,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/18\/acusan-cesar-chavez-abuso-sexual-trax\/","url_meta":{"origin":1472384,"position":0},"title":"Acusan a Cesar Chavez, l\u00edder de los trabajadores agr\u00edcolas en el siglo XX, de haber cometido abusos sexuales durante d\u00e9cadas","author":"","date":"marzo 18, 2026","format":false,"excerpt":"L\u00edderes latinos y funcionarios elegidos afirman estar conmocionados por las acusaciones \u201cprofundamente perturbadoras\u201d de conducta sexual inapropiada contra Cesar Chavez, uno de los \u00edconos de los derechos civiles m\u00e1s destacados de la comunidad latina, en un momento en el que se est\u00e1n cancelando las celebraciones anuales previstas en honor al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472361,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/19\/cesar-chavez-comunidades-reconsiderar-homenajes-trax\/","url_meta":{"origin":1472384,"position":1},"title":"Acusaciones de abuso contra Cesar Chavez obligan a las comunidades a reconsiderar los homenajes al l\u00edder latino","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Una figura cubierta por una s\u00e1bana permaneci\u00f3 el mi\u00e9rcoles en el Jard\u00edn de la Paz de la Universidad Estatal de Fresno, en California, como un fantasma en la penumbra. La gran s\u00e1bana negra, sostenida torpemente con clips de pl\u00e1stico, ocultaba la estatua de Cesar Chavez, quien pas\u00f3 d\u00e9cadas bajo los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472296,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/17\/cesar-chavez-denuncias-trax\/","url_meta":{"origin":1472384,"position":2},"title":"Cancelan celebraciones en honor a C\u00e9sar Ch\u00e1vez por &#171;graves denuncias&#187; contra el fallecido l\u00edder sindicalista","author":"","date":"marzo 17, 2026","format":false,"excerpt":"El sindicato United Farm Workers no participar\u00e1 este mes en los eventos anuales en honor a su cofundador C\u00e9sar Ch\u00e1vez debido a lo que describe como \u201cgraves denuncias\u201d, las cuales la organizaci\u00f3n no pudo detallar.Las actividades estaban programadas para el D\u00eda de C\u00e9sar Ch\u00e1vez, una festividad estatal en California que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1429581,"url":"https:\/\/noticiasya.com\/tampa\/2022\/09\/29\/gobernador-de-california-firma-ley-para-ampliar-los-derechos-de-los-trabajores-agricolas\/","url_meta":{"origin":1472384,"position":3},"title":"Gobernador de California firma ley para ampliar los derechos de los trabajores agr\u00edcolas","author":"agomez","date":"septiembre 29, 2022","format":false,"excerpt":"La ley AB 2183 fue firmada por Newsom este mi\u00e9rcoles junto con defensores y trabajadores agr\u00edcolas fuera del capitolio estatal.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/tampa\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444943,"url":"https:\/\/noticiasya.com\/tampa\/2024\/02\/05\/cual-es-el-origen-del-dia-de-la-constitucion-de-mexico-y-por-que-se-celebra-el-5-de-febrero\/","url_meta":{"origin":1472384,"position":4},"title":"\u00bfCu\u00e1l es el origen del D\u00eda de la Constituci\u00f3n de M\u00e9xico y por qu\u00e9 se celebra el 5 de febrero?","author":"agomez","date":"febrero 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Constituci\u00f3n de 1917, que rige el sistema pol\u00edtico y ordenamiento jur\u00eddico de M\u00e9xico desde hace m\u00e1s de 100 a\u00f1os, fue producto de la Revoluci\u00f3n mexicana, el movimiento que sac\u00f3 del poder al dictador Porfirio D\u00edaz y transform\u00f3 las estructuras pol\u00edticas y sociales del pa\u00eds.La Constituci\u00f3n Pol\u00edtica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473201,"url":"https:\/\/noticiasya.com\/tampa\/2026\/04\/15\/zoe-saldana-wagner-moura-100-influyentes-time-orix\/","url_meta":{"origin":1472384,"position":5},"title":"Zoe Salda\u00f1a, Wagner Moura y Claudia Sheinbaum, entre las 100 personas m\u00e1s influyentes del mundo, seg\u00fan la revista TIME","author":"","date":"abril 15, 2026","format":false,"excerpt":"La revista TIME dio a conocer este mi\u00e9rcoles su lista anual de las 100 personas m\u00e1s influyentes del mundo, en la que incluy\u00f3 a una decena de figuras de Iberoam\u00e9rica, entre las que destacan la presidenta de M\u00e9xico, Claudia Sheinbaum, y, retratados en portada el brasile\u00f1o Wagner Moura y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472384"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472384\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}