{"id":1472389,"date":"2026-03-20T12:03:43","date_gmt":"2026-03-20T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/"},"modified":"2026-03-20T12:03:43","modified_gmt":"2026-03-20T19:03:43","slug":"operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","title":{"rendered":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum"},"content":{"rendered":"<p>Luego de operativos de las fuerzas armadas de M\u00e9xico el jueves en Sinaloa, una de las hijas de Ismael \u201cMayo\u201d Zambada Garc\u00eda \u2014se\u00f1alado como uno de los fundadores del Cartel de Sinaloa y que en agosto de 2025 <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/25\/eeuu\/ismael-mayo-zambada-declara-culpable-orix\">se declar\u00f3 culpable<\/a> de cargos de narcotr\u00e1fico en Estados Unidos\u2014 fue puesta bajo custodia \u201cde manera moment\u00e1nea\u201d y luego se le liber\u00f3 al constatar que no ten\u00eda \u201cning\u00fan mandamiento judicial ni en M\u00e9xico ni en Estados Unidos\u201d, inform\u00f3 el Gobierno de Claudia Sheinbaum.<\/p>\n<p>La Secretar\u00eda de Marina (Semar), a trav\u00e9s de la Armada de M\u00e9xico, llev\u00f3 a cabo operativos el jueves en Sinaloa. En uno de ellos, <a href=\"https:\/\/x.com\/SEMAR_mx\/status\/2034721355522810131\">inform\u00f3 en un comunicado<\/a>, se detuvo a \u201cun integrante\u201d de \u201cla facci\u00f3n Los Mayos del Cartel de Sinaloa\u201d y \u201ctambi\u00e9n se localiz\u00f3 a una mujer, identificada como hija de un l\u00edder criminal, quien no cuenta con relaci\u00f3n con actividades delictivas ni mandamientos legales en su contra, por lo que fue liberada\u201d.<\/p>\n<p>Omar Garc\u00eda Harfuch, secretario de Seguridad y Protecci\u00f3n Ciudadana a nivel federal, identific\u00f3 este viernes al detenido como Omar Osvaldo \u201cN\u201d y dijo que \u201cesta persona cuenta con una orden de aprehensi\u00f3n en San Diego, Calfornia, en Estados Unidos\u201d.<\/p>\n<p>En tanto, Garc\u00eda Harfuch identific\u00f3 a la mujer como M\u00f3nica del Rosario \u201cN\u201d, quien en el momento del operativo se encontraba con una menor de edad.<\/p>\n<p>El secretario federal de Seguridad no dio el nombre completo de esta mujer; sin embargo, luego de ser cuestionado sobre m\u00e1s detalles que involucraban la posible detenci\u00f3n de una hija del cofundador del Cartel de Sinaloa, Garc\u00eda Harfuch dio informaci\u00f3n con la que se le puede identificar como M\u00f3nica del Rosario Zambada Niebla, hija del Mayo.<\/p>\n<p>\u201c(En el operativo) ella nunca fue detenida. De manera moment\u00e1nea estuvo bajo custodia, primero, para resguardar la seguridad de todos los que estaban, de los elementos de seguridad y tambi\u00e9n de las personas, incluyendo la menor de edad; y (segundo) sobre todo para verificar si ten\u00eda un mandamiento judicial aqu\u00ed en M\u00e9xico o en Estados Unidos. No tiene ning\u00fan mandamiento judicial ni en M\u00e9xico ni en EE.UU.\u201d, explic\u00f3 Harfuch.<\/p>\n<p>Enseguida, el secretario de Seguridad afirm\u00f3 que la mujer \u201cfue designada\u2026 en 2007\u201d en la lista de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), perteneciente al Departamento del Tesoro de EE.UU.<\/p>\n<p>\u201cEst\u00e1 designada en esa lista, donde son m\u00e1s o menos 311 personas, de las cuales m\u00e1s de 200 son personas morales (empresas) y el resto personas f\u00edsicas. Sin embargo, es un proceso administrativo. Desde hace casi 20 a\u00f1os que fue designada, no tiene orden de aprehensi\u00f3n ni en M\u00e9xico ni en Estados Unidos. Una vez que se corrobora esto, es entregada a sus familiares\u201d, a\u00f1adi\u00f3 Garc\u00eda Harfuch.<\/p>\n<p>M\u00f3nica del Rosario Zambada Niebla \u2014as\u00ed como otras tres hijas del Mayo Zambada y su exesposa\u2014 fue a\u00f1adida a la lista de Nacionales Especialmente Designados y Personas Bloqueadas (conocida como lista SDN) de la OFAC en <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/hp410\">mayo de 2007<\/a>.<\/p>\n<p>La OFAC incluye en esta lista tanto a empresas como a \u201cpersonas, grupos o entidades, como terroristas y narcotraficantes\u201d, designados bajo programas de sanciones contra pa\u00edses espec\u00edficos o de sanciones sin un pa\u00eds relacionado. Cuando una persona o entidad est\u00e1 en la lista de la OFAC, \u201csus activos quedan bloqueados y, por norma general, se proh\u00edbe a las personas estadounidenses realizar transacciones con ellos.\u201d, <a href=\"https:\/\/ofac.treasury.gov\/faqs\/topic\/1631\">menciona<\/a> la oficina.<\/p>\n<p>En <a href=\"https:\/\/ofac.treasury.gov\/recent-actions\/20070517\">2007<\/a>, M\u00f3nica del Rosario Zambada Niebla fue incluida en la lista SDN <a href=\"https:\/\/ofac.treasury.gov\/specially-designated-nationals-list-sdn-list\/program-tag-definitions-for-ofac-sanctions-lists#:~:text=Narcotics-,%5BSDNTK%5D,-Foreign%20Narcotics%20Kingpin\">bajo el programa<\/a> de sanciones contra cabecillas extranjeros del narcotr\u00e1fico (abreviado en ingl\u00e9s como SDNTK). En ese momento, el Departamento del Tesoro estadounidense <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/hp410\">dijo<\/a> que su designaci\u00f3n se deb\u00eda a \u201csu papel en la propiedad o el control de empresas fachada y activos de (Ismael) Zambada Garc\u00eda en M\u00e9xico\u201d.<\/p>\n<p>Seg\u00fan <a href=\"https:\/\/sanctionssearch.ofac.treas.gov\/Details.aspx?id=10357\">informaci\u00f3n de la OFAC<\/a>, Zambada Niebla naci\u00f3 en Culiac\u00e1n, Sinaloa, y tiene o est\u00e1 por cumplir 46 a\u00f1os.<\/p>\n<p>CNN consult\u00f3 a la Semar de M\u00e9xico para conocer m\u00e1s detalles de los operativos y las personas involucradas, y est\u00e1 en espera de respuesta.<\/p>\n<p>En el <a href=\"https:\/\/www.gob.mx\/sspc\/prensa\/tarjeta-informativa-421717\">comunicado<\/a> del jueves, la Semar agreg\u00f3 que, en otro de los operativos en Sinaloa, se ubic\u00f3 un inmueble \u201cutilizado por integrantes de una c\u00e9lula delictiva af\u00edn a Los Mayos\u201d.<\/p>\n<p>\u201cAl arribar al sitio, el personal naval fue objeto de una agresi\u00f3n, por lo que, en apego al marco legal vigente, repeli\u00f3 el ataque. Como resultado de estos hechos, de manera preliminar, 11 agresores vinculados con el mismo grupo criminal perdieron la vida\u201d, dijo la Marina de M\u00e9xico.<\/p>\n<p>Asimismo, la Semar indic\u00f3 que en el lugar donde se encontraban estas personas se aseguraron \u201carmas de alto poder y equipo t\u00e1ctico\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de operativos de las fuerzas armadas de M\u00e9xico el jueves en Sinaloa, una de las hijas de Ismael \u201cMayo\u201d Zambada Garc\u00eda \u2014se\u00f1alado como uno de los fundadores del Cartel de Sinaloa y que en agosto de 2025 se declar\u00f3 culpable de cargos de narcotr\u00e1fico en Estados Unidos\u2014 fue puesta bajo custodia \u201cde manera moment\u00e1nea\u201d [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472389","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &quot;bajo custodia&quot;, pero fue liberada, dice el Gobierno de Sheinbaum - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &quot;bajo custodia&quot;, pero fue liberada, dice el Gobierno de Sheinbaum - Noticias\" \/>\n<meta property=\"og:description\" content=\"Luego de operativos de las fuerzas armadas de M\u00e9xico el jueves en Sinaloa, una de las hijas de Ismael \u201cMayo\u201d Zambada Garc\u00eda \u2014se\u00f1alado como uno de los fundadores del Cartel de Sinaloa y que en agosto de 2025 se declar\u00f3 culpable de cargos de narcotr\u00e1fico en Estados Unidos\u2014 fue puesta bajo custodia \u201cde manera moment\u00e1nea\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum\",\"datePublished\":\"2026-03-20T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\",\"name\":\"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo \\\"bajo custodia\\\", pero fue liberada, dice el Gobierno de Sheinbaum - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo \"bajo custodia\", pero fue liberada, dice el Gobierno de Sheinbaum - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo \"bajo custodia\", pero fue liberada, dice el Gobierno de Sheinbaum - Noticias","og_description":"Luego de operativos de las fuerzas armadas de M\u00e9xico el jueves en Sinaloa, una de las hijas de Ismael \u201cMayo\u201d Zambada Garc\u00eda \u2014se\u00f1alado como uno de los fundadores del Cartel de Sinaloa y que en agosto de 2025 se declar\u00f3 culpable de cargos de narcotr\u00e1fico en Estados Unidos\u2014 fue puesta bajo custodia \u201cde manera moment\u00e1nea\u201d [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-20T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/"},"author":{"name":"","@id":""},"headline":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum","datePublished":"2026-03-20T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","name":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo \"bajo custodia\", pero fue liberada, dice el Gobierno de Sheinbaum - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/20\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T19:03:43Z","datePublished":"2026-03-20T19:03:43Z","dateModified":"2026-03-20T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tras operativos en Sinaloa, hija del Mayo Zambada estuvo &#171;bajo custodia&#187;, pero fue liberada, dice el Gobierno de Sheinbaum\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/20\\\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/20\\\/operativos-sinaloa-hija-mayo-zambada-liberada-sheinbaum-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T19:03:43Z\",\"datePublished\":\"2026-03-20T19:03:43Z\",\"dateModified\":\"2026-03-20T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451425,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/25\/detienen-ismael-el-mayo-zambada-cartel-de-sinaloa-trax\/","url_meta":{"origin":1472389,"position":0},"title":"Detienen en Texas a &#171;El Mayo&#187; Zambada y a un hijo de &#171;El Chapo&#187; Guzm\u00e1n","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- Dos presuntos l\u00edderes del c\u00e1rtel de Sinaola fueron detenidos este jueves en El Paso, Texas, y se encuentran bajo custodia estadounidense, inform\u00f3 este jueves El Departamento de Justicia de EE.UU.Los detenidos son Ismael \u201cEl Mayo\u201d Zambada Garc\u00eda, cofundador y supuesto l\u00edder del c\u00e1rtel y Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451873,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/14\/muerto-desaparecido-piloto-incognitas-arresto-caso-zambada-orix\/","url_meta":{"origin":1472389,"position":1},"title":"Un muerto, un desaparecido y un piloto sin identificar, algunas de las inc\u00f3gnitas en la trama que rodea el caso Zambada","author":"","date":"agosto 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- A tres semanas del arresto en Estados Unidos de los presuntos narcotraficantes Ismael \u201cel Mayo\u201d Zambada y Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo de Joaqu\u00edn \u201cel Chapo\u201d Guzm\u00e1n, el Gobierno de M\u00e9xico est\u00e1 insatisfecho con la versi\u00f3n que ofreci\u00f3 el Gobierno estadounidense y decidi\u00f3 abrir su propia investigaci\u00f3n a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451426,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/25\/quien-ismael-el-mayo-zambada-cartel-sinaloa-orix\/","url_meta":{"origin":1472389,"position":2},"title":"\u00bfQui\u00e9n es Ismael \u2018El Mayo\u2019 Zambada, presunto l\u00edder del c\u00e1rtel de Sinaloa detenido en EE.UU.?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Ismael \u2018El Mayo\u2019 Zambada se encuentra bajo custodia de Estados Unidos, confirm\u00f3 a CNN una fuente diplom\u00e1tica con conocimiento del caso.'El Mayo' Zambada es cofundador y presunto l\u00edder actual del c\u00e1rtel de Sinaloa. Su nombre ha aparecido durante a\u00f1os en los expedientes del narcotr\u00e1fico. Supuestamente, operaba principalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451457,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/26\/lideres-narcotrafico-detenidos-extraditados-sexenio-amlo-orix\/","url_meta":{"origin":1472389,"position":3},"title":"L\u00edderes del narcotr\u00e1fico detenidos y extraditados durante el sexenio de Andr\u00e9s Manuel L\u00f3pez Obrador","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Desde 2020, autoridades de M\u00e9xico y Estados Unidos han detenido y extraditado a seis l\u00edderes del narcotr\u00e1fico: Jos\u00e9 Antonio Y\u00e9pez, Rafael Caro Quintero, Ovidio Guzm\u00e1n, N\u00e9stor Isidoro P\u00e9rezs, Ismael Zambada y Joaqu\u00edn Guzm\u00e1n L\u00f3pez.Jos\u00e9 Antonio Y\u00e9pez, \u201cEl Marro\u201d (agosto de 2020)Jos\u00e9 Antonio Y\u00e9pez, \u201cEl Marro\u201d. (Cr\u00e9dito: Creative Commons)Jos\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468917,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/03\/joaquin-guzman-lopez-secuestro-mayo-zambada-orix\/","url_meta":{"origin":1472389,"position":4},"title":"Enga\u00f1ado, esposado y sedado: as\u00ed fue el &#171;secuestro&#187; del Mayo Zambada antes de su detenci\u00f3n en EE.UU., seg\u00fan Guzm\u00e1n L\u00f3pez","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Fue una de las noticias m\u00e1s sonadas del a\u00f1o pasado. No era para menos. Se trataba de la detenci\u00f3n en Estados Unidos de dos de los l\u00edderes del Cartel de Sinaloa, uno de los m\u00e1s poderosos y conocidos dentro y fuera de M\u00e9xico. Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo de Joaqu\u00edn \u201cChapo\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451466,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/27\/que-pasara-cartel-de-sinaloa-captura-dos-lideres-que-mexico-orix\/","url_meta":{"origin":1472389,"position":5},"title":"\u00bfQu\u00e9 pasar\u00e1 con el C\u00e1rtel de Sinaloa tras la captura de dos de sus l\u00edderes y qu\u00e9 significa para M\u00e9xico?","author":"","date":"julio 27, 2024","format":false,"excerpt":"(CNN) -- En una operaci\u00f3n silenciosa, Estados Unidos arrest\u00f3 el jueves en El Paso, Texas, a dos importantes l\u00edderes del C\u00e1rtel de Sinaloa: Ismael Zambada Garc\u00eda, conocido como \"El Mayo\", un narcotraficante mexicano buscado desde hace mucho tiempo, y Joaqu\u00edn Guzm\u00e1n L\u00f3pez, hijo del convicto narcotraficante Joaqu\u00edn \"El Chapo\" Guzm\u00e1n.\"Fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472389"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472389\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}