{"id":1472437,"date":"2026-03-21T23:03:41","date_gmt":"2026-03-22T06:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/"},"modified":"2026-03-21T23:03:41","modified_gmt":"2026-03-22T06:03:41","slug":"banksy-desenmascarado-anonimato-arte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","title":{"rendered":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?"},"content":{"rendered":"<p>El mayor misterio del <a href=\"https:\/\/www.cnn.com\/2026\/03\/17\/style\/singapore-nft-vignesh-sundaresan-beeple-everydays\">mundo del arte<\/a> aparentemente fue resuelto: <a href=\"https:\/\/www.cnn.com\/2025\/11\/14\/uk\/banksy-girl-with-balloon-theft-man-jailed-latam-intl\">Banksy<\/a> fue desenmascarado como un hombre de mediana edad, con gafas, de Bristol, Inglaterra, llamado Robin Gunningham.<\/p>\n<p>Su nombre fue revelado en una amplia investigaci\u00f3n de <a href=\"https:\/\/www.reuters.com\/investigates\/special-report\/global-art-banksy\/\">Reuters<\/a>, aunque muchos dicen que ha sido un secreto a voces durante a\u00f1os, ya que el tabloide brit\u00e1nico <a href=\"https:\/\/www.dailymail.co.uk\/news\/article-1034613\/Banksy-uncovered-The-nice-middle-class-boy-graffiti-guerrilla.html\">Mail on Sunday<\/a> lo inform\u00f3 ya en 2008.<\/p>\n<p>Fiel a su estilo, el artista anteriormente conocido como Banksy no ha confirmado ni desmentido su identidad y sigue manteniendo un perfil bajo. Sus representantes no respondieron a una solicitud de comentarios de CNN.<\/p>\n<p>C\u00f3mo afectar\u00e1 la revelaci\u00f3n \u2014que acapar\u00f3 titulares en todo el mundo\u2014 a su producci\u00f3n y a su valor sigue siendo incierto.<\/p>\n<p>Banksy no es el \u00fanico que prefiere permanecer en el anonimato. Entre los artistas que ocultan su identidad est\u00e1 Jerkface, un artista callejero de Nueva York conocido por sus interpretaciones \u00fanicas de personajes animados muy queridos.<\/p>\n<p>En un correo electr\u00f3nico a CNN \u2014que no revel\u00f3 su identidad\u2014, Jerkface dijo que el anonimato ha sido valorado desde hace mucho tiempo en las artes.<\/p>\n<p>\u201cSi miras todos los campos creativos, el arte visual es uno de los pocos en los que se puede expresar algo sin la necesidad de revelar la propia identidad\u201d, dijo. \u201cLos actores y los m\u00fasicos cambian su nombre real, pero a menudo no pueden ocultar f\u00e1cilmente su rostro. Los escritores han estado ocultando su identidad durante siglos\u201d.<\/p>\n<p>\u201cCreo que a la gente le gusta la honestidad de una persona abiertamente inventada\u201d, dijo Jerkface. \u201cLa gente que aprecia a estos artistas no quiere saber qui\u00e9n est\u00e1 detr\u00e1s de la m\u00e1scara. Arruina el misterio\u201d.<\/p>\n<p>A\u00f1adi\u00f3: \u201cHay una verdadera decepci\u00f3n con que se revele la identidad de Banksy. Es como decirle a alguien que la lucha libre no es real. Ya lo saben. No est\u00e1n buscando una prueba detallada\u201d.<\/p>\n<p>Nico Epstein es un consultor de arte radicado en Lisboa que tambi\u00e9n dirige una plataforma de arte en l\u00ednea llamada Collector Connoisseur y da clases en la casa de subastas Christie\u2019s sobre c\u00f3mo coleccionar y evaluar arte. Dijo a CNN que desde hace tiempo hab\u00eda \u201crumores\u201d en la industria sobre Gunningham, pero que est\u00e1 \u201cdecepcionado\u201d de que se confirmen.<\/p>\n<p>\u201cQuer\u00eda que el recuerdo del artista an\u00f3nimo \u2014y el misterio detr\u00e1s de eso\u2014 siguiera vivo. Banksy es un superh\u00e9roe para much\u00edsima gente. La gente quiere creer en ese cuento de hadas y ahora se ha terminado\u201d.<\/p>\n<p>Dijo que le hab\u00eda gustado la \u201cneutralidad\u201d de no saber si Banksy era hombre o mujer, ni cu\u00e1l era su origen. \u201cAhora que se ha vinculado de forma definitiva con un viejo tipo blanco de Bristol, ya no me interesa tanto\u201d.<\/p>\n<p>Banksy hizo grandes esfuerzos por preservar su anonimato, pero es probable que al principio haya surgido por necesidad. \u201cSer un artista an\u00f3nimo y misterioso era parte del personaje, pero tambi\u00e9n era una cuesti\u00f3n pr\u00e1ctica que le permit\u00eda evitar ser detectado por las fuerzas del orden\u201d, dijo Epstein.<\/p>\n<p>Es probable que la revelaci\u00f3n de Gunningham afecte el trabajo de Banksy, dijo Epstein, quien cree que el valor de su arte ya estaba cayendo.<\/p>\n<p>Las obras de Banksy se venden por sumas enormes. En 2021, \u201cLove is in the Bin\u201d, la pintura que se autodestruy\u00f3 parcialmente en una subasta tres a\u00f1os antes, se vendi\u00f3 por la <a href=\"https:\/\/www.cnn.com\/style\/article\/banksy-sothebys-shredded-painting-sale-results\">asombrosa cifra<\/a> de 18,5 millones de libras (US$ 25,4 millones).<\/p>\n<p>\u201cLa gran pregunta es si seguir\u00e1 siendo capaz de hacer obras interesantes ahora que ha quedado al descubierto\u201d, dijo Epstein, citando las creaciones \u201cic\u00f3nicas\u201d de Banksy en Ucrania y la Ribera Occidental. \u201cCreo que le ser\u00eda m\u00e1s dif\u00edcil hacer eso y creo que habr\u00e1 una cierta ca\u00edda en la producci\u00f3n y en el valor financiero\u201d.<\/p>\n<p>Dicho esto, pasar del anonimato a ser un artista con nombre no perjudic\u00f3 a figuras como Jean-Michel Basquiat, que empez\u00f3 como el grafitero SAMO, o Brian Donnelly, conocido profesionalmente como KAWS. Pero esos ejemplos, seg\u00fan Epstein, son raros.<\/p>\n<p>\u201cPiensa en todos los artistas callejeros que no han tenido ning\u00fan reconocimiento. Tal vez quieren poder firmar trenes y vallas publicitarias y hacer lo suyo sin ser reconocidos de esa manera. Hay muchos artistas que mantienen ese anonimato, pero no van a ser reconocidos del mismo modo por la historia del arte\u201d.<\/p>\n<p>Los motivos para el anonimato var\u00edan, como explic\u00f3 el artista detr\u00e1s de Hey Reilly, una <a href=\"https:\/\/www.instagram.com\/hey_reilly\/?hl=en\">popular cuenta de Instagram<\/a> que se burla de celebridades con im\u00e1genes alteradas mediante IA.<\/p>\n<p>\u201cPara un artista callejero, el anonimato suele ser un escudo contra el enjuiciamiento; para m\u00ed, es una herramienta de libertad creativa\u201d, dijo el artista, identificado solo como Reilly.<\/p>\n<p>En un correo electr\u00f3nico a CNN, contaron que su anonimato es un subproducto de la \u201ctimidez\u201d y de una evitaci\u00f3n de toda la vida a ser fotografiados. Aunque a menudo a la gente le resulta \u201cdesconcertante\u201d, Reilly dijo que el anonimato les hace sentirse \u201cm\u00e1s libres\u201d.<\/p>\n<p>\u201cEn una cultura obsesionada con el \u2018looksmaxxing\u2019 y la actuaci\u00f3n constante del selfie, hay un enorme alivio en simplemente decir: \u2018No\u2019. Negarse a participar en ese nivel de autoexposici\u00f3n no es solo una elecci\u00f3n personal; es una postura antimoderna. Es una forma de recuperar tu libertad frente a un sistema que exige que conviertas tu cara en una marca antes de que se te permita ser artista\u201d, dijeron.<\/p>\n<p>\u201cEn esencia, el anonimato me permiti\u00f3 esquivar el constructo de \u2018m\u00edrenme\u2019 de las redes sociales, con el que simplemente no ten\u00eda ganas de lidiar. Pero al despojarse de la identidad personal, la obra adquiere una resonancia m\u00e1s universal\u201d, dijo Reilly.<\/p>\n<p>\u201cCuando s\u00ed me encuentro con seguidores en la vida real, tenemos este maravilloso momento \u2018El mago de Oz\u2019 de conexi\u00f3n genuina, solo que sin el selfie\u201d.<\/p>\n<p>Aunque suele asociarse con las artes visuales, el anonimato es com\u00fan en otras disciplinas, incluida la m\u00fasica, con estrellas que antes fueron an\u00f3nimas como la cantante australiana <a href=\"https:\/\/www.siamusic.net\/\">Sia<\/a> y el d\u00fao franc\u00e9s de electr\u00f3nica <a href=\"https:\/\/www.daftpunk.com\/\">Daft Punk<\/a>.<\/p>\n<p>En la literatura, las hermanas Bront\u00eb intentaron contrarrestar los prejuicios contra las mujeres publicando como hombres, mientras que el seud\u00f3nimo George Eliot hace tiempo que eclips\u00f3 el nombre real de la escritora victoriana: Mary Ann Evans.<\/p>\n<p>Mucho m\u00e1s recientemente, <a href=\"https:\/\/elenaferrante.com\/\">Elena Ferrante<\/a>, el seud\u00f3nimo de la autora italiana de la aclamada serie napolitana de novelas, que comienza con \u201cMy Brilliant Friend\u201d, ha vendido millones de libros en todo el mundo. Al igual que con Banksy, la especulaci\u00f3n febril ha llevado a muchos a intentar identificarla, pero hasta la fecha no se ha demostrado nada.<\/p>\n<p>Un desenmascaramiento exitoso y de alto perfil fue el de Robert Galbraith, autor de la serie detectivesca de Cormoran Strike. Cuando el primer libro de Galbraith, \u201cThe Cuckoo\u2019s Calling\u201d, sali\u00f3 en 2013, su editorial describi\u00f3 al escritor como un exmiembro de la Rama de Investigaci\u00f3n Especial de la Polic\u00eda Militar Real. Esto, suger\u00edan, explicaba la necesidad de un seud\u00f3nimo.<\/p>\n<p>Pero pronto se descubri\u00f3 la verdad cuando <a href=\"https:\/\/www.thetimes.com\/life-style\/celebrity\/article\/jk-rowling-the-cuckoo-in-crime-novel-nest-zfnz023tkbv\">The Sunday Times<\/a> revel\u00f3 que no era otro que J. K. Rowling. Cuando se conoci\u00f3 la noticia, Rowling dijo que la privacidad hab\u00eda sido \u201cliberadora\u201d, permiti\u00e9ndole publicar \u201csin bombo ni expectativas\u201d.<\/p>\n<p>Friendred Peng, profesor titular en la University of the Arts London, dijo a CNN que hay \u201calgo profundamente cautivador en el anonimato\u201d.<\/p>\n<p>\u201cEn una cultura en la que la identidad a menudo enmarca la interpretaci\u00f3n, eliminarla permite que la obra se experimente sin sesgos ligados al origen, el g\u00e9nero o la reputaci\u00f3n, desplazando la atenci\u00f3n del autor a la idea en s\u00ed\u201d, dijo.<\/p>\n<p>\u201cNos sentimos instintivamente atra\u00eddos por el mito, y las figuras an\u00f3nimas generan intriga y narrativas culturales que pueden amplificar tanto la visibilidad como el significado.<\/p>\n<p>\u201cPero cuando se rompe el anonimato, esa din\u00e1mica cambia. La obra puede volver a anclarse al contexto personal, lo que puede reducir su universalidad al reintroducir la biograf\u00eda y, en ocasiones, los prejuicios. Por esta raz\u00f3n, el anonimato debe entenderse no como una ausencia, sino como una elecci\u00f3n art\u00edstica activa y significativa\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mayor misterio del mundo del arte aparentemente fue resuelto: Banksy fue desenmascarado como un hombre de mediana edad, con gafas, de Bristol, Inglaterra, llamado Robin Gunningham. Su nombre fue revelado en una amplia investigaci\u00f3n de Reuters, aunque muchos dicen que ha sido un secreto a voces durante a\u00f1os, ya que el tabloide brit\u00e1nico Mail [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472437","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El mayor misterio del mundo del arte aparentemente fue resuelto: Banksy fue desenmascarado como un hombre de mediana edad, con gafas, de Bristol, Inglaterra, llamado Robin Gunningham. Su nombre fue revelado en una amplia investigaci\u00f3n de Reuters, aunque muchos dicen que ha sido un secreto a voces durante a\u00f1os, ya que el tabloide brit\u00e1nico Mail [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-22T06:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?\",\"datePublished\":\"2026-03-22T06:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\"},\"wordCount\":1412,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\",\"name\":\"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-22T06:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias","og_description":"El mayor misterio del mundo del arte aparentemente fue resuelto: Banksy fue desenmascarado como un hombre de mediana edad, con gafas, de Bristol, Inglaterra, llamado Robin Gunningham. Su nombre fue revelado en una amplia investigaci\u00f3n de Reuters, aunque muchos dicen que ha sido un secreto a voces durante a\u00f1os, ya que el tabloide brit\u00e1nico Mail [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-22T06:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/"},"author":{"name":"","@id":""},"headline":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?","datePublished":"2026-03-22T06:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/"},"wordCount":1412,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","name":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-22T06:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Desenmascaran a Banksy. Pero, \u00bfqu\u00e9 tan valioso es el anonimato en el mundo del arte?","url":"http:\/\/noticiasya.com\/tampa\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2026\/03\/21\/banksy-desenmascarado-anonimato-arte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-22T06:03:41Z","datePublished":"2026-03-22T06:03:41Z","dateModified":"2026-03-22T06:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Desenmascaran a Banksy. Pero, \\u00bfqu\\u00e9 tan valioso es el anonimato en el mundo del arte?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/21\\\/banksy-desenmascarado-anonimato-arte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2026\\\/03\\\/21\\\/banksy-desenmascarado-anonimato-arte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-22T06:03:41Z\",\"datePublished\":\"2026-03-22T06:03:41Z\",\"dateModified\":\"2026-03-22T06:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1442534,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/23\/retiran-de-la-calle-una-obra-de-banksy-menos-de-una-hora-despues-de-que-la-publicara-en-linea\/","url_meta":{"origin":1472437,"position":0},"title":"Retiran de la calle una obra de Banksy menos de una hora despu\u00e9s de que la publicara en l\u00ednea","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN) -- Una nueva obra de Banksy fue retirada de una calle de Londres poco despu\u00e9s de que el artista la publicara en Instagram, seg\u00fan reportes.El artista public\u00f3 una serie de fotos de la obra \u2014que consiste en tres drones en una se\u00f1al de alto\u2014 en las redes sociales alrededor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473698,"url":"https:\/\/noticiasya.com\/tampa\/2026\/05\/01\/nueva-estatua-banksy-satiriza-patriotismo-ciego-trax\/","url_meta":{"origin":1472437,"position":1},"title":"La nueva estatua londinense de Banksy, que ondea una bandera, satiriza el patriotismo ciego","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Banksy ha confirmado que \u00e9l es el autor de una gran estatua que apareci\u00f3 misteriosamente en el centro de Londres, la cual representa a un hombre trajeado que desciende de un pedestal con una bandera que le cubre el rostro.El enigm\u00e1tico artista se atribuy\u00f3 el m\u00e9rito de la obra en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468368,"url":"https:\/\/noticiasya.com\/tampa\/2025\/11\/14\/hombre-robo-obra-nina-globo-banksy-londres-trax\/","url_meta":{"origin":1472437,"position":2},"title":"Encarcelan a un hombre por robar la obra &#171;Girl with Balloon&#187; de Banksy en un robo rel\u00e1mpago en Londres","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Un hombre fue condenado a m\u00e1s de un a\u00f1o de prisi\u00f3n por robar una copia firmada de la obra \u201cGirl with Balloon\u201d (Ni\u00f1a con globo) de Banksy en un robo rel\u00e1mpago en una galer\u00eda de Londres.Larry Fraser, de 49 a\u00f1os, fue condenado el viernes a 13 meses de prisi\u00f3n por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472459,"url":"https:\/\/noticiasya.com\/tampa\/2026\/03\/23\/5-cosas-23-marzo-2026-orix\/","url_meta":{"origin":1472437,"position":3},"title":"Las 5 cosas que debes saber este 23 de marzo: estrecho de Ormuz, ICE en aeropuertos, Cuba prepara militares y m\u00e1s","author":"","date":"marzo 23, 2026","format":false,"excerpt":"Desplegar\u00e1n agentes de ICE en los aeropuertos de EE.UU. Colisi\u00f3n en LaGuardia deja dos muertos y decenas de heridos. Padrino L\u00f3pez reconoce que tuvo \u201cdecisiones dif\u00edciles\u201d mientras era ministro de Defensa de Venezuela. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466319,"url":"https:\/\/noticiasya.com\/tampa\/2025\/09\/10\/5-cosas-10-septiembre-orix\/","url_meta":{"origin":1472437,"position":4},"title":"Las 5 cosas que debes saber este 10 de septiembre: Israel ataca en Qatar, documentos de Epstein y milicia venezolana","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"La milicia venezolana se moviliza mientras la Casa Blanca eval\u00faa sus golpes. \u00bfQu\u00e9 dicen los nuevos documentos del caso Epstein? Bolivia, \u00a1al repechaje! Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5 cosas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455177,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/16\/desmantelan-banda-vendia-botellas-vino-falso-trax\/","url_meta":{"origin":1472437,"position":5},"title":"La Polic\u00eda de Francia e Italia desmantela banda que vend\u00eda botellas de vino a\u00f1ejo falso por US$ 16.000 cada una","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Seis personas fueron detenidas como parte de una investigaci\u00f3n sobre una red de fraude enol\u00f3gica que supuestamente vend\u00eda vino franc\u00e9s falso por hasta 15.000 euros (US$ 16.300) por botella.La polic\u00eda italiana registr\u00f3 14 propiedades y confisc\u00f3 grandes cantidades de botellas de vino, etiquetas falsificadas de los mejores vi\u00f1edos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1472437"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1472437\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1472437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1472437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1472437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}