{"id":1444937,"date":"2024-02-05T08:33:28","date_gmt":"2024-02-05T16:33:28","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444937"},"modified":"2024-02-05T08:33:28","modified_gmt":"2024-02-05T16:33:28","slug":"la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","title":{"rendered":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong"},"content":{"rendered":"<p>(CNN) &#8212; Miles de aficionados al f\u00fatbol de Hong Kong quedaron decepcionados cuando la superestrella argentina Lionel Messi no salt\u00f3 al campo este domingo en un partido amistoso del Inter de Miami.<\/p>\n<p>Lo que empez\u00f3 con una ovaci\u00f3n y un entusiasmo desbordantes termin\u00f3 con abucheos y peticiones de reembolso en el estadio de Hong Kong, con aforo completo para 40.000 espectadores.<\/p>\n<p>El Inter de Miami, que quer\u00eda demostrar su val\u00eda tras no haber ganado en su gira mundial de pretemporada, se impuso c\u00f3modamente por 4-1 a un once de Hong Kong en un encuentro bautizado como Tatler XFEST Hong Kong.<\/p>\n<p>Pero incluso en los proleg\u00f3menos y durante el partido, los aficionados ten\u00edan la sensaci\u00f3n de que el resultado no les importaba; lo m\u00e1s importante era ver a Messi, campe\u00f3n del mundo y ocho veces Bal\u00f3n de Oro, sobre el terreno de juego.<\/p>\n<p>Incluso el gobierno de Hong Kong comparti\u00f3 su consternaci\u00f3n por la ausencia del jugador de 36 a\u00f1os en el partido.<\/p>\n<p>&#171;Messi no ha podido jugar hoy en el partido amistoso, y el Gobierno y los aficionados est\u00e1n igualmente decepcionados por las disposiciones adoptadas por el organizador del evento&#187;, declar\u00f3 en un comunicado este domingo. &#171;El organizador del evento debe una explicaci\u00f3n a los aficionados&#187;.<\/p>\n<p>Luis Su\u00e1rez, otro de los flamantes fichajes del equipo, tampoco jug\u00f3 pese a asistir a la rueda de prensa previa al partido, mientras que otros jugadores destacados como Jordi Alba y Sergio Busquets, solo entraron en la segunda parte.<\/p>\n<p>Sin Cristiano y con Messi solo 10 minutos, Al Nassr golea 6-0 al Inter Miami<\/p>\n<p>Messi se qued\u00f3 en el banquillo por lesi\u00f3n durante el partido del domingo en Hong Kong. (Credit: Louise Delmotte\/AP)<\/p>\n<p>La entrega adicional del trofeo, los fuegos artificiales y el discurso del copropietario del club, David Beckham, se vieron envueltos en silbidos y abucheos en un final de viaje bastante inc\u00f3modo. Los abucheos continuaron cuando las c\u00e1maras de la gran pantalla enfocaron a Messi.<\/p>\n<p>El cambio de ambiente se hab\u00eda producido hacia los \u00faltimos 20 minutos del partido: los clamores de &#171;Queremos a Messi&#187; se convirtieron en &#171;\u00bfD\u00f3nde est\u00e1 Messi?&#187;, mientras que los abucheos sonaban cada vez que un jugador que no fuera Messi era sustituido en el terreno de juego.<\/p>\n<p>Tambi\u00e9n se oyeron gritos de &#171;reembolso, reembolso, reembolso&#187;, tanto en ingl\u00e9s como en canton\u00e9s, en el tiempo a\u00f1adido. Seg\u00fan Reuters, las entradas salieron a la venta en diciembre y cuestan entre 880 y 4.880 d\u00f3lares de Hong Kong (unos US$ 113 y US$ 624 d\u00f3lares).<\/p>\n<p>CNN se ha puesto en contacto con el organizador del evento, Tatler, para pedirle comentarios.<\/p>\n<p>El &#8216;contrato&#8217; de servilleta de papel para sellar el traspaso de Lionel Messi al FC Barcelona se subastar\u00e1 con una oferta inicial de US$ 380.000<\/p>\n<p>Aficionados de Lio Messi protestan en un partido de exhibici\u00f3n del Inter de Miami en Hong Kong porque el argentino no sali\u00f3 a la cancha el 4 de febrero de 2024.<\/p>\n<p>\u00bfPor qu\u00e9 no jug\u00f3 Messi?<\/p>\n<p>En un comunicado este domingo, Tatler XFEST expres\u00f3 su &#171;extrema decepci\u00f3n&#187; por el hecho de que Messi y Su\u00e1rez no jugaran en Hong Kong y dijo que &#171;no ten\u00eda ninguna informaci\u00f3n sobre la no participaci\u00f3n&#187; de los jugadores antes del saque inicial.<\/p>\n<p>El seleccionador del Miami, Gerardo &#171;Tata&#187; Martino, explic\u00f3 que la decisi\u00f3n de no alinear a Messi se tom\u00f3 con muy poca antelaci\u00f3n y por recomendaci\u00f3n del cuerpo m\u00e9dico del club.<\/p>\n<p>&#171;Entendemos la recepci\u00f3n de los hinchas hacia la ausencia de Leo y Luis&#187;, se disculp\u00f3 Martino, que tambi\u00e9n agradeci\u00f3 a Hong Kong las &#171;atenciones&#187; recibidas durante todo el fin de semana.<\/p>\n<p>&#171;Fue una decisi\u00f3n tomada junto con nuestro equipo m\u00e9dico. Comprobamos su estado f\u00edsico y corr\u00edan el riesgo de sufrir una lesi\u00f3n si saltaban al terreno de juego, por lo que no pod\u00edan jugar.<\/p>\n<p>&#171;Entendemos la decepci\u00f3n de los aficionados y les pedimos perd\u00f3n. Nos hubiera gustado jugar con ellos aunque fuera un rato, pero el riesgo era demasiado grande&#187;.<\/p>\n<p>Martino fue presionado sobre el tipo de lesi\u00f3n que hab\u00eda sufrido Messi, ya que ya hab\u00eda informes de que el jugador estrella arrastraba un problema en los isquiotibiales desde el anterior amistoso de Miami contra el Al-Nassr en Arabia Saud\u00ed.<\/p>\n<p>&#171;Leo tiene una inflamaci\u00f3n en el aductor como vimos en las im\u00e1genes de sus m\u00fasculos. Esper\u00e1bamos una mejor\u00eda, pero la situaci\u00f3n se mantiene desde hace muchos d\u00edas&#187;, dijo Martino, quien a\u00f1adi\u00f3 que Su\u00e1rez sufri\u00f3 una lesi\u00f3n de rodilla durante el viaje a Arabia Saud\u00ed.<\/p>\n<p>&#171;Lo estuvimos controlando constantemente con el equipo m\u00e9dico, y tambi\u00e9n tuvimos que considerar nuestras obligaciones con la pr\u00f3xima MLS [Major League Soccer]. As\u00ed que llegamos a la conclusi\u00f3n de no jugar con Messi en el partido&#187;.<\/p>\n<p>&#171;En realidad, hemos estado evaluando el estado de Leo d\u00eda a d\u00eda. Ayer [s\u00e1bado] estuvo en el \u00faltimo entrenamiento [sesi\u00f3n], y lo evaluamos en el hotel hasta esta ma\u00f1ana. La decisi\u00f3n no se tom\u00f3 hasta la tarde&#187;.<\/p>\n<p>El anuncio protagonizado por Messi que se estrenar\u00e1 en el Super Bowl<\/p>\n<p>Su\u00e1rez y Martino hablan en rueda de prensa el viernes. (Cr\u00e9dito: Louise Delmotte\/AP)<\/p>\n<p>El capit\u00e1n del Hong Kong XI, Yapp Hung-fai, que jug\u00f3 la primera parte del partido de este domingo, se mostr\u00f3 &#171;por supuesto bastante decepcionado&#187; por no haber jugado contra Messi, pero agradeci\u00f3 la experiencia.<\/p>\n<p>&#171;A t\u00edtulo personal, obviamente estoy bastante decepcionado porque \u00e9l no viene mucho a Hong Kong&#187;, declar\u00f3 Yapp, que lidera un equipo de jugadores de toda la primera divisi\u00f3n.<\/p>\n<p>&#171;Pero tenemos que pensar en nuestra propia actuaci\u00f3n y no centrarnos demasiado en el rival, que segu\u00eda siendo de gran nivel. Jugar en un estadio lleno ya es satisfactorio&#187;.<\/p>\n<p>El sentimiento general era compartido por el superfan local de Messi, Christer Leung, que encabeza el club de hinchas de la selecci\u00f3n argentina de la ciudad.<\/p>\n<p>&#171;Creo que todo el mundo est\u00e1 decepcionado&#187;, declar\u00f3 a la CNN Leung, que llam\u00f3 a su hijo Lionel en honor al delantero.<\/p>\n<p>&#171;Fue inesperado, pens\u00e9 que jugar\u00eda al menos cinco minutos. Si no, no habr\u00edamos pagado el precio de las entradas para entrar aqu\u00ed. Se oyeron los \u00e1nimos, que creo que estaban justificados, pero al mismo tiempo eran improcedentes&#187;.<\/p>\n<p>&#171;Todo esto de Messi en Hong Kong se ha estado gestando durante bastante tiempo. Todo el mundo estaba muy emocionado y hubo mucho drama con las entradas.<\/p>\n<p>&#171;La sesi\u00f3n de entrenamiento [del s\u00e1bado] tambi\u00e9n fue bastante decepcionante porque no hizo gran cosa y fue muy corta. Todo el mundo esperaba que hoy fuera un poco m\u00e1s, as\u00ed que todo el mundo va a estar decepcionado.<\/p>\n<p>&#171;Pero, como seguidor suyo desde hace mucho tiempo, respeto totalmente la decisi\u00f3n de no ponerlo a jugar si realmente est\u00e1 sufriendo, porque tiene 36 a\u00f1os.<\/p>\n<p>&#171;Culpo al Inter de Miami por programar tantos amistosos en tantos lugares diferentes. Deber\u00edan haber invitado a todo el mundo a venir a Estados Unidos. Supongo que quer\u00edan hacer crecer la marca internacionalmente, lo cual tiene sentido&#187;.<\/p>\n<p>El partido del Inter de Miami contra un once de Hong Kong se disput\u00f3 ante un p\u00fablico que agot\u00f3 las entradas. (Cr\u00e9dito: Lam Yik\/USA Today Sports\/Reuters)<\/p>\n<p>La &#171;Messiman\u00eda&#187; se hab\u00eda apoderado de la ciudad con la llegada del equipo el viernes, mientras los aficionados se agolpaban en el hotel en el que se alojaban los miamenses. Mientras tanto, el estadio ya hab\u00eda alcanzado su capacidad m\u00e1xima durante la sesi\u00f3n de entrenamiento abierta del equipo la v\u00edspera.<\/p>\n<p>El ardiente apoyo a Messi tambi\u00e9n se apoder\u00f3 de China continental el verano pasado, despu\u00e9s de que la selecci\u00f3n argentina disputara un partido amistoso contra Australia en Beijing.<\/p>\n<p>Era la s\u00e9ptima vez que la superestrella visitaba China, y la octava podr\u00eda llegar en marzo, ya que Argentina confirm\u00f3 dos partidos amistosos contra Nigeria y Costa de Marfil en Hangzhou y Beijing.<\/p>\n<p>El Inter de Miami viaja ahora a Jap\u00f3n para disputar un amistoso contra el Vissel Kobe este mi\u00e9rcoles.<\/p>\n<p>&#8212; Informaci\u00f3n adicional de Kristie Lu-Stout de CNN<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Miles de aficionados al f\u00fatbol de Hong Kong quedaron decepcionados cuando la superestrella argentina Lionel Messi no salt\u00f3 al campo este domingo en un partido amistoso del Inter de Miami. Lo que empez\u00f3 con una ovaci\u00f3n y un entusiasmo desbordantes termin\u00f3 con abucheos y peticiones de reembolso en el estadio de Hong Kong, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444937","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Miles de aficionados al f\u00fatbol de Hong Kong quedaron decepcionados cuando la superestrella argentina Lionel Messi no salt\u00f3 al campo este domingo en un partido amistoso del Inter de Miami. Lo que empez\u00f3 con una ovaci\u00f3n y un entusiasmo desbordantes termin\u00f3 con abucheos y peticiones de reembolso en el estadio de Hong Kong, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T16:33:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong\",\"datePublished\":\"2024-02-05T16:33:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\"},\"wordCount\":1433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\",\"name\":\"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-05T16:33:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","og_locale":"es_ES","og_type":"article","og_title":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias","og_description":"(CNN) &#8212; Miles de aficionados al f\u00fatbol de Hong Kong quedaron decepcionados cuando la superestrella argentina Lionel Messi no salt\u00f3 al campo este domingo en un partido amistoso del Inter de Miami. Lo que empez\u00f3 con una ovaci\u00f3n y un entusiasmo desbordantes termin\u00f3 con abucheos y peticiones de reembolso en el estadio de Hong Kong, [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","og_site_name":"Noticias","article_published_time":"2024-02-05T16:33:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/"},"author":{"name":"","@id":""},"headline":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong","datePublished":"2024-02-05T16:33:28+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/"},"wordCount":1433,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","name":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-05T16:33:28+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-05T16:33:28Z","datePublished":"2024-02-05T16:33:28Z","dateModified":"2024-02-05T16:33:28Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/05\\\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/05\\\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-05T16:33:28Z\",\"datePublished\":\"2024-02-05T16:33:28Z\",\"dateModified\":\"2024-02-05T16:33:28Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445151,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","url_meta":{"origin":1444937,"position":0},"title":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi","author":"","date":"febrero 9, 2024","format":false,"excerpt":"(CNN) -- Tatler XFEST, los organizadores del partido amistoso de f\u00fatbol en Hong Kong del Inter Miami en el que Lionel Messi no jug\u00f3, anunciaron el viernes que ofrecer\u00e1n a los espectadores un reembolso del 50%.\"Pedimos disculpas a todos aquellos que se sintieron decepcionados por el partido de f\u00fatbol entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445205,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/10\/ciudad-china-cancela-un-partido-de-futbol-con-la-seleccion-de-argentina-tras-el-episodio-de-messi-en-hong-kong\/","url_meta":{"origin":1444937,"position":1},"title":"Ciudad china cancela un partido de f\u00fatbol con la selecci\u00f3n de Argentina tras el episodio de Messi en Hong Kong","author":"","date":"febrero 10, 2024","format":false,"excerpt":"(CNN) -- Una ciudad de China continental cancel\u00f3 su plan de acoger un partido de f\u00fatbol de la selecci\u00f3n nacional de Argentina en medio de una creciente reacci\u00f3n en el pa\u00eds contra su jugador estrella, Lionel Messi.Messi se ha enfrentado a una avalancha de cr\u00edticas despu\u00e9s de quedarse en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445875,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/21\/messi-china-hong-kong-partido-trax\/","url_meta":{"origin":1444937,"position":2},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445716,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/20\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china-2\/","url_meta":{"origin":1444937,"position":3},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 20, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445679,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/19\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china\/","url_meta":{"origin":1444937,"position":4},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 19, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444135,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/01\/19\/messi-suarez-busquets-y-alba-las-nuevas-estrellas-del-inter-miami-debutan-juntas-ante-el-salvador\/","url_meta":{"origin":1444937,"position":5},"title":"Messi, Su\u00e1rez, Busquets y Alba: las nuevas estrellas del Inter Miami debutan juntas ante El Salvador","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El equipo del sur de la Florida inicia su gira de amistosos con un encuentro frente a la selecci\u00f3n de El Salvador este viernes a las 8 p.m. hora del Este, en el estadio Cuscatl\u00e1n en San Salvador. El equipo de Gerardo Martino da comienzo a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1444937"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444937\/revisions"}],"predecessor-version":[{"id":1444955,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444937\/revisions\/1444955"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1444937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1444937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1444937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}