{"id":1444989,"date":"2024-02-06T08:33:29","date_gmt":"2024-02-06T16:33:29","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444989"},"modified":"2024-02-06T08:33:29","modified_gmt":"2024-02-06T16:33:29","slug":"lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","title":{"rendered":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de car\u00e1cter aut\u00f3nomo y reducir el n\u00famero de senadores y diputados.<\/p>\n<p>En el recinto parlamentario de Palacio Nacional, acompa\u00f1ado en el estrado solamente por su esposa, Beatriz Guti\u00e9rrez Muler, L\u00f3pez Obrador detall\u00f3 en presencia de su gabinete el contenido del proyecto que envi\u00f3 al Legislativo. En su criterio, en los \u00faltimos 36 a\u00f1os no se reformaron art\u00edculos de la Constituci\u00f3n del pa\u00eds \u201cpara procurar justicia\u201d, ya que todo lo aprobado por los legisladores de esos per\u00edodos \u201ctuvo como fin el af\u00e1n de lucro y el desprecio por las mayor\u00edas\u201d.<\/p>\n<p>Entre las modificaciones sugeridas tambi\u00e9n sobresale la creaci\u00f3n de un fondo semilla, con un capital inicial de 64.219 millones de pesos (unos US$ 3.774 millones), para que las pensiones de trabajadores, cuando se retiren, sea del 100 por ciento \u201cpara compensar a los trabajadores afectados por las reformas anti laborales del per\u00edodo neoliberal\u201d, seg\u00fan afirm\u00f3 el mandatario.<\/p>\n<p>&#171;No hay pruebas de que L\u00f3pez Obrador recibi\u00f3 dinero del narco en 2006&#187;, dice ex agente de la DEA<\/p>\n<p>Las actuales leyes laborales de jubilaci\u00f3n de M\u00e9xico permiten a los trabajadores aspirar a un porcentaje del \u00faltimo salario percibido en proporci\u00f3n a las semanas que cotizaron con el Instituto Mexicano del Seguro Social o con el Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado.<\/p>\n<p>Al momento de presentar su propuesta L\u00f3pez Obrador dudo del car\u00e1cter aut\u00f3nomo de los organismos que desea eliminar. \u201cS\u00ed, aut\u00f3nomos del pueblo, no de la oligarqu\u00eda, creados durante el periodo neoliberal con el \u00fanico prop\u00f3sito de proteger negocios particulares en contra del inter\u00e9s p\u00fablico\u201d, explic\u00f3.<\/p>\n<p>Como primera reforma L\u00f3pez Obrador enunci\u00f3 \u201cel reconocimiento legal y pol\u00edtico de los pueblos originarios y de los afromexicanos, a quienes se les debe el respeto por ser los pobladores m\u00e1s antiguos del territorio mexicano\u201d.<\/p>\n<p>\u201cConsultarlos cuando se realicen obras que puedan afectar su vida o entorno y dotarlos de legitimidad jur\u00eddica para recibir recursos del presupuesto y promover acciones de inconstitucionalidad de leyes que les afecten\u201d, dijo.<\/p>\n<p>En su proyecto el presidente de M\u00e9xico propone una pensi\u00f3n universal a los adultos mayores, becas a j\u00f3venes sin trabajo, una pensi\u00f3n a personas discapacitadas y la protecci\u00f3n a los animales.<\/p>\n<p>Asimismo, propuso que se proh\u00edba el uso de ma\u00edz transg\u00e9nico, la extracci\u00f3n de hidrocarburos por medio de fracking y tambi\u00e9n la prohibici\u00f3n de explotaciones mineras a cielo abierto, sin dar mayores detalles de si las actuales concesiones, de ser aprobada su propuesta, ser\u00e1n prohibidas.<\/p>\n<p>En un desaf\u00edo al Poder Judicial, L\u00f3pez Obrador propuso que los jueces, magistrados y ministros sean designados por voto directo popular y no nombrados por el poder Ejecutivo y ratificados por el Legislativo.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de car\u00e1cter aut\u00f3nomo y reducir el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444989","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de car\u00e1cter aut\u00f3nomo y reducir el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T16:33:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico\",\"datePublished\":\"2024-02-06T16:33:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\"},\"wordCount\":562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\",\"name\":\"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-06T16:33:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de car\u00e1cter aut\u00f3nomo y reducir el [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","og_site_name":"Noticias","article_published_time":"2024-02-06T16:33:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/"},"author":{"name":"","@id":""},"headline":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico","datePublished":"2024-02-06T16:33:29+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/"},"wordCount":562,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","name":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-06T16:33:29+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-06T16:33:29Z","datePublished":"2024-02-06T16:33:29Z","dateModified":"2024-02-06T16:33:29Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"L\\u00f3pez Obrador presenta proyecto de reforma a la Constituci\\u00f3n de M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/06\\\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/06\\\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-3\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-06T16:33:29Z\",\"datePublished\":\"2024-02-06T16:33:29Z\",\"dateModified\":\"2024-02-06T16:33:29Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444981,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico\/","url_meta":{"origin":1444989,"position":0},"title":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450113,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/06\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-trax\/","url_meta":{"origin":1444989,"position":1},"title":"5 claves del proyecto de L\u00f3pez Obrador para reformar la Constituci\u00f3n de M\u00e9xico","author":"","date":"junio 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444987,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/06\/lopez-obrador-presenta-proyecto-de-reforma-a-la-constitucion-de-mexico-2\/","url_meta":{"origin":1444989,"position":2},"title":"L\u00f3pez Obrador presenta proyecto de reforma a la Constituci\u00f3n de M\u00e9xico","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, present\u00f3 este lunes un proyecto de ley para reformar la Constituci\u00f3n del pa\u00eds con el objetivo, seg\u00fan dijo, de \u201cmodificar el contenido de art\u00edculos impopulares\u201d de la actual Carta Magna. Entre las propuestas destaca la eliminaci\u00f3n de organismos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457833,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/24\/sheinbaum-reforma-prohibir-maiz-transgenico-orix\/","url_meta":{"origin":1444989,"position":3},"title":"Sheinbaum formaliza su reforma para prohibir la siembra de ma\u00edz transg\u00e9nico en M\u00e9xico","author":"","date":"enero 24, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, envi\u00f3 al Congreso este jueves una propuesta de reforma a la Constituci\u00f3n para prohibir la siembra de ma\u00edz transg\u00e9nico en el pa\u00eds, una medida que, dice, es necesaria para proteger la diversidad gen\u00e9tica de esta planta.El documento, publicado en la Gaceta Parlamentaria, plantea modificar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452642,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/09\/13\/reforma-judicial-mexico-congresos-locales-orig\/","url_meta":{"origin":1444989,"position":4},"title":"Los congresos locales aprueban la reforma judicial en M\u00e9xico. \u00bfQu\u00e9 sigue?","author":"","date":"septiembre 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, anunci\u00f3 que prev\u00e9 que la reforma judicial se publique el 15 de septiembre, domingo y v\u00edspera de los festejos por la Independencia mexicana puesto que, dijo, \"es una reforma important\u00edsima\".Este jueves, se alcanz\u00f3 y super\u00f3 el m\u00ednimo de 17\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455176,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/10\/16\/senado-mexicano-reforma-constitucional-control-estatal-sector-energetico-orix\/","url_meta":{"origin":1444989,"position":5},"title":"Senado de M\u00e9xico debate la reforma oficialista que fortalece el control estatal del sector energ\u00e9tico","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El pleno del Senado de M\u00e9xico debate este mi\u00e9rcoles la iniciativa de reforma constitucional en materia energ\u00e9tica que da prioridad al Estado en la generaci\u00f3n de energ\u00eda el\u00e9ctrica. El proyecto ya fue aprobado en la C\u00e1mara de Diputados el 9 de octubre.La reforma, que modifica los art\u00edculos 25,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1444989"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444989\/revisions"}],"predecessor-version":[{"id":1445005,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1444989\/revisions\/1445005"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1444989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1444989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1444989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}