{"id":1445033,"date":"2024-02-07T06:33:27","date_gmt":"2024-02-07T14:33:27","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445033"},"modified":"2024-02-07T06:33:27","modified_gmt":"2024-02-07T14:33:27","slug":"este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","title":{"rendered":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse"},"content":{"rendered":"<p>(CNN) &#8212;  Durante los \u00faltimos a\u00f1os, Coca-Cola experiment\u00f3 con ofertas extravagantes por tiempo limitado, pero su \u00faltimo sabor es la primera incorporaci\u00f3n permanente en mucho tiempo. Algunos dicen que es parte del intento de Coca-Cola de satisfacer los gustos que cambian junto con la demograf\u00eda de Estados Unidos.<\/p>\n<p>Coca-Cola Spiced es un nuevo refresco que combina el \u201csabor ic\u00f3nico\u201d de Coca-Cola con una \u201cexplosi\u00f3n de notas refrescantes de frambuesa y sabores especiados\u201d, anunci\u00f3 la compa\u00f1\u00eda este mi\u00e9rcoles. Estar\u00e1 disponible en variedades con az\u00facar y sin az\u00facar cuando llegue a las tiendas en los EE. UU. y Canad\u00e1 en las pr\u00f3ximas semanas.<\/p>\n<p>Coca-Cola no suele agregar nuevos sabores permanentes a su l\u00ednea: Spiced se une a algunos otros sabores que siempre vende, incluido su sabor emblem\u00e1tico, cereza y vainilla.<\/p>\n<p>Se seleccion\u00f3 Spiced porque \u201cse trata de estar en la tendencia de la categor\u00eda y responder a las preferencias de nuestros consumidores\u201d, quienes anhelan sabores m\u00e1s atrevidos y potentes , dijo a CNN Sue Lynne Cha, vicepresidenta de marketing de Coca-Cola para Norteam\u00e9rica.<\/p>\n<p>La investigaci\u00f3n de Coca-Cola encontr\u00f3 un \u201caumento en la disposici\u00f3n de los consumidores a probar una bebida especiada\u201d y que la frambuesa fue seleccionada m\u00e1s de 5 millones de veces en sus m\u00e1quinas de bebidas Freestyle en 2022, que la compa\u00f1\u00eda \u201ca menudo utiliza como inspiraci\u00f3n\u201d para nuevos sabores, dijo.<\/p>\n<p>\u201cLos consumidores buscan sabores m\u00e1s atrevidos y perfiles de sabor m\u00e1s complejos. Esa es una tendencia que comenzamos a ver en la comida, pero tambi\u00e9n en las bebidas, y pensamos que era un espacio \u00fanico para jugar\u201d, dijo, y agreg\u00f3 que ha habido un \u201cdeseo de descubrimiento\u201d por parte de la gente que quiere probar algo nuevo.<\/p>\n<p>&#171;El crecimiento en las ventas de refrescos saborizados generalmente ha superado a las colas durante a\u00f1os, lo que se ve favorecido por una creciente poblaci\u00f3n multicultural&#187;, dijo Duane Stanford, editor y editor de Beverage Digest.<\/p>\n<p>&#171;Parece que Coca-Cola est\u00e1 buscando unir esa tendencia a su producto estrella con la esperanza de lograr que los consumidores j\u00f3venes consideren la franquicia completa&#187;, dijo a CNN.<\/p>\n<p>Coca-Cola Spiced sale a la venta el 19 de febrero en latas y botellas de varios tama\u00f1os en la mayor\u00eda de los minoristas nacionales.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Durante los \u00faltimos a\u00f1os, Coca-Cola experiment\u00f3 con ofertas extravagantes por tiempo limitado, pero su \u00faltimo sabor es la primera incorporaci\u00f3n permanente en mucho tiempo. Algunos dicen que es parte del intento de Coca-Cola de satisfacer los gustos que cambian junto con la demograf\u00eda de Estados Unidos. Coca-Cola Spiced es un nuevo refresco que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445033","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Durante los \u00faltimos a\u00f1os, Coca-Cola experiment\u00f3 con ofertas extravagantes por tiempo limitado, pero su \u00faltimo sabor es la primera incorporaci\u00f3n permanente en mucho tiempo. Algunos dicen que es parte del intento de Coca-Cola de satisfacer los gustos que cambian junto con la demograf\u00eda de Estados Unidos. Coca-Cola Spiced es un nuevo refresco que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T14:33:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse\",\"datePublished\":\"2024-02-07T14:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\"},\"wordCount\":415,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\",\"name\":\"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-07T14:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","og_locale":"es_ES","og_type":"article","og_title":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias","og_description":"(CNN) &#8212; Durante los \u00faltimos a\u00f1os, Coca-Cola experiment\u00f3 con ofertas extravagantes por tiempo limitado, pero su \u00faltimo sabor es la primera incorporaci\u00f3n permanente en mucho tiempo. Algunos dicen que es parte del intento de Coca-Cola de satisfacer los gustos que cambian junto con la demograf\u00eda de Estados Unidos. Coca-Cola Spiced es un nuevo refresco que [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","og_site_name":"Noticias","article_published_time":"2024-02-07T14:33:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/"},"author":{"name":"","@id":""},"headline":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse","datePublished":"2024-02-07T14:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/"},"wordCount":415,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","name":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-07T14:33:27+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-07T14:33:27Z","datePublished":"2024-02-07T14:33:27Z","dateModified":"2024-02-07T14:33:27Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Este es el nuevo sabor de Coca-Cola que lleg\\u00f3 para quedarse\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/07\\\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/07\\\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-07T14:33:27Z\",\"datePublished\":\"2024-02-07T14:33:27Z\",\"dateModified\":\"2024-02-07T14:33:27Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445055,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/07\/este-es-el-nuevo-sabor-de-coca-cola-que-llego-para-quedarse-2\/","url_meta":{"origin":1445033,"position":0},"title":"Este es el nuevo sabor de Coca-Cola que lleg\u00f3 para quedarse","author":"","date":"febrero 7, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos a\u00f1os, Coca-Cola experiment\u00f3 con ofertas extravagantes por tiempo limitado, pero su \u00faltimo sabor es la primera incorporaci\u00f3n permanente en mucho tiempo. Algunos dicen que es parte del intento de Coca-Cola de satisfacer los gustos que cambian junto con la demograf\u00eda de Estados Unidos.Coca-Cola Spiced es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453040,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/09\/25\/coca-cola-retira-sabor-permanente-spiced-trax\/","url_meta":{"origin":1445033,"position":1},"title":"Coca-Cola descontinuar\u00e1 su sabor Spiced a solo seis meses de su lanzamiento","author":"","date":"septiembre 25, 2024","format":false,"excerpt":"(CNN) -- Coca-Cola est\u00e1 descontinuando la producci\u00f3n de su nuevo sabor Spiced solo seis meses despu\u00e9s de su lanzamiento, marcando el fin de un intento fallido de atraer a los consumidores m\u00e1s j\u00f3venes.La compa\u00f1\u00eda declar\u00f3 que Coca-Cola \u201csiempre est\u00e1 observando lo que les gusta a nuestros clientes y ajustando\u201d sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450004,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/06\/03\/dr-pepper-superar-pepsi-segunda-mas-vendida-refrescos-trax\/","url_meta":{"origin":1445033,"position":2},"title":"Dr Pepper acaba de superar a Pepsi como la segunda marca m\u00e1s vendida de refrescos","author":"","date":"junio 3, 2024","format":false,"excerpt":"Nueva York (CNN) -- Coca-Cola sigue siendo el refresco m\u00e1s vendido en Estados Unidos. Sin embargo, el segundo puesto, ocupado durante mucho tiempo por Pepsi, pertenece ahora a Dr Pepper.Tras a\u00f1os ganando cuota de mercado lentamente, Dr Pepper superar\u00e1 a Pepsi como segunda marca de refrescos de EE.UU. en 2023,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467602,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/21\/coca-cola-azucar-cana-trump-trax\/","url_meta":{"origin":1445033,"position":3},"title":"Una Coca-Cola aprobada por Trump comienza a comercializarse en Estados Unidos","author":"","date":"octubre 21, 2025","format":false,"excerpt":"Coca-Cola comenz\u00f3 a vender en Estados Unidos un refresco que utiliza az\u00facar de ca\u00f1a, en lugar de jarabe de ma\u00edz de alta fructosa, tras una solicitud del presidente Donald Trump a principios de este a\u00f1o.Un portavoz de la compa\u00f1\u00eda confirm\u00f3 a CNN que el refresco ya se est\u00e1 distribuyendo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464750,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/22\/coca-cola-lanza-nueva-version-trump-trax\/","url_meta":{"origin":1445033,"position":4},"title":"Coca-Cola lanza una nueva versi\u00f3n con el ingrediente que Trump quer\u00eda","author":"","date":"julio 22, 2025","format":false,"excerpt":"Coca-Cola confirm\u00f3 este martes que lanzar\u00e1 una nueva Coca-Cola elaborada con az\u00facar de ca\u00f1a. El anuncio llega tras una publicaci\u00f3n en redes sociales del presidente Donald Trump de la semana pasada, en la que afirm\u00f3 haber convencido a la compa\u00f1\u00eda de reemplazar el jarabe de ma\u00edz de alta fructosa.La compa\u00f1\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464608,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/17\/trump-cambio-receta-coca-cola-trax\/","url_meta":{"origin":1445033,"position":5},"title":"Trump se atribuye el m\u00e9rito del cambio de dulce en Coca-Cola","author":"","date":"julio 17, 2025","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 el mi\u00e9rcoles lo que podr\u00eda ser una noticia refrescante para algunos estadounidenses: gracias a \u00e9l, Coca-Cola est\u00e1 cambiando su receta estadounidense.\u201cHe estado hablando con Coca-Cola sobre el uso de az\u00facar de ca\u00f1a REAL en la Coca-Cola en Estados Unidos, y han accedido. Quiero agradecer a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1445033"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445033\/revisions"}],"predecessor-version":[{"id":1445050,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445033\/revisions\/1445050"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1445033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1445033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1445033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}