{"id":1445079,"date":"2024-02-08T02:33:30","date_gmt":"2024-02-08T10:33:30","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445079"},"modified":"2024-02-08T02:33:30","modified_gmt":"2024-02-08T10:33:30","slug":"una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","title":{"rendered":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos y se recuperan en el hospital.<\/p>\n<p>Las autoridades no han podido ingresar a la casa desde que comenz\u00f3 el incidente la tarde de este mi\u00e9rcoles porque el incendio a\u00fan sigue activo, y les preocupa que varias personas cuyo paradero se desconoce puedan haber estado adentro cuando la estructura se quem\u00f3, inform\u00f3 el mi\u00e9rcoles el fiscal de distrito del condado de Delaware, Jack Stollsteimer, en conferencia de prensa.<\/p>\n<p>\u201cTememos que pueda haber m\u00e1s de una persona en esa casa. Sabemos que la familia de la v\u00edctima ten\u00eda muchas personas viviendo en esa casa, incluidos ni\u00f1os\u201d, dijo Stollsteimer. \u201cSomos conscientes de que hay al menos de seis a ocho personas desaparecidas de esa familia. Nuestro gran temor es que pudieran (haber estado) dentro de esa casa cuando se quem\u00f3\u201d, se\u00f1al\u00f3.<\/p>\n<p>&#171;Tenemos la esperanza de que eso no sea cierto&#187;, a\u00f1adi\u00f3. &#171;Pero no lo sabremos hasta ma\u00f1ana por la ma\u00f1ana&#187;.<\/p>\n<p>Los agentes que acudieron fueron \u201crecibidos a tiros\u201d<\/p>\n<p>Las autoridades recibieron una llamada de emergencia al 911 poco antes de las 3:50 p.m, hora local, este mi\u00e9rcoles acerca de &#171;una ni\u00f1a de 11 a\u00f1os que hab\u00eda recibido un disparo&#187; en una casa, explic\u00f3 Stollsteimer en una conferencia de prensa anterior. El condado de Delaware est\u00e1 cerca de Filadelfia.<\/p>\n<p>Agentes de tres cuerpos policiales diferentes acudieron a la escena y fueron \u201cinmediatamente recibidos con disparos\u201d, relat\u00f3 Stollsteimer. Dos agentes sufrieron impactos de bala y fueron \u201carrastrados fuera de peligro\u201d por otros uniformados, dijo.<\/p>\n<p>Ambos agentes fueron trasladados al hospital y se encuentran en condici\u00f3n estable en el Penn Presbyterian Medical Center en Filadelfia. Los funcionarios, veteranos de dos departamentos diferentes, sufrieron \u201clesiones que no ponen en riesgo su vida\u201d, detall\u00f3 el fiscal de distrito.<\/p>\n<p>Despu\u00e9s de que los agentes acudieron a la escena del tiroteo, la casa se prendi\u00f3, dijo Stollsteimer.<\/p>\n<p>Pero eso era casi todo lo que sab\u00edan las autoridades hasta la noche de este mi\u00e9rcoles, mientras los bomberos segu\u00edan trabajando por apagar el fuego m\u00e1s de cuatro horas despu\u00e9s de la llamada al 911 y ning\u00fan agente pudo ingresar a la casa.<\/p>\n<p>\u201cNo sabemos qui\u00e9n estaba en la casa, no sabemos qui\u00e9n fue la persona que dispar\u00f3, no sabemos cu\u00e1ntas personas hay all\u00ed, no sabemos su estado, no sabemos si est\u00e1n vivos&#187;, dijo el fiscal de distrito a los periodistas.<\/p>\n<p>Las autoridades tambi\u00e9n contin\u00faan investigando \u201csi una ni\u00f1a de 11 a\u00f1os recibi\u00f3 o no un disparo\u201d, dijo, y qui\u00e9n dispar\u00f3 a los agentes.<\/p>\n<p>&#171;Tenemos la intenci\u00f3n de responsabilizar a todos&#187;, a\u00f1adi\u00f3 Stollsteimer.<\/p>\n<p>Los detectives revisar\u00e1n \u201cmet\u00f3dicamente\u201d la escena en la ma\u00f1ana de este jueves y \u201cbuscar\u00e1n cad\u00e1veres y evidencia de lo que realmente sucedi\u00f3\u201d, dijo el fiscal de distrito.<\/p>\n<p>\u201cNo hay nadie m\u00e1s en peligro. Nos hemos asegurado de que toda la calle est\u00e9 vac\u00eda de gente y de que el fuego est\u00e9 pr\u00e1cticamente bajo control\u201d, afirm\u00f3 Stollsteimer.<\/p>\n<p>\u201cPero, nuevamente, no vamos a entrar a esa casa hasta que sepamos que el fuego est\u00e1 bajo control y que es seguro para esos agentes entrar all\u00ed. No queremos que otro funcionario resulte herido esta noche en el condado de Delaware\u201d.<\/p>\n<p>Preguntas sobre el aparente disparo a una ni\u00f1a<\/p>\n<p>Anteriormente, una fuente policial del condado de Delaware le hab\u00eda dicho a CNN que un individuo se hab\u00eda atrincherado en la casa.<\/p>\n<p>Otra fuente informada sobre la situaci\u00f3n tambi\u00e9n le dijo a CNN previamente que el incidente comenz\u00f3 despu\u00e9s de que alguien que dec\u00eda ser una ni\u00f1a aparentemente llam\u00f3 a la polic\u00eda y report\u00f3 que le hab\u00edan disparado. Pero la fuente dijo que no estaba claro si realmente le hab\u00edan disparado a una menor.<\/p>\n<p>En una entrevista antes de la conferencia de prensa, Stollsteimer le dijo a WPVI, afiliada de CNN, que la persona que estaba dentro de la casa le prendi\u00f3 fuego.<\/p>\n<p>Las autoridades no estaban seguras de si se trata de una ni\u00f1a involucrada, dijo.<\/p>\n<p>&#171;No tenemos conocimiento independiente de si hay o no una ni\u00f1a de 11 a\u00f1os, si hubo una ni\u00f1a de 11 a\u00f1os baleada que estaba dentro de la casa. Todo eso est\u00e1 por determinar&#187;, dijo.<\/p>\n<p>Una escena ca\u00f3tica y llamas masivas<\/p>\n<p>Las im\u00e1genes de WPVI del mi\u00e9rcoles por la tarde mostraron una escena ca\u00f3tica alrededor de la casa.<\/p>\n<p>La casa se ve\u00eda envuelta en llamas y, en menos de una hora, el fuego hab\u00eda consumido la mayor parte, dejando nada m\u00e1s que un cascar\u00f3n carbonizado y desatando enormes columnas de humo negro sobre el vecindario.<\/p>\n<p>No est\u00e1 claro c\u00f3mo comenz\u00f3 el incendio ni cu\u00e1ndo.<\/p>\n<p>Durante la respuesta inicial se vio a grupos de bomberos apostados cerca del lugar esperando para responder al incendio mientras los vecinos se reun\u00edan en la calle y observaban.<\/p>\n<p>En alg\u00fan momento, y con el fuego a\u00fan desenfrenado, se observ\u00f3 un veh\u00edculo blindado embistiendo la casa en las im\u00e1genes de WPVI.<\/p>\n<p>&#171;Escuch\u00e9 muchos disparos cuando acababa de salir de la tienda&#8230; y vi polic\u00edas corriendo de todas partes&#187;, dijo un vecino a la estaci\u00f3n, y agreg\u00f3 que escucharon a las autoridades gritar sobre un &#171;atacante&#187;.<\/p>\n<p>Amy Simonson de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos y se recuperan en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445079","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos y se recuperan en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T10:33:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda\",\"datePublished\":\"2024-02-08T10:33:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\"},\"wordCount\":987,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\",\"name\":\"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-08T10:33:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","og_locale":"es_ES","og_type":"article","og_title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias","og_description":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos y se recuperan en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","og_site_name":"Noticias","article_published_time":"2024-02-08T10:33:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/"},"author":{"name":"","@id":""},"headline":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","datePublished":"2024-02-08T10:33:30+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/"},"wordCount":987,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","name":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-08T10:33:30+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-08T10:33:30Z","datePublished":"2024-02-08T10:33:30Z","dateModified":"2024-02-08T10:33:30Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/08\\\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/08\\\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-08T10:33:30Z\",\"datePublished\":\"2024-02-08T10:33:30Z\",\"dateModified\":\"2024-02-08T10:33:30Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445083,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia-2\/","url_meta":{"origin":1445079,"position":0},"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445085,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/una-casa-se-incendia-en-medio-de-un-tiroteo-cerca-a-filadelfia-hay-por-lo-menos-de-6-a-8-personas-desaparecidas-dice-la-policia-3\/","url_meta":{"origin":1445079,"position":1},"title":"Una casa se incendia en medio de un tiroteo cerca a Filadelfia: hay por lo menos de 6 a 8 personas desaparecidas, dice la Polic\u00eda","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Entre seis y ocho personas por lo menos est\u00e1n desaparecidas despu\u00e9s de que se desatara un incendio masivo en una casa a la que las autoridades acudieron por un aparente disparo contra una ni\u00f1a, dijo un fiscal de distrito local. Dos agentes que respondieron al llamado recibieron disparos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451400,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/07\/25\/explosion-destileria-casa-cuervo-mexico-orix\/","url_meta":{"origin":1445079,"position":2},"title":"\u00bfQu\u00e9 pas\u00f3 y por qu\u00e9 hubo una explosi\u00f3n en la destiler\u00eda Casa Cuervo en M\u00e9xico? Esto es lo que sabemos","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La tarde del martes se registr\u00f3 una explosi\u00f3n en las instalaciones de la f\u00e1brica de tequila La Roje\u00f1a, que pertenece a la destiler\u00eda Casa Cuervo \u2013en la zona centro del municipio de Tequila, en Jalisco\u2013 que dej\u00f3 un saldo de seis personas fallecidas y varios heridos.Las autoridades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450651,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/06\/24\/al-menos-dieciseis-muertos-y-6-desaparecidos-en-el-incendio-de-una-fabrica-de-baterias-en-corea-del-sur-trax\/","url_meta":{"origin":1445079,"position":3},"title":"Mueren al menos a 16 personas en un incendio en una f\u00e1brica de bater\u00edas de litio en Corea del Sur","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN) -- Un incendio en una f\u00e1brica de bater\u00edas de litio en Corea del Sur mat\u00f3 al menos a 16 personas y dej\u00f3 a otras seis desaparecidas este lunes, dijeron las autoridades locales de bomberos.El incendio comenz\u00f3 alrededor de las 10:31 am hora local en una instalaci\u00f3n operada por el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461174,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/14\/cody-balmer-casa-incendiada-ben-saphiro-trax\/","url_meta":{"origin":1445079,"position":4},"title":"Qu\u00e9 pas\u00f3 en el incendio de la casa del gobernador de Pensilvania, Ben Shapiro, y qu\u00e9 sabemos del sospechoso, Cody Balmer","author":"","date":"abril 14, 2025","format":false,"excerpt":"Las autoridades de Pensilvania arrestaron a un hombre de Harrisburg que, seg\u00fan afirman, irrumpi\u00f3 en la residencia del gobernador Josh Shapiro la madrugada del domingo e inici\u00f3 un incendio mientras Shapiro y su familia dorm\u00edan.Shapiro, su esposa Lori, sus cuatro hijos, dos perros y otra familia se vieron obligados a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468837,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/30\/incendio-mortal-apartamentos-hong-kong-trax\/","url_meta":{"origin":1445079,"position":5},"title":"\u00bfC\u00f3mo un incendio en un enorme complejo habitacional de Hong Kong se volvi\u00f3 tan mortal?","author":"","date":"noviembre 30, 2025","format":false,"excerpt":"Un incendio devastador arras\u00f3 un enorme complejo habitacional en Hong Kong a inicios de esta semana y dej\u00f3 al menos 146 muertos, adem\u00e1s de numerosos desaparecidos, en el peor desastre que vive la ciudad en d\u00e9cadas.Se cree que a\u00fan hay unas 40 personas desaparecidas. Las autoridades hab\u00edan estimado inicialmente unas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1445079"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445079\/revisions"}],"predecessor-version":[{"id":1445094,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445079\/revisions\/1445094"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1445079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1445079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1445079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}