{"id":1445080,"date":"2024-02-08T03:33:36","date_gmt":"2024-02-08T11:33:36","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445080"},"modified":"2024-02-08T03:33:36","modified_gmt":"2024-02-08T11:33:36","slug":"el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","title":{"rendered":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La canciller\u00eda de Nicaragua notific\u00f3 al Gobierno de Panam\u00e1 que otorg\u00f3 asilo pol\u00edtico al expresidente Ricardo Martinelli.<\/p>\n<p>En una nota \u2015difundida en el sitio oficialista nicarag\u00fcense El 19 Digital\u2015, el Ministerio de Relaciones Exteriores se\u00f1al\u00f3 que el exmandatario lo solicit\u00f3 a su embajada en Ciudad de Panam\u00e1.<\/p>\n<p>El documento detalla que Martinelli solicit\u00f3 asilo \u201cpor considerarse perseguido por razones pol\u00edticas y encontrarse en riesgo inminente su vida, integridad f\u00edsica y seguridad\u201d.<\/p>\n<p>Agrega que solicitan al Gobierno de Panam\u00e1 brindar seguridad a Martinelli para su salida y traslado a territorio nicarag\u00fcense.<\/p>\n<p>Justicia de Panam\u00e1 condena al expresidente Ricardo Martinelli a 10 a\u00f1os de c\u00e1rcel por el caso &#171;News Business&#187;<\/p>\n<p>CNN solicit\u00f3 un comentario sobre este asunto al Gobierno de Panam\u00e1.<\/p>\n<p>CNN confirm\u00f3 el contenido de la nota con el equipo de Martinelli, que dijo que esperan que el gobierno paname\u00f1o les brinde el salvoconducto para que el expresidente pueda salir hacia Managua. Agregaron que el expresidente ingres\u00f3 este mi\u00e9rcoles a la embajada nicarag\u00fcense.<\/p>\n<p>En julio pasado, Martinelli fue condenado a 10 a\u00f1os y seis meses de c\u00e1rcel y a pagar una multa de m\u00e1s de US$ 19,2 millones al ser declarado responsable, junto a otras cuatro personas, del delito de blanqueo de capitales en el caso conocido como \u201cNew Business\u201d, relacionado con un grupo editorial que, seg\u00fan el Ministerio P\u00fablico, fue comprado con fondos que proven\u00edan de contratos con el Estado que se manejaban de forma irregular. \u00c9l se ha declarado inocente en tribunales, as\u00ed como v\u00edctima de persecuci\u00f3n pol\u00edtica.<\/p>\n<p>A pesar de la condena, el expresidente est\u00e1 en libertad y se le permiti\u00f3 inscribirse en el proceso electoral como candidato a la presidencia en la contienda actual. La semana pasada, la Corte Suprema de Justicia no admiti\u00f3 un recurso de casaci\u00f3n en el caso \u201cNew Business\u201d, por lo que dej\u00f3 en firme la condena a Martinelli, que adem\u00e1s lo inhabilita a presentarse como candidato presidencial.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La canciller\u00eda de Nicaragua notific\u00f3 al Gobierno de Panam\u00e1 que otorg\u00f3 asilo pol\u00edtico al expresidente Ricardo Martinelli. En una nota \u2015difundida en el sitio oficialista nicarag\u00fcense El 19 Digital\u2015, el Ministerio de Relaciones Exteriores se\u00f1al\u00f3 que el exmandatario lo solicit\u00f3 a su embajada en Ciudad de Panam\u00e1. El documento detalla que Martinelli [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445080","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La canciller\u00eda de Nicaragua notific\u00f3 al Gobierno de Panam\u00e1 que otorg\u00f3 asilo pol\u00edtico al expresidente Ricardo Martinelli. En una nota \u2015difundida en el sitio oficialista nicarag\u00fcense El 19 Digital\u2015, el Ministerio de Relaciones Exteriores se\u00f1al\u00f3 que el exmandatario lo solicit\u00f3 a su embajada en Ciudad de Panam\u00e1. El documento detalla que Martinelli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-08T11:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli\",\"datePublished\":\"2024-02-08T11:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\",\"name\":\"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-08T11:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La canciller\u00eda de Nicaragua notific\u00f3 al Gobierno de Panam\u00e1 que otorg\u00f3 asilo pol\u00edtico al expresidente Ricardo Martinelli. En una nota \u2015difundida en el sitio oficialista nicarag\u00fcense El 19 Digital\u2015, el Ministerio de Relaciones Exteriores se\u00f1al\u00f3 que el exmandatario lo solicit\u00f3 a su embajada en Ciudad de Panam\u00e1. El documento detalla que Martinelli [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","og_site_name":"Noticias","article_published_time":"2024-02-08T11:33:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli","datePublished":"2024-02-08T11:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","name":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-08T11:33:36+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Nicaragua otorga asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/08\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-08T11:33:36Z","datePublished":"2024-02-08T11:33:36Z","dateModified":"2024-02-08T11:33:36Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Nicaragua otorga asilo pol\\u00edtico al expresidente de Panam\\u00e1 Ricardo Martinelli\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/08\\\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/08\\\/el-gobierno-de-nicaragua-otorga-asilo-politico-al-expresidente-de-panama-ricardo-martinelli\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-08T11:33:36Z\",\"datePublished\":\"2024-02-08T11:33:36Z\",\"dateModified\":\"2024-02-08T11:33:36Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447105,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/18\/panama-martinelli-protesta-nicaragua-orix\/","url_meta":{"origin":1445080,"position":0},"title":"El Gobierno de Panam\u00e1 protesta por &#171;actitud permisiva&#187; de Nicaragua en caso Martinelli","author":"","date":"marzo 18, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El Ministerio de Relaciones Exteriores de Panam\u00e1 envi\u00f3 este lunes a la Canciller\u00eda de Nicaragua una nota de protesta formal por la \u201cactitud permisiva\u201d en la sede de la embajada nicarag\u00fcense en donde permanece el expresidente Ricardo Martinelli en calidad de asilado pol\u00edtico, inform\u00f3 la instituci\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462215,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/10\/otorga-asilo-politico-ricardo-martinelli-panama-orix\/","url_meta":{"origin":1445080,"position":1},"title":"Colombia otorga asilo pol\u00edtico a Ricardo Martinelli, expresidente de Panam\u00e1","author":"","date":"mayo 10, 2025","format":false,"excerpt":"El Gobierno de Colombia concedi\u00f3 asilo pol\u00edtico al expresidente de Panam\u00e1 Ricardo Martinelli, informaron este s\u00e1bado las canciller\u00edas de ambos pa\u00edses.La Canciller\u00eda de Panam\u00e1 dijo en un comunicado que otorg\u00f3 a Martinelli un salvoconducto para poder salir de la Embajada de Nicaragua, donde estaba asilado desde febrero de 2024, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460851,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/04\/vence-salvoconducto-martinelli-gobierno-panama-nicaragua-orix\/","url_meta":{"origin":1445080,"position":2},"title":"Vence salvoconducto de Martinelli y el Gobierno de Panam\u00e1 dice que Nicaragua no dio una respuesta","author":"","date":"abril 4, 2025","format":false,"excerpt":"El salvoconducto que el Gobierno de Ra\u00fal Mulino le concedi\u00f3 la semana pasada al expresidente de Panam\u00e1, Ricardo Martinelli, para viajar a Nicaragua venci\u00f3 tras haberse brindado una extensi\u00f3n de 72 horas el lunes.\u201cComo consecuencia de la falta de respuesta, a pesar de que se envi\u00f3 por canales formales toda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456538,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/12\/12\/panama-embajada-nicaragua-asilo-politico-orix\/","url_meta":{"origin":1445080,"position":3},"title":"Gobierno de Panam\u00e1 pide a la Embajada de Nicaragua respetar el convenio sobre asilo pol\u00edtico","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"El presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, revel\u00f3 este jueves que instruy\u00f3 a su canciller, Javier Mart\u00ednez Acha, para que enviara una primera advertencia al Gobierno de Nicaragua respecto a las actividades del expresidente paname\u00f1o Ricardo Martinelli en la embajada que ese pa\u00eds tiene en Panam\u00e1, donde permanece como asilado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460671,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/31\/nicaragua-martinelli-salvoconducto-panama-orix\/","url_meta":{"origin":1445080,"position":4},"title":"Gobierno de Nicaragua pide a Martinelli no salir de su Embajada en Panam\u00e1","author":"","date":"marzo 31, 2025","format":false,"excerpt":"La vicepresidenta de Nicaragua, Rosario Murillo, pidi\u00f3 al expresidente de Panam\u00e1 Ricardo Martinelli que no utilice el salvoconducto que el Gobierno de Panam\u00e1 le concedi\u00f3 para salir de la embajada nicarag\u00fcense en ese pa\u00eds.A trav\u00e9s de un mensaje televisado por canales oficiales, Murillo lanz\u00f3 esta advertencia argumentando temor a \u201cacciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446072,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/28\/primer-debate-presidencial-panama-candidatos-orix\/","url_meta":{"origin":1445080,"position":5},"title":"El primer debate presidencial en Panam\u00e1 se realiz\u00f3 con el podio del expresidente Ricardo Martinelli vac\u00edo","author":"","date":"febrero 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El primer debate presidencial en Panam\u00e1 para las elecciones generales del pr\u00f3ximo 5 de mayo, se hizo con un sitio vac\u00edo: el del expresidente Ricardo Martinelli. El candidato por el partido Realizando Metas se encuentra en condici\u00f3n de asilado en la Embajada de Nicaragua desde el pasado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1445080"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445080\/revisions"}],"predecessor-version":[{"id":1445096,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445080\/revisions\/1445096"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1445080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1445080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1445080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}