{"id":1445151,"date":"2024-02-09T07:33:41","date_gmt":"2024-02-09T15:33:41","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445151"},"modified":"2024-02-09T07:33:41","modified_gmt":"2024-02-09T15:33:41","slug":"ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","title":{"rendered":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi"},"content":{"rendered":"<p>(CNN) &#8212; Tatler XFEST, los organizadores del partido amistoso de f\u00fatbol en Hong Kong del Inter Miami en el que Lionel Messi no jug\u00f3, anunciaron el viernes que ofrecer\u00e1n a los espectadores un reembolso del 50%.<\/p>\n<p>&#171;Pedimos disculpas a todos aquellos que se sintieron decepcionados por el partido de f\u00fatbol entre el equipo de Hong Kong y el Inter Miami del domingo 4 de febrero. Un evento que esper\u00e1bamos que fuera el orgullo de la ciudad, y en el que hemos trabajado muy duro durante meses, se ha convertido en la fuente de una gran angustia&#187;, dice un comunicado emitido por Tatler XFEST.<\/p>\n<p>&#171;El Inter Miami se hab\u00eda comprometido por contrato a que todos sus jugadores estrella \u2014Messi, Alba, Busquets y Su\u00e1rez\u2014 jugar\u00edan 45 minutos salvo lesi\u00f3n. Sin embargo, el Inter Miami nos inform\u00f3 que Messi y Su\u00e1rez no pod\u00edan jugar por lesiones&#187;, contin\u00faa el comunicado.<\/p>\n<p>Tatler XFEST reconoci\u00f3 que las lesiones eran &#171;parte del juego&#187;, pero a\u00f1adi\u00f3 que lo que nos &#171;molest\u00f3 fue la aparente falta de respeto mostrada al p\u00fablico&#187;.<\/p>\n<p>&#171;Cuando supimos que Messi no jugar\u00eda, suplicamos a los due\u00f1os y a la gerencia del Inter Miami que le instaran a levantarse, a involucrarse con los espectadores y a explicar por qu\u00e9 no pod\u00eda jugar. No lo hizo&#187;.<\/p>\n<p>Messi s\u00ed salt\u00f3 al campo el mi\u00e9rcoles en un partido contra el Vissel Kobe en Tokio, que Tatler XFEST describi\u00f3 como &#171;otra bofetada en la cara&#187;.<\/p>\n<p>En cuanto al reembolso, Tatler XFEST dijo que no iban a &#171;eludir&#187; su &#171;responsabilidad como organizadores&#187;.<\/p>\n<p>&#171;Es por ello que Tatler Asia ofrecer\u00e1 a todos aquellos que adquirieron entradas para el d\u00eda del partido a trav\u00e9s de los canales oficiales un reembolso del 50%&#187;, finaliza el comunicado, a\u00f1adiendo que los detalles sobre el proceso de reembolso se facilitar\u00e1n a mediados de marzo.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Tatler XFEST, los organizadores del partido amistoso de f\u00fatbol en Hong Kong del Inter Miami en el que Lionel Messi no jug\u00f3, anunciaron el viernes que ofrecer\u00e1n a los espectadores un reembolso del 50%. &#171;Pedimos disculpas a todos aquellos que se sintieron decepcionados por el partido de f\u00fatbol entre el equipo de Hong [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445151","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Tatler XFEST, los organizadores del partido amistoso de f\u00fatbol en Hong Kong del Inter Miami en el que Lionel Messi no jug\u00f3, anunciaron el viernes que ofrecer\u00e1n a los espectadores un reembolso del 50%. &#171;Pedimos disculpas a todos aquellos que se sintieron decepcionados por el partido de f\u00fatbol entre el equipo de Hong [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T15:33:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi\",\"datePublished\":\"2024-02-09T15:33:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\"},\"wordCount\":344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\",\"name\":\"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-09T15:33:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","og_locale":"es_ES","og_type":"article","og_title":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias","og_description":"(CNN) &#8212; Tatler XFEST, los organizadores del partido amistoso de f\u00fatbol en Hong Kong del Inter Miami en el que Lionel Messi no jug\u00f3, anunciaron el viernes que ofrecer\u00e1n a los espectadores un reembolso del 50%. &#171;Pedimos disculpas a todos aquellos que se sintieron decepcionados por el partido de f\u00fatbol entre el equipo de Hong [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","og_site_name":"Noticias","article_published_time":"2024-02-09T15:33:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/"},"author":{"name":"","@id":""},"headline":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi","datePublished":"2024-02-09T15:33:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/"},"wordCount":344,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","name":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-09T15:33:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/02\/09\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-09T15:33:41Z","datePublished":"2024-02-09T15:33:41Z","dateModified":"2024-02-09T15:33:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Ofrecen reembolso del 50% a espectadores de Hong Kong que se quedaron sin ver a Messi\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/09\\\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/02\\\/09\\\/ofrecen-reembolso-del-50-a-espectadores-de-hong-kong-que-se-quedaron-sin-ver-a-messi\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-09T15:33:41Z\",\"datePublished\":\"2024-02-09T15:33:41Z\",\"dateModified\":\"2024-02-09T15:33:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444937,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/05\/la-ausencia-de-lionel-messi-provoca-abucheos-y-peticiones-de-reembolso-en-el-partido-del-inter-de-miami-en-hong-kong\/","url_meta":{"origin":1445151,"position":0},"title":"La ausencia de Lionel Messi provoca abucheos y peticiones de reembolso en el partido del Inter de Miami en Hong Kong","author":"","date":"febrero 5, 2024","format":false,"excerpt":"(CNN) -- Miles de aficionados al f\u00fatbol de Hong Kong quedaron decepcionados cuando la superestrella argentina Lionel Messi no salt\u00f3 al campo este domingo en un partido amistoso del Inter de Miami.Lo que empez\u00f3 con una ovaci\u00f3n y un entusiasmo desbordantes termin\u00f3 con abucheos y peticiones de reembolso en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445205,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/10\/ciudad-china-cancela-un-partido-de-futbol-con-la-seleccion-de-argentina-tras-el-episodio-de-messi-en-hong-kong\/","url_meta":{"origin":1445151,"position":1},"title":"Ciudad china cancela un partido de f\u00fatbol con la selecci\u00f3n de Argentina tras el episodio de Messi en Hong Kong","author":"","date":"febrero 10, 2024","format":false,"excerpt":"(CNN) -- Una ciudad de China continental cancel\u00f3 su plan de acoger un partido de f\u00fatbol de la selecci\u00f3n nacional de Argentina en medio de una creciente reacci\u00f3n en el pa\u00eds contra su jugador estrella, Lionel Messi.Messi se ha enfrentado a una avalancha de cr\u00edticas despu\u00e9s de quedarse en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445875,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/21\/messi-china-hong-kong-partido-trax\/","url_meta":{"origin":1445151,"position":2},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445716,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/20\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china-2\/","url_meta":{"origin":1445151,"position":3},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 20, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445679,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/19\/messi-niega-que-su-ausencia-en-el-partido-de-hong-kong-fuera-por-motivos-politicos-he-tenido-una-relacion-muy-estrecha-y-especial-con-china\/","url_meta":{"origin":1445151,"position":4},"title":"Messi niega que su ausencia en el partido de Hong Kong fuera por motivos pol\u00edticos: &#171;He tenido una relaci\u00f3n muy estrecha y especial con China&#187;","author":"","date":"febrero 19, 2024","format":false,"excerpt":"(CNN) -- Lionel Messi\u00a0todav\u00eda est\u00e1 tratando de explicar su ausencia de un\u00a0partido de f\u00fatbol en Hong Kong. La estrella del Inter Miami public\u00f3 este lunes un video en la plataforma de redes sociales china Weibo, luego de una declaraci\u00f3n que hizo en texto hace unas dos semanas.El 4 de febrero,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444135,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/01\/19\/messi-suarez-busquets-y-alba-las-nuevas-estrellas-del-inter-miami-debutan-juntas-ante-el-salvador\/","url_meta":{"origin":1445151,"position":5},"title":"Messi, Su\u00e1rez, Busquets y Alba: las nuevas estrellas del Inter Miami debutan juntas ante El Salvador","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El equipo del sur de la Florida inicia su gira de amistosos con un encuentro frente a la selecci\u00f3n de El Salvador este viernes a las 8 p.m. hora del Este, en el estadio Cuscatl\u00e1n en San Salvador. El equipo de Gerardo Martino da comienzo a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1445151"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445151\/revisions"}],"predecessor-version":[{"id":1445167,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1445151\/revisions\/1445167"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1445151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1445151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1445151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}