{"id":1451837,"date":"2024-08-13T18:03:49","date_gmt":"2024-08-14T01:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/"},"modified":"2024-08-13T18:03:49","modified_gmt":"2024-08-14T01:03:49","slug":"presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","title":{"rendered":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, plante\u00f3 este martes una reforma a las leyes electorales con el objetivo de que \u201cning\u00fan extranjero\u201d pueda pronunciarse sobre los comicios que se realizan en el pa\u00eds sudamericano.<\/p>\n<p>Rodr\u00edguez, militante del oficialista Partido Socialista Unido de Venezuela (PSUV) y uno de los hombres m\u00e1s cercanos al presidente Nicol\u00e1s Maduro, hizo esta propuesta luego de que han transcurrido m\u00e1s de dos semanas de las elecciones presidenciales del 28 de julio, en las que el Consejo Nacional Electoral (CNE) proclam\u00f3 ganador a Maduro sin mostrar los datos desglosados por centro y mesa de votaci\u00f3n.<\/p>\n<p>As\u00ed han reaccionado l\u00edderes mundiales tras los pol\u00e9micos resultados electorales en Venezuela<\/p>\n<p>La opositora Plataforma Unitaria Democr\u00e1tica (PUD) rechaza el resultado y afirma que el triunfador fue Edmundo Gonz\u00e1lez Urrutia. El anuncio del CNE tambi\u00e9n ha sido cuestionado por algunos gobiernos de la regi\u00f3n \u2014siete de ellos han reconocido a Gonz\u00e1lez Urrutia como el triunfador\u2014 y organizaciones no gubernamentales.<\/p>\n<p>Durante la sesi\u00f3n de la Asamblea Nacional realizada esta tarde, Rodr\u00edguez se refiri\u00f3 a algunas de esas cr\u00edticas e insisti\u00f3 en que Venezuela necesita reformas electorales que frenen pronunciamientos que consider\u00f3 violaciones a su soberan\u00eda.<\/p>\n<p>Estados Unidos reconoce al opositor Edmundo Gonz\u00e1lez como ganador de las elecciones presidenciales en Venezuela<\/p>\n<p>\u201cPropongo que nosotros hagamos una reforma de las leyes electorales de Venezuela para que nunca m\u00e1s ning\u00fan extranjero venga a tomar posici\u00f3n sobre nada que tenga que ver con las elecciones de Venezuela. \u00bfPor qu\u00e9 tienen que venir? \u00bfA cuenta de qu\u00e9? \u00bfQu\u00e9 tipo de capacidad tienen?\u201d, dijo.<\/p>\n<p>Entre otros, el diputado se refiri\u00f3 a los pronunciamientos de expertos de la Organizaci\u00f3n de las Naciones Unidas y del Centro Carter, que calific\u00f3 de \u201cbasura\u201d despu\u00e9s de que cuestionaran los resultados del CNE.<br \/>\nPocos d\u00edas despu\u00e9s de las votaciones, el Centro Carter public\u00f3 el informe de su misi\u00f3n de observaci\u00f3n electoral, que concluy\u00f3 que la contienda en Venezuela no cumpli\u00f3 con los par\u00e1metros para ser considerada democr\u00e1tica.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, plante\u00f3 este martes una reforma a las leyes electorales con el objetivo de que \u201cning\u00fan extranjero\u201d pueda pronunciarse sobre los comicios que se realizan en el pa\u00eds sudamericano. Rodr\u00edguez, militante del oficialista Partido Socialista Unido de Venezuela (PSUV) y uno de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451837","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, plante\u00f3 este martes una reforma a las leyes electorales con el objetivo de que \u201cning\u00fan extranjero\u201d pueda pronunciarse sobre los comicios que se realizan en el pa\u00eds sudamericano. Rodr\u00edguez, militante del oficialista Partido Socialista Unido de Venezuela (PSUV) y uno de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-14T01:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds\",\"datePublished\":\"2024-08-14T01:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\"},\"wordCount\":400,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\",\"name\":\"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-14T01:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, plante\u00f3 este martes una reforma a las leyes electorales con el objetivo de que \u201cning\u00fan extranjero\u201d pueda pronunciarse sobre los comicios que se realizan en el pa\u00eds sudamericano. Rodr\u00edguez, militante del oficialista Partido Socialista Unido de Venezuela (PSUV) y uno de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","og_site_name":"Noticias","article_published_time":"2024-08-14T01:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/"},"author":{"name":"","@id":""},"headline":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds","datePublished":"2024-08-14T01:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/"},"wordCount":400,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","url":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","name":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-14T01:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El presidente de la Asamblea de Venezuela propone reformas electorales para que \u201cning\u00fan extranjero\u201d se pronuncie sobre comicios en el pa\u00eds","url":"http:\/\/noticiasya.com\/washington-dc\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2024\/08\/13\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-14T01:03:49Z","datePublished":"2024-08-14T01:03:49Z","dateModified":"2024-08-14T01:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El presidente de la Asamblea de Venezuela propone reformas electorales para que \\u201cning\\u00fan extranjero\\u201d se pronuncie sobre comicios en el pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/08\\\/13\\\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2024\\\/08\\\/13\\\/presidente-asamblea-venezuela-reformas-electorales-ningun-extranjero-pronuncie-comicios-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-14T01:03:49Z\",\"datePublished\":\"2024-08-14T01:03:49Z\",\"dateModified\":\"2024-08-14T01:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1454999,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/10\/08\/venezuela-romper-relaciones-espana-asamblea-nacional-maduro-orix\/","url_meta":{"origin":1451837,"position":0},"title":"La Asamblea Nacional de Venezuela pide a Maduro romper relaciones con Espa\u00f1a","author":"","date":"octubre 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Asamblea Nacional de Venezuela controlada por el chavismo aprob\u00f3 este martes un acuerdo para pedirle al presidente Nicol\u00e1s Maduro que rompa relaciones diplom\u00e1ticas, consulares y comerciales con el Reino de Espa\u00f1a, en represalia por la decisi\u00f3n del Congreso de los Diputados, aunque con el voto en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451066,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/07\/12\/como-votar-extranjero-elecciones-venezuela-2024-fecha-requisitos-orix\/","url_meta":{"origin":1451837,"position":1},"title":"C\u00f3mo votar desde el extranjero para las elecciones presidenciales de Venezuela: fecha y requisitos","author":"","date":"julio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Miles de venezolanos en el extranjero participar\u00e1n en las elecciones presidenciales del 28 de julio para elegir, entre 10 candidatos, a quien ser\u00e1 su pr\u00f3ximo presidente.Para estos comicios solo pueden participar aquellos venezolanos que sean mayores de 18 a\u00f1os, que posean residencia o cualquier otro estatus que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452097,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/08\/23\/machado-critica-tribunal-supremo-venezuela-resultados-electorales-maduro-sentencia-historica-contundente-orix\/","url_meta":{"origin":1451837,"position":2},"title":"Machado critica al Tribunal Supremo de Venezuela por validar los resultados electorales; Maduro dice que la sentencia es \u201chist\u00f3rica y contundente\u201d","author":"","date":"agosto 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La l\u00edder opositora venezolana Mar\u00eda Corina Machado critic\u00f3 este jueves al Tribunal Supremo de Justicia de Venezuela (TSJ) por validar los resultados de las elecciones del 28 de julio \u2014de las que hasta ahora no se han publicado las actas desglosadas por mesa de votaci\u00f3n\u2014, mientras que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462819,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/26\/resultados-elecciones-oficialismo-abstencion-orix\/","url_meta":{"origin":1451837,"position":3},"title":"Los resultados en la elecci\u00f3n criticada en Venezuela: dominio del oficialismo y participaci\u00f3n del 42%, seg\u00fan CNE","author":"","date":"mayo 26, 2025","format":false,"excerpt":"Los resultados anunciados por las autoridades de las elecciones regionales, parlamentarias y de Consejos Legislativos en Venezuela reiteran el dominio del oficialismo en un ambiente de poca participaci\u00f3n electoral y concentraci\u00f3n de poder.La jornada estuvo marcada por la fragmentaci\u00f3n de la oposici\u00f3n, pues una parte importante no particip\u00f3 y llam\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457392,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/09\/como-llego-maduro-poder-venezuela-orix\/","url_meta":{"origin":1451837,"position":4},"title":"\u00bfC\u00f3mo lleg\u00f3 Nicol\u00e1s Maduro al poder en Venezuela y cu\u00e1nto tiempo lleva?","author":"","date":"enero 9, 2025","format":false,"excerpt":"El Consejo Nacional Electoral de Venezuela le dio la victoria en las elecciones presidenciales del 28 de julio a Nicol\u00e1s Maduro sin presentar los resultados desglosados por mesa y centro de votaci\u00f3n. La oposici\u00f3n no reconoce los resultados y varios l\u00edderes internacionales pidieron transparencia. El 10 de enero est\u00e1 previsto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451926,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/08\/16\/lula-da-silva-gobierno-maduro-venezuela-regimen-desagradable-sesgo-autoritario-orix\/","url_meta":{"origin":1451837,"position":5},"title":"Lula da Silva dice que el Gobierno de Maduro en Venezuela es un r\u00e9gimen con un &#171;sesgo autoritario&#187;, pero &#171;no es una dictadura&#187;","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, calific\u00f3 este viernes al Gobierno de Nicol\u00e1s Maduro en Venezuela como un r\u00e9gimen \"muy desagradable\" con un \"sesgo autoritario\", aunque aclar\u00f3 que no lo considera una dictadura.\"Creo\u00a0que\u00a0Venezuela\u00a0vive\u00a0en\u00a0un r\u00e9gimen muy\u00a0desagradable. No creo\u00a0que sea una dictadura, es diferente a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1451837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1451837"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1451837\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1451837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1451837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1451837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}