{"id":1457937,"date":"2025-01-27T19:03:46","date_gmt":"2025-01-28T03:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/"},"modified":"2025-01-27T19:03:46","modified_gmt":"2025-01-28T03:03:46","slug":"detenidos-biden-deportados-trump-guatemaltecos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","title":{"rendered":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas"},"content":{"rendered":"<p>El vuelo aterriz\u00f3 sin contratiempos a media ma\u00f1ana, con el sol asomando de vez en cuando entre las nubes sobre Ciudad de Guatemala.<\/p>\n<p>Sin embargo, en lugar de dirigirse a la zona de llegadas internacionales, el avi\u00f3n se dirigi\u00f3 a la zona militar del aeropuerto, mientras los aviones de combate se escuchaban por encima, zigzagueando en ejercicios de entrenamiento.<\/p>\n<p>Cuando se abrieron las puertas del avi\u00f3n, docenas de hombres y mujeres fueron conducidos a la pista, donde fueron recibidos por una emocionada vicepresidenta de Guatemala, Karin Herrera, y otros funcionarios, y luego conducidos a un centro de recepci\u00f3n para deportados.<\/p>\n<p>\u201c\u00a1Buenos d\u00edas!\u201d, grit\u00f3 una. \u201c\u00bfC\u00f3mo estan, paisanos?\u201d<\/p>\n<p>Se trataba de un vuelo ch\u00e1rter de deportaci\u00f3n de Estados Unidos, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/24\/eeuu\/deportacion-inmigrantes-aviones-militares-trax\">una operaci\u00f3n<\/a> que ha ganado nueva atenci\u00f3n desde la toma de posesi\u00f3n del presidente Donald Trump la semana pasada y sus promesas de expulsar a millones de migrantes indocumentados.<\/p>\n<p>Si hab\u00eda algo de verg\u00fcenza o animosidad cuando el vuelo parti\u00f3 de Alexandria, Louisiana, justo antes del amanecer, nada de eso era evidente cuando los migrantes caminaron de regreso a suelo guatemalteco, muchos arrastrando los pies con los tenis abiertos, los cordones fueron tomados por las autoridades estadounidenses en una pr\u00e1ctica de seguridad com\u00fan, y nunca fueron devueltos.<\/p>\n<p>Los pasajeros \u2014todos adultos en este vuelo\u2014 fueron recibidos con galletas y caf\u00e9 y procesados eficientemente en el centro de recepci\u00f3n de migrantes.<\/p>\n<p>Los vuelos de repatriaci\u00f3n han sido un proceso continuo, dijo Herrera a CNN, y a\u00f1adi\u00f3 que no hubo un aumento desde que Trump lleg\u00f3 al poder. La \u00fanica diferencia, dijo, fue el uso de aviones militares como el que lleg\u00f3 m\u00e1s tarde el lunes.<\/p>\n<p>No quiso hablar sobre la disputa del fin de semana entre Colombia y Estados Unidos sobre el uso de aviones militares, y dijo que su atenci\u00f3n se enfocaba en sus ciudadanos.<\/p>\n<p>\u201cEstamos comprometidos con su integridad y sus derechos b\u00e1sicos\u201d, dijo Herrera.<\/p>\n<p>Algunos de los guatemaltecos que regresaron hab\u00edan vivido y trabajado en Estados Unidos durante a\u00f1os. Algunos hablaban ingl\u00e9s con fluidez. Pero todos hab\u00edan entrado sin permiso ni documentos, por lo que estaban sujetos a deportaci\u00f3n.<\/p>\n<p>Los migrantes salieron de Estados Unidos como delincuentes, y nos contaron que les esposaron a bordo hasta que salieron del espacio a\u00e9reo estadounidense en su vuelo hacia el sur. Pero tanto si estaban deseando volver a su pa\u00eds como si no, la recepci\u00f3n oficial que recibieron fue en su mayor\u00eda muy c\u00e1lida, como si los hubieran extra\u00f1ado mucho. Algunos permanecieron esposados y escoltados por la polic\u00eda, pues se esperaba que fueran procesados por delitos presuntamente cometidos en su pa\u00eds.<\/p>\n<p>Pero la mayor\u00eda se sent\u00f3 a tomar un tentempi\u00e9 mientras los llamaban por su nombre y les entregaban documentos de identidad provisionales. Ya no eran \u201cindocumentados\u201d.<\/p>\n<p>Es posible que tengan aptitudes y habilidades que les permitan encontrar trabajo y una buena vida en su pa\u00eds de origen, en beneficio propio y tambi\u00e9n de Guatemala, seg\u00fan las autoridades.<\/p>\n<p>Los migrantes deportados aplaudieron a Herrera despu\u00e9s de que pronunciara un breve discurso en la sala de llegadas, pero cada uno tiene su propia opini\u00f3n sobre si har\u00e1n caso a los llamados a quedarse.<\/p>\n<p>Sara Tot-Botoz llevaba 10 a\u00f1os viviendo en Alabama, trabajando en la construcci\u00f3n, techando y reparando veh\u00edculos, adem\u00e1s de cuidar de dos de sus hijos, ya adultos, y de sus nietos.<\/p>\n<p>Hace unos siete meses, cuando sal\u00eda de un Walmart con uno de sus nietos, la polic\u00eda la detuvo y la mult\u00f3 por no llevar al ni\u00f1o en la sillita del coche.<\/p>\n<p>Despu\u00e9s de que se descubriera su condici\u00f3n de inmigrante, pas\u00f3 dos meses en la c\u00e1rcel en Alabama y luego cinco meses detenida por el Servicio de Inmigraci\u00f3n y Control de Aduanas en Louisiana, dijo.<\/p>\n<p>Una vez procesada de vuelta a Guatemala, dijo que su primer pensamiento fue quitarse la sudadera gris sin forma que llevaba y ponerse su ropa ind\u00edgena. Y luego comer algo bueno.<\/p>\n<p>Tot-Botoz, de 43 a\u00f1os, esperaba sus pertenencias. S\u00f3lo un pu\u00f1ado de inmigrantes llevaba maletas para sus cosas. La mayor\u00eda de los dem\u00e1s esperaban a que les entregaran un gran saco de pl\u00e1stico con todo lo que se hab\u00edan llevado de Estados Unidos.<\/p>\n<p>Mientras otros cargaban sus tel\u00e9fonos en bancos de energ\u00eda gratuitos para llamar a amigos o familiares, Tot-Botoz se cambi\u00f3 y sali\u00f3 a toda prisa a la calle.<\/p>\n<p>All\u00ed estaba otra de sus hijas, de 25 a\u00f1os, que no ve\u00eda a su madre desde que ten\u00eda 15 a\u00f1os.<\/p>\n<p>Las dos mujeres se abrazaron largo rato, cada una llorando.<\/p>\n<p>No hab\u00edan estado en contacto desde que Tot-Botoz fue detenida y, aunque hab\u00eda mucho de lo que ponerse al d\u00eda, durante unos minutos s\u00f3lo quer\u00edan abrazarse.<\/p>\n<p>\u201cAhora se siente peligroso en Estados Unidos\u201d, dijo Tot-Botoz a CNN, y explic\u00f3 que los migrantes indocumentados pueden ser detenidos en cualquier lugar.<\/p>\n<p>Tot-Botoz dijo a CNN que por ahora quiere volver a su comunidad ind\u00edgena, a unas cinco horas en autom\u00f3vil, y no marcharse nunca.<\/p>\n<p>No obstante, Fidel Ambrocio dijo que todav\u00eda ve\u00eda su futuro en Estados Unidos.<\/p>\n<p>Coment\u00f3 que hab\u00eda vivido all\u00ed un total de 19 a\u00f1os, lleg\u00f3 por primera vez cuando era adolescente y se fue voluntariamente por un tiempo en 2018 antes de volver al norte.<\/p>\n<p>Tiene esposa, una hija de cuatro a\u00f1os y un hijo peque\u00f1o, nacido apenas un par de meses antes de ser detenido, seg\u00fan dijo, por una antigua orden de detenci\u00f3n por allanamiento de morada en casa de la madre de su exesposa.<\/p>\n<p>Ambrocio, de 35 a\u00f1os, que hab\u00eda trabajado en la construcci\u00f3n en Montgomery, Alabama, parec\u00eda casi aturdido por estar de vuelta en Guatemala.<\/p>\n<p>Tambi\u00e9n estaba enojado, sin comprender por qu\u00e9 fue deportado cuando la mayor parte de la ret\u00f3rica de Trump y su equipo ha sido sobre enviar a los delincuentes violentos fuera del pa\u00eds.<\/p>\n<p>\u201cNo somos criminales\u201d, insisti\u00f3, y dijo que no consideraba que su infracci\u00f3n fuera un delito grave.<\/p>\n<p>Los migrantes con los que habl\u00f3 CNN fueron todos detenidos mientras Joe Biden era presidente, y pasaron por procedimientos de expulsi\u00f3n que los llevaron a estar en el vuelo de Louisiana.<\/p>\n<p>Ambrocio dijo a CNN que intentar\u00eda volver a Estados Unidos. Legalmente, dijo, tiene que esperar 10 a\u00f1os antes de solicitar un visado, pero dijo que podr\u00eda intentarlo en dos o cuatro a\u00f1os, incluso si eso significaba viajar ilegalmente y enfrentarse a las consecuencias que pudieran ser.<\/p>\n<p>\u201cSi no puedo volver nunca, intentar\u00e9 traer a mi esposa y a mis hijos\u201d, admiti\u00f3. \u201cSer\u00e1 un gran reto\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vuelo aterriz\u00f3 sin contratiempos a media ma\u00f1ana, con el sol asomando de vez en cuando entre las nubes sobre Ciudad de Guatemala. Sin embargo, en lugar de dirigirse a la zona de llegadas internacionales, el avi\u00f3n se dirigi\u00f3 a la zona militar del aeropuerto, mientras los aviones de combate se escuchaban por encima, zigzagueando [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457937","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El vuelo aterriz\u00f3 sin contratiempos a media ma\u00f1ana, con el sol asomando de vez en cuando entre las nubes sobre Ciudad de Guatemala. Sin embargo, en lugar de dirigirse a la zona de llegadas internacionales, el avi\u00f3n se dirigi\u00f3 a la zona militar del aeropuerto, mientras los aviones de combate se escuchaban por encima, zigzagueando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T03:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas\",\"datePublished\":\"2025-01-28T03:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\"},\"wordCount\":1182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\",\"name\":\"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-28T03:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias","og_description":"El vuelo aterriz\u00f3 sin contratiempos a media ma\u00f1ana, con el sol asomando de vez en cuando entre las nubes sobre Ciudad de Guatemala. Sin embargo, en lugar de dirigirse a la zona de llegadas internacionales, el avi\u00f3n se dirigi\u00f3 a la zona militar del aeropuerto, mientras los aviones de combate se escuchaban por encima, zigzagueando [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-28T03:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/"},"author":{"name":"","@id":""},"headline":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas","datePublished":"2025-01-28T03:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/"},"wordCount":1182,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","name":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-28T03:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/detenidos-biden-deportados-trump-guatemaltecos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-28T03:03:46Z","datePublished":"2025-01-28T03:03:46Z","dateModified":"2025-01-28T03:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detenidos con Biden, deportados con Trump: guatemaltecos son devueltos y recibidos con galletas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/27\\\/detenidos-biden-deportados-trump-guatemaltecos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/27\\\/detenidos-biden-deportados-trump-guatemaltecos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-28T03:03:46Z\",\"datePublished\":\"2025-01-28T03:03:46Z\",\"dateModified\":\"2025-01-28T03:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468409,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/16\/venezolanos-deportados-eeuu-avion-caracas-trax\/","url_meta":{"origin":1457937,"position":0},"title":"M\u00e1s de 290 venezolanos deportados de EE.UU. llegaron a Caracas en vuelo de repatriaci\u00f3n","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"Un vuelo con 298 ciudadanos venezolanos que fueron deportados de Estados Unidos lleg\u00f3 a Caracas el viernes, inform\u00f3 el Ministerio del Interior, Justicia y Paz de Venezuela.A su llegada desde El Paso al Aeropuerto Internacional de Maiquet\u00eda Sim\u00f3n Bol\u00edvar, los deportados fueron recibidos por autoridades de seguridad ciudadana que siguieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458700,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/02\/13\/deportacion-migrantes-paises-asiaticos-panama-trax\/","url_meta":{"origin":1457937,"position":1},"title":"Mulino afirma que EE.UU. deport\u00f3 a migrantes de varios pa\u00edses asi\u00e1ticos a Panam\u00e1","author":"","date":"febrero 13, 2025","format":false,"excerpt":"Un avi\u00f3n militar estadounidense que deport\u00f3 a 119 ciudadanos no paname\u00f1os, incluidos inmigrantes de varios pa\u00edses asi\u00e1ticos, lleg\u00f3 a la naci\u00f3n centroamericana el mi\u00e9rcoles, dijo el presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, en una conferencia de prensa este jueves.Los migrantes, de \u201clas nacionalidades m\u00e1s diversas del mundo\u201d, fueron recibidos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457433,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/10\/pasajeros-evacuan-vuelo-delta-atlanta-trax\/","url_meta":{"origin":1457937,"position":2},"title":"Pasajeros evacuan por tobog\u00e1n vuelo de Delta, tras despegue fallido en pista llena de nieve en Atlanta","author":"","date":"enero 10, 2025","format":false,"excerpt":"Un avi\u00f3n de Delta Air Lines con m\u00e1s de 200 personas a bordo fue evacuado en la pista del aeropuerto de Atlanta este viernes por la ma\u00f1ana, despu\u00e9s de que un problema de motor caus\u00f3 un despegue abortado, dejando a cuatro personas lesionadas, dijeron la aerol\u00ednea y funcionarios de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460810,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/03\/vuelo-198-migrantes-deportados-eeuu-venezuela-orix\/","url_meta":{"origin":1457937,"position":3},"title":"Un nuevo vuelo con 198 migrantes deportados por EE.UU. llega a Venezuela","author":"","date":"abril 3, 2025","format":false,"excerpt":"Un vuelo con 198 migrantes venezolanos deportados por Estados Unidos lleg\u00f3 la tarde de este jueves al Aeropuerto Internacional de Maiquet\u00eda, estado La Guaira, dijo a periodistas el ministro de Transporte del pa\u00eds sudamericano, Ram\u00f3n Vel\u00e1squez, momentos despu\u00e9s del aterrizaje del avi\u00f3n.La aeronave, de la empresa estatal Conviasa, traslad\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457955,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/petro-aviones-colombianos-deportados-sin-esposas-orix\/","url_meta":{"origin":1457937,"position":4},"title":"Llega a Colombia el primer vuelo con deportados. Petro dice que llegan &#171;libres y dignos&#187;","author":"","date":"enero 28, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, comparti\u00f3 im\u00e1genes este martes del primer vuelo con los colombianos deportados de EE.UU. al llegar a Bogot\u00e1, proveniente de Texas. El mandatario dijo en una publicaci\u00f3n de X que \u201cel migrante no es un delincuente es un ser humano que quiere trabajar y progresar,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460615,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/30\/vuelo-inmigrantes-deportados-eeuu-caracas-venezuela-trax\/","url_meta":{"origin":1457937,"position":5},"title":"Llega a Venezuela un nuevo vuelo con 175 inmigrantes deportados de EE.UU.","author":"","date":"marzo 30, 2025","format":false,"excerpt":"Un avi\u00f3n que transportaba inmigrantes deportados de Estados Unidos aterriz\u00f3 en Venezuela este domingo, el tercer vuelo de este tipo desde que ambas naciones acordaron reanudar los vuelos de repatriaci\u00f3n a principios de este mes, seg\u00fan un equipo de CNN en el lugar.El vuelo, que despeg\u00f3 de Texas, aterriz\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1457937"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457937\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1457937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1457937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1457937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}