{"id":1457939,"date":"2025-01-27T20:03:44","date_gmt":"2025-01-28T04:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/"},"modified":"2025-01-27T20:03:44","modified_gmt":"2025-01-28T04:03:44","slug":"departamento-justicia-despide-funcionarios-investigaron-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","title":{"rendered":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero"},"content":{"rendered":"<p>M\u00e1s de una docena de funcionarios que trabajaron en las investigaciones penales sobre Donald Trump fueron despedidos, seg\u00fan fuentes familiarizadas con el asunto.<\/p>\n<p>Una carta del secretario de Justicia en funciones, James McHenry, a los funcionarios dec\u00eda que no se puede \u201cconfiar\u201d en ellos para que apliquen \u201cfielmente\u201d la agenda de Trump.<\/p>\n<p>\u201cUstedes jugaron un papel significativo en la persecuci\u00f3n contra el presidente Trump. El buen funcionamiento del gobierno depende cr\u00edticamente de la confianza que los funcionarios superiores depositan en sus subordinados\u201d, escribi\u00f3 McHenry. \u201cDado su papel significativo en el enjuiciamiento del presidente, no creo que el liderazgo del Departamento pueda confiar en usted para ayudar a implementar fielmente la agenda del presidente\u201d.<\/p>\n<p>Los despidos se producen cuando el Gobierno de Trump est\u00e1 tomando medidas concretas para investigar a los fiscales que supervisaron los casos penales contra los acusados del 6 de enero despu\u00e9s de que Trump prometiera buscar represalias como una promesa clave de su campa\u00f1a, seg\u00fan m\u00faltiples fuentes que vieron un memorando interno sobre el asunto.<\/p>\n<p>Ed Martin, fiscal estadounidense interino en Washington, puso en marcha una investigaci\u00f3n sobre los fiscales que presentaron cargos de obstrucci\u00f3n bajo el <a href=\"https:\/\/www.law.cornell.edu\/uscode\/text\/18\/1512\">C\u00f3digo de Estados Unidos 1512 (c)<\/a> contra algunos agitadores que finalmente fueron desestimados debido a una decisi\u00f3n de la Corte Suprema el verano pasado.<\/p>\n<p>Al referirse al esfuerzo como un \u201cproyecto especial\u201d, Martin escribi\u00f3 en el memorando emitido este lunes que los abogados deben entregar \u201ctoda la informaci\u00f3n que tengan relacionada con el uso de los cargos 1512, incluyendo todos los archivos, documentos, notas, correos electr\u00f3nicos y otra informaci\u00f3n\u201d a dos de los fiscales de mucho tiempo de la oficina que deben presentar un informe sobre la investigaci\u00f3n antes del viernes.<\/p>\n<p>\u201cObviamente, el uso fue un gran fracaso de nuestra oficina \u2013decisi\u00f3n de la Corte Suprema\u2013 y tenemos que llegar al fondo de la misma\u201d, dice el memorando, en referencia a la sentencia de la Corte de Suprema de junio que limit\u00f3 el poder de los fiscales federales para perseguir cargos de obstrucci\u00f3n contra los agitadores del 6 de enero.<\/p>\n<p>La petici\u00f3n de documentos se extiende tambi\u00e9n a los fiscales que han abandonado la fiscal\u00eda.<\/p>\n<p>La medida ocurre en un momento en que el Departamento de Justicia ya ha sufrido una dr\u00e1stica reorganizaci\u00f3n al ser reasignados funcionarios relacionados con investigaciones de alto perfil, incluido el caso ahora desestimado contra el propio Trump por sus esfuerzos para anular las elecciones presidenciales de 2020.<\/p>\n<p>Los fiscales que trabajaron en los casos del 6 de enero dijeron a CNN que el memorando aumenta la preocupaci\u00f3n de que el Departamento de Justicia de Trump est\u00e9 comenzando a \u201cinvestigar a los investigadores\u201d, como ha amenazado durante mucho tiempo. Una persona que trabaj\u00f3 en casos de disturbios en el Capitolio dijo a CNN que los fiscales no saben si esta investigaci\u00f3n busca presentar cargos penales o civiles, y que algunos est\u00e1n empezando a contratar a sus propios abogados para su defensa.<\/p>\n<p>Un alto funcionario de la administraci\u00f3n familiarizado con el correo electr\u00f3nico de Martin describe esto como una misi\u00f3n de \u201cinvestigaci\u00f3n\u201d, y se\u00f1ala un \u201cenorme desperdicio de recursos\u201d.<\/p>\n<p>\u201cLa oficina anterior meti\u00f3 la pata presentando cientos de casos que acabaron siendo desestimados por la Corte Suprema, merece la pena llegar al fondo de la mala toma de decisiones\u201d, dijo la persona.<\/p>\n<p>CNN se puso en contacto con el Departamento de Justicia para solicitar sus comentarios.<\/p>\n<p>Martin, un activista y analista de l\u00ednea dura y socialmente conservador que fue organizador del movimiento \u201cStop the Steal\u201d, fue elegido para el cargo la semana pasada. Desde que asumi\u00f3 el cargo, ha elogiado a Trump por conceder indultos masivos a acusados el 6 de enero.<\/p>\n<p>Tambi\u00e9n presion\u00f3 con \u00e9xito a un juez para que anulara las restricciones de viaje impuestas a los miembros de los Oath Keepers tras su puesta en libertad: \u201cSi un juez decidiera prohibir a Jim Biden, al general Mark Milley o a cualquier otra persona visitar la capital de Estados Unidos \u2014incluso despu\u00e9s de recibir un indulto preventivo de \u00faltima hora del expresidente\u2014, creo que la mayor\u00eda de los estadounidenses se opondr\u00edan. Las personas a las que se hace referencia en nuestra moci\u00f3n han visto conmutadas sus sentencias, punto, fin de la sentencia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de una docena de funcionarios que trabajaron en las investigaciones penales sobre Donald Trump fueron despedidos, seg\u00fan fuentes familiarizadas con el asunto. Una carta del secretario de Justicia en funciones, James McHenry, a los funcionarios dec\u00eda que no se puede \u201cconfiar\u201d en ellos para que apliquen \u201cfielmente\u201d la agenda de Trump. \u201cUstedes jugaron un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457939","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &quot;proyecto especial&quot; sobre el 6 de enero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &quot;proyecto especial&quot; sobre el 6 de enero - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de una docena de funcionarios que trabajaron en las investigaciones penales sobre Donald Trump fueron despedidos, seg\u00fan fuentes familiarizadas con el asunto. Una carta del secretario de Justicia en funciones, James McHenry, a los funcionarios dec\u00eda que no se puede \u201cconfiar\u201d en ellos para que apliquen \u201cfielmente\u201d la agenda de Trump. \u201cUstedes jugaron un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T04:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero\",\"datePublished\":\"2025-01-28T04:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\"},\"wordCount\":762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\",\"name\":\"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza \\\"proyecto especial\\\" sobre el 6 de enero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-28T04:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza \"proyecto especial\" sobre el 6 de enero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza \"proyecto especial\" sobre el 6 de enero - Noticias","og_description":"M\u00e1s de una docena de funcionarios que trabajaron en las investigaciones penales sobre Donald Trump fueron despedidos, seg\u00fan fuentes familiarizadas con el asunto. Una carta del secretario de Justicia en funciones, James McHenry, a los funcionarios dec\u00eda que no se puede \u201cconfiar\u201d en ellos para que apliquen \u201cfielmente\u201d la agenda de Trump. \u201cUstedes jugaron un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-28T04:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero","datePublished":"2025-01-28T04:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/"},"wordCount":762,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","name":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza \"proyecto especial\" sobre el 6 de enero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-28T04:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/27\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-28T04:03:44Z","datePublished":"2025-01-28T04:03:44Z","dateModified":"2025-01-28T04:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Departamento de Justicia despide a funcionarios que investigaron a Trump y lanza &#171;proyecto especial&#187; sobre el 6 de enero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/27\\\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/27\\\/departamento-justicia-despide-funcionarios-investigaron-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-28T04:03:44Z\",\"datePublished\":\"2025-01-28T04:03:44Z\",\"dateModified\":\"2025-01-28T04:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457948,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/analisis-trump-agenda-de-represalias-trax\/","url_meta":{"origin":1457939,"position":0},"title":"AN\u00c1LISIS |Trump emprende su agenda de represalias con entusiasmo","author":"","date":"enero 28, 2025","format":false,"excerpt":"Para Donald Trump, la venganza es un plato que se sirve bien caliente.El presidente no perdi\u00f3 tiempo en cumplir sus frecuentes promesas electorales de venganza, con un torrente de purgas e indultos.Trump envi\u00f3 un mensaje escalofriante a trav\u00e9s del Gobierno de EE.UU.: los funcionarios que se le crucen, investiguen sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458192,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/02\/04\/trump-musk-gobierno-federal-analisis-trax\/","url_meta":{"origin":1457939,"position":1},"title":"AN\u00c1LISIS | Musk y Trump buscan actuar con rapidez y agitar el sistema del gobierno federal","author":"","date":"febrero 4, 2025","format":false,"excerpt":"Elon Musk y el presidente Donald Trump est\u00e1n aplicando al Gobierno estadounidense la filosof\u00eda de Silicon Valley de \u201cmoverse r\u00e1pido y romper cosas\u201d.Los acontecimientos se suceden sin cesar mientras los dos hombres trabajan con rapidez para reimaginar elementos del gobierno federal, purgar a funcionarios que no les gustan o en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465144,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/05\/gobierno-trump-debate-divulgar-transcripcion-entrevista-ghislaine-maxwell-trax\/","url_meta":{"origin":1457939,"position":2},"title":"Gobierno de Trump debate si publicar o no transcripci\u00f3n de la entrevista del vicesecretario de Justicia con Ghislaine Maxwell","author":"","date":"agosto 5, 2025","format":false,"excerpt":"El Departamento de Justicia tiene una grabaci\u00f3n de audio de la entrevista que realiz\u00f3 el mes pasado a Ghislaine Maxwell, socia de Jeffrey Epstein, y el Gobierno est\u00e1 considerando divulgar p\u00fablicamente una transcripci\u00f3n de la misma, dijeron a CNN tres altos funcionarios del Gobierno.Hasta ahora, no se sab\u00eda de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455760,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/11\/11\/trump-busca-secretario-justicia-represalias-trax\/","url_meta":{"origin":1457939,"position":3},"title":"Trump busca a su secretario de Justicia mientras los funcionarios del Departamento de Justicia se preocupan por el caos y las represalias","author":"","date":"noviembre 11, 2024","format":false,"excerpt":"(CNN) --\u00a0Desde su resort costero de Florida, Donald Trump est\u00e1 organizando un casting para cubrir el puesto m\u00e1s dif\u00edcil de Washington: secretario de Justicia.Aunque Trump termin\u00f3 en malos t\u00e9rminos con muchos miembros del Gabinete, ning\u00fan puesto estuvo m\u00e1s en el centro de su hervidero de caos que el de l\u00edder\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473357,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/21\/dentro-audicion-blanche-secretario-justicia-ee-uu-trax\/","url_meta":{"origin":1457939,"position":4},"title":"Esto es lo que est\u00e1 haciendo Todd Blanche para quedarse con el puesto de secretario de Justicia de EE.UU.","author":"","date":"abril 21, 2026","format":false,"excerpt":"El secretario interino de Justicia de EE.UU. Todd Blanche viaj\u00f3 a Florida el lunes, donde se reuni\u00f3 con el nuevo fiscal designado para encargarse de uno de los casos m\u00e1s importantes para el presidente Donald Trump: la investigaci\u00f3n sobre el exdirector de la CIA y cr\u00edtico de Trump, John Brennan.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467629,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/22\/trump-reclamo-230-millones-departamento-justicia-trax\/","url_meta":{"origin":1457939,"position":5},"title":"Trump dice que &#171;podr\u00eda&#187; reclamarle US$ 230 millones a su propio Departamento de Justicia","author":"","date":"octubre 22, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, dijo el martes que \u201cpodr\u00eda\u201d pedir US$ 230 millones a su propio Departamento de Justicia como compensaci\u00f3n por las investigaciones pasadas sobre \u00e9l, aunque afirm\u00f3 tener poco conocimiento de los detalles y dijo que donar\u00eda el dinero a la caridad.\u201cPodr\u00eda ser\u201d, respondi\u00f3 Trump cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1457939"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457939\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1457939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1457939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1457939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}