{"id":1457979,"date":"2025-01-28T22:03:50","date_gmt":"2025-01-29T06:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/"},"modified":"2025-01-28T22:03:50","modified_gmt":"2025-01-29T06:03:50","slug":"elon-musk-spacex-rescatar-astronautas-varados-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","title":{"rendered":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar"},"content":{"rendered":"<p>En una publicaci\u00f3n en la plataforma de redes sociales X, el CEO de SpaceX, Elon Musk, dijo este martes que la administraci\u00f3n Biden dej\u00f3 a dos astronautas \u201cvarados\u201d y que el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a SpaceX que intervenga para rescatarlos.<\/p>\n<p>Sin embargo, la NASA ya hab\u00eda implementado un plan hace meses cuando pidi\u00f3 a SpaceX que regresara a los astronautas Suni Williams y Butch Wilmore de la Estaci\u00f3n Espacial Internacional (ISS, por sus siglas en ingl\u00e9s) como parte de su misi\u00f3n Crew-9. Un retraso en ese plan se anunci\u00f3 en diciembre porque los equipos de la misi\u00f3n dijeron que necesitaban m\u00e1s tiempo para preparar un nuevo veh\u00edculo de SpaceX.<\/p>\n<p>\u201cEl @POTUS ha pedido a @SpaceX que traiga a casa a los 2 astronautas varados en la @Space_Station lo antes posible. Lo haremos\u201d, dice la <a href=\"https:\/\/x.com\/elonmusk\/status\/1884365928038563880\">publicaci\u00f3n<\/a> de Musk. \u201cTerrible que la administraci\u00f3n Biden los haya dejado all\u00ed tanto tiempo\u201d.<\/p>\n<p>En una publicaci\u00f3n en su plataforma de redes sociales Truth Social, el presidente Trump reiter\u00f3 el comentario, diciendo \u201clos 2 valientes astronautas que han sido virtualmente abandonados en el espacio por la administraci\u00f3n Biden\u201d.<\/p>\n<p>\u201cHan estado esperando durante muchos meses en @Space Station\u201d, dice la publicaci\u00f3n. \u201cElon pronto estar\u00e1 en camino. Con suerte, todos estar\u00e1n a salvo. \u00a1Buena suerte Elon!!!\u201d<\/p>\n<p>CNN se puso en contacto con la NASA, SpaceX y la Casa Blanca para obtener comentarios. Ninguno respondi\u00f3 de inmediato.<\/p>\n<p>Aunque la situaci\u00f3n de Williams y Wilmore es inusual, con los dos astronautas incapaces de regresar a casa en la nave espacial de Boeing que los llev\u00f3 a la estaci\u00f3n espacial, su viaje de regreso est\u00e1 programado para ser relativamente rutinario, ya que deben volar a casa con otros astronautas como parte de una rotaci\u00f3n de tripulaci\u00f3n programada.<\/p>\n<p>Williams y Wilmore pilotaron la primera misi\u00f3n tripulada de la nave espacial Starliner de Boeing, que se lanz\u00f3 desde Florida en junio de 2024 y experiment\u00f3 un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/06\/28\/nave-espacial-boeing-starliner-meses-regreso-tierra-trax\/\">viaje accidentado hacia la ISS<\/a>. Inicialmente, se esperaba que los astronautas pasaran aproximadamente una semana en el laboratorio orbital.<\/p>\n<p>Despu\u00e9s de que Starliner lleg\u00f3 a la estaci\u00f3n espacial, la NASA y Boeing trabajaron durante semanas para comprender mejor los problemas, incluidos las fugas de helio y los problemas de propulsi\u00f3n, que afectaron la primera etapa de la misi\u00f3n de prueba.<\/p>\n<p>La NASA finalmente decidi\u00f3 que era demasiado arriesgado devolver Starliner con la tripulaci\u00f3n. Y la agencia anunci\u00f3 en agosto pasado que estaba pidiendo a SpaceX que trajera a Williams y Wilmore a casa a bordo de la c\u00e1psula Crew-9 de SpaceX. Ese veh\u00edculo est\u00e1 actualmente acoplado a la estaci\u00f3n espacial, donde Williams y Wilmore se han convertido en miembros oficiales del personal de la ISS mientras esperan su regreso a casa.<\/p>\n<p>La NASA dijo anteriormente que la c\u00e1psula Crew-9 regresar\u00eda a casa tan pronto como en febrero. No obstante, la agencia actualiz\u00f3 ese cronograma en diciembre, diciendo que SpaceX necesitaba m\u00e1s tiempo para completar la c\u00e1psula que usar\u00eda para la misi\u00f3n Crew-10, que, siguiendo el precedente de la NASA, necesitar\u00eda lanzarse antes de que Crew-9 deje la ISS. En ese momento, la agencia dijo que Crew-9 apuntar\u00eda a su regreso no antes de finales de marzo.<\/p>\n<p>Aunque reconocieron que ha habido partes dif\u00edciles de su misi\u00f3n, Williams y Wilmore parec\u00edan de buen humor durante una entrevista el 8 de enero con el exadministrador de la NASA Bill Nelson.<\/p>\n<p>\u201cTenemos mucha ropa. Estamos bien alimentados\u201d, dijo Wilmore.<\/p>\n<p>Williams agreg\u00f3: \u201cEs un gran equipo y, no, no se siente como si fu\u00e9ramos n\u00e1ufragos\u201d.<\/p>\n<p>\u201cEventualmente queremos ir a casa porque dejamos a nuestras familias hace un tiempo, pero tenemos mucho que hacer mientras estamos aqu\u00ed\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Williams complet\u00f3 una caminata espacial la semana pasada y tanto Williams como Wilmore est\u00e1n programados para salir de la ISS para otra caminata espacial este jueves.<\/p>\n<p>Desde que los equipos de la misi\u00f3n comenzaron el largo proceso de evaluar los problemas de la nave espacial Starliner, y finalmente decidieron traer a Williams y Wilmore a casa en una c\u00e1psula de SpaceX, los funcionarios de la NASA y Boeing han insistido en que los astronautas nunca estuvieron varados.<\/p>\n<p>Steve Stich, gerente del programa de tripulaci\u00f3n comercial de la NASA, se\u00f1al\u00f3 durante una conferencia de prensa el a\u00f1o pasado que Williams y Wilmore siempre tuvieron la opci\u00f3n de volar a casa en Starliner en caso de emergencia o, una vez que el veh\u00edculo SpaceX Crew-9 llegara, regresar a la Tierra a bordo de esa nave.<\/p>\n<p>\u201cEn mi opini\u00f3n, nunca est\u00e1n atrapados o varados\u201d, dijo Stich. \u201cSiempre tuvieron una forma de salir de la estaci\u00f3n espacial. Y para m\u00ed, cuando alguien est\u00e1 varado, hay un lugar del que no pueden salir\u201d.<\/p>\n<p>En una entrevista con CNN la semana pasada, Nelson, el exjefe de la NASA, habl\u00f3 en profundidad sobre la decisi\u00f3n de extender la estancia de los astronautas en el espacio, enfatizando que la decisi\u00f3n se tom\u00f3 con la seguridad de los astronautas como prioridad, y a pesar de las objeciones de Boeing.<\/p>\n<p>Entre el liderazgo de la NASA, la decisi\u00f3n anunciada en agosto de llevar a Williams y Wilmore a casa en un Crew Dragon de SpaceX en lugar de Starliner fue un\u00e1nime.<\/p>\n<p>\u201cPam (Melroy, la administradora adjunta, y) la posici\u00f3n n\u00famero tres en la NASA, Bob Cabana, hab\u00edan volado en el espacio, los tres\u201d, dijo Nelson. \u201cAs\u00ed que los tres fuimos enormemente impactados por las experiencias que hab\u00edamos tenido (con los desastres de Columbia y Challenger), y como resultado de eso, hemos insistido absolutamente en la m\u00e1xima seguridad posible, y hemos insistido en ese mensaje\u201d.<\/p>\n<p>Nelson agreg\u00f3: \u201cAl final, hubo un desacuerdo con Boeing. Boeing pens\u00f3 que era seguro para ellos regresar en el Starliner. Pero la NASA fue un\u00e1nime al decir que no deber\u00edan regresar en Starliner\u201d.<\/p>\n<p>Por eso la agencia opt\u00f3 por traer a los astronautas a casa en el Crew-9 de SpaceX.<\/p>\n<p>La misi\u00f3n Crew-9 de SpaceX, que tambi\u00e9n incluye al astronauta de la NASA Nick Hague y al cosmonauta ruso Aleksandr Gorbunov entre su tripulaci\u00f3n, lleg\u00f3 al puesto orbital en septiembre. Williams y Wilmore han estado en la estaci\u00f3n durante m\u00e1s de siete meses, y habr\u00e1n acumulado aproximadamente nueve meses en el espacio si regresan a casa a finales de marzo o principios de abril.<\/p>\n<p>Las misiones rutinarias a la ISS regularmente duran seis meses. Pero no es raro que los astronautas obtengan una extensi\u00f3n inesperada mientras est\u00e1n en \u00f3rbita, por d\u00edas, semanas o incluso meses.<\/p>\n<p>El astronauta de la NASA Frank Rubio, por ejemplo, tiene el r\u00e9cord estadounidense de la estancia continua m\u00e1s larga en la estaci\u00f3n espacial. Pas\u00f3 371 d\u00edas all\u00ed en una misi\u00f3n que termin\u00f3 en 2023.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una publicaci\u00f3n en la plataforma de redes sociales X, el CEO de SpaceX, Elon Musk, dijo este martes que la administraci\u00f3n Biden dej\u00f3 a dos astronautas \u201cvarados\u201d y que el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a SpaceX que intervenga para rescatarlos. Sin embargo, la NASA ya hab\u00eda implementado un plan hace meses [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457979","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &quot;varados&quot;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &quot;varados&quot;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias\" \/>\n<meta property=\"og:description\" content=\"En una publicaci\u00f3n en la plataforma de redes sociales X, el CEO de SpaceX, Elon Musk, dijo este martes que la administraci\u00f3n Biden dej\u00f3 a dos astronautas \u201cvarados\u201d y que el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a SpaceX que intervenga para rescatarlos. Sin embargo, la NASA ya hab\u00eda implementado un plan hace meses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-29T06:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar\",\"datePublished\":\"2025-01-29T06:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\"},\"wordCount\":1205,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\",\"name\":\"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas \\\"varados\\\". Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-29T06:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas \"varados\". Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas \"varados\". Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias","og_description":"En una publicaci\u00f3n en la plataforma de redes sociales X, el CEO de SpaceX, Elon Musk, dijo este martes que la administraci\u00f3n Biden dej\u00f3 a dos astronautas \u201cvarados\u201d y que el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a SpaceX que intervenga para rescatarlos. Sin embargo, la NASA ya hab\u00eda implementado un plan hace meses [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-29T06:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/"},"author":{"name":"","@id":""},"headline":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar","datePublished":"2025-01-29T06:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/"},"wordCount":1205,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","name":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas \"varados\". Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-29T06:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Elon Musk dice que SpaceX rescatar\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\u00f3n por la que eso podr\u00eda sonar familiar","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/01\/28\/elon-musk-spacex-rescatar-astronautas-varados-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-29T06:03:50Z","datePublished":"2025-01-29T06:03:50Z","dateModified":"2025-01-29T06:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Elon Musk dice que SpaceX rescatar\\u00e1 a dos astronautas &#171;varados&#187;. Esta es la raz\\u00f3n por la que eso podr\\u00eda sonar familiar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/28\\\/elon-musk-spacex-rescatar-astronautas-varados-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/01\\\/28\\\/elon-musk-spacex-rescatar-astronautas-varados-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-29T06:03:50Z\",\"datePublished\":\"2025-01-29T06:03:50Z\",\"dateModified\":\"2025-01-29T06:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459861,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","url_meta":{"origin":1457979,"position":0},"title":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Una tripulaci\u00f3n de astronautas internacionales programada para ser lanzada hacia la Estaci\u00f3n Espacial Internacional (EEI) en una misi\u00f3n que relevar\u00e1 a Butch Wilmore y Suni Williams de la NASA, lo que les permitir\u00e1 regresar a casa despu\u00e9s de un viaje inesperadamente largo y pol\u00edticamente cargado, tendr\u00e1 que esperar un poco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459947,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/14\/spacex-crew-10-butch-wilmore-suni-williams-nasa-regreso-trax\/","url_meta":{"origin":1457979,"position":1},"title":"El lanzamiento de SpaceX Crew-10 allanar\u00e1 el camino para que Butch Wilmore y Suni Williams de la NASA regresen a casa","author":"","date":"marzo 14, 2025","format":false,"excerpt":"SpaceX est\u00e1 una vez m\u00e1s en camino de intentar lanzar una tripulaci\u00f3n de astronautas en una misi\u00f3n para relevar a Sunni Williams y Butch Wilmore de la NASA, permiti\u00e9ndoles regresar a casa desde la Estaci\u00f3n Espacial Internacional despu\u00e9s de un viaje de varios d\u00edas que se convirti\u00f3 en un viaje\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458604,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/02\/11\/nasa-astronautas-boeing-antes-capsula-spacex-trax\/","url_meta":{"origin":1457979,"position":2},"title":"La NASA traer\u00e1 a los astronautas de Boeing a casa d\u00edas antes de lo esperado tras el cambio de c\u00e1psula de SpaceX","author":"","date":"febrero 11, 2025","format":false,"excerpt":"La NASA dijo este martes que podr\u00eda traer a casa a Butch Wilmore y Suni Williams \u2014los dos astronautas que se lanzaron en el primer vuelo de prueba tripulado del Boeing Starliner y han permanecido en la estaci\u00f3n espacial meses m\u00e1s de lo esperado\u2014 un par de semanas antes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459987,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/16\/spacex-wilmore-williams-nasa-regresen-trax\/","url_meta":{"origin":1457979,"position":3},"title":"Crew-10 de SpaceX llega a la ISS, allanando el camino para que Wilmore y Williams de la NASA regresen a casa","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Una tripulaci\u00f3n de astronautas de la NASA arrib\u00f3 a la Estaci\u00f3n Espacial Internacional para reemplazar a Suni Williams y Butch Wilmore, permiti\u00e9ndole al d\u00fao regresar a casa despu\u00e9s de un viaje de varios d\u00edas que se convirti\u00f3 en nueve meses pol\u00edticamente cargados.La misi\u00f3n Crew-10, parte de una rotaci\u00f3n rutinaria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460663,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/31\/astronautas-nasa-hablan-inesperada-mision-9-meses-trax\/","url_meta":{"origin":1457979,"position":4},"title":"Astronautas de la NASA hablan por primera vez tras una inesperada misi\u00f3n de 9 meses en el espacio","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Dos astronautas cuya estancia planificada de una semana en la \u00f3rbita baja de la Tierra se convirti\u00f3 inesperadamente en una misi\u00f3n de m\u00e1s de 9 meses debido a problemas en la nave espacial, hablaron p\u00fablicamente con reporteros el lunes por primera vez desde su regreso a la tierra firme el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471027,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/02\/09\/musk-ambicion-marte-apunta-luna-trax\/","url_meta":{"origin":1457979,"position":5},"title":"Musk modera su ambici\u00f3n de establecer presencia humana en Marte y apunta a la Luna","author":"","date":"febrero 9, 2026","format":false,"excerpt":"La ambici\u00f3n de Elon Musk de establecerse en Marte alg\u00fan d\u00eda parece haber quedado relegada a un objetivo m\u00e1s cercano y alcanzable: enviar humanos a vivir en la Luna.En una declaraci\u00f3n en X este domingo, el multimillonario dijo que su compa\u00f1\u00eda SpaceX ahora ha cambiado sus prioridades para impulsar la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1457979"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1457979\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1457979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1457979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1457979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}