{"id":1465533,"date":"2025-08-15T08:03:42","date_gmt":"2025-08-15T15:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/"},"modified":"2025-08-15T08:03:42","modified_gmt":"2025-08-15T15:03:42","slug":"bondi-maduro-denuncia-puente-aereo-narcotrafico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","title":{"rendered":"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico"},"content":{"rendered":"<p>La secretaria de Justicia de Estados Unidos, Pam Bondi, denunci\u00f3 un presunto \u201cpuente a\u00e9reo\u201d de tr\u00e1fico ilegal existente entre Venezuela, Honduras, Guatemala y M\u00e9xico.<\/p>\n<p>\u201cHay un puente a\u00e9reo donde el r\u00e9gimen venezolano paga para tener libre acceso al espacio a\u00e9reo y sin ser detectado en Honduras, Guatemala y M\u00e9xico\u201d, dijo Bondi durante <a href=\"https:\/\/x.com\/CanalAntigua\/status\/1955958841528492502\">una entrevista<\/a> con Fox News.<\/p>\n<p>La funcionaria afirm\u00f3, sin presentar pruebas, que a trav\u00e9s de este supuesto circuito \u201cpueden traficar y transportar estas drogas. Tambi\u00e9n est\u00e1n intercambiando dinero por sobornos, est\u00e1n intercambiando armas a los puertos de entrada y al espacio a\u00e9reo, para llevar todas estas drogas a todos estos pa\u00edses y a EE.UU.\u201d.<\/p>\n<p>CNN contact\u00f3 a la Canciller\u00eda y al Ministerio de Comunicaci\u00f3n de Venezuela para pedir comentarios.<\/p>\n<p>Si bien no se refiri\u00f3 puntualmente a los dichos de Bondi, el presidente Nicl\u00e1s Maduro s\u00ed habl\u00f3 de una \u201cguerra psicol\u00f3gica\u201d contra Venezuela. \u201cAhora el imperialismo tiene una guerra de declaraciones, una guerra psicol\u00f3gica. Una guerra (en la que) ellos creen que, subestimando al pueblo de Venezuela y de Am\u00e9rica Latina, se van a imponer de esa manera\u201d, sostuvo . \u201cEllos all\u00e1 con su guerra de declaraciones, anuncios, mentira, all\u00e1 ellos con sus guerras. Ac\u00e1 nosotros, con nuestra victoria, con nuestra paz, con nuestros avances, con nuestros planes\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Por su parte, el canciller de Venezuela, Yv\u00e1n Gil, poste\u00f3 en Telegram una foto de Bondi con el siguiente comentario: \u201cQuiere hacer pasar como bienes personales dos aviones del Estado venezolano, robados con complicidad de Luis Abinader y llevados a EE.UU\u201d.<\/p>\n<p>El Gobierno de Guatemala rechaz\u00f3 las aseveraciones y asegur\u00f3 en un <a href=\"https:\/\/prensa.gob.gt\/comunicado\/el-gobierno-de-guatemala-no-permite-el-uso-de-su-espacio-aereo-por-redes-criminales\">comunicado<\/a> que \u201cno permite el uso de su espacio a\u00e9reo por redes criminales\u201d. Repasaron adem\u00e1s acciones que han llevado a cabo en la lucha contra el narcotr\u00e1fico y en cooperaci\u00f3n con autoridades estadounidenses.<\/p>\n<p>Mientras tanto, la Canciller\u00eda de Honduras indic\u00f3 que rechaza \u201cde forma en\u00e9rgica la falsa declaraci\u00f3n\u201d de Bondi. \u201cEl Gobierno de la presidenta Xiomara Castro libra una ofensiva hist\u00f3rica contra el crimen transnacional del narcotr\u00e1fico, ejecutando los decomisos de coca\u00edna m\u00e1s grandes y jam\u00e1s registrados\u201d, sostuvo la Secretar\u00eda de Relaciones Exteriores en un <a href=\"https:\/\/x.com\/CancilleriaHN\/status\/1955834026494697631\">mensaje en X<\/a>.<\/p>\n<p>CNN realiz\u00f3 una consulta con la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico y est\u00e1 a la espera de respuesta.<\/p>\n<p>Se trata de otra acusaci\u00f3n del Gobierno de Estados Unidos contra Venezuela, que en los \u00faltimos d\u00edas arremeti\u00f3 contra Maduro, al <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/07\/eeuu\/gobierno-trump-duplica-recompensa-nicolas-maduro-50-millones-trax\">duplicar la recompensa<\/a> por informaci\u00f3n que conduzca a su arresto, elev\u00e1ndola a US$ 50 millones.<\/p>\n<p>Bondi lo acus\u00f3 la semana pasada de utilizar miembros de c\u00e1rteles para traer \u201cdrogas mortales y violencia a nuestro pa\u00eds\u201d, un anuncio que tanto el Gobierno venezolano como varias instituciones del pa\u00eds rechazaron.<\/p>\n<p>En la entrevista del mi\u00e9rcoles, la secretaria de Justicia de EE.UU.  dijo tambi\u00e9n que el Gobierno del presidente Donald Trump ha confiscado m\u00e1s de US$ 700 millones en activos a Maduro. Bondi no aclar\u00f3 si los bienes confiscados estaban a nombre de Maduro o de otras personas vinculadas al l\u00edder venezolano.<\/p>\n<p>CNN contact\u00f3 al Departamento de Justicia estadounidense para solicitar m\u00e1s informaci\u00f3n y espera respuesta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria de Justicia de Estados Unidos, Pam Bondi, denunci\u00f3 un presunto \u201cpuente a\u00e9reo\u201d de tr\u00e1fico ilegal existente entre Venezuela, Honduras, Guatemala y M\u00e9xico. \u201cHay un puente a\u00e9reo donde el r\u00e9gimen venezolano paga para tener libre acceso al espacio a\u00e9reo y sin ser detectado en Honduras, Guatemala y M\u00e9xico\u201d, dijo Bondi durante una entrevista con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465533","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bondi denuncia un presunto &quot;puente a\u00e9reo&quot; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bondi denuncia un presunto &quot;puente a\u00e9reo&quot; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"La secretaria de Justicia de Estados Unidos, Pam Bondi, denunci\u00f3 un presunto \u201cpuente a\u00e9reo\u201d de tr\u00e1fico ilegal existente entre Venezuela, Honduras, Guatemala y M\u00e9xico. \u201cHay un puente a\u00e9reo donde el r\u00e9gimen venezolano paga para tener libre acceso al espacio a\u00e9reo y sin ser detectado en Honduras, Guatemala y M\u00e9xico\u201d, dijo Bondi durante una entrevista con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-15T15:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico\",\"datePublished\":\"2025-08-15T15:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\",\"name\":\"Bondi denuncia un presunto \\\"puente a\u00e9reo\\\" de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-15T15:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bondi denuncia un presunto \"puente a\u00e9reo\" de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Bondi denuncia un presunto \"puente a\u00e9reo\" de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias","og_description":"La secretaria de Justicia de Estados Unidos, Pam Bondi, denunci\u00f3 un presunto \u201cpuente a\u00e9reo\u201d de tr\u00e1fico ilegal existente entre Venezuela, Honduras, Guatemala y M\u00e9xico. \u201cHay un puente a\u00e9reo donde el r\u00e9gimen venezolano paga para tener libre acceso al espacio a\u00e9reo y sin ser detectado en Honduras, Guatemala y M\u00e9xico\u201d, dijo Bondi durante una entrevista con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","og_site_name":"Noticias","article_published_time":"2025-08-15T15:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/"},"author":{"name":"","@id":""},"headline":"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico","datePublished":"2025-08-15T15:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","url":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","name":"Bondi denuncia un presunto \"puente a\u00e9reo\" de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-15T15:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bondi denuncia un presunto &#171;puente a\u00e9reo&#187; de Venezuela para el narcotr\u00e1fico a trav\u00e9s de Honduras, Guatemala y M\u00e9xico","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-15T15:03:42Z","datePublished":"2025-08-15T15:03:42Z","dateModified":"2025-08-15T15:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bondi denuncia un presunto &#171;puente a\\u00e9reo&#187; de Venezuela para el narcotr\\u00e1fico a trav\\u00e9s de Honduras, Guatemala y M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/15\\\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/15\\\/bondi-maduro-denuncia-puente-aereo-narcotrafico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-15T15:03:42Z\",\"datePublished\":\"2025-08-15T15:03:42Z\",\"dateModified\":\"2025-08-15T15:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465539,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/despliegue-militar-eeuu-caribe-sheinbaum-reaccion-orix\/","url_meta":{"origin":1465533,"position":0},"title":"Tras despliegue militar de EE.UU. en el Caribe, M\u00e9xico dice que est\u00e1 a favor de la &#171;autodeterminaci\u00f3n de los pueblos&#187;","author":"","date":"agosto 15, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, reaccion\u00f3 este viernes al despliegue militar de Estados Unidos en el Caribe, diciendo que su gobierno est\u00e1 a favor de la \u201cautodeterminaci\u00f3n de los pueblos\u201d.\u201cTienen desplegados en aguas internacionales, en el sur (del Caribe), entre Panam\u00e1 y Sudam\u00e9rica, es decir, entre Centroam\u00e9rica y Sudam\u00e9rica,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468823,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/29\/eeuu-venezuela-crisis-aerea-tension-mas-aislada-orix\/","url_meta":{"origin":1465533,"position":1},"title":"Por la tensi\u00f3n con EE.UU., Venezuela enfrenta una crisis a\u00e9rea y queda a\u00fan m\u00e1s aislada","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Mientras recrudece la tensi\u00f3n por el despliegue militar de Estados Unidos en el Caribe, se complica cada vez m\u00e1s la situaci\u00f3n relacionada con el espacio a\u00e9reo de Venezuela.Este s\u00e1bado, el presidente de Estados Unidos, Donald Trump, pidi\u00f3 a aerol\u00edneas, pilotos y redes criminales que consideraran el \u201cespacio a\u00e9reo sobre y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470629,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/29\/trump-anuncia-apertura-espacio-aereo-vuelos-venezuela-orix\/","url_meta":{"origin":1465533,"position":2},"title":"Trump anuncia que los estadounidenses podr\u00e1n viajar &#171;pronto&#187; a Venezuela","author":"","date":"enero 29, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, anunci\u00f3 este jueves que el espacio a\u00e9reo sobre Venezuela quedar\u00e1 habilitado para vuelos comerciales de Estados Unidos, asegurando que los ciudadanos estadounidenses podr\u00e1n viajar \u201cmuy pronto\u201d de forma segura al pa\u00eds sudamericano.A pesar de que el Gobierno de Venezuela siempre defendi\u00f3 que sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468880,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/02\/colombia-cucuta-frontera-venezuela-crisis-aerea-orix\/","url_meta":{"origin":1465533,"position":3},"title":"Con la crisis a\u00e9rea, la frontera con Colombia se convierte en una de las pocas puertas de entrada y salida a Venezuela","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"En medio de la tensi\u00f3n en el Caribe, muchas personas que ten\u00edan boletos comprados para viajar en avi\u00f3n de Colombia a Venezuela tuvieron que cambiar sus planes y moverse por tierra hasta la ciudad fronteriza de C\u00facuta, en el noreste del pa\u00eds.Este fin de semana, Donald Trump advirti\u00f3 en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464108,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/01\/5-cosas-1-julio-orix\/","url_meta":{"origin":1465533,"position":4},"title":"Las 5 cosas que debes saber este 1 de julio: Trump en &#171;Alligator Alcatraz&#187;, Bondi sobre M\u00e9xico y semifinales Copa Oro","author":"","date":"julio 1, 2025","format":false,"excerpt":"Trump visitar\u00e1 hoy el centro de detenci\u00f3n de inmigrantes \u201cAlligator Alcatraz\u201d. Pam Bondi llam\u00f3 \u201cadversario extranjero\u201d a M\u00e9xico por una sola raz\u00f3n. Investigan el hallazgo de 383 cuerpos en un crematorio en Ciudad Ju\u00e1rez, Chihuahua. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468821,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/29\/trump-mantiene-presion-venezuela-espacio-aereo-cerrado-trax\/","url_meta":{"origin":1465533,"position":5},"title":"Trump mantiene la campa\u00f1a de presi\u00f3n sobre Venezuela diciendo que su espacio a\u00e9reo debe considerarse cerrado","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Estados Unidos contin\u00faa este s\u00e1bado con su campa\u00f1a de presi\u00f3n contra Venezuela con el presidente Donald Trump, que emiti\u00f3 una amplia directiva en redes sociales advirtiendo a aerol\u00edneas, pilotos y redes criminales que eviten el espacio a\u00e9reo venezolano.\u201cPor favor, consideren que el espacio a\u00e9reo sobre Venezuela y sus alrededores est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1465533"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465533\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1465533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1465533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1465533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}