{"id":1465550,"date":"2025-08-15T20:03:39","date_gmt":"2025-08-16T03:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/"},"modified":"2025-08-15T20:03:39","modified_gmt":"2025-08-16T03:03:39","slug":"hombre-grita-agentes-ice-tribunal-los-angeles-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","title":{"rendered":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo"},"content":{"rendered":"<p>Un hombre grit\u00f3 pidiendo ayuda mientras un grupo de hombres \u2014uno de los cuales dijo pertenecer al Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2014 lo levantaba y lo empujaba a un veh\u00edculo afuera de un tribunal de Los \u00c1ngeles el mi\u00e9rcoles, seg\u00fan muestra un video.<\/p>\n<p>La detenci\u00f3n ha sido condenada por el juez principal del condado y los abogados del hombre, quienes afirman que este tipo de operativos disuadir\u00e1 a las personas de acudir a los tribunales.<\/p>\n<p>El video, obtenido por el Los Angeles Times, muestra al hombre siendo llevado con las manos atadas a la espalda. Quienes lo detienen visten de civil y algunos llevan mascarillas. El hombre grita repetidamente: \u201c\u00bfAlguien me puede ayudar, por favor?\u201d, mientras forcejea.<\/p>\n<p>Luego es empujado al asiento trasero de un autom\u00f3vil sin identificaci\u00f3n. No est\u00e1 claro a d\u00f3nde lo llevaron.<\/p>\n<p>Ni el ICE ni el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) respondieron a las preguntas de CNN sobre si el ICE particip\u00f3 en la detenci\u00f3n o por qu\u00e9 el hombre fue detenido. El incidente ocurre mientras el ICE realiza cada vez m\u00e1s arrestos en tribunales bajo nuevas directrices del Gobierno de Trump.<\/p>\n<p>El juez presidente de la Corte Superior del Condado de Los \u00c1ngeles emiti\u00f3 una declaraci\u00f3n cr\u00edtica, diciendo que estos operativos afectan negativamente al sistema judicial.<\/p>\n<p>\u201cAunque rara vez se nos notifica sobre actividades federales de inmigraci\u00f3n fuera de nuestros tribunales, me preocupa profundamente este tipo de acciones\u201d, dijo el juez Sergio C. Tapia II en un comunicado.<\/p>\n<p>\u201cEstas demostraciones intimidantes e innecesarias socavan la confianza p\u00fablica en el sistema de justicia, disuaden a las personas de buscar justicia y env\u00edan un mensaje peligroso a las comunidades inmigrantes de que no es seguro participar plenamente en el proceso legal\u201d.<\/p>\n<p>En el video, un testigo pregunta el nombre del detenido y \u00e9l responde: \u201cSteven Reyes\u201d.<\/p>\n<p>Registros judiciales muestran que un hombre llamado Steven Reyes, representado por la Oficina del Defensor P\u00fablico Alternativo del Condado de Los \u00c1ngeles, ten\u00eda una audiencia el mi\u00e9rcoles por un cargo estatal de posesi\u00f3n o compra de drogas ilegales con intenci\u00f3n de venta. Se hab\u00eda declarado inocente el 31 de julio y estaba en libertad bajo palabra.<\/p>\n<p>La portavoz Jenny Cheng confirm\u00f3 que el hombre detenido est\u00e1 representado por esa oficina, pero no dijo si se trata del mismo Steven Reyes acusado por drogas.<\/p>\n<p>\u201cEstos supuestos agentes del ICE, sin orden judicial ni explicaci\u00f3n, claramente privaron a nuestro cliente de su libertad sin el debido proceso\u201d, dijo Cheng a CNN.<\/p>\n<p>\u201cEs impactante ver a cualquier persona ser secuestrada violentamente por un grupo de individuos, en su mayor\u00eda enmascarados e imposibles de identificar. Estas detenciones agresivas del ICE amenazan la integridad del sistema judicial y desalientan la participaci\u00f3n\u201d.<\/p>\n<p>La detenci\u00f3n ocurri\u00f3 fuera del Centro de Justicia Penal Clara Shortridge Foltz, seg\u00fan el Times y LA Public Press, que obtuvo el video de un testigo y public\u00f3 un clip editado en redes sociales.<\/p>\n<p>En el video m\u00e1s largo, un testigo pregunta a uno de los hombres si es del ICE. El hombre responde: \u201cS\u00ed\u201d. Cuando le piden m\u00e1s informaci\u00f3n, muestra r\u00e1pidamente una placa dos veces, que parece ser de Investigaciones de Seguridad Nacional, aunque el video es borroso.<\/p>\n<p>La persona que graba pregunta si tienen una orden de arresto, pero los hombres no responden.<\/p>\n<p>CNN ha solicitado informaci\u00f3n al ICE sobre el arresto, el estatus migratorio de Reyes, si est\u00e1 bajo custodia del ICE, d\u00f3nde se encuentra y los cargos exactos que enfrenta.<\/p>\n<p>El ICE y el Departamento de Seguridad Nacional operaban antes bajo directrices que limitaban la aplicaci\u00f3n de la ley migratoria en tribunales, pero el Gobierno de Trump elimin\u00f3 esas restricciones al inicio de su segundo mandato. Agentes enmascarados han estado apareciendo en tribunales de todo el pa\u00eds para arrestar a inmigrantes.<\/p>\n<p>Funcionarios de Trump argumentan que la gu\u00eda anterior dificultaba la labor de los agentes para detener a personas peligrosas.<\/p>\n<p>\u201cLa capacidad de las fuerzas del orden para arrestar a criminales extranjeros ilegales en los tribunales es de sentido com\u00fan\u201d, dijo la portavoz del DHS, Tricia McLaughlin, en un comunicado de mayo. \u201cAhorra recursos porque ya saben d\u00f3nde estar\u00e1 el objetivo y es m\u00e1s seguro para los agentes y la comunidad. Estos extranjeros ilegales ya han pasado por seguridad y han sido revisados para no portar armas\u201d.<\/p>\n<p>Grupos de derechos de inmigrantes afirman que el aumento de arrestos en tribunales por parte del ICE refleja una tendencia m\u00e1s amplia de aplicaci\u00f3n de la ley migratoria en lugares antes considerados fuera de l\u00edmites.<\/p>\n<p>La fiscal\u00eda del condado de Los \u00c1ngeles, que procesa a Reyes por el cargo de drogas, dijo que no ten\u00eda conocimiento previo ni particip\u00f3 en la detenci\u00f3n.<\/p>\n<p>\u201cNuestro objetivo es buscar justicia para las v\u00edctimas y responsabilizar a los criminales\u201d, dijo la fiscal\u00eda en un comunicado. \u201cDetener a un acusado antes de que concluya el proceso judicial interfiere con nuestra capacidad de procesar casos y no favorece la b\u00fasqueda de justicia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un hombre grit\u00f3 pidiendo ayuda mientras un grupo de hombres \u2014uno de los cuales dijo pertenecer al Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2014 lo levantaba y lo empujaba a un veh\u00edculo afuera de un tribunal de Los \u00c1ngeles el mi\u00e9rcoles, seg\u00fan muestra un video. La detenci\u00f3n ha sido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465550","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un hombre grit\u00f3 pidiendo ayuda mientras un grupo de hombres \u2014uno de los cuales dijo pertenecer al Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2014 lo levantaba y lo empujaba a un veh\u00edculo afuera de un tribunal de Los \u00c1ngeles el mi\u00e9rcoles, seg\u00fan muestra un video. La detenci\u00f3n ha sido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-16T03:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo\",\"datePublished\":\"2025-08-16T03:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\"},\"wordCount\":912,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\",\"name\":\"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-16T03:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias","og_description":"Un hombre grit\u00f3 pidiendo ayuda mientras un grupo de hombres \u2014uno de los cuales dijo pertenecer al Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s)\u2014 lo levantaba y lo empujaba a un veh\u00edculo afuera de un tribunal de Los \u00c1ngeles el mi\u00e9rcoles, seg\u00fan muestra un video. La detenci\u00f3n ha sido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-16T03:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/"},"author":{"name":"","@id":""},"headline":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo","datePublished":"2025-08-16T03:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/"},"wordCount":912,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","name":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-16T03:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \u00c1ngeles y lo suben a un veh\u00edculo","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/15\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-16T03:03:39Z","datePublished":"2025-08-16T03:03:39Z","dateModified":"2025-08-16T03:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hombre grita por ayuda mientras supuestos agentes del ICE lo sacan de tribunal de Los \\u00c1ngeles y lo suben a un veh\\u00edculo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/15\\\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/15\\\/hombre-grita-agentes-ice-tribunal-los-angeles-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-16T03:03:39Z\",\"datePublished\":\"2025-08-16T03:03:39Z\",\"dateModified\":\"2025-08-16T03:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466881,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/09\/26\/defensores-inmigrantes-arresto-migrante-colombiano-iowa-trax\/","url_meta":{"origin":1465550,"position":0},"title":"Defensores de inmigrantes denuncian que agentes del ICE arrestaron a migrante colombiano en un supermercado de Iowa","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"El grupo de defensa de inmigrantes Escucha Mi Voz protest\u00f3 por el arresto el jueves de uno de sus miembros, el migrante colombiano Jorge Elieser Gonz\u00e1lez Ochoa, en la ciudad de Iowa, alegando que agentes del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) vestidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457035,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/12\/27\/sentencian-muerte-hombre-atropellar-multitud-china-trax\/","url_meta":{"origin":1465550,"position":1},"title":"Condenan a muerte a un hombre que embisti\u00f3 su coche contra una multitud en China","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"Un hombre que mat\u00f3 a 35 personas al embestir su veh\u00edculo contra una multitud en un centro deportivo en el sur de China fue sentenciado a muerte, informaron los medios estatales este viernes.Fan Weiqiu, de 62 a\u00f1os, embisti\u00f3 su veh\u00edculo contra personas que estaban haciendo ejercicio en el lugar al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467198,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/08\/residentes-chicago-intervienen-patrulla-fronteriza-detengan-hombre-trax\/","url_meta":{"origin":1465550,"position":2},"title":"Residentes de Chicago intervienen para impedir que agentes de la Patrulla Fronteriza detengan a un hombre","author":"","date":"octubre 8, 2025","format":false,"excerpt":"Agentes de la Patrulla Fronteriza no pudieron detener a un hombre en Chicago el s\u00e1bado despu\u00e9s de que intervinieron testigos, seg\u00fan muestra una grabaci\u00f3n del hecho.En el video, compartido con CNN, se ve a dos agentes enmascarados de la Patrulla Fronteriza de Estados Unidos tirando de un hombre no identificado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455142,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/10\/16\/video-camara-corporal-policias-phoenix-golpeando-hombre-sordo-trax\/","url_meta":{"origin":1465550,"position":3},"title":"Video de c\u00e1mara corporal muestra a dos polic\u00edas de Phoenix golpeando y electrocutando a un hombre sordo en el suelo","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN) -- Un video de una c\u00e1mara corporal publicado recientemente muestra a dos agentes de polic\u00eda de Phoenix gritando \u00f3rdenes a un hombre negro mientras est\u00e1 tendido boca abajo en el suelo, con un agente d\u00e1ndole pu\u00f1etazos repetidamente y otro dispar\u00e1ndole con una pistola el\u00e9ctrica.Tyron McAlpin, de 34 a\u00f1os, es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470144,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/16\/renee-good-911-detalles-muerte-trax\/","url_meta":{"origin":1465550,"position":4},"title":"Transcripciones del 911 y un informe revelan detalles de la muerte de Renee Good y la reacci\u00f3n de su comunidad en tiempo real","author":"","date":"enero 16, 2026","format":false,"excerpt":"Despu\u00e9s de que Renee Good fuera baleada la semana pasada por un agente federal de inmigraci\u00f3n en Minneapolis, la madre de tres hijos estaba \u201cinconsciente, sin respirar, con pulso d\u00e9bil, irregular e intermitente\u201d, seg\u00fan un informe del Departamento de Bomberos de la ciudad.\u201cVi\u2026 a un agente de ICE disparar dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464778,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/23\/policia-florida-hombre-negro-golpeado-agentes-parada-trafico-trax\/","url_meta":{"origin":1465550,"position":5},"title":"Cr\u00edticas a Polic\u00eda de Florida tras viralizarse video de hombre negro golpeado y arrastrado por agentes en parada de tr\u00e1fico","author":"","date":"julio 23, 2025","format":false,"excerpt":"Un video de tel\u00e9fono celular que muestra a un oficial de polic\u00eda blanco de Jacksonville, Florida, golpeando a un hombre negro en la cara durante una parada de tr\u00e1fico en febrero antes de sacarlo de su autom\u00f3vil se volvi\u00f3 viral, provoc\u00f3 indignaci\u00f3n y dio lugar a relatos contradictorios del incidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1465550"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465550\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1465550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1465550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1465550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}