{"id":1465559,"date":"2025-08-16T09:03:38","date_gmt":"2025-08-16T16:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/"},"modified":"2025-08-16T09:03:38","modified_gmt":"2025-08-16T16:03:38","slug":"rio-mississippi-1967-desaparecido-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","title":{"rendered":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967"},"content":{"rendered":"<p>Dos pescadores de Minnesota hicieron un descubrimiento inesperado en el fondo del r\u00edo Mississippi esta semana, cuando la tecnolog\u00eda de sonar los llev\u00f3 a lo que las autoridades dicen que podr\u00eda ser un avance en un caso sin resolver de varias d\u00e9cadas.<\/p>\n<p>Brody Loch, uno de los pescadores, dijo a la filial de CNN, WCCO, que detect\u00f3 un auto en el r\u00edo usando su dispositivo de sonar el fin de semana pasado. Tres d\u00edas despu\u00e9s, el mi\u00e9rcoles, buzos localizaron el veh\u00edculo y encontraron restos humanos en su interior, dijo el sheriff del condado de Stearns, Steve Soyka, a CNN.<\/p>\n<p>\u201cFue 100 % suerte, si mi amigo no hubiera atrapado ese walleye, hubi\u00e9ramos seguido flotando r\u00edo abajo y nunca lo habr\u00edamos encontrado\u201d, dijo Loch a WCCO.<\/p>\n<p>Soyka dijo que tem\u00eda que el auto, un Buick de la d\u00e9cada de 1960, pudiera desarmarse si lo sacaban a la superficie, dado el tiempo que hab\u00eda estado sumergido. Pero cuando los investigadores sacaron el Buick del r\u00edo, \u201csorprendentemente, sali\u00f3 bastante intacto\u201d, se\u00f1al\u00f3.<\/p>\n<p>Tras trabajar con una empresa local de gr\u00faas para sacar el auto del agua, los investigadores compararon el n\u00famero de identificaci\u00f3n del veh\u00edculo con el de Roy Benn, quien desapareci\u00f3 en septiembre de 1967, seg\u00fan un comunicado de prensa de la oficina del sheriff.<\/p>\n<p>Oriundo de Sauk Rapids, Minnesota, Benn fue visto por \u00faltima vez conduciendo un Buick Electra azul met\u00e1lico de 1963, seg\u00fan un bolet\u00edn de persona desaparecida de la Oficina de Aprehensi\u00f3n Criminal de Minnesota.<\/p>\n<p>\u201cBas\u00e1ndonos en los restos humanos, los objetos encontrados en el auto y la verificaci\u00f3n del n\u00famero VIN del veh\u00edculo, las oficinas del sheriff (locales) creen que se trata del se\u00f1or Benn\u201d, indic\u00f3 la oficina del sheriff del condado de Stearns en el comunicado.<\/p>\n<p>Seg\u00fan la oficina, Benn fue reportado \u201cportando una gran suma de dinero cuando fue visto por \u00faltima vez\u201d.<\/p>\n<p>La b\u00fasqueda de Benn continu\u00f3 durante meses despu\u00e9s de su desaparici\u00f3n, y durante m\u00e1s de cinco d\u00e9cadas despu\u00e9s de haber sido visto por \u00faltima vez.<\/p>\n<p>Archivos del St. Cloud Daily Times revisados por CNN arrojan luz sobre el hombre que desapareci\u00f3 sin dejar rastro hace casi 60 a\u00f1os, despu\u00e9s de haber sido visto por \u00faltima vez cenando, ese mismo d\u00eda, en el King\u2019s Supper Club al norte de Sartell, Minnesota.<\/p>\n<p>Benn, de 59 a\u00f1os en el momento de su desaparici\u00f3n, era un empresario y due\u00f1o del St. Cloud Appliance Repair Service, cuya esposa hab\u00eda fallecido el a\u00f1o anterior, seg\u00fan inform\u00f3 el St. Cloud Daily Times.<\/p>\n<p>Su hermano, Walter Benn, trabaj\u00f3 con funcionarios de las fuerzas del orden tras la desaparici\u00f3n de Roy, mientras los investigadores segu\u00edan pistas que no llevaron a nada.<\/p>\n<p>El sheriff del condado de Benton, Troy Heck, cuyo departamento est\u00e1 encargado de investigar el caso de Roy Benn desde su desaparici\u00f3n, dijo a CNN que los investigadores de su oficina han recibido pistas a lo largo de los a\u00f1os, pero ninguna \u201cdio resultado\u201d.<\/p>\n<p>Walter Benn prepar\u00f3 las pertenencias personales de su hermano para su venta en una subasta en 1968, seg\u00fan archivos del St. Cloud Daily Times.<\/p>\n<p>Roy Benn fue declarado legalmente muerto en 1975, ocho a\u00f1os despu\u00e9s de su desaparici\u00f3n, seg\u00fan los archivos del St. Cloud Daily Times.<\/p>\n<p>La oficina del sheriff del condado de Benton lidera la investigaci\u00f3n del caso, y los restos encontrados en el Buick han sido enviados a la oficina del forense para su examen.<\/p>\n<p>Heck advirti\u00f3 que \u201calgunas de las t\u00e9cnicas t\u00edpicas que nuestros socios, la oficina del forense, usar\u00edan para identificar no ser\u00e1n muy efectivas\u201d debido al tiempo que el cuerpo ha estado bajo el agua.<\/p>\n<p>\u201cCreemos que hay una fuerte indicaci\u00f3n de que este ser\u00e1 el veh\u00edculo de Roy Benn, y que esos probablemente sean sus restos\u201d, dijo Heck.<\/p>\n<p>Heck agreg\u00f3 que los familiares directos sobrevivientes de Roy Benn ya fueron informados del hallazgo. El departamento ya se hab\u00eda puesto en contacto con ellos previamente para obtener ADN familiar.<\/p>\n<p>\u201cEstamos agradecidos de que probablemente finalmente hayamos conseguido el avance que necesit\u00e1bamos para darle cierre a esta familia\u201d, afirm\u00f3 Heck.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos pescadores de Minnesota hicieron un descubrimiento inesperado en el fondo del r\u00edo Mississippi esta semana, cuando la tecnolog\u00eda de sonar los llev\u00f3 a lo que las autoridades dicen que podr\u00eda ser un avance en un caso sin resolver de varias d\u00e9cadas. Brody Loch, uno de los pescadores, dijo a la filial de CNN, WCCO, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465559","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Dos pescadores de Minnesota hicieron un descubrimiento inesperado en el fondo del r\u00edo Mississippi esta semana, cuando la tecnolog\u00eda de sonar los llev\u00f3 a lo que las autoridades dicen que podr\u00eda ser un avance en un caso sin resolver de varias d\u00e9cadas. Brody Loch, uno de los pescadores, dijo a la filial de CNN, WCCO, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-16T16:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967\",\"datePublished\":\"2025-08-16T16:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\"},\"wordCount\":761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\",\"name\":\"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-16T16:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias","og_description":"Dos pescadores de Minnesota hicieron un descubrimiento inesperado en el fondo del r\u00edo Mississippi esta semana, cuando la tecnolog\u00eda de sonar los llev\u00f3 a lo que las autoridades dicen que podr\u00eda ser un avance en un caso sin resolver de varias d\u00e9cadas. Brody Loch, uno de los pescadores, dijo a la filial de CNN, WCCO, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-16T16:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/"},"author":{"name":"","@id":""},"headline":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967","datePublished":"2025-08-16T16:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/"},"wordCount":761,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","name":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-16T16:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-16T16:03:38Z","datePublished":"2025-08-16T16:03:38Z","dateModified":"2025-08-16T16:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un pescador crey\\u00f3 ver un auto en el fondo del r\\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/16\\\/rio-mississippi-1967-desaparecido-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/16\\\/rio-mississippi-1967-desaparecido-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-16T16:03:38Z\",\"datePublished\":\"2025-08-16T16:03:38Z\",\"dateModified\":\"2025-08-16T16:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1442733,"url":"https:\/\/noticiasya.com\/washington-dc\/2023\/12\/27\/los-pescadores-que-investigaban-algo-brillante-llevaron-al-rescate-milagroso-de-un-hombre-de-indiana-atrapado-en-un-camion-accidentado-durante-dias-dice-la-policia\/","url_meta":{"origin":1465559,"position":0},"title":"Los pescadores que investigaban algo brillante llevaron al rescate &#171;milagroso&#187; de un hombre de Indiana atrapado en un cami\u00f3n accidentado durante d\u00edas, dice la polic\u00eda","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) -- Algo brillante cerca de un arroyo y un caso de curiosidad llevaron este martes a dos pescadores de Indiana hasta un hombre de 27 a\u00f1os que hab\u00eda estado luchando por su vida durante d\u00edas solo en un cami\u00f3n destrozado: un descubrimiento que la Polic\u00eda estatal aclama como un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458124,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/02\/02\/agotador-esfuerzo-victimas-tragedia-aerea-washington-trax\/","url_meta":{"origin":1465559,"position":1},"title":"As\u00ed es el agotador esfuerzo para recuperar los cuerpos de 67 v\u00edctimas del accidente a\u00e9reo en la ciudad de Washington","author":"","date":"febrero 2, 2025","format":false,"excerpt":"Las familias estaban esperando en el aeropuerto para dar la bienvenida a sus seres queridos cuando su avi\u00f3n, a pocos minutos de aterrizar, choc\u00f3 en el aire con un helic\u00f3ptero militar en una feroz explosi\u00f3n, sumergiendo 67 vidas llenas de promesas en las fr\u00edas y oscuras aguas del r\u00edo Potomac.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444676,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/01\/30\/resolvieron-el-misterio-de-amelia-earhart-un-sonar-podria-haber-descubierto-su-avion-perdido-segun-investigadores\/","url_meta":{"origin":1465559,"position":2},"title":"\u00bfResolvieron el misterio de Amelia Earhart? Un sonar podr\u00eda haber descubierto su avi\u00f3n perdido, seg\u00fan investigadores","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN) -- La tr\u00e1gica y misteriosa desaparici\u00f3n de la revolucionaria aviadora Amelia Earhart mientras sobrevolaba el oc\u00e9ano Pac\u00edfico ha cautivado al mundo durante casi 87 a\u00f1os, dando lugar a innumerables investigaciones y expediciones en busca de respuestas sobre lo que le ocurri\u00f3 a la querida piloto.El \u00faltimo grupo en sumarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444675,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/01\/30\/un-sonar-podria-haber-descubierto-el-avion-perdido-de-amelia-earhart-segun-los-investigadores\/","url_meta":{"origin":1465559,"position":3},"title":"Un sonar podr\u00eda haber descubierto el avi\u00f3n perdido de Amelia Earhart, seg\u00fan los investigadores","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN) -- La tr\u00e1gica y misteriosa desaparici\u00f3n de la revolucionaria aviadora Amelia Earhart mientras sobrevolaba el oc\u00e9ano Pac\u00edfico ha cautivado al mundo durante casi 87 a\u00f1os, dando lugar a innumerables investigaciones y expediciones en busca de respuestas sobre lo que le ocurri\u00f3 a la querida piloto.El \u00faltimo grupo en sumarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445893,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/21\/pescadores-desaparecidos-venice-florida-trax\/","url_meta":{"origin":1465559,"position":4},"title":"Cuatro pescadores salieron en un bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) --\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales.\u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445684,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","url_meta":{"origin":1465559,"position":5},"title":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado","author":"","date":"febrero 19, 2024","format":false,"excerpt":"(CNN) --\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales.\u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1465559"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465559\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1465559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1465559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1465559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}