{"id":1465577,"date":"2025-08-17T10:03:39","date_gmt":"2025-08-17T17:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/"},"modified":"2025-08-17T10:03:39","modified_gmt":"2025-08-17T17:03:39","slug":"huracan-erin-riesgos-corrientes-resaca-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","title":{"rendered":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana"},"content":{"rendered":"<p>Se espera que el riesgo de oleaje peligroso y corrientes de resaca potencialmente mortales aumente en las playas a lo largo de la costa este de Estados Unidos, las Bahamas, Bermudas y el Atl\u00e1ntico canadiense en los pr\u00f3ximos d\u00edas debido al hurac\u00e1n Erin, seg\u00fan el Centro Nacional de Huracanes de EE.UU. (NHC, por sus siglas en ingl\u00e9s).<\/p>\n<p>El pron\u00f3stico es que Erin duplique o incluso triplique su tama\u00f1o a medida que avanza por el Atl\u00e1ntico, entre Bermudas y la costa este de Estados Unidos, esta semana. Esta expansi\u00f3n permitir\u00e1 una mayor extensi\u00f3n de sus efectos. El campo de viento en expansi\u00f3n producir\u00e1 condiciones oce\u00e1nicas agitadas en gran parte del Atl\u00e1ntico occidental, se\u00f1al\u00f3 el NHC la ma\u00f1ana de este domingo.<\/p>\n<p>Es importante se\u00f1alar que la amenaza de corrientes de resaca aumentar\u00e1 antes que el oleaje alto, por lo que el Servicio Meteorol\u00f3gico de EE.UU. advierte a las personas que no basen el nivel de riesgo en si ven o no olas grandes.<\/p>\n<p>Las marejadas grandes, incluso provenientes de un hurac\u00e1n Erin distante, generar\u00e1n corrientes de resaca frecuentes y fuertes, as\u00ed como condiciones de oleaje agitado que comenzar\u00e1n el lunes a lo largo de las playas del sur y continuar\u00e1n hasta las \u00e1reas costeras del noreste para fines de la semana.<\/p>\n<p>\u201cAl analizar c\u00f3mo han perdido la vida las personas en Estados Unidos en los \u00faltimos diez a\u00f1os debido a tormentas tropicales y huracanes, alrededor del 12 % de ellas fue por corrientes de resaca\u201d, dijo Cassandra Mora, meteor\u00f3loga del NHC.<\/p>\n<p>Como comparaci\u00f3n, el hurac\u00e1n Lorenzo, en 2019, caus\u00f3 la muerte de ocho personas por corrientes de resaca, aunque ese cicl\u00f3n tropical en s\u00ed se encontraba a casi 3.200 km de la costa, seg\u00fan el NHC.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se espera que el riesgo de oleaje peligroso y corrientes de resaca potencialmente mortales aumente en las playas a lo largo de la costa este de Estados Unidos, las Bahamas, Bermudas y el Atl\u00e1ntico canadiense en los pr\u00f3ximos d\u00edas debido al hurac\u00e1n Erin, seg\u00fan el Centro Nacional de Huracanes de EE.UU. (NHC, por sus siglas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465577","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se espera que el riesgo de oleaje peligroso y corrientes de resaca potencialmente mortales aumente en las playas a lo largo de la costa este de Estados Unidos, las Bahamas, Bermudas y el Atl\u00e1ntico canadiense en los pr\u00f3ximos d\u00edas debido al hurac\u00e1n Erin, seg\u00fan el Centro Nacional de Huracanes de EE.UU. (NHC, por sus siglas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-17T17:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana\",\"datePublished\":\"2025-08-17T17:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\",\"name\":\"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-17T17:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias","og_description":"Se espera que el riesgo de oleaje peligroso y corrientes de resaca potencialmente mortales aumente en las playas a lo largo de la costa este de Estados Unidos, las Bahamas, Bermudas y el Atl\u00e1ntico canadiense en los pr\u00f3ximos d\u00edas debido al hurac\u00e1n Erin, seg\u00fan el Centro Nacional de Huracanes de EE.UU. (NHC, por sus siglas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-17T17:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana","datePublished":"2025-08-17T17:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","name":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-17T17:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El hurac\u00e1n Erin generar\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/17\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-17T17:03:39Z","datePublished":"2025-08-17T17:03:39Z","dateModified":"2025-08-17T17:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El hurac\\u00e1n Erin generar\\u00e1 un mayor riesgo de corrientes de resaca a lo largo de la costa este de EE.UU. esta semana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/17\\\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/17\\\/huracan-erin-riesgos-corrientes-resaca-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-17T17:03:39Z\",\"datePublished\":\"2025-08-17T17:03:39Z\",\"dateModified\":\"2025-08-17T17:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451930,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/08\/17\/ernesto-toca-tierra-bermudas-trax\/","url_meta":{"origin":1465577,"position":0},"title":"Ernesto toca tierra en Bermudas como categor\u00eda 1","author":"","date":"agosto 17, 2024","format":false,"excerpt":"(CNN) -- El hurac\u00e1n Ernesto es de categor\u00eda 1 con vientos sostenidos de 85 mph y r\u00e1fagas de 105 mph seg\u00fan la actualizaci\u00f3n de las 5am EDT del Centro Nacional de Huracanes. Este sistema se encuentra actualmente directamente sobre las Bermudas.\"Se esperan condiciones de hurac\u00e1n en las Bermudas durante las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465628,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/carolina-del-norte-evacuar-huracan-erin-trax\/","url_meta":{"origin":1465577,"position":1},"title":"Las zonas de Carolina del Norte que deben evacuar por el hurac\u00e1n Erin","author":"","date":"agosto 19, 2025","format":false,"excerpt":"Carolina del Norte emiti\u00f3 \u00f3rdenes de evacuaci\u00f3n para \u00e1reas de los condados de Dare y Hyde por los posibles efectos de Erin, que avanza este martes por la costa atl\u00e1ntica como hurac\u00e1n categor\u00eda 2.Erin, que se intensific\u00f3 r\u00e1pidamente el fin de semana pero que no se prevee que toque tierra,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465733,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/21\/erin-huracan-carolina-del-norte-trax\/","url_meta":{"origin":1465577,"position":2},"title":"El hurac\u00e1n Erin se aleja de la costa este de EE.UU., pero sigue siendo una amenaza para la zona","author":"","date":"agosto 21, 2025","format":false,"excerpt":"Erin comienza a alejarse de Estados Unidos, pero no hay que sentirse aliviado todav\u00eda: el enorme hurac\u00e1n sigue agitando el oc\u00e9ano Atl\u00e1ntico, y mantiene condiciones peligrosas a lo largo de m\u00e1s de 1.600 kil\u00f3metros de la costa este.El hurac\u00e1n Erin ha causado importantes perturbaciones en las comunidades costeras esta semana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465624,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/trayectoria-huracan-erin-donde-esta-direccion-orix\/","url_meta":{"origin":1465577,"position":3},"title":"Trayectoria del hurac\u00e1n Erin: d\u00f3nde est\u00e1 y hacia d\u00f3nde se dirige","author":"","date":"agosto 19, 2025","format":false,"excerpt":"El hurac\u00e1n Erin, ahora de categor\u00eda 3, contin\u00faa su avance por el oc\u00e9ano Atl\u00e1ntico la ma\u00f1ana de este martes, amenazado con llevar corrientes de resaca mortales a toda la costa este de Estados Unidos.Los pronosticadores del Centro Nacional de Huracanes (NHC, por sus siglas en ingl\u00e9s) no prev\u00e9n que Erin,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467007,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/01\/trayectoria-huracan-humberto-donde-esta-direccion-orix\/","url_meta":{"origin":1465577,"position":4},"title":"Trayectoria del hurac\u00e1n Humberto: d\u00f3nde est\u00e1 y hacia d\u00f3nde se dirige","author":"","date":"octubre 1, 2025","format":false,"excerpt":"El hurac\u00e1n Humberto sigue suponiendo este mi\u00e9rcoles una amenaza para las Bermudas y la costa este de Estados Unidos con oleaje peligroso y corrientes de resaca, pero el fen\u00f3meno corre el riesgo de dispersarse a medida que pierde intensidad.Seg\u00fan el reporte m\u00e1s reciente del Centro Nacional de Huracanes (NHC, por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465560,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/16\/erin-huracan-4-caribe-trax\/","url_meta":{"origin":1465577,"position":5},"title":"Erin ya es un poco com\u00fan hurac\u00e1n categor\u00eda 5. Y se pronostica que duplicar\u00e1 o triplicar\u00e1 su tama\u00f1o","author":"","date":"agosto 16, 2025","format":false,"excerpt":"El hurac\u00e1n Erin se est\u00e1 intensificando r\u00e1pidamente mientras avanza sobre el noreste del Caribe este s\u00e1bado, provocando fuerte oleaje y generando lluvias y r\u00e1fagas de vientos a las islas situadas al sur de su trayectoria.Erin se ha convertido en un hurac\u00e1n de categor\u00eda 5 con vientos sostenidos de 260 km\/h\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1465577"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465577\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1465577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1465577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1465577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}