{"id":1465674,"date":"2025-08-19T20:03:41","date_gmt":"2025-08-20T03:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/"},"modified":"2025-08-19T20:03:41","modified_gmt":"2025-08-20T03:03:41","slug":"abogados-abrego-garcia-juez-desestime-caso-penal-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","title":{"rendered":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;"},"content":{"rendered":"<p>Los abogados de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/06\/eeuu\/quien-es-kilmar-abrego-garcia-el-salvador-deportado-eeuu-orix\">Kilmar \u00c1brego Garc\u00eda <\/a>solicitan al juez federal que supervisa su caso penal que desestime los cargos de tr\u00e1fico de personas que enfrenta, argumentando que el Departamento de Justicia de Estados Unidos lo seleccion\u00f3 para enjuiciarlo despu\u00e9s de que \u00e9l impugn\u00f3 su deportaci\u00f3n indebida a El Salvador a principios de este a\u00f1o.<\/p>\n<p>La solicitud, presentada este martes ante el juez de distrito Waverly Crenshaw en Nashville, se produce pocos d\u00edas antes de que se espere que \u00c1brego Garc\u00eda sea liberado de la custodia penal mientras espera su juicio por los cargos federales.<\/p>\n<p>El escrito de 35 p\u00e1ginas dirigido a Crenshaw acusa al Gobierno de Donald Trump de iniciar el proceso penal como represalia por la prolongada batalla legal de \u00c1brego Garc\u00eda contra su deportaci\u00f3n en marzo. El padre de tres hijos, residente en Maryland, fue deportado en violaci\u00f3n de una orden judicial previa que prohib\u00eda expresamente su expulsi\u00f3n a El Salvador.<\/p>\n<p>\u201cEl se\u00f1or \u00c1brego respondi\u00f3 a la conducta ilegal del Gobierno presentando una demanda. En lugar de corregir su error y devolverlo a Estados Unidos, el Gobierno luch\u00f3 en todos los niveles del sistema judicial federal\u201d, escribieron sus abogados. \u201cY en todos los niveles, \u00c1brego gan\u00f3. Este caso es el resultado del esfuerzo del Gobierno por castigarlo por atreverse a defenderse en vez de aceptar una injusticia\u201d.<\/p>\n<p>Los abogados piden a Crenshaw, designado por el expresidente Barack Obama, que desestime los dos cargos penales presentados este a\u00f1o, argumentando que \u00c1brego es v\u00edctima de \u201cacusaci\u00f3n selectiva o vengativa\u201d.<\/p>\n<p>\u201cEstas mociones son poco frecuentes y rara vez prosperan. Pero si alguna vez ha habido un caso para desestimar por estos motivos, es este. El Gobierno intenta usar este caso \u2014y este tribunal\u2014 para castigar al se\u00f1or \u00c1brego por haber impugnado con \u00e9xito su expulsi\u00f3n ilegal. Eso constituye una violaci\u00f3n constitucional fundamental\u201d, escribieron en los documentos judiciales. \u201cLa acusaci\u00f3n debe ser desestimada\u201d.<\/p>\n<p>El escrito cita declaraciones de funcionarios del Gobierno \u2014desde Trump hasta la secretaria de Justicia, Pam Bondi\u2014 para argumentar que el proceso penal busca justificar \u201cafirmaciones falsas de que deportarlo a El Salvador fue lo correcto\u201d.<\/p>\n<p>Tambi\u00e9n se\u00f1ala que la detenci\u00f3n de tr\u00e1nsito que es el centro del caso ocurri\u00f3 a\u00f1os antes, lo que, hecho que sus abogados alegan, \u201ces suficiente para establecer un efecto discriminatorio\u201d.<\/p>\n<p>\u201cEn total, el Gobierno tard\u00f3 903 d\u00edas desde la detenci\u00f3n de tr\u00e1nsito en este caso \u2014el 30 de noviembre de 2022\u2014 para presentar una acusaci\u00f3n formal el 21 de mayo de 2025\u201d, escribieron, agregando que no encontraron ning\u00fan caso similar en el circuito federal que revisa apelaciones de Tennessee y otros estados.<\/p>\n<p>El juicio de \u00c1brego Garc\u00eda est\u00e1 programado para enero de 2026.<\/p>\n<p>El mes pasado, Crenshaw rechaz\u00f3 revocar la decisi\u00f3n de otra jueza que permiti\u00f3 que \u00c1brego Garc\u00eda permaneciera en libertad mientras espera el juicio. Sin embargo, ha <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/23\/eeuu\/abrego-garcia-seguira-detenido-un-mes-no-peligro-trax\">permanecido detenido<\/a> porque la jueza magistrada suspendi\u00f3 su orden de liberaci\u00f3n por un mes. Se espera que esa suspensi\u00f3n termine esta semana.<\/p>\n<p>Mientras tanto, la jueza federal en Maryland que supervisa el caso presentado por \u00c1brego Garc\u00eda y su familia para asegurar su regreso a Estados Unidos desde El Salvador ha prohibido que el Gobierno lo deporte nuevamente de forma expedita una vez que sea liberado de la custodia penal.<\/p>\n<p>Esa decisi\u00f3n de la jueza de distrito Paula Xinis, tambi\u00e9n designada por Obama, busca dos cosas: restituir a \u00c1brego Garc\u00eda a la situaci\u00f3n migratoria en la que se encontraba antes de su deportaci\u00f3n en marzo y garantizar que no se violen nuevamente sus derechos al debido proceso si las autoridades intentan expulsarlo de Estados Unidos por segunda vez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los abogados de Kilmar \u00c1brego Garc\u00eda solicitan al juez federal que supervisa su caso penal que desestime los cargos de tr\u00e1fico de personas que enfrenta, argumentando que el Departamento de Justicia de Estados Unidos lo seleccion\u00f3 para enjuiciarlo despu\u00e9s de que \u00e9l impugn\u00f3 su deportaci\u00f3n indebida a El Salvador a principios de este a\u00f1o. La [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465674","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &quot;acusaci\u00f3n selectiva y vengativa&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &quot;acusaci\u00f3n selectiva y vengativa&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los abogados de Kilmar \u00c1brego Garc\u00eda solicitan al juez federal que supervisa su caso penal que desestime los cargos de tr\u00e1fico de personas que enfrenta, argumentando que el Departamento de Justicia de Estados Unidos lo seleccion\u00f3 para enjuiciarlo despu\u00e9s de que \u00e9l impugn\u00f3 su deportaci\u00f3n indebida a El Salvador a principios de este a\u00f1o. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T03:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;\",\"datePublished\":\"2025-08-20T03:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\"},\"wordCount\":665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\",\"name\":\"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando \\\"acusaci\u00f3n selectiva y vengativa\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-20T03:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando \"acusaci\u00f3n selectiva y vengativa\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando \"acusaci\u00f3n selectiva y vengativa\" - Noticias","og_description":"Los abogados de Kilmar \u00c1brego Garc\u00eda solicitan al juez federal que supervisa su caso penal que desestime los cargos de tr\u00e1fico de personas que enfrenta, argumentando que el Departamento de Justicia de Estados Unidos lo seleccion\u00f3 para enjuiciarlo despu\u00e9s de que \u00e9l impugn\u00f3 su deportaci\u00f3n indebida a El Salvador a principios de este a\u00f1o. La [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-20T03:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/"},"author":{"name":"","@id":""},"headline":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;","datePublished":"2025-08-20T03:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/"},"wordCount":665,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","name":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando \"acusaci\u00f3n selectiva y vengativa\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-20T03:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los abogados de \u00c1brego Garc\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\u00f3n selectiva y vengativa&#187;","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/08\/19\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-20T03:03:41Z","datePublished":"2025-08-20T03:03:41Z","dateModified":"2025-08-20T03:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los abogados de \\u00c1brego Garc\\u00eda piden al juez que desestime su caso penal, alegando &#171;acusaci\\u00f3n selectiva y vengativa&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/19\\\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/08\\\/19\\\/abogados-abrego-garcia-juez-desestime-caso-penal-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-20T03:03:41Z\",\"datePublished\":\"2025-08-20T03:03:41Z\",\"dateModified\":\"2025-08-20T03:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465011,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/31\/juez-abrego-garcia-gobierno-modere-comentarios-trax\/","url_meta":{"origin":1465674,"position":0},"title":"Juez en el caso de \u00c1brego Garc\u00eda pide al Gobierno de Trump que modere comentarios p\u00fablicos para asegurar un juicio justo","author":"","date":"julio 31, 2025","format":false,"excerpt":"El juez federal en Tennessee que supervisa el caso penal de Kilmar \u00c1brego Garc\u00eda le dijo este jueves al Gobierno Trump que los funcionarios deben moderar sus comentarios p\u00fablicos sobre \u00e9l para asegurar que reciba un juicio justo.La orden del juez de distrito de EE.UU. Waverly Crenshaw llega una semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469674,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/30\/funcionarios-presionando-cargos-penales-abrego-garcia-trax\/","url_meta":{"origin":1465674,"position":1},"title":"Funcionarios del Departamento de Justicia habr\u00edan presionando para presentar cargos penales contra \u00c1brego Garc\u00eda, dice juez","author":"","date":"diciembre 30, 2025","format":false,"excerpt":"Archivos internos del Departamento de Justicia \u201csugieren\u201d que altos funcionarios en Washington trabajaron con fiscales federales en Nashville para procesar a Kilmar \u00c1brego Garc\u00eda despu\u00e9s de que \u00e9l luchara contra su deportaci\u00f3n injusta a El Salvador, dijo un juez federal en una reciente decisi\u00f3n desclasificada.La opini\u00f3n del 3 de diciembre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465962,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/29\/abrego-garcia-juez-orden-silencio-trax\/","url_meta":{"origin":1465674,"position":2},"title":"Abogados de \u00c1brego Garc\u00eda solicitan al juez una orden de silencio contra funcionarios de la administraci\u00f3n Trump","author":"","date":"agosto 29, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda, el hombre deportado injustamente a El Salvador a principios de este a\u00f1o, est\u00e1n pidiendo nuevamente al juez federal que supervisa su caso penal de supuesto tr\u00e1fico de personas que ordene a los funcionarios de la administraci\u00f3n Trump que dejen de hacer comentarios negativos que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465969,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/29\/kilmar-abrego-garcia-juez-orden-silencio-trax\/","url_meta":{"origin":1465674,"position":3},"title":"Abogados de Kilmar \u00c1brego Garc\u00eda solicitan al juez una orden de silencio contra funcionarios de la administraci\u00f3n Trump","author":"","date":"agosto 29, 2025","format":false,"excerpt":"Los abogados de Kilmar \u00c1brego Garc\u00eda, el hombre deportado injustamente a El Salvador a principios de este a\u00f1o, est\u00e1n pidiendo nuevamente al juez federal que supervisa su caso penal de supuesto tr\u00e1fico de personas que ordene a los funcionarios de la administraci\u00f3n Trump que dejen de hacer comentarios negativos que,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464795,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/23\/abrego-garcia-seguira-detenido-un-mes-no-peligro-trax\/","url_meta":{"origin":1465674,"position":4},"title":"\u00c1brego Garc\u00eda seguir\u00e1 detenido al menos un mes, aunque el juez rechaz\u00f3 que sea un peligro, como dijo el Gobierno de Trump","author":"","date":"julio 23, 2025","format":false,"excerpt":"Un juez federal en Tennessee rechaz\u00f3 este mi\u00e9rcoles anular la decisi\u00f3n de otro juez que permite que Kilmar \u00c1brego Garc\u00eda permanezca en libertad mientras espera juicio por cargos de tr\u00e1fico de personas, aunque seguir\u00e1 detenido al menos otro mes.El juez de distrito Waverly Crenshaw determin\u00f3 que los fiscales federales no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465749,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/22\/kilmar-abrego-garcia-podria-quedar-libertad-trax\/","url_meta":{"origin":1465674,"position":5},"title":"Kilmar \u00c1brego Garc\u00eda podr\u00eda quedar en libertad este viernes. Estas son las claves del caso","author":"","date":"agosto 22, 2025","format":false,"excerpt":"Kilmar \u00c1brego Garc\u00eda podr\u00eda ser liberado de custodia federal tan pronto como este viernes, en el giro m\u00e1s reciente de una saga legal dram\u00e1tica que rodea al padre de tres hijos de Maryland que fue deportado injustamente.Desde que regres\u00f3 hace tres meses a Estados Unidos desde El Salvador, hacia donde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1465674"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1465674\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1465674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1465674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1465674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}