{"id":1469211,"date":"2025-12-12T08:03:47","date_gmt":"2025-12-12T16:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/"},"modified":"2025-12-12T08:03:47","modified_gmt":"2025-12-12T16:03:47","slug":"transicion-irreversible-maria-corina-machado-gobierno-maduro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","title":{"rendered":"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela"},"content":{"rendered":"<p>La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 este viernes que \u201cla transici\u00f3n es irreversible\u201d en el Gobierno del presidente de Venezuela, Nicol\u00e1s Maduro, en medio de las tensiones entre el pa\u00eds sudamericano y Estados Unidos.<\/p>\n<p>\u201cYo creo que ha quedado muy claro que el conflicto venezolano es absolutamente prioritario en materia de seguridad nacional de los Estados Unidos y en materia de seguridad hemisf\u00e9rica\u201d, dijo Machado en conferencia de prensa en Oslo. \u201cDe modo que la transici\u00f3n es irreversible\u201d.<\/p>\n<p>La opositora venezolana \u2014que lleg\u00f3 a Oslo el jueves luego de un viaje complejo desde Venezuela para asistir a la capital noruega en el marco del Premio Nobel de la Paz otorgado a ella\u2014 afirm\u00f3 que Estados Unidos no es el \u00fanico pa\u00eds que se est\u00e1 preparando para la transici\u00f3n democr\u00e1tica en Venezuela.<\/p>\n<p>\u201cEn otras partes del mundo ya se est\u00e1n preparando para la transici\u00f3n que avanza a la democracia en Venezuela. Por muchas razones, una de ellas es precisamente la migraci\u00f3n. Millones de venezolanos que se han visto obligados a dejar su pa\u00eds y que tambi\u00e9n ya se est\u00e1n preparando haciendo sus maletas para volver\u201d, declar\u00f3 Machado a la pregunta de CNN en la rueda de prensa.<\/p>\n<p>\u201cDonde estamos fundamentalmente concentrados es c\u00f3mo podemos asegurar que sea una transici\u00f3n ordenada, pac\u00edfica, d\u00f3nde los resultados de la reconstrucci\u00f3n del pa\u00eds se sientan lo m\u00e1s pronto para los venezolanos\u201d, a\u00f1adi\u00f3.<\/p>\n<p>\u201cYo tengo hoy en d\u00eda confianza de que la inmensa mayor\u00eda de las fuerzas armadas venezolanas y de las polic\u00edas venezolanas, en el instante que inicie la transici\u00f3n, van a acatar \u00f3rdenes, lineamientos, instrucciones de los superiores que ser\u00e1n designados por la autoridad civil debidamente electa por los venezolanos\u201d, concluy\u00f3 Machado.<\/p>\n<p>Desde <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/09\/venezuela\/trump-planes-despues-maduro-venezuela-trax\">hace meses<\/a>, EE.UU. ha llevado a cabo una campa\u00f1a de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/11\/eeuu\/analisis-trump-venezuela-petrolero-escalada-trax\">presi\u00f3n<\/a> que ha visto a las fuerzas armadas estadounidenses mover miles de tropas y un grupo de ataque de portaaviones al Caribe y al presidente Donald Trump emitir reiteradas amenazas contra Maduro.<\/p>\n<p>Seg\u00fan fuentes consultadas por <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/09\/venezuela\/trump-planes-despues-maduro-venezuela-trax\">CNN<\/a>, la administraci\u00f3n de Trump est\u00e1 trabajando en planes para el d\u00eda despu\u00e9s en caso de que Maduro sea expulsado del poder. Los planes incluyen m\u00faltiples opciones sobre c\u00f3mo podr\u00eda ser la acci\u00f3n de Estados Unidos para llenar el vac\u00edo de poder y estabilizar el pa\u00eds si Maduro se va voluntariamente como parte de una salida negociada o se ve obligado a irse despu\u00e9s de ataques estadounidenses a objetivos dentro de Venezuela u otra acci\u00f3n directa, dijeron las fuentes.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/09\/venezuela\/trump-planes-despues-maduro-venezuela-trax\">Trump<\/a> habl\u00f3 por tel\u00e9fono con Maduro a finales del mes pasado, pocos d\u00edas antes de que entrara en vigor la designaci\u00f3n estadounidense del presidente de Venezuela y sus aliados gubernamentales como miembros de una organizaci\u00f3n terrorista extranjera. Un alto funcionario de la Casa Blanca afirm\u00f3 que, si bien la llamada no fue necesariamente pol\u00e9mica, el presidente s\u00ed le dio una especie de ultim\u00e1tum a su hom\u00f3logo, dici\u00e9ndole que a Maduro le conven\u00eda abandonar el pa\u00eds y que Trump ten\u00eda la intenci\u00f3n de seguir \u201cdestruyendo\u201d barcos.<\/p>\n<p>Por su parte, Maduro <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/03\/venezuela\/maduro-confirma-llamada-trump-trax\">describi\u00f3<\/a> la llamada con Trump como respetuosa y \u201ccordial\u201d, pero no ofreci\u00f3 detalles sobre los temas tratados.<\/p>\n<p>\u201cSi esa llamada significa que se est\u00e1n dando pasos hacia un di\u00e1logo respetuoso de Estado a Estado, de pa\u00eds a pa\u00eds, entonces bienvenido el di\u00e1logo, bienvenida la diplomacia, porque siempre buscaremos la paz\u201d, dijo Maduro.<\/p>\n<p>Rosa Yolanda Villavicencio, canciller de Colombia, dijo que si el presidente de Venezuela, Nicol\u00e1s Maduro, llegase a salir de su pa\u00eds para una transici\u00f3n en el poder, Colombia le ofrecer\u00eda protecci\u00f3n.<\/p>\n<p>\u201cEn el momento de tensi\u00f3n que existe (entre Estados Unidos y Venezuela), hay que negociar, y seguramente, si EE.UU. exige una transici\u00f3n o un cambio, es una cosa (la salida de Venezuela) que ellos deben valorar. Si esa salida implica que \u00e9l (Maduro) deba vivir en otro pa\u00eds o pedir la protecci\u00f3n, Colombia no tendr\u00eda por qu\u00e9 decirle que no\u201d, dijo Villavicencio en una <a href=\"https:\/\/x.com\/UltimaHoraCR\/status\/1999113396822704509?s=20\">entrevista<\/a> el jueves con el medio local Caracol.<\/p>\n<p>En tanto, el presidente de Colombia, Gustavo Petro, <a href=\"https:\/\/cnnespanol.cnn.com\/mundo\/live-news\/corina-machado-entrega-premio-nobel-paz-orix?post-id=cmj0bf4aa0005356ui6v31kcz\">dijo<\/a> el mi\u00e9rcoles que Venezuela necesita una \u201crevoluci\u00f3n democr\u00e1tica\u201d y pidi\u00f3 un \u201cgobierno de transici\u00f3n\u201d.<\/p>\n<p>\u201cEl Gobierno de Maduro debe entender que la respuesta a una agresi\u00f3n externa no es solo un alistamiento militar sino una revoluci\u00f3n democr\u00e1tica. Es con m\u00e1s democracia como se defiende un pa\u00eds no con m\u00e1s represiones ineficientes\u201d, escribi\u00f3 Petro en<a href=\"https:\/\/x.com\/petrogustavo\/status\/1998774566219403429\"> su cuenta de X.<\/a><\/p>\n<p>\u201cEs hora de una amnist\u00eda general y de un gobierno de transici\u00f3n con la inclusi\u00f3n de todos y de todas. La patria de Bol\u00edvar no debe ser invadida ni por extranjeros no por ret\u00f3ricas vac\u00edas no por c\u00e1rceles del alma. La patria de Bol\u00edvar se defiende con m\u00e1s democracia y soberan\u00eda\u201d, agreg\u00f3 el mandatario de Colombia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 este viernes que \u201cla transici\u00f3n es irreversible\u201d en el Gobierno del presidente de Venezuela, Nicol\u00e1s Maduro, en medio de las tensiones entre el pa\u00eds sudamericano y Estados Unidos. \u201cYo creo que ha quedado muy claro que el conflicto venezolano es absolutamente prioritario en materia de seguridad nacional [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469211","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;La transici\u00f3n es irreversible&quot;, dice Mar\u00eda Corina Machado sobre Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;La transici\u00f3n es irreversible&quot;, dice Mar\u00eda Corina Machado sobre Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 este viernes que \u201cla transici\u00f3n es irreversible\u201d en el Gobierno del presidente de Venezuela, Nicol\u00e1s Maduro, en medio de las tensiones entre el pa\u00eds sudamericano y Estados Unidos. \u201cYo creo que ha quedado muy claro que el conflicto venezolano es absolutamente prioritario en materia de seguridad nacional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T16:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela\",\"datePublished\":\"2025-12-12T16:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\"},\"wordCount\":893,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\",\"name\":\"\\\"La transici\u00f3n es irreversible\\\", dice Mar\u00eda Corina Machado sobre Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-12T16:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"La transici\u00f3n es irreversible\", dice Mar\u00eda Corina Machado sobre Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"La transici\u00f3n es irreversible\", dice Mar\u00eda Corina Machado sobre Venezuela - Noticias","og_description":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 este viernes que \u201cla transici\u00f3n es irreversible\u201d en el Gobierno del presidente de Venezuela, Nicol\u00e1s Maduro, en medio de las tensiones entre el pa\u00eds sudamericano y Estados Unidos. \u201cYo creo que ha quedado muy claro que el conflicto venezolano es absolutamente prioritario en materia de seguridad nacional [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-12T16:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela","datePublished":"2025-12-12T16:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/"},"wordCount":893,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","name":"\"La transici\u00f3n es irreversible\", dice Mar\u00eda Corina Machado sobre Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-12T16:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;La transici\u00f3n es irreversible&#187;, dice Mar\u00eda Corina Machado sobre Venezuela","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/12\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-12T16:03:47Z","datePublished":"2025-12-12T16:03:47Z","dateModified":"2025-12-12T16:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;La transici\\u00f3n es irreversible&#187;, dice Mar\\u00eda Corina Machado sobre Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/12\\\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/12\\\/transicion-irreversible-maria-corina-machado-gobierno-maduro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-12T16:03:47Z\",\"datePublished\":\"2025-12-12T16:03:47Z\",\"dateModified\":\"2025-12-12T16:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469760,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/03\/trump-maria-corina-machado-venezuela-orix\/","url_meta":{"origin":1469211,"position":0},"title":"Trump cuestiona la capacidad de Mar\u00eda Corina Machado para liderar Venezuela: &#171;No tiene el apoyo&#187;","author":"","date":"enero 3, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, puso en duda este s\u00e1bado la capacidad de la l\u00edder opositora venezolana Mar\u00eda Corina Machado para gobernar el pa\u00eds tras la captura de Nicol\u00e1s Maduro, al afirmar que no cree que cuente con el respaldo necesario dentro de Venezuela.Consultado por periodistas sobre si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467257,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/10\/maria-corina-machado-nobel-paz-impulso-orix\/","url_meta":{"origin":1469211,"position":1},"title":"Mar\u00eda Corina Machado dice que el Nobel de Paz &#171;es un impulso para concluir&#187; la tarea de &#171;conquistar la libertad&#187;","author":"","date":"octubre 10, 2025","format":false,"excerpt":"La dirigente opositora venezolana Mar\u00eda Corina Machado, premiada este viernes con el Nobel de la Paz, afirm\u00f3 que el galard\u00f3n es un impulso \u201cpara concluir\u201d la tarea de \u201cconquistar la libertad\u201d en el pa\u00eds\u201cEste inmenso reconocimiento a la lucha de todos los venezolanos es un impulso para concluir nuestra tarea:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470572,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/28\/machado-transicion-respaldo-eeuu-rubio-orix\/","url_meta":{"origin":1469211,"position":2},"title":"Machado se re\u00fane con Rubio en Washington y dice que la oposici\u00f3n venezolana tiene el respaldo de EE.UU.","author":"","date":"enero 28, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado dijo este mi\u00e9rcoles que el movimiento pol\u00edtico que encabeza tiene el apoyo de Estados Unidos y de otros pa\u00edses para que en Venezuela se concrete una transici\u00f3n luego del derrocamiento del presidente Nicol\u00e1s Maduro, quien el 3 de enero fue capturado en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467253,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/10\/10\/premio-nobel-paz-maria-corina-machado-lider-opositora-venezolana-trax\/","url_meta":{"origin":1469211,"position":3},"title":"Premio Nobel de la Paz para Mar\u00eda Corina Machado, l\u00edder opositora venezolana","author":"","date":"octubre 10, 2025","format":false,"excerpt":"El Premio Nobel de la Paz 2025 fue otorgado a Mar\u00eda Corina Machado por \u201cpromover los derechos democr\u00e1ticos del pueblo de Venezuela\u201d.El Comit\u00e9 Noruego del Nobel afirm\u00f3 que Mar\u00eda Corina Machado hab\u00eda ayudado a \u201cmantener encendida la llama de la democracia frente a una oscuridad creciente\u201d.Al anunciar el premio en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469750,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/03\/maria-corina-machado-edmundo-gonzalez-captura-maduro-orix\/","url_meta":{"origin":1469211,"position":4},"title":"Mar\u00eda Corina Machado dice que Edmundo Gonz\u00e1lez debe asumir como &#171;leg\u00edtimo presidente&#187; de Venezuela tras captura de Maduro","author":"","date":"enero 3, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado public\u00f3 un mensaje en sus redes sociales tras conocerse la noticia de la captura de Nicol\u00e1s Maduro por parte de Estados Unidos. En su mensaje, Machado dijo que Edmundo Gonz\u00e1lez Urrutia debe asumir como \u201cleg\u00edtimo presidente\u201d de Venezuela.\u201cEsta es la hora de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471771,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/01\/maria-corina-machado-regreso-semanas-orix\/","url_meta":{"origin":1469211,"position":5},"title":"Mar\u00eda Corina Machado anunci\u00f3 que volver\u00e1 a Venezuela &#171;en las pr\u00f3ximas semanas&#187;","author":"","date":"marzo 1, 2026","format":false,"excerpt":"La l\u00edder opositora venezolana Mar\u00eda Corina Machado anunci\u00f3 este domingo que en las \u201cpr\u00f3ximas semanas\u201d volver\u00e1 a su pa\u00eds, donde se preparar\u00e1, seg\u00fan dijo, para \u201cuna nueva y gigantesca victoria electoral\u201d, a casi dos meses de la captura del presidente Nicol\u00e1s Maduro por parte de fuerzas estadounidenses.Machado, quien sali\u00f3 del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469211"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469211\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}