{"id":1469258,"date":"2025-12-14T15:03:50","date_gmt":"2025-12-14T23:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/"},"modified":"2025-12-14T15:03:50","modified_gmt":"2025-12-14T23:03:50","slug":"chile-kast-vence-segunda-vuelta-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","title":{"rendered":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha"},"content":{"rendered":"<p>El ultraderechista Jos\u00e9 Antonio Kast fue elegido presidente de Chile al vencer este domingo a la izquierdista Jeannette Jara, seg\u00fan los resultados oficiales preliminares, en una segunda vuelta que lo ten\u00eda como favorito luego de haber recibido el apoyo de otros l\u00edderes afines.<\/p>\n<p>Con el 83,43 % de los votos computados hasta las 17:35 horas, tiempo de Miami, Kast tiene el 58,61 %, una amplia ventaja frente al 41,39 % de Jara, <a href=\"https:\/\/segundavotacion.servel.cl\/\">seg\u00fan los datos del Servicio Electoral de Chile<\/a> (Servel).<\/p>\n<p>Tras la difusi\u00f3n de los resultados preliminares, Jara reconoci\u00f3 su derrota con un mensaje en su cuenta de X.<\/p>\n<p>\u201cLa democracia habl\u00f3 fuerte y claro. Me acabo de comunicar con el Presidente electo<a href=\"https:\/\/x.com\/joseantoniokast\"> @joseantoniokast<\/a> para desearle \u00e9xito por el bien de Chile\u201d, dijo.<\/p>\n<p>\u201cA quienes nos apoyaron y fueron convocados por nuestra candidatura, tengan claro que seguiremos trabajando por avanzar en una mejor vida en nuestra patria. Juntos y de pie, como siempre lo hemos hecho\u201d, agreg\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ultraderechista Jos\u00e9 Antonio Kast fue elegido presidente de Chile al vencer este domingo a la izquierdista Jeannette Jara, seg\u00fan los resultados oficiales preliminares, en una segunda vuelta que lo ten\u00eda como favorito luego de haber recibido el apoyo de otros l\u00edderes afines. Con el 83,43 % de los votos computados hasta las 17:35 horas, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469258","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ultraderechista Jos\u00e9 Antonio Kast fue elegido presidente de Chile al vencer este domingo a la izquierdista Jeannette Jara, seg\u00fan los resultados oficiales preliminares, en una segunda vuelta que lo ten\u00eda como favorito luego de haber recibido el apoyo de otros l\u00edderes afines. Con el 83,43 % de los votos computados hasta las 17:35 horas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-14T23:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha\",\"datePublished\":\"2025-12-14T23:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\"},\"wordCount\":189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\",\"name\":\"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-14T23:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias","og_description":"El ultraderechista Jos\u00e9 Antonio Kast fue elegido presidente de Chile al vencer este domingo a la izquierdista Jeannette Jara, seg\u00fan los resultados oficiales preliminares, en una segunda vuelta que lo ten\u00eda como favorito luego de haber recibido el apoyo de otros l\u00edderes afines. Con el 83,43 % de los votos computados hasta las 17:35 horas, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-14T23:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/"},"author":{"name":"","@id":""},"headline":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha","datePublished":"2025-12-14T23:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/"},"wordCount":189,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","name":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-14T23:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/14\/chile-kast-vence-segunda-vuelta-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-14T23:03:50Z","datePublished":"2025-12-14T23:03:50Z","dateModified":"2025-12-14T23:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Kast vence a Jara en segunda vuelta y Chile vuelve a girar, esta vez a la ultraderecha\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/14\\\/chile-kast-vence-segunda-vuelta-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/14\\\/chile-kast-vence-segunda-vuelta-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-14T23:03:50Z\",\"datePublished\":\"2025-12-14T23:03:50Z\",\"dateModified\":\"2025-12-14T23:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468406,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/16\/elecciones-chile-jara-kast-segunda-vuelta-orix\/","url_meta":{"origin":1469258,"position":0},"title":"Elecciones en Chile: Jeannette Jara y Jos\u00e9 Antonio Kast se enfrentar\u00e1n en segunda vuelta por la presidencia","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"La candidata oficialista Jeannette Jara, militante del Partido Comunista y abanderada de la coalici\u00f3n Unidad por Chile, y el opositor Jos\u00e9 Antonio Kast, fundador del Partido Republicano, competir\u00e1n en una segunda vuelta electoral el 14 de diciembre por la Presidencia de Chile, de acuerdo con los resultados preliminares publicados este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468412,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/16\/chile-jara-kast-segunda-vuelta-claves-orix\/","url_meta":{"origin":1469258,"position":1},"title":"Jara vs. Kast: las claves de por qu\u00e9 habr\u00e1 una segunda vuelta en Chile y cu\u00e1l candidato parte con mayor ventaja","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"La definici\u00f3n de qui\u00e9n encabezar\u00e1 la Presidencia de Chile para el per\u00edodo 2026-2030 tendr\u00e1 que esperar un mes, pero desde la noche de este domingo algunas se\u00f1ales indican qu\u00e9 candidato arranca con m\u00e1s fuerza la carrera hacia la segunda vuelta del 14 de diciembre.Jeannette Jara, candidata oficialista, militante del Partido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469256,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/14\/mapa-resultados-elecciones-chile-jara-kast-orix\/","url_meta":{"origin":1469258,"position":2},"title":"Mapa de resultados de la segunda vuelta de las elecciones presidenciales en Chile 2025: d\u00f3nde ganan Kast y Jara","author":"","date":"diciembre 14, 2025","format":false,"excerpt":"Chile lleg\u00f3 a la segunda vuelta presidencial con Jos\u00e9 Antonio Kast como favorito, tras reunir el apoyo de toda la derecha, y con Jeannette Jara intentando remontar una desventaja marcada por la baja aprobaci\u00f3n del Gobierno de Gabriel Boric. Aunque representan polos opuestos en lo ideol\u00f3gico, ambos candidatos convergen en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469145,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/10\/jara-cast-claves-debate-candidatos-presidente-chile-efe\/","url_meta":{"origin":1469258,"position":3},"title":"El \u00faltimo debate entre Kast y Jara, candidatos a la presidencia de Chile, fue el m\u00e1s intenso: estas son las claves","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"La izquierdista Jeannette Jara y el ultraderechista Jos\u00e9 Antonio Kast protagonizaron la noche de este martes un intenso debate presidencial que evidenci\u00f3 la distancia que existe entre sus modelos de pa\u00eds y su diferente aproximaci\u00f3n para resolver las principales preocupaciones de la poblaci\u00f3n, como la seguridad, el control migratorio y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468498,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/19\/chile-elecciones-congreso-dividido-derecha-orix\/","url_meta":{"origin":1469258,"position":4},"title":"Partidos de derecha quedan cerca de la mayor\u00eda en el Congreso de Chile: un escenario ideal para Kast, si gana","author":"","date":"noviembre 19, 2025","format":false,"excerpt":"Jeannette Jara, candidata de la izquierda, y Jos\u00e9 Antonio Kast, candidato de la ultraderecha, se preparan para disputar la Presidencia de Chile en la segunda vuelta que se realizar\u00e1 en menos de un mes, el 14 de diciembre. Pero sin importar qui\u00e9n de ellos gane, ambos ya pueden tener una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469215,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/12\/chile-elecciones-presidenciales-segunda-vuelta-kast-jara-extremos-orix\/","url_meta":{"origin":1469258,"position":5},"title":"Chile elige presidente entre dos extremos, pero con una misma agenda: la seguridad y la inmigraci\u00f3n","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"Chile elige este domingo un nuevo presidente en una segunda vuelta marcada por el favoritismo de Jos\u00e9 Antonio Kast, el candidato ultraderechista que recibi\u00f3 el apoyo de otros competidores afines, por encima de la izquierdista Jeannette Jara, cuya popularidad fue arrastrada por la baja aprobaci\u00f3n del Gobierno del saliente mandatario,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469258"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469258\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}