{"id":1469359,"date":"2025-12-17T15:03:47","date_gmt":"2025-12-17T23:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/"},"modified":"2025-12-17T15:03:47","modified_gmt":"2025-12-17T23:03:47","slug":"busqueda-atacante-universidad-brown-equivocado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","title":{"rendered":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado"},"content":{"rendered":"<p>La ma\u00f1ana del domingo, mientras los investigadores preparaban una orden de registro para una habitaci\u00f3n de hotel en Coventry, Rhode Island, el director del FBI, Kash Patel, celebraba en redes sociales que una persona relevante para la investigaci\u00f3n hab\u00eda sido detenida en el caso del tiroteo de la Universidad de Brown.<\/p>\n<p>Al mismo tiempo, el alcalde de Providence, Brett Smiley, anunciaba la detenci\u00f3n del hombre desde un podio y les dec\u00eda a los residentes que pod\u00edan \u201crespirar un poco m\u00e1s tranquilos\u201d.<\/p>\n<p>Result\u00f3 ser el <a href=\"https:\/\/www.cnn.com\/2025\/12\/16\/us\/brown-university-shooting-investigation\">hombre equivocado.<\/a><\/p>\n<p>El anuncio de Patel, realizado en una publicaci\u00f3n en la red social X, destacaba el papel del FBI al usar datos de torres de telefon\u00eda celular para encontrar a la presunta persona relevante para la investigaci\u00f3n. Para ese momento, sin embargo, algunos investigadores ya sab\u00edan que el tel\u00e9fono celular de dicha persona no hab\u00eda sido identificado en el lugar del tiroteo, lo que arrojaba dudas sobre la participaci\u00f3n del hombre, dijeron a CNN tres personas familiarizadas con la investigaci\u00f3n.<\/p>\n<p>En cuesti\u00f3n de horas, esas dudas aumentaron cuando los investigadores determinaron que las pruebas en los casquillos encontrados en la escena del tiroteo no coincid\u00edan con el ADN de la persona relevante para la investigaci\u00f3n, dijeron dos de las fuentes. Dos pistolas encontradas en la habitaci\u00f3n de hotel de esta persona tampoco coincid\u00edan con la bal\u00edstica de los casquillos, y una prueba de residuos en las manos del hombre result\u00f3 negativa, indicaron las fuentes.<\/p>\n<p>El hombre detenido fue liberado m\u00e1s tarde ese domingo.<\/p>\n<p>\u201cEs justo decir que no hay ninguna raz\u00f3n para considerarlo persona relevante para la investigaci\u00f3n\u201d, dijo el domingo el fiscal general de Rhode Island, Peter Neronha, sobre el hombre que hab\u00eda sido detenido. \u201cPor eso est\u00e1 siendo liberado\u201d.<\/p>\n<p>Cabe se\u00f1alar que el tiroteo en la Universidad de Brown es una investigaci\u00f3n dirigida a nivel local y estatal, y el papel del FBI es asistir. Luego de tensiones durante el fin de semana, los funcionarios se reagruparon el lunes y Patel envi\u00f3 m\u00e1s recursos a Providence para apoyar la investigaci\u00f3n.<\/p>\n<p>Ahora el FBI ofrece una recompensa de US$ 50.000 por pistas que lleven a la identificaci\u00f3n y condena del atacante.<\/p>\n<p>La publicaci\u00f3n de Patel en X del domingo por la noche, en la que dec\u00eda \u201cactivamos el Equipo de An\u00e1lisis de Encuestas Celulares para proporcionar capacidades cr\u00edticas de geolocalizaci\u00f3n\u201d, proyectaba un trabajo investigativo preciso y confianza en que los investigadores se acercaban al posible responsable.<\/p>\n<p>Dichos datos de torres de telefon\u00eda celular, que muestran ubicaciones precisas y movimiento de tel\u00e9fonos que se conectan a torres cercanas, han sido clave para encontrar sospechosos en cr\u00edmenes, incluyendo al hombre acusado en la investigaci\u00f3n de bombas de tubo puestas cerca de las sedes del RNC y DNC en la ciudad de Washington, en 2021.<\/p>\n<p>La publicaci\u00f3n del director del FBI en redes sociales enfureci\u00f3 a funcionarios locales y estatales en Rhode Island, quienes la consideraron prematura y perjudicial para la investigaci\u00f3n.<\/p>\n<p>Una persona familiarizada con la publicaci\u00f3n del director del FBI en redes sociales dijo que Patel se refer\u00eda al uso de los datos CAST para ubicar la localizaci\u00f3n de la persona en el hotel.<\/p>\n<p>El FBI declin\u00f3 hacer comentarios.<\/p>\n<p>El mensaje en X  y su reacci\u00f3n recuerdan un episodio anterior en el que Patel anunci\u00f3 prematuramente un arresto en el asesinato en septiembre del activista<a href=\"https:\/\/www.cnn.com\/2025\/09\/13\/politics\/kash-patel-fbi-leadership-concerns\"> conservador Charlie Kirk.<\/a><\/p>\n<p>Antes de convertirse en director del FBI, Patel cultiv\u00f3 una gran cercan\u00eda a movimiento MAGA con frecuentes apariciones en podcasts y publicaciones en redes sociales donde atacaba al FBI con teor\u00edas conspirativas sobre el \u201cestado profundo\u201d. Ahora, sigue siendo r\u00e1pido para publicar en redes sociales, incluso en medio de investigaciones en curso.<\/p>\n<p>Al ser consultado en una audiencia del Senado sobre su err\u00f3nea publicaci\u00f3n en redes sociales durante la investigaci\u00f3n de Kirk, Patel reconoci\u00f3 que podr\u00eda haber usado una mejor terminolog\u00eda pero defendi\u00f3 su publicaci\u00f3n: \u201cno lo veo como un error. Lo veo como algo \u2014trabajar con el p\u00fablico para identificar que hab\u00eda un sujeto bajo custodia\u201d.<\/p>\n<p>Los funcionarios locales y estatales de Rhode Island que supervisan el caso del tiroteo de Brown dicen que han tenido una buena relaci\u00f3n de trabajo con los funcionarios del FBI con sede en Boston que trabajan con ellos en Rhode Island. No est\u00e1n tan satisfechos con la alta direcci\u00f3n del FBI.<\/p>\n<p>En una entrevista con Erin Burnett de CNN, Neronha expres\u00f3 su frustraci\u00f3n porque la informaci\u00f3n sobre la persona relevante para la investigaci\u00f3n se hab\u00eda hecho p\u00fablica.<\/p>\n<p>\u201cCreo que personas que no est\u00e1n familiarizadas ni tienen experiencia en investigaciones se precipitaron\u201d, dijo Neronha la noche del lunes.<\/p>\n<p>En este caso, hab\u00eda otros que tambi\u00e9n estaban en el radar como posibles personas relevantes para la investigaci\u00f3n.<\/p>\n<p>Aun as\u00ed, los fiscales locales trabajaron para redactar una orden de registro para la habitaci\u00f3n del hotel. La persona relevante para el caso hab\u00eda apagado su tel\u00e9fono durante un periodo, lo cual algunos investigadores consideraron sospechoso, dijeron dos personas familiarizadas con la investigaci\u00f3n a CNN.<\/p>\n<p>Esa noche, m\u00e1s tarde, fue liberado despu\u00e9s de que los investigadores descubrieran otra informaci\u00f3n que parec\u00eda apuntar en distintas direcciones, dijeron funcionarios policiales.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana del domingo, mientras los investigadores preparaban una orden de registro para una habitaci\u00f3n de hotel en Coventry, Rhode Island, el director del FBI, Kash Patel, celebraba en redes sociales que una persona relevante para la investigaci\u00f3n hab\u00eda sido detenida en el caso del tiroteo de la Universidad de Brown. Al mismo tiempo, el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469359","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias\" \/>\n<meta property=\"og:description\" content=\"La ma\u00f1ana del domingo, mientras los investigadores preparaban una orden de registro para una habitaci\u00f3n de hotel en Coventry, Rhode Island, el director del FBI, Kash Patel, celebraba en redes sociales que una persona relevante para la investigaci\u00f3n hab\u00eda sido detenida en el caso del tiroteo de la Universidad de Brown. Al mismo tiempo, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-17T23:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado\",\"datePublished\":\"2025-12-17T23:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\"},\"wordCount\":954,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\",\"name\":\"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-17T23:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias","og_description":"La ma\u00f1ana del domingo, mientras los investigadores preparaban una orden de registro para una habitaci\u00f3n de hotel en Coventry, Rhode Island, el director del FBI, Kash Patel, celebraba en redes sociales que una persona relevante para la investigaci\u00f3n hab\u00eda sido detenida en el caso del tiroteo de la Universidad de Brown. Al mismo tiempo, el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-17T23:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/"},"author":{"name":"","@id":""},"headline":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado","datePublished":"2025-12-17T23:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/"},"wordCount":954,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","name":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-17T23:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los tropiezos en la b\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/17\/busqueda-atacante-universidad-brown-equivocado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-17T23:03:47Z","datePublished":"2025-12-17T23:03:47Z","dateModified":"2025-12-17T23:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los tropiezos en la b\\u00fasqueda del atacante en la Universidad de Brown llevaron a la captura del hombre equivocado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/17\\\/busqueda-atacante-universidad-brown-equivocado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/17\\\/busqueda-atacante-universidad-brown-equivocado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-17T23:03:47Z\",\"datePublished\":\"2025-12-17T23:03:47Z\",\"dateModified\":\"2025-12-17T23:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466414,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/09\/13\/crecientes-preocupaciones-liderazgo-patel-fbi-trax\/","url_meta":{"origin":1469359,"position":0},"title":"&#171;Es inaceptable&#187;: Crecientes preocupaciones sobre el liderazgo de Patel en el FBI","author":"","date":"septiembre 13, 2025","format":false,"excerpt":"Al acercarse al micr\u00f3fono en una conferencia de prensa este viernes por la ma\u00f1ana en Utah, el director del FBI, Kash Patel, no perdi\u00f3 tiempo en explicar lo que llev\u00f3 a la captura del sospechoso del asesinato del activista conservador Charlie Kirk.\u201cEsto es lo que pasa cuando dejas que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473443,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/23\/nyt-novia-patel-investiga-periodista-trax\/","url_meta":{"origin":1469359,"position":1},"title":"The New York Times denuncia la &#171;alarmante&#187; investigaci\u00f3n contra su reportera que escribi\u00f3 sobre la novia del director del FBI","author":"","date":"abril 23, 2026","format":false,"excerpt":"The New York Times inform\u00f3 que el FBI \u201cinici\u00f3 una investigaci\u00f3n\u201d contra su reportera Elizabeth Williamson despu\u00e9s de que \u00e9sta publicara un art\u00edculo sobre el director del FBI, Kash Patel, titulado \u201cLa novia de Patel busca fama y fortuna, escoltada por un equipo SWAT del FBI\u201d.El editor ejecutivo del Times,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469300,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/16\/que-sabemos-tiroteo-universidad-brown-orix\/","url_meta":{"origin":1469359,"position":2},"title":"\u00bfQu\u00e9 pas\u00f3 en el tiroteo de la Universidad de Brown? Lo que sabemos del sospechoso, las v\u00edctimas y m\u00e1s","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Pasaron m\u00e1s de 72 horas desde que un hombre armado abri\u00f3 fuego en el campus de la Universidad de Brown, en Providence, Rhode Island, matando a dos estudiantes e hiriendo a nueve m\u00e1s. Mientras contin\u00faa su b\u00fasqueda, las autoridades difundieron nuevas im\u00e1genes y una descripci\u00f3n actualizada de una persona relevante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466477,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/09\/15\/tyler-robinson-mensaje-charlie-kirk-antes-asesinato-director-fbi-trax\/","url_meta":{"origin":1469359,"position":3},"title":"Tyler Robinson, sospechoso de asesinar a Charlie Kirk, escribi\u00f3 mensaje antes del tiroteo, dice director del FBI","author":"","date":"septiembre 15, 2025","format":false,"excerpt":"El sospechoso del asesinato de Charlie Kirk escribi\u00f3 antes del tiroteo que ten\u00eda la \u201coportunidad de matar\u201d al influencer conservador y que la iba a tomar, dijo este lunes el director del FBI, Kash Patel.El mensaje fue escrito antes del tiroteo del mi\u00e9rcoles, seg\u00fan declar\u00f3 Patel a Fox News. No\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465757,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/22\/fbi-registra-casa-john-bolton-trax\/","url_meta":{"origin":1469359,"position":4},"title":"El FBI registra la casa de John Bolton como parte de una investigaci\u00f3n de seguridad nacional","author":"","date":"agosto 22, 2025","format":false,"excerpt":"El FBI llev\u00f3 a cabo un registro autorizado por un tribunal en el domicilio de John Bolton como parte de una investigaci\u00f3n de seguridad nacional para determinar si revel\u00f3 informaci\u00f3n clasificada en su libro de 2020, seg\u00fan dos personas familiarizadas con el asunto.CNN observ\u00f3 a personal del FBI en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456194,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/12\/02\/trump-quiere-reemplazar-director-fbi-kash-patel-trax\/","url_meta":{"origin":1469359,"position":5},"title":"Trump anuncia que tiene la intenci\u00f3n de reemplazar al actual director del FBI con Kash Patel","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El presidente electo de Estados Unidos, Donald Trump, anunci\u00f3 este s\u00e1bado que tiene la intenci\u00f3n de elegir a Kash Patel para servir como el pr\u00f3ximo director del FBI.El actual director del FBI, Christopher Wray, tendr\u00eda que renunciar o ser despedido para crear una vacante. Wray fue nombrado por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469359"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469359\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}