{"id":1469392,"date":"2025-12-18T08:03:49","date_gmt":"2025-12-18T16:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/"},"modified":"2025-12-18T08:03:49","modified_gmt":"2025-12-18T16:03:49","slug":"flota-sombra-rusia-espionaje-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","title":{"rendered":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia"},"content":{"rendered":"<p>Personal ruso con v\u00ednculos con las Fuerzas Armadas y los servicios de seguridad del pa\u00eds ha participado en labores de espionaje en aguas europeas mientras trabajaba de forma encubierta en buques que transportan petr\u00f3leo ruso, dijeron en exclusiva a CNN fuentes de inteligencia occidentales y ucranianas.<\/p>\n<p>Desde la invasi\u00f3n a gran escala de Ucrania en 2022, Mosc\u00fa ha construido la llamada flota en la sombra, compuesta por cientos de petroleros. Estas embarcaciones trasladan el petr\u00f3leo ruso desde puertos del B\u00e1ltico y del mar Negro pese a las sanciones occidentales, lo que le genera al Kremlin cientos de millones de d\u00f3lares cada a\u00f1o.<\/p>\n<p>En los \u00faltimos meses, algunos de estos barcos \u2014a menudo registrados en pa\u00edses no relacionados\u2014 han incorporado tripulantes adicionales poco antes de zarpar, seg\u00fan la inteligencia ucraniana. CNN ha visto dos listas de tripulaci\u00f3n de estas naves en las que el personal es predominantemente no ruso, pero los documentos tambi\u00e9n incluyen un par de nombres rusos, junto con los datos de sus pasaportes, al final del listado.<\/p>\n<p>La incorporaci\u00f3n de rusos con antecedentes en seguridad a las tripulaciones de la flota en la sombra ha encendido las alarmas en capitales europeas, ya que ilustra hasta qu\u00e9 punto se han vuelto descaradas las t\u00e1cticas del Kremlin.<\/p>\n<p>Tras hablar con m\u00faltiples fuentes de inteligencia, CNN ha establecido que varios de estos hombres trabajan para una empresa rusa de car\u00e1cter reservado llamada Moran Security. Algunos de ellos son mercenarios, dijeron las fuentes, que previamente trabajaron para contratistas militares privados rusos, como el notorio grupo Wagner.<\/p>\n<p>Moran es una empresa de seguridad privada con v\u00ednculos con las Fuerzas Armadas y los servicios de inteligencia de Rusia, seg\u00fan fuentes de inteligencia occidentales. La firma fue sancionada por el Departamento del Tesoro de EE.UU. en 2024 por prestar \u201cservicios de seguridad armada\u201d a empresas estatales rusas con el objetivo de \u201cintensificar la presi\u00f3n sobre Rusia por su continua guerra cruel y no provocada contra Ucrania\u201d.<\/p>\n<p>Seg\u00fan fuentes de inteligencia ucranianas y occidentales, personal de Moran ha sido desplegado en m\u00faltiples petroleros de la flota en la sombra de Rusia y con frecuencia son los \u00fanicos rusos a bordo.<\/p>\n<p>La inteligencia ucraniana dijo que observ\u00f3 la incorporaci\u00f3n de estos guardias a los buques de la flota en la sombra hace unos seis meses.<\/p>\n<p>Una fuente de inteligencia occidental a\u00f1adi\u00f3 que, en una ocasi\u00f3n, personal de Moran tom\u00f3 fotograf\u00edas de instalaciones militares europeas desde uno de los buques de la flota en la sombra. La fuente no ofreci\u00f3 m\u00e1s detalles.<\/p>\n<p>Los rusos a bordo tambi\u00e9n tienen la tarea de vigilar a los capitanes de los buques, ya que la mayor\u00eda no son ciudadanos rusos, seg\u00fan Oleksandr Stakhnevych, del Servicio de Inteligencia Exterior de Ucrania.<\/p>\n<p>Una fuente de inteligencia occidental coincidi\u00f3 con esa evaluaci\u00f3n y se\u00f1al\u00f3 que, \u201cen el caso de Moran, no participan en combates directos. Se aseguran de que sus contratistas act\u00faen en consonancia con los intereses del Kremlin\u201d.<\/p>\n<p>La presencia y las actividades de los rusos a bordo de estos buques generan una preocupaci\u00f3n creciente entre los servicios de seguridad europeos, dado el n\u00famero de embarcaciones de la flota en la sombra que navegan cerca de las costas del continente y el potencial de espionaje.<\/p>\n<p>Funcionarios de seguridad dicen que colocar hombres armados con antecedentes militares en estos buques es otra herramienta m\u00e1s en el arsenal de t\u00e1cticas de guerra h\u00edbrida del Kremlin, dise\u00f1adas para causar disrupci\u00f3n en Europa. Fuentes de inteligencia tambi\u00e9n dijeron a CNN que estos hombres han participado en actos de sabotaje, aunque no ofrecieron m\u00e1s detalles.<\/p>\n<p>\u201cTener grupos privados armados a bordo de los buques de la flota en la sombra es un caso cl\u00e1sico de negaci\u00f3n plausible\u201d, dijo a CNN Jacob Kaarsbo, exfuncionario de inteligencia de Dinamarca.<\/p>\n<p>\u201cCualquiera con un m\u00ednimo de conocimiento sabe que estos tipos reciben \u00f3rdenes del Estado ruso, pero es dif\u00edcil probarlo\u201d, a\u00f1adi\u00f3.<\/p>\n<p>CNN present\u00f3 los hallazgos de la inteligencia ucraniana y occidental \u2014que se\u00f1alan que Moran opera en coordinaci\u00f3n con la inteligencia rusa y est\u00e1 involucrada en espionaje y sabotaje en toda Europa\u2014 a Alexey Badikov, a quien el Departamento del Tesoro de EE.UU. incluy\u00f3 como director ejecutivo de la empresa. Contactado por tel\u00e9fono, Badikov dijo a CNN que es el subdirector del Grupo Moran Security y que tiene su base \u201cprincipalmente\u201d en San Petersburgo, pero se neg\u00f3 a comentar cualquiera de las acusaciones.<\/p>\n<p>CNN reconstruy\u00f3 las actividades recientes de Moran en uno de estos buques mediante la revisi\u00f3n de informaci\u00f3n de inteligencia ucraniana, evaluaciones de inteligencia occidental y el an\u00e1lisis de im\u00e1genes satelitales y datos mar\u00edtimos.<\/p>\n<p>Se trata de un petrolero sancionado llamado Boracay, que ha cambiado con frecuencia de nombre y de registro oficial a lo largo de los \u00faltimos tres a\u00f1os.<\/p>\n<p>El 20 de septiembre, dos hombres rusos abordaron el Boracay en el puerto b\u00e1ltico de Primorsk, cerca de San Petersburgo, seg\u00fan registros obtenidos por CNN. Im\u00e1genes satelitales y datos de seguimiento de embarcaciones mostraron al buque en ese puerto en esa fecha.<\/p>\n<p>Los hombres no eran marineros tradicionales, sino que figuraban en la lista de tripulaci\u00f3n simplemente como t\u00e9cnicos. Eran los \u00fanicos rusos a bordo del buque, cuya tripulaci\u00f3n estaba compuesta por ciudadanos de China, Myanmar y Bangladesh, seg\u00fan el documento.<\/p>\n<p>La inteligencia exterior de Ucrania identific\u00f3 a los dos hombres y CNN confirm\u00f3 sus nombres con fuentes de inteligencia occidentales.<\/p>\n<p>Uno de ellos es un exagente de polic\u00eda que anteriormente trabaj\u00f3 para la empresa militar privada rusa Wagner, seg\u00fan una fuente de inteligencia occidental. Ninguno de los dos tiene un perfil relevante en internet y no est\u00e1 claro cu\u00e1les eran sus actividades a bordo del Boracay.<\/p>\n<p>Consultado sobre si pod\u00eda confirmar que ambos hombres trabajaban para Moran Security, Badikov dijo a CNN: \u201cNo estoy en condiciones de confirmarlo\u201d. Al insistirle, afirm\u00f3 que \u201cno tiene idea\u201d.<\/p>\n<p>Durante otro viaje realizado por el Boracay en julio, uno de los hombres a bordo hab\u00eda servido en el regimiento especial de polic\u00eda del Ministerio del Interior de Rusia, y otro ten\u00eda registrado como domicilio el Ministerio de Defensa ruso, seg\u00fan la inteligencia exterior de Ucrania.<\/p>\n<p>Muchos buques de la flota en la sombra navegan por el mar B\u00e1ltico, un punto mar\u00edtimo estrat\u00e9gico que bordea varios Estados miembros de la OTAN, entre ellos Dinamarca y Suecia, cuyas autoridades siguen de cerca a estas embarcaciones.<\/p>\n<p>Pr\u00e1cticos mar\u00edtimos daneses, que suben a los petroleros para ayudarlos a navegar por los estrechos, dicen que con frecuencia hay hombres rusos a bordo que parecen estar claramente al mando y que muestran hostilidad hacia los inspectores.<\/p>\n<p>\u201cHe visto personalmente al menos dos buques de la flota en la sombra en los que la tripulaci\u00f3n es mayoritariamente no rusa, pero de repente aparecen uno o dos rusos en la lista\u201d, dijo Bjarne Caesar Skinnerup, uno de los oficiales con m\u00e1s experiencia del servicio estatal de pr\u00e1cticos de Dinamarca, DanPilot.<\/p>\n<p>En ocasiones, a\u00f1adi\u00f3, esos hombres visten uniformes que en al menos un caso parec\u00edan ser de camuflaje de la Armada rusa.<\/p>\n<p>\u201cA bordo, parece que ellos mandan en el barco, que tienen m\u00e1s poder incluso que el capit\u00e1n\u201d, dijo Skinnerup a CNN.<\/p>\n<p>En julio, DanPilot envi\u00f3 un correo electr\u00f3nico a la Autoridad de Gesti\u00f3n de Emergencias de Dinamarca en el que advert\u00eda: \u201cHay cada vez m\u00e1s reportes de buques que tienen algunos tripulantes adicionales, probablemente rusos, que visten uniformes militares y est\u00e1n muy activos tomando fotograf\u00edas, entre otras cosas, de las \u00e1reas del puente\u201d.<\/p>\n<p>El correo fue compartido con CNN por el medio de investigaci\u00f3n Danwatch, que ha informado ampliamente sobre la flota en la sombra de Rusia.<\/p>\n<p>Por su parte, un portavoz de la guardia costera de Suecia dijo a CNN que anteriormente hab\u00edan visto hombres a bordo de buques de la flota en la sombra que no parec\u00edan formar parte de una embarcaci\u00f3n mercante.<\/p>\n<p>Una alta comandante de la Armada sueca, Ewa Skoog Haslum, se\u00f1al\u00f3 el a\u00f1o pasado que algunos petroleros vinculados a Rusia en el B\u00e1ltico transportaban \u201cantenas y m\u00e1stiles que normalmente no corresponden\u201d a buques mercantes.<\/p>\n<p>El Boracay acapar\u00f3 titulares en septiembre cuando transportaba un cargamento de petr\u00f3leo ruso con destino a India.<\/p>\n<p>Dos d\u00edas despu\u00e9s de salir de Primorsk, el 22 de septiembre, el buque se encontraba frente a la costa de Dinamarca justo cuando una serie de avistamientos de drones interrumpi\u00f3 el tr\u00e1fico en el aeropuerto de Copenhague. Otros drones volaron cerca de bases militares danesas.<\/p>\n<p>En ese momento, la polic\u00eda de Copenhague dijo que estaba investigando si buques que se encontraban en la zona hab\u00edan lanzado los drones, pero no precis\u00f3 cu\u00e1les.<\/p>\n<p>Los datos de seguimiento mar\u00edtimo muestran que el Boracay naveg\u00f3 hacia el sur por la costa occidental de Dinamarca la noche del 24 de septiembre, cuando se reportaron otros drones volando al norte de la ciudad de Esbjerg y cerca de varios aeropuertos de la zona.<\/p>\n<p>Una fuente de inteligencia occidental dijo a CNN que \u201cla coincidencia entre el incidente y la presencia del buque en el \u00e1rea puede considerarse sospechosa\u201d.<\/p>\n<p>D\u00edas despu\u00e9s de estos hechos, las Fuerzas Armadas de Francia abordaron el Boracay frente a la costa de Breta\u00f1a, en el noroeste del pa\u00eds, despu\u00e9s de que el buque no presentara pruebas de su nacionalidad. No se encontraron drones a bordo.<\/p>\n<p>Fue entonces cuando se descubri\u00f3 que dos ciudadanos rusos formaban parte de la tripulaci\u00f3n, seg\u00fan fuentes de seguridad occidentales. Ambos fueron interrogados en privado, indicaron las fuentes.<\/p>\n<p>El capit\u00e1n chino del buque fue detenido y posteriormente acusado por las autoridades francesas de \u201cdesobedecer instrucciones\u201d. El Boracay afirmaba navegar bajo bandera de Ben\u00edn desde septiembre, pero los fiscales franceses dijeron que investigaban la \u201cfalta de documentaci\u00f3n sobre la nacionalidad del buque y su afiliaci\u00f3n de bandera\u201d.<\/p>\n<p>En ese momento, las autoridades de Francia y Dinamarca declinaron comentar si la investigaci\u00f3n francesa sobre el Boracay estaba relacionada con los incidentes de drones registrados en Dinamarca.<\/p>\n<p>Kaarsbo, el exfuncionario de inteligencia, dijo que, aunque no es posible demostrar si los hombres est\u00e1n entrenados como pilotos de drones, \u201cestos tipos no son simples marineros inocentes\u2026 hay una probabilidad considerable de que sean capaces de lanzar drones\u201d.<\/p>\n<p>Badikov, sin embargo, rechaz\u00f3 esa hip\u00f3tesis y dijo a CNN que es \u201ccompletamente descabellado\u201d que \u201cun petrolero de crudo lance drones sobre Dinamarca\u201d.<\/p>\n<p>\u201cSi quisieras usar drones, los lanzar\u00edas desde barcos pesqueros\u2026 no desde un gran petrolero\u201d, a\u00f1adi\u00f3, porque \u201ct\u00e9cnicamente no es seguro y nadie lo har\u00eda\u201d.<\/p>\n<p>Un funcionario europeo de inteligencia dijo a CNN: \u201cNuestra hip\u00f3tesis de trabajo es que buques rusos han estado involucrados en al menos algunos de los eventos de drones no explicados cerca de las costas europeas\u201d.<\/p>\n<p>El nuevo jefe de inteligencia exterior del Reino Unido, Blaise Metreweli, dijo esta semana que \u201cRusia nos est\u00e1 poniendo a prueba en la zona gris con t\u00e1cticas que est\u00e1n justo por debajo del umbral de la guerra\u201d, como \u201cdrones sobrevolando aeropuertos y bases, y actividades agresivas en nuestros mares, tanto en la superficie como bajo las olas\u201d.<\/p>\n<p>Fuentes de inteligencia ucranianas compartieron con CNN los nombres de ocho hombres rusos que hab\u00edan estado a bordo de otros buques de la flota en la sombra y que recorrieron una ruta similar alrededor de Europa en el \u00faltimo a\u00f1o. Varios de ellos ten\u00edan v\u00ednculos con las Fuerzas Armadas rusas.<\/p>\n<p>CNN no pudo contactar a la administraci\u00f3n del Boracay.<\/p>\n<p>Tras pasar por Europa, el buque continu\u00f3 hacia el puerto de Vadinar, en el oeste de India, donde descarg\u00f3 un cargamento de petr\u00f3leo ruso el 1 de noviembre, seg\u00fan Kpler, una firma global de datos y an\u00e1lisis.<\/p>\n<p>El Grupo Moran Security fue fundado en 2009 y ha tenido amplios v\u00ednculos con el notorio contratista militar privado Wagner, as\u00ed como con las Fuerzas Armadas y los servicios de inteligencia de Rusia, seg\u00fan fuentes de inteligencia occidentales.<\/p>\n<p>Dos antiguos directores de Moran, Evgeny Sidorov y Vadim Gusev, fundaron en 2013 el Cuerpo Eslavo, la empresa militar privada de la que posteriormente surgi\u00f3 Wagner. Canales de Telegram vinculados a Wagner han mostrado a personal de Moran en el mar, y hace m\u00e1s de una d\u00e9cada la compa\u00f1\u00eda particip\u00f3 en operaciones contra la pirater\u00eda frente a las costas de Somalia.<\/p>\n<p>Los perfiles en redes sociales de algunos integrantes de Moran tambi\u00e9n muestran v\u00ednculos con Wagner, que fue pr\u00e1cticamente desmantelado despu\u00e9s de que su entonces jefe, Yevgeny Prigozhin, encabezara un fallido levantamiento en Rusia en 2023.<\/p>\n<p>En su sitio web, el grupo Moran se\u00f1ala que busca \u201coficiales en servicio activo o retirados que hayan servido en unidades de fuerzas especiales (GRU, tropas aerotransportadas, comandos navales) y que hayan completado al menos dos despliegues\u201d. El GRU es el servicio de inteligencia militar de Rusia.<\/p>\n<p>El presidente de Moran, Vyacheslav Kalashnikov, es un teniente coronel retirado del servicio de inteligencia del FSB ruso, mientras que dos de los directivos que figuran en su sitio web son excomandantes de submarinos nucleares.<\/p>\n<p>El grupo promociona una amplia gama de servicios, entre ellos log\u00edstica internacional, seguridad f\u00edsica mar\u00edtima y terrestre, as\u00ed como operaciones de inteligencia. Seg\u00fan la inteligencia ucraniana, personal de Moran tambi\u00e9n tuvo un papel en Siria en apoyo al ahora derrocado r\u00e9gimen de Assad, al igual que Wagner.<\/p>\n<p>La designaci\u00f3n del Departamento del Tesoro de EE.UU. del a\u00f1o pasado indic\u00f3 que la empresa \u201cofrece servicios de seguridad armada y ha operado bajo contrato para empresas estatales rusas\u201d. Una de ellas es Sovcomflot, la naviera estatal de Rusia, que aparece en el sitio web de Moran como cliente.<\/p>\n<p>La inteligencia ucraniana dijo que observ\u00f3 la incorporaci\u00f3n de estos equipos a bordo de la flota en la sombra hace unos seis meses.<\/p>\n<p>Moran tiene un historial irregular. Seg\u00fan el registro mercantil, la empresa parece haber cerrado operaciones en Rusia en 2017 y haber abierto una oficina en la exrep\u00fablica sovi\u00e9tica de Georgia al a\u00f1o siguiente, una presencia que habr\u00eda sido de corta duraci\u00f3n.<\/p>\n<p>Ahora, sin embargo, Moran Security est\u00e1 registrada tanto en Mosc\u00fa como en Belice y el grupo parece tener una misi\u00f3n nueva y en expansi\u00f3n. Belice es ampliamente reconocida como una jurisdicci\u00f3n utilizada para crear empresas fachada que ocultan a los verdaderos beneficiarios de un negocio.<\/p>\n<p>Mientras la flota en la sombra de Rusia parece ampliar su alcance y ambici\u00f3n, Europa enfrenta un delicado dilema.<\/p>\n<p>Skinnerup, el pr\u00e1ctico mar\u00edtimo dan\u00e9s, cree que deber\u00eda haber una acci\u00f3n internacional conjunta m\u00e1s firme para interceptar buques sin seguro y sin el registro adecuado, como ocurre con muchos de los que integran la flota en la sombra.<\/p>\n<p>\u201c\u00bfNos atrevemos a hacerlo? Porque, \u00bfcu\u00e1l ser\u00eda la reacci\u00f3n de Rusia?\u201d, se pregunt\u00f3.<\/p>\n<p>\u201cPor eso el Gobierno de Dinamarca a\u00fan no ha hecho nada, porque somos un pa\u00eds extremadamente peque\u00f1o y, si hacemos algo, tiene que ser una acci\u00f3n europea conjunta\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal ruso con v\u00ednculos con las Fuerzas Armadas y los servicios de seguridad del pa\u00eds ha participado en labores de espionaje en aguas europeas mientras trabajaba de forma encubierta en buques que transportan petr\u00f3leo ruso, dijeron en exclusiva a CNN fuentes de inteligencia occidentales y ucranianas. Desde la invasi\u00f3n a gran escala de Ucrania en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469392","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Personal ruso con v\u00ednculos con las Fuerzas Armadas y los servicios de seguridad del pa\u00eds ha participado en labores de espionaje en aguas europeas mientras trabajaba de forma encubierta en buques que transportan petr\u00f3leo ruso, dijeron en exclusiva a CNN fuentes de inteligencia occidentales y ucranianas. Desde la invasi\u00f3n a gran escala de Ucrania en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T16:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia\",\"datePublished\":\"2025-12-18T16:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\"},\"wordCount\":2624,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\",\"name\":\"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-18T16:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias","og_description":"Personal ruso con v\u00ednculos con las Fuerzas Armadas y los servicios de seguridad del pa\u00eds ha participado en labores de espionaje en aguas europeas mientras trabajaba de forma encubierta en buques que transportan petr\u00f3leo ruso, dijeron en exclusiva a CNN fuentes de inteligencia occidentales y ucranianas. Desde la invasi\u00f3n a gran escala de Ucrania en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-18T16:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/"},"author":{"name":"","@id":""},"headline":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia","datePublished":"2025-12-18T16:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/"},"wordCount":2624,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","name":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-18T16:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las t\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\u00e9n funciona como un recurso de espionaje, seg\u00fan inteligencia","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/flota-sombra-rusia-espionaje-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-18T16:03:49Z","datePublished":"2025-12-18T16:03:49Z","dateModified":"2025-12-18T16:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las t\\u00e1cticas del Kremlin: la flota en la sombra de Rusia tambi\\u00e9n funciona como un recurso de espionaje, seg\\u00fan inteligencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/18\\\/flota-sombra-rusia-espionaje-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/18\\\/flota-sombra-rusia-espionaje-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-18T16:03:49Z\",\"datePublished\":\"2025-12-18T16:03:49Z\",\"dateModified\":\"2025-12-18T16:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462555,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/20\/avion-combate-ruso-protege-buque-flota-moscu-trax\/","url_meta":{"origin":1469392,"position":0},"title":"Avi\u00f3n de combate ruso protege a buque de &#171;flota sombra&#187; en primera acci\u00f3n de este tipo por parte de Mosc\u00fa, dicen funcionarios","author":"","date":"mayo 20, 2025","format":false,"excerpt":"Hasta la semana pasada, una flota secreta de barcos que transportaba petr\u00f3leo ruso por todo el mundo no mostraba v\u00ednculos claros con el Kremlin. Esto cambi\u00f3 cuando, en una dram\u00e1tica escalada, Rusia utiliz\u00f3 un avi\u00f3n de combate en un aparente intento de proteger a uno de los petroleros que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445898,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/21\/rusia-kremlin-india-estados-unidos-petroleo-trax\/","url_meta":{"origin":1469392,"position":1},"title":"El Gobierno de Rusia nunca ha sido m\u00e1s rico&#8230; gracias a un socio estrat\u00e9gico de EE.UU.","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Rusia est\u00e1 entrando en su tercer a\u00f1o de guerra en Ucrania con una cantidad sin precedentes de efectivo en las arcas del Gobierno, impulsada por un r\u00e9cord de US$ 37.000 millones en ventas de petr\u00f3leo crudo a la India el a\u00f1o pasado, seg\u00fan un nuevo an\u00e1lisis, que concluye\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472677,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/30\/petrolero-ruso-llega-cuba-efe\/","url_meta":{"origin":1469392,"position":2},"title":"Petrolero ruso con 100.000 toneladas de crudo llega a Cuba, seg\u00fan las autoridades rusas","author":"","date":"marzo 30, 2026","format":false,"excerpt":"El petrolero Anatoli Kolodkin con 100.000 toneladas de crudo (m\u00e1s de 700.000 barriles) arrib\u00f3 este lunes a Cuba, seg\u00fan inform\u00f3 el Ministerio de Transporte de Rusia, en lo que supone el primer cargamento de petr\u00f3leo que llega a la isla en los \u00faltimos tres meses.\u201cEn estos momentos el barco espera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472052,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/10\/trum-india-petroleo-ruso-iran-socava-objetivo-trax\/","url_meta":{"origin":1469392,"position":3},"title":"Trump quer\u00eda que la India se alejara del petr\u00f3leo ruso. Su guerra con Ir\u00e1n ahora est\u00e1 socavando ese objetivo","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Durante gran parte del a\u00f1o pasado, Washington intent\u00f3 dejar sin dinero a la maquinaria de guerra de Mosc\u00fa, en parte eliminando a uno de sus clientes m\u00e1s leales: la India.Bajo la campa\u00f1a de presi\u00f3n del presidente Donald Trump, la Casa Blanca impuso altos aranceles a muchas de las exportaciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465164,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/08\/06\/analisis-trump-india-petroleo-ruso-trax\/","url_meta":{"origin":1469392,"position":4},"title":"Trump quiere que India deje de comprar petr\u00f3leo a Rusia. \u00bfPor qu\u00e9 Modi dice que no?","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El primer ministro de India, Narendra Modi, estuvo realizando un complicado acto de equilibrio: mantener relaciones cercanas tanto con el presidente de EE.UU., Donald Trump, como con el l\u00edder de Rusia, Vladimir Putin, mientras insiste en que su pa\u00eds es una parte neutral en la guerra en Ucrania, para consternaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468824,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/11\/29\/flota-encubierta-rusa-explosion-ucrania-trax\/","url_meta":{"origin":1469392,"position":5},"title":"Ucrania afirma que atac\u00f3 petroleros de la &#171;flota fantasma&#187; de Rusia con drones submarinos en el mar Negro","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"Drones submarinos ucranianos atacaron a dos petroleros pertenecientes a la \u201cflota fantasma\u201d rusa en el mar Negro, seg\u00fan un funcionario de los servicios de seguridad ucranianos (SBU).Ucrania se atribuy\u00f3 los ataques tras las explosiones que alcanzaron a los dos buques entre el viernes y el s\u00e1bado.Una fuente de seguridad ucraniana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469392"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469392\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}