{"id":1469410,"date":"2025-12-18T19:03:39","date_gmt":"2025-12-19T03:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/"},"modified":"2025-12-18T19:03:39","modified_gmt":"2025-12-19T03:03:39","slug":"atacaque-dos-embarcaciones-mata-cinco-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","title":{"rendered":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas"},"content":{"rendered":"<p>Las Fuerzas Armadas de Estados Unidos realizaron ataques contra dos presuntas embarcaciones de narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico este jueves, en los que murieron cinco personas, seg\u00fan el Comando Sur de Estados Unidos.<\/p>\n<p>\u201cEl 18 de diciembre, por orden de @SecWarPete Hegseth, la Fuerza de Tarea Conjunta Southern Spear realiz\u00f3 ataques letales contra dos embarcaciones operadas por organizaciones designadas como terroristas en aguas internacionales\u201d, escribi\u00f3 el Comando Sur de Estados Unidos <a href=\"https:\/\/x.com\/Southcom\/status\/2001840669313135099\">en X.<\/a><\/p>\n<p>El ataque de este jueves eleva el total de muertos en los ataques a al menos 104 personas y marca el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/17\/eeuu\/embarcacion-trafico-drogas-pacifico-trax\">tercer ataque de esta semana.<\/a><\/p>\n<p>El Comando Sur de Estados Unidos agreg\u00f3 que ning\u00fan militar estadounidense result\u00f3 herido en el ataque.<\/p>\n<p>Los ataques a embarcaciones sospechosas de narcotr\u00e1fico forman parte de una campa\u00f1a en curso, denominada Operaci\u00f3n Southern Spear, que el Gobierno de Trump ha dicho que busca frenar el tr\u00e1fico de narc\u00f3ticos.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Fuerzas Armadas de Estados Unidos realizaron ataques contra dos presuntas embarcaciones de narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico este jueves, en los que murieron cinco personas, seg\u00fan el Comando Sur de Estados Unidos. \u201cEl 18 de diciembre, por orden de @SecWarPete Hegseth, la Fuerza de Tarea Conjunta Southern Spear realiz\u00f3 ataques letales contra [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469410","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las Fuerzas Armadas de Estados Unidos realizaron ataques contra dos presuntas embarcaciones de narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico este jueves, en los que murieron cinco personas, seg\u00fan el Comando Sur de Estados Unidos. \u201cEl 18 de diciembre, por orden de @SecWarPete Hegseth, la Fuerza de Tarea Conjunta Southern Spear realiz\u00f3 ataques letales contra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T03:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas\",\"datePublished\":\"2025-12-19T03:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\"},\"wordCount\":194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\",\"name\":\"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-19T03:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias","og_description":"Las Fuerzas Armadas de Estados Unidos realizaron ataques contra dos presuntas embarcaciones de narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico este jueves, en los que murieron cinco personas, seg\u00fan el Comando Sur de Estados Unidos. \u201cEl 18 de diciembre, por orden de @SecWarPete Hegseth, la Fuerza de Tarea Conjunta Southern Spear realiz\u00f3 ataques letales contra [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-19T03:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas","datePublished":"2025-12-19T03:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/"},"wordCount":194,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","name":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-19T03:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. ataca dos embarcaciones m\u00e1s en el oc\u00e9ano Pac\u00edfico y mata a cinco personas","url":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2025\/12\/18\/atacaque-dos-embarcaciones-mata-cinco-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-19T03:03:39Z","datePublished":"2025-12-19T03:03:39Z","dateModified":"2025-12-19T03:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. ataca dos embarcaciones m\\u00e1s en el oc\\u00e9ano Pac\\u00edfico y mata a cinco personas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/18\\\/atacaque-dos-embarcaciones-mata-cinco-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2025\\\/12\\\/18\\\/atacaque-dos-embarcaciones-mata-cinco-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-19T03:03:39Z\",\"datePublished\":\"2025-12-19T03:03:39Z\",\"dateModified\":\"2025-12-19T03:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470924,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/02\/05\/ataque-barco-pacifico-oriental-mata-dos-trax\/","url_meta":{"origin":1469410,"position":0},"title":"EE.UU. ataca otro barco en el Pac\u00edfico oriental y mata a dos personas","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Las Fuerzas Armadas de Estados Unidos realizaron un ataque contra otra presunta embarcaci\u00f3n de narcotr\u00e1fico en el oc\u00e9ano Pac\u00edfico oriental este jueves, en el que murieron dos personas, seg\u00fan el Comando Sur de EE.UU.\u201cEl 5 de febrero, por orden del comandante del Comando Sur, general Francis L. Donovan, la Fuerza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469652,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/29\/cronologia-ataques-eeuu-caribe-pacifico-venezuela-orix\/","url_meta":{"origin":1469410,"position":1},"title":"31 botes destruidos, m\u00e1s de 100 muertos y una crisis que crece en Caribe y Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"Este lunes, a pocos d\u00edas de cerrar el 2025, las Fuerzas Militares de EE.UU. ejecutaron otro ataque contra una presunta embarcaci\u00f3n de narcotr\u00e1fico en el oc\u00e9ano Pac\u00edfico oriental en el que murieron dos personas, seg\u00fan el Comando Sur de EE.UU.Con ello, desde el 2 de septiembre suman 31 botes destruidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469508,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/22\/ataque-embarcacion-pacifico-oriental-mata-uno-trax\/","url_meta":{"origin":1469410,"position":2},"title":"EE.UU. ataca una embarcaci\u00f3n en el Pac\u00edfico oriental y mata a una persona","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"Las Fuerzas Armadas de Estados Unidos realizaron un ataque contra una \u201cembarcaci\u00f3n de bajo perfil\u201d que presuntamente traficaba drogas en el oc\u00e9ano Pac\u00edfico oriental este lunes, en el que muri\u00f3 una persona, seg\u00fan el Comando Sur de EE.UU.\u201cEl 22 de diciembre, por orden del secretario de Defensa, Pete Hegseth, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469512,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/23\/cronologia-ataques-eeuu-caribe-pacifico-venezuela-narcotrafico-orix\/","url_meta":{"origin":1469410,"position":3},"title":"30 botes destruidos, m\u00e1s de 100 muertos y una crisis que crece en Caribe y Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"Este lunes, las Fuerzas Armadas de Estados Unidos realizaron un ataque contra una \u201cembarcaci\u00f3n de bajo perfil\u201d que presuntamente traficaba drogas en el oc\u00e9ano Pac\u00edfico oriental. Seg\u00fan el Comando Sur de EE.UU., en el ataque muri\u00f3 una persona.Con ello, desde el 2 de septiembre suman 30 botes destruidos en 26\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469299,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/16\/ataques-botes-eeuu-caribe-pacifico-narco-venezuela-cronologia-orix\/","url_meta":{"origin":1469410,"position":4},"title":"25 botes destruidos, 95 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Las Fuerzas Militares de EE.UU. atacaron tres embarcaciones presuntamente dedicadas al narcotr\u00e1fico en el este del oc\u00e9ano Pac\u00edfico el lunes. Seg\u00fan el Comando Sur de EE.UU., al menos ocho personas murieron como resultado del operativo.Con ello, desde el 2 de septiembre suman 25 botes destruidos en 23 ataques efectuados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471501,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/02\/20\/ataque-barco-pacifico-oriental-mata-3-trax\/","url_meta":{"origin":1469410,"position":5},"title":"EE.UU. ataca otro barco en el Pac\u00edfico Oriental que presuntamente transportaba drogas y mata a 3 personas","author":"","date":"febrero 20, 2026","format":false,"excerpt":"Las Fuerzas Armadas de Estados Unidos realizaron un ataque contra otra embarcaci\u00f3n que presuntamente transportaba drogas en el oc\u00e9ano Pac\u00edfico oriental este viernes, en el que murieron tres personas, seg\u00fan el Comando Sur de Estados Unidos.\u201cEl 20 de febrero, por orden del comandante del Comando Sur, general Francis L. Donovan,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469410"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469410\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}