{"id":1469836,"date":"2026-01-06T12:03:44","date_gmt":"2026-01-06T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/"},"modified":"2026-01-06T12:03:44","modified_gmt":"2026-01-06T20:03:44","slug":"eeuu-maduro-ley-enemigos-extranjeros-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","title":{"rendered":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para  deportaciones"},"content":{"rendered":"<p>Horas despu\u00e9s de que el derrocado l\u00edder venezolano Nicol\u00e1s Maduro fuera acusado formalmente de narcoterrorismo y otros delitos en Nueva York, el Departamento de Justicia utiliz\u00f3 la acusaci\u00f3n formal en un tribunal federal a 2.099 kil\u00f3metros de distancia para defender la capacidad del presidente Donald Trump de usar una facultad para tiempos de guerra con el fin de acelerar algunas deportaciones.<\/p>\n<p>El presidente invoc\u00f3 la Ley de Enemigos Extranjeros, del siglo XVIII, en marzo pasado para deportar r\u00e1pidamente a presuntos miembros del Tren de Aragua (TdA), una banda venezolana que \u00e9l design\u00f3 como organizaci\u00f3n terrorista extranjera que actuaba en connivencia con el Gobierno de Maduro para perjudicar a Estados Unidos.<\/p>\n<p>Refiri\u00e9ndose a los comentarios de Trump anunciando el arresto de Maduro en Caracas, los abogados del Departamento de Justicia declararon ante el Tribunal de Apelaciones del Quinto Circuito de EE.UU. que los dram\u00e1ticos acontecimientos \u201csubrayan el control del r\u00e9gimen de Maduro sobre el TdA y su invasi\u00f3n violenta o incursi\u00f3n depredadora en suelo estadounidense\u201d.<\/p>\n<p>\u201cComo resultado, queda a\u00fan m\u00e1s claro que la invocaci\u00f3n de la Ley de Enemigos Extranjeros por parte del Presidente formaba parte de una misi\u00f3n de seguridad nacional de alto nivel que existe al margen de la interferencia judicial\u201d, escribieron en una carta dirigida al tribunal de apelaciones.<\/p>\n<p>Este tribunal, con sede en Nueva Orleans, escuchar\u00e1 los argumentos a finales de este mes en una importante impugnaci\u00f3n del uso de la ley por parte de Trump.<\/p>\n<p>Al invocar la Ley de Enemigos Extranjeros el a\u00f1o pasado, Trump mencion\u00f3 la persecuci\u00f3n criminal que Estados Unidos ha llevado a cabo durante a\u00f1os contra Maduro y otros, y afirm\u00f3 que el Gobierno del entonces l\u00edder venezolano estaba ordenando al Tren de Aragua que llevara a cabo una \u201cguerra irregular\u201d contra Estados Unidos.<\/p>\n<p>Se desconoce el impacto, si lo hubiera, que podr\u00eda tener el caso penal de Maduro en la impugnaci\u00f3n de la Ley de Enemigos Extranjeros, pendiente ante el tribunal de apelaciones, seg\u00fan informaron expertos legales a CNN.<\/p>\n<p>\u201cLas acusaciones contra Maduro no aportan mayor prueba de que hayamos sido \u2018invadidos\u2019 por Venezuela ni de que hayamos sido objeto de una \u2018incursi\u00f3n depredadora\u2019 como esgrim\u00eda la proclamaci\u00f3n que el presidente Trump realiz\u00f3 en marzo pasado\u201d, declar\u00f3 Steve Vladeck, analista de la Corte Suprema de CNN y profesor del Centro de Derecho de la Universidad de Georgetown.<\/p>\n<p>El caso del Quinto Circuito se ha considerado durante mucho tiempo como el veh\u00edculo mediante el cual el uso de la Ley de Enemigos Extranjeros por parte de Trump llegar\u00e1 a la Corte Suprema para su revisi\u00f3n final.<\/p>\n<p>El verano pasado, un panel de tres jueces de la corte dictamin\u00f3 que Trump estaba usando la ley ilegalmente, concluyendo que no se hab\u00eda producido una \u201cincursi\u00f3n depredadora\u201d ni una \u201cinvasi\u00f3n\u201d por parte de miembros del Tren de Aragua en Estados Unidos, como Trump afirm\u00f3 en marzo.<\/p>\n<p>En ese momento, los dos jueces de la mayor\u00eda declararon que el tribunal no ten\u00eda la facultad de revisar las afirmaciones de Trump sobre que Maduro dirig\u00eda las actividades de la pandilla en Estados Unidos, pero rechazaron el mismo argumento presentado en la presentaci\u00f3n del lunes: que los tribunales federales no ten\u00edan absolutamente ning\u00fan papel que desempe\u00f1ar en el escrutinio del uso de la ley por parte de Trump.<\/p>\n<p>Sin embargo, la decisi\u00f3n del panel fue r\u00e1pidamente revocada por el pleno del Quinto Circuito cuando el tribunal, repleto de juristas conservadores, accedi\u00f3 a volver a intentar el caso, esta vez con todos los jueces en actividad.<\/p>\n<p>A mediados de marzo, Trump deport\u00f3 a decenas de venezolanos bajo la ley, pero no ha podido llevar a cabo m\u00e1s deportaciones debido a una serie de impugnaciones legales que avanzan r\u00e1pidamente, incluyendo la derivada de Texas, que ahora est\u00e1 siendo evaluada por el Quinto Circuito.<\/p>\n<p>En impugnaciones similares presentadas en otros tribunales de Estados Unidos, los jueces de primera instancia afirmaron que Trump no estaba otorgando a los migrantes el debido proceso antes de deportarlos bajo la ley.<\/p>\n<p>El Gobierno se sinti\u00f3 atra\u00eddo por esa facultad para tiempos de guerra porque inicialmente argument\u00f3 que los funcionarios pod\u00edan usar la ley sin tener que notificar con antelaci\u00f3n a los migrantes su designaci\u00f3n como enemigos extranjeros ni la oportunidad de interponer recursos legales antes de su expulsi\u00f3n. Sin embargo, la Corte Suprema, sin decidir oficialmente si Trump estaba usando la ley legalmente, dictamin\u00f3 el a\u00f1o pasado que dicho debido proceso deb\u00eda otorgarse a los migrantes afectados por ella.<\/p>\n<p>Entre el grupo de juristas que frustr\u00f3 la capacidad del Gobierno para usar la ley con rapidez se encuentra Alvin Hellerstein, el juez federal de Manhattan que tambi\u00e9n supervisa el caso penal de Maduro.<\/p>\n<p>En mayo, Hellerstein, designado por el expresidente Bill Clinton, impidi\u00f3 que el Gobierno usara la ley contra los migrantes en el Distrito Sur de Nueva York y, al igual que el Quinto Circuito, rechaz\u00f3 los argumentos reiterados en la presentaci\u00f3n del lunes ante el tribunal de apelaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horas despu\u00e9s de que el derrocado l\u00edder venezolano Nicol\u00e1s Maduro fuera acusado formalmente de narcoterrorismo y otros delitos en Nueva York, el Departamento de Justicia utiliz\u00f3 la acusaci\u00f3n formal en un tribunal federal a 2.099 kil\u00f3metros de distancia para defender la capacidad del presidente Donald Trump de usar una facultad para tiempos de guerra con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469836","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"Horas despu\u00e9s de que el derrocado l\u00edder venezolano Nicol\u00e1s Maduro fuera acusado formalmente de narcoterrorismo y otros delitos en Nueva York, el Departamento de Justicia utiliz\u00f3 la acusaci\u00f3n formal en un tribunal federal a 2.099 kil\u00f3metros de distancia para defender la capacidad del presidente Donald Trump de usar una facultad para tiempos de guerra con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones\",\"datePublished\":\"2026-01-06T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\"},\"wordCount\":903,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\",\"name\":\"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-06T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias","og_description":"Horas despu\u00e9s de que el derrocado l\u00edder venezolano Nicol\u00e1s Maduro fuera acusado formalmente de narcoterrorismo y otros delitos en Nueva York, el Departamento de Justicia utiliz\u00f3 la acusaci\u00f3n formal en un tribunal federal a 2.099 kil\u00f3metros de distancia para defender la capacidad del presidente Donald Trump de usar una facultad para tiempos de guerra con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-06T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/"},"author":{"name":"","@id":""},"headline":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones","datePublished":"2026-01-06T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/"},"wordCount":903,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","name":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-06T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para deportaciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para  deportaciones","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/eeuu-maduro-ley-enemigos-extranjeros-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-06T20:03:44Z","datePublished":"2026-01-06T20:03:44Z","dateModified":"2026-01-06T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Departamento de Justicia utiliza el caso de Maduro para defender el uso de Ley de Enemigos Extranjeros para  deportaciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/01\\\/06\\\/eeuu-maduro-ley-enemigos-extranjeros-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/01\\\/06\\\/eeuu-maduro-ley-enemigos-extranjeros-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-06T20:03:44Z\",\"datePublished\":\"2026-01-06T20:03:44Z\",\"dateModified\":\"2026-01-06T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461373,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/18\/departamento-justicia-no-vuelos-deportacion-ley-enemigos-extranjeros-trax\/","url_meta":{"origin":1469836,"position":0},"title":"Juez no detendr\u00e1 vuelos de deportaci\u00f3n bajo la Ley de Enemigos Extranjeros","author":"","date":"abril 18, 2025","format":false,"excerpt":"Un juez federal en la ciudad de Washington dijo a los abogados de los migrantes en Texas que cre\u00edan que el Gobierno de Trump est\u00e1 a punto de deportarlos r\u00e1pidamente bajo la Ley de Enemigos Extranjeros que no ten\u00eda el poder de detener las deportaciones, aunque estaba preocupado por las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460464,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/26\/corte-mantiene-bloqueo-temporal-uso-ley-enemigos-extranjeros-deportaciones-trax\/","url_meta":{"origin":1469836,"position":1},"title":"Corte de apelaciones mantiene bloqueo temporal al uso de la Ley de Enemigos Extranjeros para deportaciones","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Una corte federal de apelaciones mantiene, tras una decisi\u00f3n dividida, un bloqueo temporal a la facultad del presidente Donald Trump de usar la Ley de Enemigos Extranjeros para deportar r\u00e1pidamente a presuntos miembros de una pandilla venezolana.El Tribunal de Apelaciones del Circuito de Washington fall\u00f3 por 2 votos a 1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460099,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/18\/departamento-justicia-vuelos-deportaciones-ley-enemigos-extranjeros-trax\/","url_meta":{"origin":1469836,"position":2},"title":"Juez da al Departamento de Justicia otro plazo para dar detalles sobre vuelos de deportaci\u00f3n bajo Ley de Enemigos Extranjeros","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Un juez federal est\u00e1 dando al Departamento de Justicia hasta el mi\u00e9rcoles al mediod\u00eda para proporcionarle, bajo secreto, m\u00e1s informaci\u00f3n sobre las deportaciones que el Gobierno de Donald Trump llev\u00f3 a cabo en virtud del uso por parte del presidente de la Ley de Enemigos Extranjeros.La demanda del juez del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459989,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/16\/trump-deporta-ley-enemigos-extranjeros-juez-trax\/","url_meta":{"origin":1469836,"position":3},"title":"Gobierno de Trump deporta a cientos de personas bajo la Ley de Enemigos Extranjeros a pesar de prohibici\u00f3n de juez","author":"","date":"marzo 16, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 este domingo que cientos de personas fueron deportadas del pa\u00eds despu\u00e9s de que el presidente Donald Trump invocara la Ley de Enemigos Extranjeros, una amplia facultad para tiempos de guerra que solo se ha utilizado en tres ocasiones anteriores, para acelerar las deportaciones de migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462013,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/05\/gobierno-de-trump-argumentos-ley-enemigos-extranjeros-deportados-trax\/","url_meta":{"origin":1469836,"position":4},"title":"Gobierno de Trump defiende el corto tiempo de apelaci\u00f3n de deportados bajo la Ley de Enemigos Extranjeros","author":"","date":"mayo 5, 2025","format":false,"excerpt":"El Gobierno de Trump reiter\u00f3 este lunes su postura sobre los detenidos venezolanos en EE.UU. que podr\u00edan ser sujetos a deportaci\u00f3n bajo la Ley de Enemigos Extranjeros, diciendo a un juez federal en Pensilvania que un detenido no est\u00e1 designado para ser enviado a una brutal prisi\u00f3n salvadore\u00f1a bajo la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462141,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/08\/corte-apelaciones-regreso-solicitante-asilo-deportado-el-salvador-trax\/","url_meta":{"origin":1469836,"position":5},"title":"Corte de apelaciones pausa orden que exige al Gobierno de Trump facilitar regreso de solicitante de asilo deportado","author":"","date":"mayo 8, 2025","format":false,"excerpt":"Una corte federal de apelaciones paus\u00f3 brevemente una orden de un juez que indicaba que el Gobierno de Trump deb\u00eda \u201cfacilitar\u201d el regreso de un refugiado venezolano de 20 a\u00f1os que fue deportado a El Salvador a principios de este a\u00f1o en violaci\u00f3n de un acuerdo judicial que protege a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469836"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469836\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}