{"id":1469840,"date":"2026-01-06T14:03:40","date_gmt":"2026-01-06T22:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/"},"modified":"2026-01-06T14:03:40","modified_gmt":"2026-01-06T22:03:40","slug":"infame-carcel-donde-esta-maduro-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","title":{"rendered":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro"},"content":{"rendered":"<p>Una c\u00e1rcel federal con un historial documentado de <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/12\/15\/apagon-nueva-york-investigacion-crimen-trax\/\">cortes de electricidad<\/a>, falta de personal y quejas de personas detenidas acaba de recibir a dos internos de alto perfil.<\/p>\n<p>El presidente venezolano derrocado Nicol\u00e1s Maduro y su esposa, Cilia Flores, fueron trasladados el s\u00e1bado al famoso Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) de Brooklyn, tras su captura por parte de las Fuerzas Armadas de Estados Unidos en Caracas hace solo unos d\u00edas. El matrimonio enfrenta cargos penales en Estados Unidos.<\/p>\n<p>La pareja no es la \u00fanica de alto perfil que ha pasado por las paredes del MDC. <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/10\/18\/carcel-mdc-brooklyn-mayo-zamabada-garcia-luna-diddy-combs-presos-orix\/\">El edificio ha albergado a figuras notables<\/a> como el magnate del hip-hop <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/03\/eeuu\/sean-diddy-combs-cargos-acusan-orix\">Sean \u201cDiddy\u201d Combs<\/a>, el cantante R. Kelly, Martin Shkreli, conocido como el \u201cPharma Bro\u201d, la socialit\u00e9 y c\u00f3mplice de Jeffrey Epstein, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/03\/eeuu\/ghislaine-maxwell-liberacion-prision-trax\">Ghislaine Maxwell<\/a>, el que fuera ni\u00f1o prodigio de las criptomonedas Sam Bankman-Fried, el capo del narcotr\u00e1fico Joaqu\u00edn <a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/el-chapo-dos-rostros-de-un-capo\">\u201cEl Chapo\u201d<\/a> Guzm\u00e1n, los raperos Fetty Wap y <a href=\"https:\/\/cnnespanol.cnn.com\/video\/rapero-tekashi-6ix9ine-condena-crimen-organizado-pkg-digital-original\/\">Tekashi 6ix9ine<\/a>, e incluso el expresidente de Honduras <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/02\/latinoamerica\/causas-juan-orlando-hernandez-indulto-orix\">Juan Orlando Hern\u00e1ndez<\/a>, quien fue condenado por tr\u00e1fico de drogas antes de ser indultado el a\u00f1o pasado por el presidente Donald Trump.<\/p>\n<p>El presunto l\u00edder del cartel<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/25\/eeuu\/ismael-mayo-zambada-declara-culpable-orix\"> Ismael \u201cEl Mayo\u201d Zambada Garc\u00eda <\/a>y <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/21\/eeuu\/luigi-mangione-comparece-corte-nueva-york-trax\">Luigi Mangione<\/a>, quien se declar\u00f3 no culpable del asesinato a tiros de un ejecutivo de UnitedHealth Group, figuran entre los internos actuales del centro.<\/p>\n<p>En su primera comparecencia ante un tribunal en Nueva York este lunes, Maduro y Flores se declararon no culpables  de los cargos de tr\u00e1fico de drogas y armas y, por el momento, optaron por no impugnar su detenci\u00f3n.<\/p>\n<p>A continuaci\u00f3n, se ofrece una visi\u00f3n de c\u00f3mo es la vida dentro del MDC Brooklyn desde la perspectiva de internos, abogados y jueces:<\/p>\n<p>Construido en la d\u00e9cada de 1990 para aliviar el hacinamiento en las c\u00e1rceles de la ciudad de Nueva York, el MDC Brooklyn es un centro de detenci\u00f3n preventiva para personas acusadas ante tribunales federales en Nueva York. All\u00ed hay una mezcla de sospechosos y acusados, incluidos imputados por delitos graves, casos de alto perfil y otros que esperan sentencia o traslado.<\/p>\n<p>La Oficina Federal de Prisiones oper\u00f3 dos centros \u2014uno en Brooklyn y otro en Manhattan\u2014 hasta 2021, cuando cerr\u00f3 el de Manhattan tras las cr\u00edticas por su gesti\u00f3n de la muerte por suicidio en 2019 del financiero multimillonario y <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/juez-revelar-registros-judiciales-jeffrey-epstein-trax\">acusado de tr\u00e1fico sexual Jeffrey Epstein<\/a>.<\/p>\n<p>Antes de su captura, Maduro viv\u00eda principalmente en el Palacio de Miraflores, una extensa residencia presidencial conocida por su arquitectura neocl\u00e1sica, grandes ventanales, salones majestuosos y patios cuidados, lo que contrasta radicalmente con las instalaciones del Metropolitan Detention Center.<\/p>\n<p>Descrito tanto por abogados como por internos como \u201crepugnante\u201d, con condiciones \u201chorribles\u201d, el centro es la \u00fanica c\u00e1rcel federal que presta servicio a la ciudad m\u00e1s grande del pa\u00eds.<\/p>\n<p>Para sus m\u00e1s de 1.300 internos, la vida diaria en la c\u00e1rcel federal puede ser extenuante.<\/p>\n<p>Es oscura, superpoblada y ruidosa, seg\u00fan Elie Honig, analista legal s\u00e9nior de CNN, quien ha estado dentro del edificio en numerosas ocasiones.<\/p>\n<p>Aunque todas las prisiones son lugares miserables, dijo, \u201cel MDC es quiz\u00e1 el m\u00e1s miserable\u201d de todos los que ha visitado.<\/p>\n<p>Las personas detenidas en la Unidad de Vivienda Especial, conocida como SHU, donde probablemente est\u00e9 recluido Maduro por razones de seguridad, permanecen en confinamiento solitario bajo condiciones restrictivas, dijo a CNN Daniel McGuinnes, abogado penalista y de derechos civiles que representa a varios clientes detenidos en el MDC.<\/p>\n<p>Seg\u00fan un informe del Departamento de Justicia, los reclusos pasan hasta 23 horas encerrados en sus celdas, con protocolos de custodia estrictos cuando salen de ellas y acceso limitado a llamadas telef\u00f3nicas con sus abogados.<\/p>\n<p>La c\u00e1rcel tambi\u00e9n ha enfrentado una falta cr\u00f3nica de personal, adem\u00e1s de quejas por moho, hongos y mala calidad de la comida, se\u00f1al\u00f3 McGuinnes.<\/p>\n<p>El acceso a atenci\u00f3n m\u00e9dica y dental en el centro siempre ha sido \u201chorrible\u201d, seg\u00fan McGuinnes, quien se\u00f1al\u00f3 que con frecuencia debe recordar a sus clientes que documenten minuciosamente sus solicitudes de dicha atenci\u00f3n.<\/p>\n<p>\u201cEn alg\u00fan momento tengo que intervenir y solicitarlo en su nombre\u201d, dijo, \u201cporque simplemente no se hace\u201d.<\/p>\n<p>CNN solicit\u00f3 comentarios a la Oficina Federal de Prisiones.<\/p>\n<p>Un prolongado corte de electricidad sumi\u00f3 al centro penitenciario en una crisis, dejando a los internos en casi total oscuridad durante una semana a comienzos de 2019, en medio de una ola de fr\u00edo polar. El corte de energ\u00eda motiv\u00f3 una investigaci\u00f3n del Departamento de Justicia para determinar si la Oficina Federal de Prisiones contaba con planes de contingencia adecuados para hacer frente al problema.<\/p>\n<p>Una demanda presentada en nombre de los internos aleg\u00f3 que permanecieron confinados en sus celdas durante d\u00edas, con inodoros inservibles y otras condiciones insalubres. La Oficina Federal de Prisiones lleg\u00f3 finalmente a un acuerdo y compens\u00f3 a casi 1.600 internos con un total aproximado de US$ 10 millones por haber soportado condiciones g\u00e9lidas e inhumanas debido al corte de energ\u00eda.<\/p>\n<p>Michael Horowitz, inspector general del Departamento de Justicia de Estados Unidos en ese momento, dijo que se determin\u00f3 \u201cque los problemas de calefacci\u00f3n hab\u00edan sido un problema de larga data en la c\u00e1rcel, que exist\u00eda antes, durante y despu\u00e9s del incendio y el corte de energ\u00eda, y que no estaban relacionados con esos eventos\u201d.<\/p>\n<p>A comienzos de 2024, la Oficina Federal de Prisiones nombr\u00f3 un equipo de acci\u00f3n urgente para \u201canalizar de manera integral los desaf\u00edos en el MDC Brooklyn\u201d, dijo a CNN Emery Nelson, portavoz de la agencia.<\/p>\n<p>\u201cEl trabajo del equipo contin\u00faa, pero ya ha incrementado el personal permanente de la instituci\u00f3n  (incluidos los guardias y el personal m\u00e9dico), ha atendido m\u00e1s de 700 solicitudes de mantenimiento atrasadas y ha mantenido un enfoque sostenido en los problemas se\u00f1alados en dos decisiones judiciales recientes\u201d, afirm\u00f3 Nelson en ese momento.<\/p>\n<p>Pese a esas mejoras, las condiciones en el Centro de Detenci\u00f3n Metropolitano parec\u00edan empeorar con el paso de los meses.<\/p>\n<p>En junio de 2024, Uriel Whyte, un interno a la espera de juicio por cargos relacionados con armas, fue apu\u00f1alado hasta la muerte por otro interno, seg\u00fan un comunicado del Departamento de Justicia.<\/p>\n<p>Un mes despu\u00e9s, el interno Edwin Cordero muri\u00f3 en una pelea que estall\u00f3 dentro de la prisi\u00f3n. Su abogado dijo a The New York Times que su cliente fue \u201cotra v\u00edctima del MDC Brooklyn, una c\u00e1rcel federal hacinada, con falta de personal y abandonada, que es un infierno en la Tierra\u201d.<\/p>\n<p>M\u00e1s tarde, en septiembre, el Departamento de Justicia anunci\u00f3 que cinco internos fueron acusados por esos homicidios y un sexto por intento de asesinato por presuntamente apu\u00f1alar 44 veces a otro interno con un arma improvisada. Mientras tanto, otro interno fue enviado al hospital con un picahielo clavado en la espalda, seg\u00fan el comunicado.<\/p>\n<p>En una operaci\u00f3n multiagencial realizada al mes siguiente, como parte de una iniciativa m\u00e1s amplia de seguridad, los investigadores incautaron \u201cuna serie de dispositivos electr\u00f3nicos, drogas y parafernalia asociada, as\u00ed como armas de fabricaci\u00f3n casera\u201d, inform\u00f3 ese a\u00f1o la Oficina Federal de Prisiones en un comunicado.<\/p>\n<p>\u201cEstos cargos demuestran el compromiso del Departamento de Justicia de erradicar la violencia y el comportamiento criminal en los centros federales de detenci\u00f3n, un componente fundamental de nuestro trabajo para mejorar las condiciones en toda la Oficina Federal de Prisiones\u201d, dijo entonces Lisa Monaco, vicesecretaria de Justicia.<\/p>\n<p>La situaci\u00f3n en el recinto se volvi\u00f3 tan preocupante que al menos dos jueces federales se negaron a condenar a<a href=\"https:\/\/www.nytimes.com\/2024\/08\/08\/nyregion\/tax-fraud-mdc-brooklyn.html\"> los acusados<\/a> al MDC en 2024 debido al entorno abandonado, seg\u00fan inform\u00f3<a href=\"https:\/\/www.nytimes.com\/2024\/01\/04\/nyregion\/brooklyn-judge-mdc-jail.html\"> The New York Times<\/a>.<\/p>\n<p>En s\u00edntesis: \u201cEs un lugar muy dif\u00edcil para estar como interno\u201d, dijo en 2024 Marc Agnifilo, abogado de Diddy, al referirse al centro en 2024, y as\u00ed lo argument\u00f3 ante el tribunal.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una c\u00e1rcel federal con un historial documentado de cortes de electricidad, falta de personal y quejas de personas detenidas acaba de recibir a dos internos de alto perfil. El presidente venezolano derrocado Nicol\u00e1s Maduro y su esposa, Cilia Flores, fueron trasladados el s\u00e1bado al famoso Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469840","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una c\u00e1rcel federal con un historial documentado de cortes de electricidad, falta de personal y quejas de personas detenidas acaba de recibir a dos internos de alto perfil. El presidente venezolano derrocado Nicol\u00e1s Maduro y su esposa, Cilia Flores, fueron trasladados el s\u00e1bado al famoso Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T22:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro\",\"datePublished\":\"2026-01-06T22:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\"},\"wordCount\":1378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\",\"name\":\"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-06T22:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias","og_description":"Una c\u00e1rcel federal con un historial documentado de cortes de electricidad, falta de personal y quejas de personas detenidas acaba de recibir a dos internos de alto perfil. El presidente venezolano derrocado Nicol\u00e1s Maduro y su esposa, Cilia Flores, fueron trasladados el s\u00e1bado al famoso Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-06T22:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/"},"author":{"name":"","@id":""},"headline":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro","datePublished":"2026-01-06T22:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/"},"wordCount":1378,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","name":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-06T22:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Centro de Detenci\u00f3n Metropolitano de Brooklyn: c\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/01\/06\/infame-carcel-donde-esta-maduro-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-06T22:03:40Z","datePublished":"2026-01-06T22:03:40Z","dateModified":"2026-01-06T22:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Centro de Detenci\\u00f3n Metropolitano de Brooklyn: c\\u00f3mo es la infame c\\u00e1rcel donde est\\u00e1 detenido Maduro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/01\\\/06\\\/infame-carcel-donde-esta-maduro-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/01\\\/06\\\/infame-carcel-donde-esta-maduro-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-06T22:03:40Z\",\"datePublished\":\"2026-01-06T22:03:40Z\",\"dateModified\":\"2026-01-06T22:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460452,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/26\/mdc-brooklyn-carcel-caro-quintero-orix\/","url_meta":{"origin":1469840,"position":0},"title":"El &#171;infierno en la tierra&#187;: la c\u00e1rcel MDC en la que est\u00e1n Caro Quintero, el Mayo Zambada y otros presos de alto perfil","author":"","date":"marzo 26, 2025","format":false,"excerpt":"No hay c\u00e1rcel que sea un para\u00edso, pero el Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) de Nueva York ha sido descrito como \u201cel infierno en la tierra\u201d. Por all\u00ed pasaron varios presos de alto perfil, entre ellos, el expresidente de Honduras Juan Orlando Hern\u00e1ndez y Genaro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464762,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/22\/mdc-brooklyn-carcel-fito-caro-quintero-zamabada-orix\/","url_meta":{"origin":1469840,"position":1},"title":"El &#171;infierno en la tierra&#187;: la c\u00e1rcel MDC en la que est\u00e1n Fito, Caro Quintero, el Mayo Zambada y otros presos de alto perfil","author":"","date":"julio 22, 2025","format":false,"excerpt":"No hay c\u00e1rcel que sea un para\u00edso, pero el Centro de Detenci\u00f3n Metropolitano (MDC, por sus siglas en ingl\u00e9s) de Nueva York ha sido descrito como \u201cel infierno en la tierra\u201d. Por all\u00ed pasaron varios presos de alto perfil, entre ellos el expresidente de Honduras Juan Orlando Hern\u00e1ndez y Genaro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469876,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/07\/separados-aislados-maduro-y-cilia-prision-brooklyn-trax\/","url_meta":{"origin":1469840,"position":2},"title":"As\u00ed ser\u00eda la vida de Nicol\u00e1s Maduro y su esposa Cilia Flores en la prisi\u00f3n MDC de Nueva York","author":"","date":"enero 7, 2026","format":false,"excerpt":"Nicol\u00e1s Maduro y su esposa, Cilia Flores, pueden esperar razonablemente que sucedan dos cosas mientras se acostumbran a su nueva vida cotidiana en el famoso Centro de Detenci\u00f3n Metropolitano de Brooklyn (MDC, por sus siglas en ingl\u00e9s): estar\u00e1n inc\u00f3modos y estar\u00e1n fuera de peligro.\u201cRealmente es un infierno\u201d, dijo el consultor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472533,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/25\/nicolas-maduro-cilia-flores-vida-prision-eeuu-orix\/","url_meta":{"origin":1469840,"position":3},"title":"Maduro y Cilia Flores ya llevan m\u00e1s de 80 d\u00edas en el MDC de Brooklyn. As\u00ed es la vida en esa prisi\u00f3n","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Mientras se acerca la pr\u00f3xima audiencia judicial en Nueva York, el hijo de Nicol\u00e1s Maduro proyecta una imagen optimista y desafiante sobre la vida de su padre y su esposa, Cilia Flores, tras las rejas. Sin embargo, personas con acceso a esa prisi\u00f3n, entrevistadas por CNN, dan cuenta de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472576,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/26\/nicolas-maduro-cilia-flores-segunda-audiencia-eeuu-proceso-penal-orix\/","url_meta":{"origin":1469840,"position":4},"title":"\u00bfQu\u00e9 ha pasado en el proceso penal de Nicol\u00e1s Maduro y Cilia Flores hasta ahora?","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Nicol\u00e1s Maduro y Cilia Flores volver\u00e1n a la corte este jueves. A los 83 d\u00edas de su captura en un operativo militar de Estados Unidos, el derrocado presidente de Venezuela y su esposa tendr\u00e1n su segunda audiencia frente a la justicia estadounidense, ante la que son acusados de delitos relacionados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469856,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/07\/5-cosas-7-de-enero-orix\/","url_meta":{"origin":1469840,"position":5},"title":"Las 5 cosas que debes saber este 7 de enero","author":"","date":"enero 7, 2026","format":false,"excerpt":"Trump pone a Groenlandia en alerta. La econom\u00eda de Cuba podr\u00eda enfrentar un golpe faltal si pierde el petr\u00f3leo que le env\u00eda Venezuela. \u00bfC\u00f3mo es la infame c\u00e1rcel donde est\u00e1 detenido Maduro? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1469840"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1469840\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1469840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1469840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1469840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}