{"id":1473040,"date":"2026-04-10T14:03:41","date_gmt":"2026-04-10T21:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/"},"modified":"2026-04-10T14:03:41","modified_gmt":"2026-04-10T21:03:41","slug":"producto-mas-popular-apple-ahora-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","title":{"rendered":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA"},"content":{"rendered":"<p>La configuraci\u00f3n de computadora en casa de Matt Shumer es un poco m\u00e1s extra\u00f1a que la de la mayor\u00eda.<\/p>\n<p>\u00c9l y su compa\u00f1ero de apartamento tienen cada uno una mini computadora de Apple en la cocina, ambos dispositivos trabajando silenciosamente en segundo plano. Todo lo que Shumer tiene que hacer es darle una tarea amplia al asistente virtual que corre en su Mac mini, y este se encarga del resto. Eso incluye acciones que normalmente requerir\u00edan escribir, hacer clic y desplazarse, como navegar por sitios web e iniciar sesi\u00f3n en cuentas.<\/p>\n<p>Puede parecer extra\u00f1o para sus amigos fuera del mundo tecnol\u00f3gico, pero para entusiastas como \u00e9l, \u201ces como: \u2018ah, claro, hay una computadora us\u00e1ndose a s\u00ed misma\u2019\u201d, comenta.<\/p>\n<p>Shumer, inversionista en inteligencia artificial y autor de un<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/30\/ciencia\/inteligencia-artificial-sacudio-mundo-que-viene-trax\"> ensayo viral sobre IA y empleos publicado en febrero<\/a>, es uno de muchos entusiastas tecnol\u00f3gicos que recientemente compraron un Mac mini para ejecutar el popular agente de IA OpenClaw.<\/p>\n<p>Los aficionados a la IA han estado comprando la peque\u00f1a computadora de escritorio plateada de Apple porque re\u00fane los elementos adecuados para ejecutar agentes de IA: un dise\u00f1o pr\u00e1ctico, potencia de procesamiento y un precio relativamente accesible en un momento en que <a href=\"https:\/\/www.cnn.com\/2026\/02\/27\/tech\/ai-memory-chips-smartphones-intl-hnk\">los costos de memoria est\u00e1n aumentando<\/a>. Apple declin\u00f3 hacer comentarios para esta historia, pero analistas dijeron a CNN que los env\u00edos de Mac crecieron el a\u00f1o pasado.<\/p>\n<p>El Mac mini se ha convertido en un s\u00edmbolo de estatus entre los experimentadores de IA, y algunos analistas dicen que su creciente popularidad podr\u00eda anticipar un cambio m\u00e1s amplio en la forma en que las personas usan las computadoras.<\/p>\n<p>\u201cCreemos que estamos en esta fase altamente transformadora para la industria de las PC\u201d, dijo Linn Huang, analista de la International Data Corporation que sigue el mercado de computadoras personales. \u201cNo solo hablamos de cambios en el hardware, sino de una transformaci\u00f3n profunda de la experiencia del usuario\u201d.<\/p>\n<p>El Mac mini de Apple, de forma similar a un disco, esencialmente una versi\u00f3n peque\u00f1a de una torre de computadora pensada para conectarse a un teclado y monitor externos, existe desde hace a\u00f1os. La versi\u00f3n m\u00e1s reciente fue lanzada en 2024.<\/p>\n<p>Pero el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/29\/economia\/langostas-openclaw-china-inteligencia-artificial-trax\">entusiasmo por OpenClaw<\/a>, un agente aut\u00f3nomo de IA que puede operar el dispositivo de un usuario para completar tareas, ha convertido a esta peque\u00f1a computadora de Apple en un producto muy demandado en los \u00faltimos meses.<\/p>\n<p>Los tiempos de env\u00edo para ciertas configuraciones del Mac mini han subido hasta 10-12 semanas, con la fecha m\u00e1s temprana de recogida en tiendas Apple en Nueva York a mediados de julio.<\/p>\n<p>Shumer dijo que incluso un empleado de una tienda Apple se refiri\u00f3 al Mac mini como una \u201cm\u00e1quina OpenClaw\u201d cuando recientemente visit\u00f3 una tienda en Nueva York.<\/p>\n<p>Es dif\u00edcil determinar si OpenClaw ha impulsado los resultados de Apple, ya que la empresa no desglosa ventas por producto individual y OpenClaw solo se lanz\u00f3 en noviembre.<\/p>\n<p>Aun as\u00ed, la firma de investigaci\u00f3n de mercado Omdia estim\u00f3 que los env\u00edos del Mac mini crecieron en dos d\u00edgitos en 2025 frente a 2024. Kieren Jessop, gerente de investigaci\u00f3n de Omdia, describi\u00f3 la popularidad anecd\u00f3tica del Mac mini en los c\u00edrculos tecnol\u00f3gicos como \u201creal\u201d y \u201cduradera\u201d en un correo a CNN.<\/p>\n<p>Huang tambi\u00e9n se\u00f1al\u00f3 que las ventas de computadoras de escritorio Mac crecieron m\u00e1s que las de laptops en 2025.<\/p>\n<p>Un Mac mini no es obligatorio para usar OpenClaw, pero hay varias razones por las que muchos lo prefieren.<\/p>\n<p>Ejecutar modelos de IA en una computadora en lugar de la nube suele ser m\u00e1s privado, ya que la informaci\u00f3n no tiene que salir del dispositivo. Usar una computadora separada para OpenClaw tambi\u00e9n es m\u00e1s seguro, ya que los usuarios pueden cargarla \u00fanicamente con la informaci\u00f3n a la que quieren que el agente tenga acceso.<\/p>\n<p>Con un precio inicial de US$ 599, tambi\u00e9n es relativamente accesible en un momento en que los costos de memoria est\u00e1n aumentando.<\/p>\n<p>El dise\u00f1o del Mac mini tambi\u00e9n atrae a algunos usuarios de OpenClaw. El agente de IA puede realizar tareas de forma aut\u00f3noma sin preguntas o comandos constantes, por lo que no necesita una computadora con pantalla y teclado conectados como una laptop.<\/p>\n<p>La mayor\u00eda de los usuarios conectan su agente OpenClaw a servicios accesibles desde el tel\u00e9fono, como aplicaciones de mensajer\u00eda. Roy Derks, gerente principal de producto en IBM, tiene OpenClaw instalado en su Mac mini dom\u00e9stico y se comunica con \u00e9l a trav\u00e9s de aplicaciones como WhatsApp o Telegram. Lo usa principalmente para investigar temas de su vida personal mientras est\u00e1 en la oficina, como juguetes para su hijo.<\/p>\n<p>\u201cEst\u00e1 funcionando en segundo plano, haciendo cosas que yo no estoy haciendo en el trabajo\u201d, dijo.<\/p>\n<p>El desarrollador de aplicaciones Cl\u00e9ment Sauvage dijo a CNN que tiene tres Mac mini ejecutando OpenClaw: uno para operaciones personales, como correos y listas de tareas; otro para desarrollo y proyectos; y un tercero que act\u00faa como un \u201ccerebro central\u201d para coordinar tareas entre las m\u00e1quinas.<\/p>\n<p>El entusiasmo en torno a OpenClaw ha crecido hasta convertirse en una comunidad global de desarrolladores y entusiastas tecnol\u00f3gicos. Est\u00e1n surgiendo conferencias de OpenClaw en todo el mundo. Derks asisti\u00f3 a una en San Francisco, donde dijo que la gente segu\u00eda haciendo fila incluso dos horas despu\u00e9s de haber comenzado el evento.<\/p>\n<p>Aunque la langosta se ha convertido en la mascota principal del agente, el Mac mini tambi\u00e9n se ha transformado en un s\u00edmbolo propio. En Etsy, <a href=\"https:\/\/www.etsy.com\/listing\/4474487686\/mac-mini-m4-stand-openclaw-inspired-3d?ls=a&#038;ga_order=most_relevant&#038;ga_search_type=all&#038;ga_view_type=gallery&#038;ga_search_query=openclaw+mac+mini&#038;ref=sc_gallery-1-2&#038;sr_prefetch=0&#038;pf_from=search&#038;pro=1&#038;frs=1&#038;plkey=EuqUEa3saPwUY-8-K7hTZAleaz7e%3ALTfb5b25e0212cf7c54c6040dc1043b4283f1d6527\">se pueden encontrar soportes para Mac mini con forma de pinza de langosta<\/a>. Sauvage dise\u00f1\u00f3 un set de pines coleccionables para la pr\u00f3xima conferencia Worldwide Developers Conference de Apple; uno muestra una langosta sobre un Mac mini.<\/p>\n<p>El inter\u00e9s por el Mac mini puede parecer de nicho hoy. Pero forma parte de una tendencia m\u00e1s amplia que algunos analistas ven sobre el papel de las computadoras en el mundo de la IA. Es exactamente el p\u00fablico al que apunta el fabricante de chips Nvidia con su computadora DGX Spark, aunque ese dispositivo es mucho m\u00e1s caro y tiene mayor capacidad de procesamiento.<\/p>\n<p>El CEO de Nvidia, Jensen Huang, destac\u00f3 <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/22\/economia\/ai-burbujas-temores-ganancias-nvidia-trax\">la capacidad de los modelos de IA que funcionan en DGX Spark<\/a> para controlar un robot dom\u00e9stico durante su conferencia en CES en enero. OpenClaw tambi\u00e9n fue un tema central en la conferencia GTC de Nvidia en marzo.<\/p>\n<p>\u201cTodav\u00eda estamos en la fase de innovadores de esta tendencia, pero la trayectoria es clara\u201d, dijo Jessop por correo electr\u00f3nico.<\/p>\n<p>Shumer disfruta tener una representaci\u00f3n f\u00edsica de su asistente personal de IA en su hogar.<\/p>\n<p>\u201cCambia la forma en que lo piensas, la manera en que lo usas, las tareas que le das\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La configuraci\u00f3n de computadora en casa de Matt Shumer es un poco m\u00e1s extra\u00f1a que la de la mayor\u00eda. \u00c9l y su compa\u00f1ero de apartamento tienen cada uno una mini computadora de Apple en la cocina, ambos dispositivos trabajando silenciosamente en segundo plano. Todo lo que Shumer tiene que hacer es darle una tarea amplia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473040","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias\" \/>\n<meta property=\"og:description\" content=\"La configuraci\u00f3n de computadora en casa de Matt Shumer es un poco m\u00e1s extra\u00f1a que la de la mayor\u00eda. \u00c9l y su compa\u00f1ero de apartamento tienen cada uno una mini computadora de Apple en la cocina, ambos dispositivos trabajando silenciosamente en segundo plano. Todo lo que Shumer tiene que hacer es darle una tarea amplia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T21:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA\",\"datePublished\":\"2026-04-10T21:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\"},\"wordCount\":1196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\",\"name\":\"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-10T21:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias","og_description":"La configuraci\u00f3n de computadora en casa de Matt Shumer es un poco m\u00e1s extra\u00f1a que la de la mayor\u00eda. \u00c9l y su compa\u00f1ero de apartamento tienen cada uno una mini computadora de Apple en la cocina, ambos dispositivos trabajando silenciosamente en segundo plano. Todo lo que Shumer tiene que hacer es darle una tarea amplia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-10T21:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/"},"author":{"name":"","@id":""},"headline":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA","datePublished":"2026-04-10T21:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/"},"wordCount":1196,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","name":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-10T21:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Este inesperado producto estrella de Apple despeg\u00f3 gracias a la IA","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/10\/producto-mas-popular-apple-ahora-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-10T21:03:41Z","datePublished":"2026-04-10T21:03:41Z","dateModified":"2026-04-10T21:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Este inesperado producto estrella de Apple despeg\\u00f3 gracias a la IA\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/10\\\/producto-mas-popular-apple-ahora-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/10\\\/producto-mas-popular-apple-ahora-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-10T21:03:41Z\",\"datePublished\":\"2026-04-10T21:03:41Z\",\"dateModified\":\"2026-04-10T21:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1444702,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/01\/31\/lo-que-hay-que-saber-sobre-los-implantes-cerebrales-humanos\/","url_meta":{"origin":1473040,"position":0},"title":"Lo que hay que saber sobre los implantes cerebrales humanos","author":"","date":"enero 31, 2024","format":false,"excerpt":"(CNN) -- La startup Neuralink de Elon Musk implant\u00f3 un chip de computadora en el cerebro de una persona este domingo, dijo este lunes en una publicaci\u00f3n en su plataforma X , aunque ofreci\u00f3 pocos detalles. Otras empresas que realizan trabajos similares est\u00e1n m\u00e1s avanzados en el proceso de investigaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445865,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/02\/21\/elon-musk-primer-sujeto-ensayo-humanos-neuralink-controlar-mouse-pensamiento-trax\/","url_meta":{"origin":1473040,"position":1},"title":"Elon Musk dice que el primer sujeto del ensayo en humanos de Neuralink puede controlar un mouse de computadora con un implante cerebral","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) \u2013 Elon Musk afirm\u00f3 que el primer participante en un ensayo humano de Neuralink puede controlar un mouse de computadora con su cerebro, casi un mes despu\u00e9s de que le implantaran el chip de la compa\u00f1\u00eda. Pero los detalles siguen siendo escasos, y otras empresas que trabajan en interfaces\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464634,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/07\/17\/chatgpt-actualizacion-openai-trax\/","url_meta":{"origin":1473040,"position":2},"title":"ChatGPT ahora puede &#171;pensar&#187; y &#171;actuar&#187; por ti tras una nueva actualizaci\u00f3n","author":"","date":"julio 17, 2025","format":false,"excerpt":"OpenAI anunci\u00f3 el jueves una nueva funci\u00f3n para ChatGPT que permite al popular chatbot ejecutar acciones en nombre del usuario. Esto forma parte de un esfuerzo de toda la industria para cambiar la forma en que las personas hacen las cosas en internet: los gigantes tecnol\u00f3gicos esperan que, en lugar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469023,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/12\/06\/apple-tim-cook-cambios-iderazgo-trax\/","url_meta":{"origin":1473040,"position":3},"title":"\u00bfQu\u00e9 est\u00e1 cambiando en Apple?","author":"","date":"diciembre 6, 2025","format":false,"excerpt":"Apple durante d\u00e9cadas ha sido conocida por una serie consistente de productos de consumo con dise\u00f1o vanguardista, que definen y han dado forma al modo en que las personas usan la tecnolog\u00eda.Ahora, la compa\u00f1\u00eda conocida por su estabilidad est\u00e1 pasando por una reestructuraci\u00f3n en la cima, ya que tanto Apple\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450173,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/06\/09\/apple-volver-moda-iphone-oportunidad-acciones-trax\/","url_meta":{"origin":1473040,"position":4},"title":"Apple tiene que volver a poner de moda el iPhone; esta es su oportunidad","author":"","date":"junio 9, 2024","format":false,"excerpt":"(CNN) -- Apple no ha dado a los usuarios una raz\u00f3n significativa para comprar un iPhone actualizado en cuatro a\u00f1os, desde que lanz\u00f3 la conectividad 5G con el iPhone 12, una tendencia preocupante para el negocio principal del gigante tecnol\u00f3gico. Eso podr\u00eda cambiar esta semana.El iPhone aport\u00f3 m\u00e1s de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466237,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","url_meta":{"origin":1473040,"position":5},"title":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"El iPhone necesita una renovaci\u00f3n y podr\u00eda verse el 9 de septiembre, cuando se espera que Apple anuncie un modelo de iPhone totalmente nuevo y m\u00e1s delgado, que podr\u00eda llamarse \u201ciPhone Air\u201d, junto con el iPhone 17 y nuevos modelos de Apple Watch en su evento anual principal.Ese tipo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1473040"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473040\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1473040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1473040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1473040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}