{"id":1473056,"date":"2026-04-11T07:03:49","date_gmt":"2026-04-11T14:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/"},"modified":"2026-04-11T07:03:49","modified_gmt":"2026-04-11T14:03:49","slug":"hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","title":{"rendered":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina"},"content":{"rendered":"<p>Ana lleg\u00f3 al hospital en ayunas y con la decisi\u00f3n tomada. D\u00edas antes, la prueba de embarazo hab\u00eda resultado positiva, pero desde el nacimiento de su tercer hijo, ella y su marido hab\u00edan dado por terminados los planes de agrandar la familia. Despu\u00e9s de asesorarse, una m\u00e9dica le indic\u00f3 los pasos a seguir para acceder a un aborto. La pr\u00e1ctica ser\u00eda en el Hospital Materno Infantil de San Isidro, en la provincia de Buenos Aires, donde lleg\u00f3 esa ma\u00f1ana de septiembre lista para la intervenci\u00f3n.<\/p>\n<p>Desde 2020, la interrupci\u00f3n voluntaria del embarazo es <a href=\"https:\/\/www.argentina.gob.ar\/noticias\/ley-no-27610-acceso-la-interrupcion-voluntaria-del-embarazo-ive-obligatoriedad-de-brindar\">legal<\/a> en Argentina y los centros de salud de todo el pa\u00eds deben garantizarla a quienes la requieran en un plazo m\u00e1ximo de diez d\u00edas, hasta la semana 14 de gestaci\u00f3n. Sin embargo, desde la llegada de Javier Milei al poder, hay profesionales de la salud y organismos de derechos humanos que denuncian faltantes de insumos y dificultad en el acceso a la intervenci\u00f3n. Seg\u00fan datos de Amnist\u00eda Internacional Argentina, en 2025 las denuncias por impedimentos y falta de informaci\u00f3n se triplicaron.<\/p>\n<p>En el Hospital Materno Infantil de San Isidro, uno de los municipios m\u00e1s ricos del pa\u00eds, adem\u00e1s, pacientes, m\u00e9dicos y profesionales de la salud alegan la existencia de un consultorio atendido por mujeres que no forman parte del personal de salud del hospital y buscan persuadir, obstaculizar y dilatar la atenci\u00f3n.<\/p>\n<p>Apenas supo que estaba embarazada, Ana -cuyo nombre fue modificado para preservar su intimidad- busc\u00f3 informaci\u00f3n en Internet para saber c\u00f3mo acceder a lo establecido en la ley 27.610. En Buenos Aires existe una l\u00ednea gratuita que deriva los pedidos seg\u00fan domicilio. Seg\u00fan relata, le dieron turno un d\u00eda despu\u00e9s para una consulta con una profesional m\u00e9dica en un centro de atenci\u00f3n primaria. All\u00ed le indicaron cu\u00e1l ser\u00eda el procedimiento: aspiraci\u00f3n Manual Endouterina (AMEU), una intervenci\u00f3n ambulatoria que se utiliza para vaciar el \u00fatero de forma segura. Dos d\u00edas despu\u00e9s, fue citada al Hospital Materno Infantil.<\/p>\n<p>\u201cLa doctora me recibe y me dice que antes del quir\u00f3fano tengo que pasar por un consultorio de consejer\u00eda\u201d, cuenta a CNN Ana. Seg\u00fan su relato, all\u00ed la recibieron dos mujeres que no se identificaron como personal de salud. CNN no pudo constatar de manera independiente qui\u00e9n la recibi\u00f3 ni las mujeres a las que hace referencia.<\/p>\n<p>\u201cCuando les digo que ya estaba en ayunas porque fui para practicarme una AMEU, me dicen que no, que eso no iba a suceder ese mismo d\u00eda\u201d, recuerda Ana.<\/p>\n<p>En la conversaci\u00f3n dice que le preguntaron datos muy personales y que a medida que les iba dando distintas razones de por qu\u00e9 tom\u00f3 su decisi\u00f3n, buscaban motivos para convencerla de que hiciera lo contrario. \u201cLes cont\u00e9 que ten\u00eda tres hijos y me dijeron que por ah\u00ed esta era la hija que me faltaba, que trate de conectar con el embarazo, que hable con toda mi familia y les cuente\u201d, relata Ana.<\/p>\n<p>Durante meses, CNN intent\u00f3 recibir una respuesta a estas alegaciones por parte de la direcci\u00f3n del Hospital. Recientemente, la nueva directora del instituto, que asumi\u00f3 al cargo a inicios de 2026, neg\u00f3 tener conocimiento de estos procedimientos.<\/p>\n<p>El testimonio de Ana no es el \u00fanico. Desde Amnist\u00eda Internacional Argentina explican que a partir de 2024 empezaron a recibir informaci\u00f3n de pacientes que coincid\u00edan con lo expresado por Ana sobre la atenci\u00f3n en el Hospital Materno.<\/p>\n<p>\u201cEn este contexto de desmantelamiento de las pol\u00edticas p\u00fablicas a nivel nacional, aparecieron unos dispositivos que se denominan maternidades vulnerables que, en lugar de acompa\u00f1ar a una mujer, lo que buscan es disuadirla de su decisi\u00f3n de interrumpir el embarazo, la desinforman y ejercen pr\u00e1cticas coercitivas\u201d. dice Lucila Galkin, directora de G\u00e9nero y Diversidad de Amnist\u00eda Internacional Argentina.<\/p>\n<p>Las pacientes que llegan al hospital buscando un aborto son recibidas en la mesa de entrada y derivadas a una sala de espera a la que se llega a trav\u00e9s de un largo pasillo. Rodeadas de puertas cerradas, las mujeres esperan a que las llamen por su nombre.<\/p>\n<p>Cada consultorio tiene el suyo: ecograf\u00eda, enfermer\u00eda. Solo una salita no lo tiene. La puerta es blanca y est\u00e1 entornada. Mujeres sin delantal entran y salen, incluso en medio de las consultas. CNN pudo constatar que all\u00ed atienden las \u201cvoluntarias\u201d.<\/p>\n<p>En los relatos que recopil\u00f3 Amnist\u00eda Internacional Argentina los di\u00e1logos se repiten. \u201cLes ofrecen escarpines, pa\u00f1ales, tratan de convencerlas de que es riesgoso abortar exagerando ampliamente sus consecuencias y dici\u00e9ndoles que los den en adopci\u00f3n\u201d, dice Galkin.<\/p>\n<p>En 2024, la organizaci\u00f3n dice que hizo presentaciones formales en el Hospital, ante la Secretar\u00eda de Salud del Municipio y ante la Direcci\u00f3n Provincial de Salud Sexual y Reproductiva y el dispositivo dej\u00f3 de funcionar por un tiempo.<\/p>\n<p>La Secretar\u00eda de Salud no contest\u00f3 a la solicitud de CNN sobre la realizaci\u00f3n de tales presentaciones. La Direcci\u00f3n del Hospital neg\u00f3 tener conocimiento.<\/p>\n<p>Sin embargo, desde el a\u00f1o pasado Amnist\u00eda Internacional dijo a CNN que recibi\u00f3 nuevos relatos.<\/p>\n<p>\u201cHan llegado a decirles, por ejemplo, que hay mujeres que se suicidan luego de acceder al aborto por la culpa posterior, que les mostraron mu\u00f1ecos de beb\u00e9s en la consulta o que entraron mujeres en el marco de la consulta m\u00e9dica y entregaron una virgen. Todas conductas sumamente invasivas, coercitivas y graves. Violan el trato digno y los derechos del paciente y por supuesto, la autonom\u00eda reproductiva\u201d, cuenta Lucila Galkin.<\/p>\n<p>Dos profesionales de Salud de San Isidro que pidieron mantener su nombre en reserva para no enfrentar represalias contaron en exclusiva a CNN c\u00f3mo alegan que funciona la pr\u00e1ctica desde adentro. Agregan que reciben presiones y que, si bien todav\u00eda encuentran mecanismos para garantizar los abortos, su trabajo se ha complicado.<\/p>\n<p>\u201cCuando cambi\u00f3 el signo de la gesti\u00f3n pol\u00edtica, comenzaron las dificultades, pero desde que lleg\u00f3 el nuevo secretario de Salud, el hostigamiento se ha hecho mayor\u201d, sostienen.<\/p>\n<p>Tras varios pedidos de entrevista, las autoridades del Municipio de San Isidro prefirieron responder a CNN por escrito: \u201cEn cumplimiento con la ley, en San Isidro trabaja un equipo de consejer\u00eda en derechos integrado por profesionales: obstetras, ecografistas, psic\u00f3logos, enfermeras, abogadas y voluntarias. Este equipo garantiza el acceso a la informaci\u00f3n y brinda una atenci\u00f3n integral y acompa\u00f1amiento a todas las madres embarazadas, sea cual fuera la decisi\u00f3n que tomen amparadas por la ley\u201d.<\/p>\n<p>\u201cCasado con Lola y pap\u00e1 de 7 hijos. M\u00e9dico pediatra\u201d, se describe a s\u00ed mismo en su perfil de Instagram Pablo Mar\u00eda de la Torre, el actual secretario de Salud de San Isidro. Tambi\u00e9n exfuncionario del gobierno de Javier Milei, fue desplazado de su cargo a mediados de 2024 como secretario de Ni\u00f1ez, Adolescencia y Familia de la Naci\u00f3n en el ministerio de Capital Humano tras un <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/06\/04\/cronologia-escandalo-alimentos-galpones-argentina-orix\">esc\u00e1ndalo por bolsones de alimentos no distribu\u00eddos<\/a> en comedores. Tras su salida, asegur\u00f3: \u201cTengo la conciencia y las manos limpias\u201d.<\/p>\n<p>En 2018, cuando el debate sobre el derecho al aborto lleg\u00f3 al Congreso de Argentina y los pa\u00f1uelos verdes se volv\u00edan una postal emblema para toda la regi\u00f3n, De la Torre fue uno de los exponentes opositores a la iniciativa. \u201cHe visto las secuelas del s\u00edndrome posaborto y es devastador: depresi\u00f3n, intentos de suicidio, baja autoestima, reca\u00eddas de la salud mental cercanas a la fecha del aborto, llanto f\u00e1cil\u201d, dec\u00eda ante el recinto, sin pruebas cient\u00edficas. El <a href=\"https:\/\/www.apa.org\/pi\/women\/programs\/abortion\/mental-health.pdf\">consenso m\u00e9dico internacional<\/a>, respaldado por <a href=\"https:\/\/www.who.int\/publications\/i\/item\/9789240039483\">organismos<\/a> como la Organizaci\u00f3n Mundial de la Salud y la American PsychologicalAssociation, indica que el aborto seguro no aumenta el riesgo de trastornos mentales.<\/p>\n<p>En ese entonces, De La Torre era secretario de Salud en San Miguel, municipio del cual es un referente pol\u00edtico junto a su hermano Joaqu\u00edn de la Torre, exintendente. Durante su gesti\u00f3n implement\u00f3 pol\u00edticas -que ahora traslad\u00f3 a San Isidro- como el Camino de la Embarazada, un programa que propone un recorrido \u201cpuerta por puerta\u201d de un equipo m\u00e9dico en territorios vulnerables para identificar a las mujeres embarazadas, a trav\u00e9s de ecograf\u00edas ambulatorias y as\u00ed poder hacerles un seguimiento.<\/p>\n<p>Hist\u00f3ricamente, varias organizaciones de derechos humanos denuncian que en San Miguel no es posible acceder al aborto. En 2025, la justicia sancion\u00f3 al municipio por no dar informaci\u00f3n p\u00fablica sobre el acceso a la Ley de Interrupci\u00f3n Voluntaria del Embarazo. Las autoridades locales dijeron a CNN que \u201cexiste una controversia en tr\u00e1mite que a\u00fan no se encuentra resuelta\u201d y que el municipio cumple con el acceso a las pr\u00e1cticas previstas en la Ley.<\/p>\n<p>De la Torre lleva a\u00f1os de militancia contra la ley de aborto. Durante su <a href=\"https:\/\/www.youtube.com\/watch?v=6TmJV2lfDfs\">alocuci\u00f3n<\/a> en el Congreso, en 2018, mencion\u00f3 adem\u00e1s unas consejer\u00edas que se hab\u00edan puesto en marcha en San Miguel: \u201cEn la noticia del embarazo, a trav\u00e9s de la consejer\u00eda, les damos ayuda e informaci\u00f3n a las mujeres que atraviesan un momento de fuerte duda. Aquellas que han pasado por la consejer\u00eda, a pesar de sus dificultades, han continuado con sus embarazos\u201d.<\/p>\n<p>El ahora secretario de Salud lleg\u00f3 al municipio de San Isidro, cuya intendencia est\u00e1 a cargo de Ram\u00f3n Lan\u00fas, a comienzos de 2025. Lan\u00fas, -quien ha declarado p\u00fablicamente su posici\u00f3n en contra del aborto &#8211; present\u00f3 en 2025 una lista en alianza con La Libertad Avanza, el partido del presidente Javier Milei.<\/p>\n<p>Desde la llegada del actual gobierno, en diciembre de 2023, la pol\u00edtica de ajuste impact\u00f3 directamente en el acceso al aborto a nivel nacional. En un informe de septiembre de 2025, Amnist\u00eda Internacional Argentina denuncia que se registra \u201cuna suspensi\u00f3n total de la compra y distribuci\u00f3n de insumos esenciales para garantizar el acceso a la IVE\/ILE\u201d.<\/p>\n<p>CNN consult\u00f3 con el ministerio de Salud de la Naci\u00f3n y respondieron que son los prestadores de salud quienes tienen la obligaci\u00f3n de garantizar el derecho al aborto y que es potestad de cada provincia.<\/p>\n<p>Al igual que relatan activistas dedicados a la atenci\u00f3n en el territorio, los organismos de derechos humanos reportan que las primeras denuncias en el Municipio se dieron con la llegada de Lan\u00fas a la intendencia y que se intensificaron desde la gesti\u00f3n de De la Torre en Salud.<\/p>\n<p>CNN solicit\u00f3 formalmente entrevistar al secretario de Salud Pablo De La Torre, pero ante las negativas se convino enviar las preguntas de manera escrita.<\/p>\n<p>En este sentido, las autoridades de San Isidro dijeron a CNN que la actuaci\u00f3n del municipio es acorde a la ley vigente.<\/p>\n<p>Durante esta investigaci\u00f3n, los dos profesionales de la salud que trabajan en la atenci\u00f3n de pacientes de distintas unidades del municipio revelaron en exclusiva a CNN la existencia de un protocolo de actuaci\u00f3n interno que verifica parte de los mecanismos que pueden demorar la atenci\u00f3n aplicados en San Isidro. CNN, adem\u00e1s, constat\u00f3 la veracidad del documento de manera independiente.<\/p>\n<p>De acuerdo con el relato de los m\u00e9dicos y la documentaci\u00f3n compartida con este medio, en junio de 2025, la municipalidad de San Isidro envi\u00f3 a todos los centros de salud del distrito una circular con la firma de De la Torre y tres documentos adjuntos, entre ellos el protocolo de actuaci\u00f3n en caso de \u201c<em>solicitud de interrupci\u00f3n voluntaria del embarazo (IVE) e interrupci\u00f3n legal del embarazo (ILE)\u201d.<\/em><\/p>\n<p>All\u00ed se indica que todas las consultas relacionadas a la pr\u00e1ctica -ya sea en Centros de Atenci\u00f3n Primarios de la Salud (CAPS) o cualquier sala del distrito- deben ser derivadas al Hospital Materno Infantil y que la farmacia de ese hospital es el \u00fanico centro autorizado para la dispensa de medicaci\u00f3n.<\/p>\n<p>En la hoja de ruta de cada paciente, adjunta al protocolo, se establecen seis instancias previas al acceso a la pr\u00e1ctica, entre ellas una consejer\u00eda al principio y otra al final. Sin embargo, la ley nacional que establece que la persona que pide un aborto tiene derecho a acceder a informaci\u00f3n clara, y con la sola firma del consentimiento informado debe poder avanzar con la IVE.<\/p>\n<p>\u201cObligan a las mujeres a pasar por m\u00e1s de una consejer\u00eda para el acceso al aborto, lo cual va en contra de la Ley de Interrupci\u00f3n Voluntaria Legal del Embarazo. Adem\u00e1s, estas supuestas maternidades vulnerables, les dicen que obligatoriamente tienen que tener una consulta psicol\u00f3gica previa para acceder, lo cual tambi\u00e9n est\u00e1 en contra de lo que establece el marco legal vigente\u201d, aclara Lucila Galkin.<\/p>\n<p>Especialistas aseguran que esta pr\u00e1ctica viola el principio de celeridad y atenci\u00f3n sin barreras que propone la ley, teniendo en cuenta el plazo l\u00edmite para realizarse un aborto legal.<\/p>\n<p>El abogado argentino Agustin Nacarato lo explica en detalle. \u201cEl protocolo de San Isidro vulnera la ley de interrupci\u00f3n voluntaria del embarazo de manera articulada\u201d, sostiene y se\u00f1ala tres aspectos puntuales que \u201cfuncionan como sistema\u201d.<\/p>\n<p>\u201cMientras que la legislaci\u00f3n nacional establece que los servicios de acompa\u00f1amiento son voluntarios y no condicionan el acceso al procedimiento, que la decisi\u00f3n de la paciente no puede ser interferida ni sometida a juicios de orden personal o religioso y que el acceso debe concretarse en un plazo m\u00e1ximo de diez d\u00edas corridos, el protocolo de San Isidro opera en sentido contrario\u201d, subraya. \u201cConvierte el acompa\u00f1amiento en obligatorio, crea las condiciones para que las instancias previas al procedimiento funcionen como oportunidades de interferencia sobre una decisi\u00f3n que la ley ordena respetar y, al multiplicar las etapas, pone en riesgo estructural el plazo legal\u201d.<\/p>\n<p>En este sentido, una de las dos fuentes del sistema de Salud con las que habl\u00f3 CNN, con conocimiento de la atenci\u00f3n del Hospital Materno Infantil de San Isidro cont\u00f3 que estas pr\u00e1cticas han llegado a demorar el acceso al aborto hasta un mes.<\/p>\n<p>\u201cNo se trata de excesos aislados\u201d, subraya Nacarato sobre el texto del protocolo. \u201cCada paso habilita el siguiente, y el resultado es que lo que la ley de Interrupci\u00f3n Voluntaria del Embarazo pens\u00f3 como derechos de la paciente, el protocolo los reencuadra como requisitos que el sistema le impone\u201d, concluye.<\/p>\n<p>Amnist\u00eda Internacional Argentina realiz\u00f3 un pedido de acceso a la informaci\u00f3n a la provincia de Buenos Aires sobre la implementaci\u00f3n de la ley en esa instituci\u00f3n. Seg\u00fan los datos aportados, en el transcurso de 2024 y 2025 se entregaron cerca de un 40 % menos de tratamientos con misoprostol que en todo el 2023.<\/p>\n<p>Si bien la aplicaci\u00f3n del protocolo todav\u00eda no se traduce en un descenso taxativo en los casos, entre 2023 y 2024, se practicaron un 10 % menos de ILE\/IVE. Profesionales de la salud afirman que contin\u00faan garantizando la pr\u00e1ctica a pesar de la resistencia oficial. Seg\u00fan relataron a CNN, todav\u00eda encuentran espacios para llevar adelante las intervenciones cuando las pacientes no logran ser persuadidas en las consejer\u00edas o ante los mecanismos de dilaci\u00f3n que plantea el protocolo.<\/p>\n<p>Ante los pedidos de informaci\u00f3n por parte de CNN, el Municipio de San isidro eligi\u00f3 no responder de manera espec\u00edfica sobre el protocolo, aunque no neg\u00f3 su existencia.<\/p>\n<p>En alg\u00fan momento, durante el transcurso de esa conversaci\u00f3n, Ana dice que dos mujeres m\u00e1s ingresaron al consultorio. Relata que interrumpieron la charla y una de ellas le dio un paquete a una de las mujeres con las que estaba hablando.<\/p>\n<p>Despu\u00e9s de m\u00e1s de una hora de consejer\u00eda, Ana supo que ten\u00eda que salir de ah\u00ed como fuera. \u201cEra muy notorio que estaban tratando de cambiar el rumbo de mi decisi\u00f3n\u201d, dice.<\/p>\n<p>Entonces, acept\u00f3 tomar el turno psicol\u00f3gico unos d\u00edas m\u00e1s tarde y la consulta lleg\u00f3 a su fin.<\/p>\n<p>Ana relata que una de ellas abri\u00f3 el paquete que le hab\u00edan dejado y le mostr\u00f3 su contenido: \u201cEra una virgen. Me dijo que ella no ten\u00eda idea de lo que hab\u00eda dentro de la caja y que lo ten\u00eda que tomar como una se\u00f1al\u201d, explica.<\/p>\n<p>Sin embargo, con la misma convicci\u00f3n que cuando vio el test de embarazo, sali\u00f3 del consultorio, se acerc\u00f3 a la m\u00e9dica del hospital y le dijo que estaba lista para la intervenci\u00f3n.<\/p>\n<p>Finalmente, Ana pudo acceder a un aborto, pero le preocupa que no todas las mujeres puedan lograrlo.<\/p>\n<p>\u201cEstoy tranquila porque mal o bien logr\u00e9 acceder al procedimiento que estaba buscando. Pero atr\u00e1s m\u00edo entr\u00f3 otra chica a la consejer\u00eda y antes de m\u00ed estaba saliendo otra, y es muy claro el objetivo de ese consultorio, no s\u00e9 si con alguna otra chica lo lograr\u00e1n es violento, aunque ellas no se manifiesten de manera violenta, no est\u00e1 bueno lo que sucede ah\u00ed adentro\u201d.<\/p>\n<p>D\u00edas m\u00e1s tarde, se tatu\u00f3 una virgen en uno de sus brazos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ana lleg\u00f3 al hospital en ayunas y con la decisi\u00f3n tomada. D\u00edas antes, la prueba de embarazo hab\u00eda resultado positiva, pero desde el nacimiento de su tercer hijo, ella y su marido hab\u00edan dado por terminados los planes de agrandar la familia. Despu\u00e9s de asesorarse, una m\u00e9dica le indic\u00f3 los pasos a seguir para acceder [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473056","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ana lleg\u00f3 al hospital en ayunas y con la decisi\u00f3n tomada. D\u00edas antes, la prueba de embarazo hab\u00eda resultado positiva, pero desde el nacimiento de su tercer hijo, ella y su marido hab\u00edan dado por terminados los planes de agrandar la familia. Despu\u00e9s de asesorarse, una m\u00e9dica le indic\u00f3 los pasos a seguir para acceder [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T14:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina\",\"datePublished\":\"2026-04-11T14:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\"},\"wordCount\":2922,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\",\"name\":\"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-11T14:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias","og_description":"Ana lleg\u00f3 al hospital en ayunas y con la decisi\u00f3n tomada. D\u00edas antes, la prueba de embarazo hab\u00eda resultado positiva, pero desde el nacimiento de su tercer hijo, ella y su marido hab\u00edan dado por terminados los planes de agrandar la familia. Despu\u00e9s de asesorarse, una m\u00e9dica le indic\u00f3 los pasos a seguir para acceder [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-11T14:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/"},"author":{"name":"","@id":""},"headline":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina","datePublished":"2026-04-11T14:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/"},"wordCount":2922,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","name":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-11T14:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fue al hospital para abortar, le entregaron una virgen: alegan obst\u00e1culos en la ley de interrupci\u00f3n del embarazo en Argentina","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-11T14:03:49Z","datePublished":"2026-04-11T14:03:49Z","dateModified":"2026-04-11T14:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fue al hospital para abortar, le entregaron una virgen: alegan obst\\u00e1culos en la ley de interrupci\\u00f3n del embarazo en Argentina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/11\\\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/11\\\/hospital-abortar-virgen-alegan-obstaculos-ley-interrupcion-embarazo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-11T14:03:49Z\",\"datePublished\":\"2026-04-11T14:03:49Z\",\"dateModified\":\"2026-04-11T14:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459718,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/10\/vientre-subrogado-abadono-bebe-argetina-orix\/","url_meta":{"origin":1473056,"position":0},"title":"Investigan caso de abandono de una beb\u00e9 concebida por subrogaci\u00f3n de vientre en Argentina","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Luc\u00eda (que no es identificada con su nombre real por pedido de la Justicia) ten\u00eda prevista su fecha de parto para los primeros d\u00edas de enero. Ya hab\u00eda hecho los planes: cuando llegara el momento dar\u00eda a luz en una cl\u00ednica de Buenos Aires, a donde ir\u00eda desde la provincia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449555,"url":"https:\/\/noticiasya.com\/washington-dc\/2024\/05\/17\/suspenden-juicio-politico-fiscal-ecuador-diana-salazar-embarazo-orix\/","url_meta":{"origin":1473056,"position":1},"title":"Suspenden temporalmente procesos de juicio pol\u00edtico en contra de la fiscal general de Ecuador debido a su embarazo de riesgo","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La fiscal general de Ecuador, Diana Salazar, no tendr\u00e1 que acudir a la Asamblea Nacional para responder a los dos procesos de juicio pol\u00edtico propuestos en su contra debido a su situaci\u00f3n de vulnerabilidad por su embarazo considerado como de \u201calto riesgo\u201d.Tal como estaba previsto, el Consejo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462019,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/05\/05\/rihanna-anuncio-embarazo-gala-met-trax\/","url_meta":{"origin":1473056,"position":2},"title":"Rihanna revela su tercer embarazo en la Gala del Met","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Despu\u00e9s de revelar su segundo embarazo de forma dram\u00e1tica durante su actuaci\u00f3n en el descanso de la Super Bowl 2023, Rihanna volvi\u00f3 a hacer lo propio estrenando el tercero en la alfombra roja de la Met Gala.Fue la \u00faltima asistente en llegar al Museo Metropolitano de Arte de Nueva York\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1409995,"url":"https:\/\/noticiasya.com\/washington-dc\/2022\/06\/30\/suspension-de-abortos-en-arizona-causa-afluencia-de-citas-en-san-diego\/","url_meta":{"origin":1473056,"position":3},"title":"Suspensi\u00f3n de abortos en Arizona causa afluencia de citas en San Diego","author":"agomez","date":"junio 30, 2022","format":false,"excerpt":"La medicaci\u00f3n es generalmente efectiva dentro de las primeras 11 semanas de embarazo.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1411383,"url":"https:\/\/noticiasya.com\/washington-dc\/2022\/07\/07\/instalan-clinica-para-abortos-a-metros-de-la-frontera-podria-atraer-a-estadounidenses\/","url_meta":{"origin":1473056,"position":4},"title":"Instalan cl\u00ednica para abortos a metros de la frontera, podr\u00eda atraer a estadounidenses","author":"agomez","date":"julio 7, 2022","format":"video","excerpt":"Las instalaciones son operadas por la fundaci\u00f3n MSI, que lleva m\u00e1s de 20 a\u00f1os en M\u00e9xico.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470460,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/01\/25\/deporta-mujer-colombiana-8-meses-embarazo-asilo-orix\/","url_meta":{"origin":1473056,"position":5},"title":"EE.UU. deporta a una mujer colombiana con 8 meses de embarazo que hab\u00eda solicitado asilo","author":"agomez","date":"enero 25, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos deport\u00f3 el mi\u00e9rcoles a Zharik Daniela Buitrago Ortiz, una mujer colombiana con ocho meses de embarazo que hab\u00eda llegado al pa\u00eds en noviembre del a\u00f1o pasado para solicitar asilo junto con otros miembros de su familia.La deportaci\u00f3n de Buitrago Ortiz se llev\u00f3 a cabo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1473056"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473056\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1473056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1473056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1473056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}