{"id":1473062,"date":"2026-04-11T09:03:49","date_gmt":"2026-04-11T16:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/"},"modified":"2026-04-11T09:03:49","modified_gmt":"2026-04-11T16:03:49","slug":"rafael-lopez-aliaga-candidato-elecciones-peru-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","title":{"rendered":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente"},"content":{"rendered":"<p>Miembro del Opus Dei, ultraconservador y c\u00e9libe desde los 19 a\u00f1os, Rafael L\u00f3pez Aliaga apelar\u00e1 a la fe para lograr lo que ning\u00fan alcalde de Lima logr\u00f3 hasta ahora en m\u00e1s de cien a\u00f1os de historia pol\u00edtica de Per\u00fa: romper la \u201cmaldici\u00f3n\u201d y llegar a ser presidente.<\/p>\n<p>En un escenario de fragmentaci\u00f3n, indecisi\u00f3n e incertidumbre, con un r\u00e9cord de 35 candidatos postulados a la presidencia, L\u00f3pez Aliaga se ubicaba en las \u00faltimas semanas oscilando entre un segundo y tercer lugar <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/05\/latinoamerica\/elecciones-peru-encuestas-candidatos-favoritos-orix\">en algunas encuestas de intenci\u00f3n de voto<\/a>, disputando el espacio principalmente contra la candidata conservadora, Keiko Fujimori, y el c\u00f3mico Carlos \u00c1lvarez, del partido Pa\u00eds para Todos.<\/p>\n<p>Hasta la semana previa a los comicios presidenciales, en los que tambi\u00e9n se definir\u00e1 la composici\u00f3n del Congreso, ning\u00fan candidato hab\u00eda logrado superar el 15 % de intenci\u00f3n de voto en las encuestas publicadas.<\/p>\n<p>En ese contexto, las posibilidades de que L\u00f3pez Aliaga llegue a la presidencia son probablemente mayores en una segunda vuelta que lo enfrente cara a cara con Fujimori, dice a CNN Henry Ziemer, investigador asociado del Programa de las Am\u00e9ricas del Centro de Estudios Estrat\u00e9gicos e Internacionales (CSIS, por sus siglas en ingl\u00e9s).<\/p>\n<p>Ese, dice el investigador, es su desaf\u00edo: lograr disputar un balotaje en un panorama donde son varios los candidatos que, al igual que \u00e9l, buscan capitalizar la preocupaci\u00f3n por la inseguridad y el crimen organizado, dos temas <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/08\/latinoamerica\/peru-crimen-inseguridad-elecciones-orix\">clave para los peruanos<\/a>.<\/p>\n<p>\u201cYo soy del Opus Dei desde muy chico, desde los 19 a\u00f1os, con celibato incluido, lo cual es una opci\u00f3n m\u00eda personal\u00edsima y me alimenta en base a la eucarist\u00eda diaria. Eso es lo que me da fuerza, y que no he dejado\u201d, dijo L\u00f3pez Aliaga el domingo <a href=\"https:\/\/www.youtube.com\/watch?v=PSD6R79BjdM\">en una entrevista<\/a> con el medio local Andahuaylas TV.<\/p>\n<p>Desde entonces hasta la actualidad, con 65 a\u00f1os, \u201cno ha habido un d\u00eda en que no comulgue\u201d, dice el empresario, que se postula por segunda vez para presidente \u2014ya lo hizo en 2021, cuando qued\u00f3 en tercer lugar\u2014 y tiene entre sus referentes al expresidente de Brasil, Jair Bolsonaro, y al presidente de Estados Unidos, Donald Trump, a quienes parece unirlo el estilo confrontativo.<\/p>\n<p>Ingeniero industrial y nacido en la ciudad peruana de Chiclayo, L\u00f3pez Aliaga es hijo de padres ingenieros qu\u00edmicos. Adem\u00e1s de definirse como un hombre de fe, creci\u00f3 viendo a su padre administrar una empresa de ca\u00f1a de az\u00facar y dice que all\u00ed se origin\u00f3 su amor por la ciencia.<\/p>\n<p>Con una larga trayectoria en distintos bancos, L\u00f3pez se vincul\u00f3 luego como empresario en el sector tur\u00edstico y hotelero de Per\u00fa. Invirti\u00f3 en hoteles de lujo en el Machu Picchu y en trenes que trasladan a turistas hasta el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/16\/latinoamerica\/machu-picchu-riesgo-siete-maravillas-mundo-orix\">hist\u00f3rico santuario<\/a>. Fund\u00f3 adem\u00e1s tres colegios y un centro tecnol\u00f3gico.<\/p>\n<p>Su carrera pol\u00edtica comenz\u00f3 como regidor provincial, cargo que ocup\u00f3 durante 13 a\u00f1os, entre 2007 y 2020. Luego asumi\u00f3 como alcalde de Lima en 2022, cuando prometi\u00f3 que llevar\u00eda a la capital peruana a ser <a href=\"https:\/\/www.facebook.com\/RafaelLopezAliagaOficial\/videos\/lima-potencia-mundial\/1462515004182897\/\">\u201cpotencia mundial\u201d<\/a>. Renunci\u00f3 al cargo en octubre de 2025 para ser candidato presidencial.<\/p>\n<p>Conocido popularmente como \u201cPorky\u201d, por su aspecto que se asemeja al del dibujo animado, ha tomado ese apodo y lo ha hecho parte de su identidad. Se ha opuesto abiertamente al <a href=\"https:\/\/x.com\/rlopezaliaga1\/status\/1337531999645528064\">aborto legal<\/a>, al que considera un \u201ccrimen abominable\u201d, y al matrimonio entre personas del mismo g\u00e9nero: para \u00e9l, el \u00fanico matrimonio que existe es <a href=\"https:\/\/x.com\/rlopezaliaga1\/status\/1323670077112287232\">entre un hombre y una mujer<\/a>.<\/p>\n<p>Las posturas sociales conservadoras de L\u00f3pez Aliaga, as\u00ed como su enfoque de mano dura frente a la delincuencia y la migraci\u00f3n, se alinean estrechamente con las del votante medio en Per\u00fa, dice a CNN Nicol\u00e1s Sald\u00edas, analista s\u00e9nior del Economist Intelligence Unit (EIU) para Am\u00e9rica Latina y el Caribe. Su experiencia como exalcalde de Lima y su personalidad \u201csingular\u201d, sumado a una \u201cs\u00f3lida base de apoyo en Lima\u201d jugaron a su favor para posicionarse entre decenas de candidatos, agrega Sald\u00edas.<\/p>\n<p>Su partido <a href=\"https:\/\/x.com\/rlopezaliaga1\/status\/1215073024740941824\">Renovaci\u00f3n Popular<\/a> (antes el Partido Solidaridad Nacional) se sienta en las bases de la filosof\u00eda socialcristiana, \u201cprovida y profamilia\u201d y <a href=\"https:\/\/rafaellopezaliaga.pe\/conoceme\/\">le declara \u201cla guerra al comunismo\u201d<\/a> y al feminismo.<\/p>\n<p>\u00c9l, por su parte, se define como <a href=\"https:\/\/x.com\/rlopezaliaga1\">pol\u00edtico, catedr\u00e1tico y empresario<\/a> y ha escrito libros sobre el sistema financiero y de inversi\u00f3n peruano, adem\u00e1s de dar clases en la Universidad Nacional de Ingenier\u00eda.<\/p>\n<p>Cuatro ejes estructuran <a href=\"https:\/\/rafaellopezaliaga.pe\/plan-2026\/\">su propuesta<\/a>: el fin de la delincuencia; salud y educaci\u00f3n; infraestructura y desarrollo nacional; y reducci\u00f3n del Estado y lucha contra la corrupci\u00f3n.<\/p>\n<p>P<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/08\/latinoamerica\/peru-crimen-inseguridad-elecciones-orix#:~:text=L%C3%B3pez%20Aliaga%20prometi%C3%B3%20la%20construcci%C3%B3n%20de%20c%C3%A1rceles%20aisladas%20y%20la%20expulsi%C3%B3n%20de%20extranjeros%20ilegales%20adem%C3%A1s%20de%20retirar%20al%20pa%C3%ADs%20de%20la%20Corte%20Interamericana%20de%20Derechos%20Humanos%20para%20aplicar%20la%20pena%20de%20muerte%20y%20reinstaurar%20tribunales%20con%20jueces%20sin%20rostro\">rometi\u00f3 la construcci\u00f3n de c\u00e1rceles aisladas<\/a> replicando el modelo del presidente Nayib Bukele en El Salvador; expulsar a extranjeros indocumentados y retirar al pa\u00eds de la Corte Interamericana de Derechos Humanos (CIDH) para aplicar la pena de muerte, adem\u00e1s de reformar el Poder Judicial para condenar a jueces que dejen a delincuentes en libertad.<\/p>\n<p>\u201cSu \u00e9nfasis en la seguridad, su ret\u00f3rica de mano dura y su compromiso de fortalecer los lazos con Estados Unidos y El Salvador para combatir el crimen organizado podr\u00edan resultar atractivos para la derecha pol\u00edtica, al tiempo que se libera de la hist\u00f3rica carga del fujimorismo que ha relegado a Keiko a un segundo plano constante\u201d, dice Ziemer, que sigue de cerca el desarrollo de la instancia electoral en Per\u00fa.<\/p>\n<p>En <a href=\"https:\/\/rafaellopezaliaga.pe\/plan-2026\/\">t\u00e9rminos estatales<\/a>, propone entre otras cosas reducir ministerios y eliminar la pauta publicitaria para medios: \u201cNo m\u00e1s mermelada para la prensa\u201d. Busca tambi\u00e9n reducir sueldos de funcionarios p\u00fablicos y hacer que los cargos pol\u00edticos de presidentes, congresistas, gobernadores regionales y alcaldes sean ad honorem.<\/p>\n<p>Per\u00fa, que ha tenido 8 presidentes durante la \u00faltima d\u00e9cada, se enfrenta a la oportunidad de superar una larga crisis de legitimidad pol\u00edtica: volver\u00e1 a tener un congreso bicameral con un nuevo Senado.<\/p>\n<p>\u201cLa transici\u00f3n del pa\u00eds a un sistema legislativo bicameral podr\u00eda contribuir a reducir la inestabilidad, ya que el anterior sistema unicameral daba a los legisladores un gran poder para destituir a los presidentes en ejercicio\u201d, analiz\u00f3 el investigador asociado del CSIS. El candidato que logre una victoria contundente en la segunda vuelta, podr\u00eda luego reclamar \u201cun aut\u00e9ntico mandato popular\u201d y limitar as\u00ed el creciente poder del sistema legislativo en la pol\u00edtica peruana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miembro del Opus Dei, ultraconservador y c\u00e9libe desde los 19 a\u00f1os, Rafael L\u00f3pez Aliaga apelar\u00e1 a la fe para lograr lo que ning\u00fan alcalde de Lima logr\u00f3 hasta ahora en m\u00e1s de cien a\u00f1os de historia pol\u00edtica de Per\u00fa: romper la \u201cmaldici\u00f3n\u201d y llegar a ser presidente. En un escenario de fragmentaci\u00f3n, indecisi\u00f3n e incertidumbre, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473062","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Miembro del Opus Dei, ultraconservador y c\u00e9libe desde los 19 a\u00f1os, Rafael L\u00f3pez Aliaga apelar\u00e1 a la fe para lograr lo que ning\u00fan alcalde de Lima logr\u00f3 hasta ahora en m\u00e1s de cien a\u00f1os de historia pol\u00edtica de Per\u00fa: romper la \u201cmaldici\u00f3n\u201d y llegar a ser presidente. En un escenario de fragmentaci\u00f3n, indecisi\u00f3n e incertidumbre, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-11T16:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente\",\"datePublished\":\"2026-04-11T16:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\"},\"wordCount\":1117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\",\"name\":\"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-11T16:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias","og_description":"Miembro del Opus Dei, ultraconservador y c\u00e9libe desde los 19 a\u00f1os, Rafael L\u00f3pez Aliaga apelar\u00e1 a la fe para lograr lo que ning\u00fan alcalde de Lima logr\u00f3 hasta ahora en m\u00e1s de cien a\u00f1os de historia pol\u00edtica de Per\u00fa: romper la \u201cmaldici\u00f3n\u201d y llegar a ser presidente. En un escenario de fragmentaci\u00f3n, indecisi\u00f3n e incertidumbre, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-11T16:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/"},"author":{"name":"","@id":""},"headline":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente","datePublished":"2026-04-11T16:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/"},"wordCount":1117,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","name":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-11T16:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rafael L\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\u00f3rica tendencia y llegar a ser presidente","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-11T16:03:49Z","datePublished":"2026-04-11T16:03:49Z","dateModified":"2026-04-11T16:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rafael L\\u00f3pez Aliaga, el exalcalde de Lima que quiere romper una hist\\u00f3rica tendencia y llegar a ser presidente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/11\\\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/11\\\/rafael-lopez-aliaga-candidato-elecciones-peru-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-11T16:03:49Z\",\"datePublished\":\"2026-04-11T16:03:49Z\",\"dateModified\":\"2026-04-11T16:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473251,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/16\/economia-peru-incertidumbre-electoral-orix\/","url_meta":{"origin":1473062,"position":0},"title":"La econom\u00eda de Per\u00fa empieza a sentir el impacto de la incertidumbre electoral","author":"","date":"abril 16, 2026","format":false,"excerpt":"La incertidumbre electoral en Per\u00fa comenz\u00f3 a permear en la econom\u00eda, que durante la \u00faltima d\u00e9cada de inestabilidad pol\u00edtica ha mostrado resiliencia, principalmente en la inflaci\u00f3n y la fortaleza de su moneda, pero que no escapa del impacto en los indicadores de cara a un posible giro en la conducci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473095,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/13\/peru-incidentes-ensombrecen-elecciones-orix\/","url_meta":{"origin":1473062,"position":1},"title":"As\u00ed fueron los incidentes que ensombrecieron las elecciones en Per\u00fa","author":"","date":"abril 13, 2026","format":false,"excerpt":"Per\u00fa tuvo este domingo una larga jornada electoral, marcada por retrasos que desde temprano dificultaron la apertura de muchos centros de votaci\u00f3n, generaron molestia entre candidatos y ciudadanos, derivaron en que se ampliara el horario para votar y demoraron el escrutinio.Hasta la ma\u00f1ana de este lunes se ha computado poco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473192,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/15\/peru-candidato-izquierdista-roberto-sanchez-orix\/","url_meta":{"origin":1473062,"position":2},"title":"Qui\u00e9n es y qu\u00e9 propone Roberto S\u00e1nchez, el izquierdista que pugna por pasar a la segunda vuelta en Per\u00fa","author":"","date":"abril 15, 2026","format":false,"excerpt":"El candidato izquierdista Roberto S\u00e1nchez, con una propuesta que reivindica al detenido expresidente Pedro Castillo, aspira a pasar a la segunda vuelta en las elecciones en Per\u00fa, un lugar que disputa voto a voto con el ultraderechista Rafael L\u00f3pez Aliaga, mientras la conservadora Keiko Fujimori encabeza el conteo.El postulante y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473066,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/11\/roberto-sanchez-alfonso-lopez-chau-candidatos-izquierda-peru-orix\/","url_meta":{"origin":1473062,"position":3},"title":"\u00bfQui\u00e9nes son y qu\u00e9 proponen Roberto S\u00e1nchez y Alfonso L\u00f3pez-Chau, candidatos de izquierda a la presidencia de Per\u00fa?","author":"","date":"abril 11, 2026","format":false,"excerpt":"M\u00e1s de 27 millones de votantes est\u00e1n habilitados para elegir al pr\u00f3ximo presidente de Per\u00fa este domingo 12 de abril, en unas elecciones que seg\u00fan las estimaciones podr\u00edan definirse reci\u00e9n en una segunda vuelta en junio.Es que, hasta la semana previa a los comicios presidenciales, en los que tambi\u00e9n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472796,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/02\/peru-elecciones-favoritos-encuestas-orix\/","url_meta":{"origin":1473062,"position":4},"title":"\u00bfQui\u00e9nes son los candidatos favoritos para las elecciones presidenciales de Per\u00fa? Esto dicen las encuestas","author":"","date":"abril 2, 2026","format":false,"excerpt":"A menos de dos semanas de las elecciones presidenciales en Per\u00fa, la fragmentaci\u00f3n pol\u00edtica se mantiene en las encuestas, donde ning\u00fan candidato llega al 12 % de intenci\u00f3n de voto, lo que mantiene vol\u00e1til la situaci\u00f3n y no descarta alguna irrupci\u00f3n sorpresiva de cara a una segura segunda vuelta.Keiko Fujimori,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472882,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/05\/elecciones-peru-encuestas-candidatos-favoritos-orix\/","url_meta":{"origin":1473062,"position":5},"title":"\u00bfQui\u00e9nes son los candidatos favoritos para las elecciones presidenciales de Per\u00fa? Esto dicen las \u00faltimas encuestas","author":"","date":"abril 5, 2026","format":false,"excerpt":"El c\u00f3mico Carlos \u00c1lvarez pas\u00f3 al segundo puesto en intenci\u00f3n de voto a una semana de las elecciones presidenciales en Per\u00fa, seg\u00fan un estudio de la consultora Ipsos publicado por el peri\u00f3dico Per\u00fa21, por detr\u00e1s de la candidata conservadora Keiko Fujimori, en un escenario de alta fragmentaci\u00f3n que inyecta de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1473062"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473062\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1473062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1473062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1473062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}