{"id":1473115,"date":"2026-04-13T17:03:52","date_gmt":"2026-04-14T00:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/"},"modified":"2026-04-13T17:03:52","modified_gmt":"2026-04-14T00:03:52","slug":"iran-nuevas-negociaciones-ormuz-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","title":{"rendered":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo"},"content":{"rendered":"<p>Las conversaciones que <a href=\"https:\/\/www.cnn.com\/2026\/04\/13\/world\/live-news\/iran-us-war-trump-hormuz\">no lograron un avance<\/a> entre Estados Unidos e Ir\u00e1n no fueron la \u00faltima palabra en las negociaciones, dijeron el lunes funcionarios en EE.UU. y en la regi\u00f3n.<\/p>\n<p>Y el presidente Donald Trump sigue abierto a reanudar pronto las negociaciones presenciales si cree que Teher\u00e1n est\u00e1 listo para someterse a sus exigencias, seg\u00fan personas familiarizadas con el asunto.<\/p>\n<p>Funcionarios de Trump est\u00e1n discutiendo internamente los detalles de una posible segunda reuni\u00f3n, presencial, con funcionarios iran\u00edes antes de que expire un cese del fuego el 21 de abril, dijo a CNN una fuente familiarizada con las conversaciones, aunque no est\u00e1 claro si esa reuni\u00f3n se concretar\u00eda.<\/p>\n<p>Los funcionarios eval\u00faan posibles fechas y lugares en caso de que las conversaciones en curso con Ir\u00e1n y los mediadores en la regi\u00f3n avancen en los pr\u00f3ximos d\u00edas, dijo la fuente, al describir las discusiones como preliminares. \u201cNecesitamos estar preparados para poner algo en marcha r\u00e1pidamente si las cosas van en esa direcci\u00f3n\u201d, dijo la fuente.<\/p>\n<p>Pero, dada la anterior resistencia iran\u00ed a una serie de exigencias de EE.UU., se desconoce si Teher\u00e1n vaya a someterse a los t\u00e9rminos de Trump en el corto plazo, incluso cuando EE.UU. comenz\u00f3 el lunes por la ma\u00f1ana un bloqueo de los puertos iran\u00edes. Con el estrecho de Ormuz todav\u00eda, en la pr\u00e1ctica, cerrado, Ir\u00e1n cree que disfruta de una influencia sustancial sobre EE.UU., una postura que qued\u00f3 clara para los negociadores en Islamabad este fin de semana.<\/p>\n<p>Trump y el vicepresidente J. D. Vance tienen una visi\u00f3n distinta: tras semanas de guerra, Ir\u00e1n est\u00e1 gravemente debilitado y har\u00eda bien en aceptar todas sus exigencias.<br \/>Desde su punto de vista, el bloqueo es otra t\u00e1ctica de presi\u00f3n \u2014una destinada a subir la temperatura sobre Ir\u00e1n para que regrese a las conversaciones de una manera m\u00e1s conciliadora\u2014, dijeron funcionarios.<\/p>\n<p>Trump dijo el lunes que Ir\u00e1n hab\u00eda llamado al Gobierno m\u00e1s temprano esa ma\u00f1ana y que \u201cles gustar\u00eda llegar a un acuerdo desesperadamente\u201d. No especific\u00f3 qui\u00e9n hab\u00eda hecho la llamada ni qui\u00e9n en Washington la hab\u00eda recibido. Apenas un d\u00eda antes, hab\u00eda dicho que no le importaba si se alcanzaba un acuerdo.<\/p>\n<p>El bloqueo tambi\u00e9n ha inyectado nueva incertidumbre en la situaci\u00f3n: sigue sin estar claro, por ejemplo, hasta d\u00f3nde est\u00e1 dispuesto a llegar EE.UU. militarmente para hacerlo cumplir y c\u00f3mo podr\u00eda reaccionar Ir\u00e1n en los pr\u00f3ximos d\u00edas y semanas.<\/p>\n<p>Funcionarios del Gobierno siguen siendo optimistas de que es posible una salida diplom\u00e1tica, dijeron personas familiarizadas con las conversaciones. Dependiendo del ritmo de las negociaciones en los pr\u00f3ximos d\u00edas, EE.UU. e Ir\u00e1n tambi\u00e9n podr\u00edan extender el plazo del cese del fuego para disponer de m\u00e1s tiempo, dijeron.<\/p>\n<p>\u201cHay un compromiso continuo entre EE.UU. e Ir\u00e1n y avances para intentar lograr un acuerdo\u201d, dijo un funcionario de EE.UU.<\/p>\n<p>Una fuente regional dijo a CNN que podr\u00eda haber otra ronda de negociaciones y que Turqu\u00eda trabaja para tender puentes entre las dos partes. La reuni\u00f3n del s\u00e1bado, de 21 horas, en Islamabad fue la culminaci\u00f3n de semanas de negociaciones con altos funcionarios de EE.UU. e intermediarios, incluidos Pakist\u00e1n, pero tambi\u00e9n Turqu\u00eda, Egipto y Om\u00e1n, entre otros.<\/p>\n<p>Antes de que todas las partes acordaran Islamabad, se hab\u00edan barajado varios lugares para las negociaciones del s\u00e1bado, incluidos Ginebra, Viena y Estambul. Ginebra e Islamabad vuelven a estar sobre la mesa como posibles opciones para otra ronda, dijo la fuente familiarizada con las conversaciones.<\/p>\n<p>A pesar de que la sesi\u00f3n del s\u00e1bado dur\u00f3 m\u00e1s de lo esperado, seg\u00fan fuentes familiarizadas con las conversaciones, funcionarios del Gobierno sostienen que era poco probable que una sola reuni\u00f3n lograra un acuerdo final. M\u00e1s bien, los funcionarios hab\u00edan anticipado que las conversaciones del fin de semana pasado probablemente ser\u00edan una de muchas negociaciones a lo largo del alto el fuego de dos semanas.<\/p>\n<p>Y Trump, as\u00ed como muchos de sus asesores m\u00e1s cercanos, est\u00e1 ansioso por que el alto el fuego tenga \u00e9xito y porque ambas partes alcancen una soluci\u00f3n diplom\u00e1tica, indicaron las fuentes. Muchos funcionarios del Gobierno no desean que se reanuden los ataques militares, y varios reconocen que los estadounidenses tambi\u00e9n est\u00e1n perdiendo la paciencia con la guerra.<\/p>\n<p>Vance, mientras part\u00eda de Islamabad temprano el domingo, dijo que hab\u00eda puesto sobre la mesa una oferta \u201cmejor y final\u201d, lo que sugiere que a\u00fan hab\u00eda tiempo para que Ir\u00e1n aceptara todas las condiciones de EE.UU.<\/p>\n<p>Pero muchas de las \u201cl\u00edneas rojas\u201d que EE.UU. ha fijado para Ir\u00e1n son t\u00e9rminos que Teher\u00e1n ya hab\u00eda rechazado previamente, una postura de l\u00ednea dura que parece no haber cambiado incluso despu\u00e9s de seis semanas de guerra.<\/p>\n<p>Seg\u00fan un funcionario de la Casa Blanca, los par\u00e1metros no negociables incluyen que Ir\u00e1n ponga fin a todo su enriquecimiento de uranio; desmantele sus principales instalaciones de enriquecimiento nuclear, que quedaron gravemente da\u00f1adas durante un bombardeo de EE.UU. en junio de 2025; y recupere los m\u00e1s de 400 kilogramos de uranio altamente enriquecido que se cree que est\u00e1n enterrados.<\/p>\n<p>El desacuerdo nuclear parece no haber cambiado desde antes de que comenzara la guerra. Fue la negativa de Ir\u00e1n a renunciar al enriquecimiento y a entregar los 400 kilogramos de uranio de pureza casi apta para una bomba lo que hizo que una ronda anterior de negociaciones, encabezada por Steve Witkoff y Jared Kushner, se estancara.<\/p>\n<p>En Islamabad el s\u00e1bado, ambas partes presentaron ofertas destinadas a resolver el tema nuclear, dijeron funcionarios. Los negociadores estadounidenses propusieron que Ir\u00e1n aceptara una pausa de 20 a\u00f1os en el enriquecimiento de uranio, dijo una fuente familiarizada con las discusiones.<\/p>\n<p>Trump ha afirmado previamente que EE.UU. e Ir\u00e1n trabajar\u00edan juntos para retirar lo que \u00e9l llama el \u201cpolvo nuclear\u201d, aunque Ir\u00e1n pareci\u00f3 no inmutarse.<\/p>\n<p>Se desconoce si una propuesta anterior, en la que EE.UU. proporcionar\u00eda a Ir\u00e1n combustible nuclear durante una d\u00e9cada a cambio de que Teher\u00e1n detuviera todo enriquecimiento, segu\u00eda sobre la mesa.<\/p>\n<p>Si bien las negociaciones del s\u00e1bado fueron duras por momentos, ambas partes s\u00ed desarrollaron cierta medida de respeto mutuo tras pasar horas a puerta cerrada, seg\u00fan Trump y otras personas familiarizadas con las conversaciones.<\/p>\n<p>Seg\u00fan el ministro de Relaciones Exteriores de Ir\u00e1n, las reuniones parecieron avanzar de manera fruct\u00edfera hasta los \u00faltimos momentos.<\/p>\n<p>\u201cEn conversaciones intensivas al m\u00e1s alto nivel en 47 a\u00f1os, Ir\u00e1n se comprometi\u00f3 con EE.UU. de buena fe para poner fin a la guerra\u201d, escribi\u00f3 Abbas Araghchi en X. \u201cPero cuando est\u00e1bamos a solo unos mil\u00edmetros del \u2018MoU de Islamabad\u2019, nos encontramos con maximalismo, cambios de condiciones y bloqueo\u201d.<\/p>\n<p>El bloqueo naval de EE.UU. subraya c\u00f3mo la reapertura del estrecho de Ormuz se ha convertido r\u00e1pidamente en un objetivo principal de la guerra, a medida que se hac\u00eda cada vez m\u00e1s evidente para funcionarios de EE.UU. que Ir\u00e1n estaba tanto dispuesto como capacitado para soportar semanas de bombardeos con el fin de mantener su control sobre la v\u00eda mar\u00edtima.<\/p>\n<p>Pero es una medida que tambi\u00e9n plantea nuevos riesgos para la Marina de EE.UU., que enfrenta las amenazas asim\u00e9tricas de lanchas r\u00e1pidas iran\u00edes, drones y minas en la disputada v\u00eda mar\u00edtima. Funcionarios de Trump hab\u00edan postergado previamente dar un paso tan dr\u00e1stico con la esperanza de encontrar formas alternativas que pudieran aumentar el flujo de petr\u00f3leo a trav\u00e9s del estrecho y mantener bajos los precios de la energ\u00eda, incluida la oferta de reasegurar a los petroleros, plantear la posibilidad de escoltas navales e incluso levantar ciertas sanciones sobre las propias ventas de petr\u00f3leo de Ir\u00e1n.<\/p>\n<p>Sin embargo, con el r\u00e9gimen iran\u00ed consolidando el poder y se\u00f1alando planes para imponer un sistema permanente de cobro de peajes que lo mantendr\u00eda en control de la ruta mar\u00edtima, funcionarios de EE.UU. en las \u00faltimas dos semanas comenzaron una planificaci\u00f3n m\u00e1s seria para cortar la principal fuente de ingresos de Ir\u00e1n, dijo una persona familiarizada con las discusiones internas.<\/p>\n<p>El bloqueo representa quiz\u00e1 la mejor de las opciones menguantes de Trump para aflojar el control de Ir\u00e1n sobre el estrecho, dijeron analistas energ\u00e9ticos que lo ven como mucho menos riesgoso que una operaci\u00f3n terrestre y con m\u00e1s probabilidades de tener \u00e9xito que continuar la campa\u00f1a de bombardeos de EE.UU.<\/p>\n<p>Es probable que el r\u00e9gimen pueda resistir la presi\u00f3n econ\u00f3mica al menos durante las pr\u00f3ximas tres a cuatro semanas antes de que el perjuicio se vuelva significativo, dijo Gregory Brew, un analista s\u00e9nior sobre Ir\u00e1n y el sector energ\u00e9tico en Eurasia Group.<\/p>\n<p>Pero podr\u00eda tardar a\u00fan m\u00e1s debido a que EE.UU. levant\u00f3 sanciones sobre el petr\u00f3leo iran\u00ed hace unas semanas, cuando Trump estaba m\u00e1s enfocado en impulsar los suministros mundiales de petr\u00f3leo que en retomar el control del estrecho. La indulgencia previa permiti\u00f3 a Ir\u00e1n enviar millones de barriles m\u00e1s a otros pa\u00edses que de pronto ten\u00edan permitido comprar su petr\u00f3leo directamente, d\u00e1ndole un mayor colch\u00f3n financiero para resistir el bloqueo.<\/p>\n<p>\u201cYa tienen petr\u00f3leo en el agua\u201d, dijo Brew. \u201cEso sugiere que podr\u00edan resistir un bloqueo durante un tiempo\u201d.<\/p>\n<p>Mientras tanto, es probable que el bloqueo ponga a prueba la capacidad de la Casa Blanca para gestionar precios del combustible a\u00fan m\u00e1s altos. La interrupci\u00f3n de las exportaciones de petr\u00f3leo iran\u00ed significa que lo poco que hab\u00eda estado saliendo del estrecho quedar\u00e1 completamente cortado, agravando a\u00fan m\u00e1s la escasez mundial de suministro energ\u00e9tico, y elevando todav\u00eda m\u00e1s los ya caros precios de la gasolina en EE.UU.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las conversaciones que no lograron un avance entre Estados Unidos e Ir\u00e1n no fueron la \u00faltima palabra en las negociaciones, dijeron el lunes funcionarios en EE.UU. y en la regi\u00f3n. Y el presidente Donald Trump sigue abierto a reanudar pronto las negociaciones presenciales si cree que Teher\u00e1n est\u00e1 listo para someterse a sus exigencias, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473115","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las conversaciones que no lograron un avance entre Estados Unidos e Ir\u00e1n no fueron la \u00faltima palabra en las negociaciones, dijeron el lunes funcionarios en EE.UU. y en la regi\u00f3n. Y el presidente Donald Trump sigue abierto a reanudar pronto las negociaciones presenciales si cree que Teher\u00e1n est\u00e1 listo para someterse a sus exigencias, seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T00:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo\",\"datePublished\":\"2026-04-14T00:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\"},\"wordCount\":1761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\",\"name\":\"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-14T00:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias","og_description":"Las conversaciones que no lograron un avance entre Estados Unidos e Ir\u00e1n no fueron la \u00faltima palabra en las negociaciones, dijeron el lunes funcionarios en EE.UU. y en la regi\u00f3n. Y el presidente Donald Trump sigue abierto a reanudar pronto las negociaciones presenciales si cree que Teher\u00e1n est\u00e1 listo para someterse a sus exigencias, seg\u00fan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-14T00:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo","datePublished":"2026-04-14T00:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/"},"wordCount":1761,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","name":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-14T00:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\u00e1n mientras se afianza el bloqueo","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/13\/iran-nuevas-negociaciones-ormuz-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-14T00:03:52Z","datePublished":"2026-04-14T00:03:52Z","dateModified":"2026-04-14T00:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. contempla una posible segunda ronda de conversaciones presenciales con Ir\\u00e1n mientras se afianza el bloqueo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/13\\\/iran-nuevas-negociaciones-ormuz-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/13\\\/iran-nuevas-negociaciones-ormuz-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-14T00:03:52Z\",\"datePublished\":\"2026-04-14T00:03:52Z\",\"dateModified\":\"2026-04-14T00:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461109,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/12\/eeuu-iran-conversaciones-nucleares-trax\/","url_meta":{"origin":1473115,"position":0},"title":"EE.UU. e Ir\u00e1n comienzan unas cruciales conversaciones nucleares en medio de amenazas de guerra de Trump","author":"","date":"abril 12, 2025","format":false,"excerpt":"Ir\u00e1n y Estados Unidos comienzan este s\u00e1bado conversaciones de alto riesgo para alcanzar un nuevo acuerdo nuclear, precedidas por la amenaza del presidente Trump de ataques militares en caso de un fracaso y la advertencia de Teher\u00e1n de que cualquier ataque en su contra arrastrar\u00eda a EE.UU. a un conflicto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461088,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/11\/iran-conversaciones-nucleares-trump-guerra-trax\/","url_meta":{"origin":1473115,"position":1},"title":"EE.UU. e Ir\u00e1n comenzar\u00e1n conversaciones nucleares cr\u00edticas mientras Trump amenaza con la guerra","author":"","date":"abril 11, 2025","format":false,"excerpt":"Ir\u00e1n y Estados Unidos comenzar\u00e1n conversaciones cruciales el s\u00e1bado para alcanzar un nuevo acuerdo nuclear en un esfuerzo por aliviar las tensiones y evitar otro conflicto en Medio Oriente que podr\u00eda afectar a\u00fan m\u00e1s a la regi\u00f3n en general.La reuni\u00f3n, que se llevar\u00e1 a cabo en Om\u00e1n, podr\u00eda ser la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460978,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/08\/posible-acuerdo-conversaciones-nucleares-eeuu-iran-trax\/","url_meta":{"origin":1473115,"position":2},"title":"\u00bfPodr\u00edan las conversaciones nucleares entre EE.UU. e Ir\u00e1n derivar en un acuerdo?","author":"","date":"abril 8, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, estaba hablando con periodistas junto al primer ministro de Israel, Benjamin Netanyahu, en la Oficina Oval el lunes cuando hizo un anuncio sorpresa: las conversaciones nucleares directas est\u00e1n en marcha entre EE.UU. e Ir\u00e1n y una \u201creuni\u00f3n muy importante\u201d tendr\u00e1 lugar el s\u00e1bado.Si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472558,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/03\/25\/obstaculos-fin-guerra-iran-trax\/","url_meta":{"origin":1473115,"position":3},"title":"Los obst\u00e1culos para poner fin a la guerra se hacen evidentes mientras EE.UU. e Ir\u00e1n plantean demandas marcadamente diferentes","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Hace casi exactamente un mes, el enviado especial de Estados Unidos Steve Witkoff y Jared Kushner se reunieron indirectamente con los iran\u00edes en Ginebra mientras el Gobierno de Trump segu\u00eda afirmando que la diplomacia era su opci\u00f3n preferida. Dos d\u00edas despu\u00e9s, Estados Unidos e Israel lanzaron su guerra contra Ir\u00e1n.Ahora,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459676,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/08\/lider-supremo-iran-rechaza-conversaciones-nucleares-maton-ee-uu-trax\/","url_meta":{"origin":1473115,"position":4},"title":"El l\u00edder supremo de Ir\u00e1n rechaza las conversaciones nucleares con el &#171;mat\u00f3n&#187; EE.UU.","author":"","date":"marzo 8, 2025","format":false,"excerpt":"El l\u00edder supremo de Ir\u00e1n, el ayatol\u00e1 Al\u00ed Jamenei, dijo que los llamados a negociaciones por parte de \u201cestados matones\u201d tienen como objetivo dominar a otros, no resolver problemas, despu\u00e9s de que el presidente de Estados Unidos, Donald Trump, lo instara a llegar a un acuerdo nuclear.Trump dijo a Fox\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463984,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/06\/26\/diplomacia-reanudar-conversaciones-iran-trax\/","url_meta":{"origin":1473115,"position":5},"title":"Revelan un intento secreto de la diplomacia de EE.UU. para reanudar las conversaciones con Ir\u00e1n","author":"","date":"junio 26, 2025","format":false,"excerpt":"El Gobierno de Trump ha considerado la posibilidad de ayudar a Ir\u00e1n a acceder a hasta US$ 30.000 millones para desarrollar un programa nuclear de producci\u00f3n de energ\u00eda civil, flexibilizar las sanciones y liberar miles de millones de d\u00f3lares en fondos iran\u00edes restringidos, todo ello como parte de una campa\u00f1a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1473115"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473115\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1473115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1473115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1473115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}