{"id":1473407,"date":"2026-04-22T13:03:57","date_gmt":"2026-04-22T20:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/"},"modified":"2026-04-22T13:03:57","modified_gmt":"2026-04-22T20:03:57","slug":"pandilleros-megajuicio-asesinatos-el-salvador-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","title":{"rendered":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022"},"content":{"rendered":"<p>Los asesinatos del sangriento \u00faltimo fin de semana de marzo de 2022, episodio que marc\u00f3 un punto de inflexi\u00f3n en la pol\u00edtica de seguridad del presidente Nayib Bukele, llegaron a un juicio masivo que comenz\u00f3 esta semana contra 486 presuntos miembros de la pandilla MS-13, un proceso bajo un nuevo modelo penal que es criticado por organismos de derechos humanos por restricciones al acceso a la defensa.<\/p>\n<p>Uniformados de blanco, rapados y con mascarillas, cientos de acusados siguen el juicio por videoconferencia. De ellos, 413 est\u00e1n detenidos en el Centro de Confinamiento contra el Terrorismo (CECOT), una c\u00e1rcel de m\u00e1xima seguridad emblema del Gobierno de Bukele, y otros 73 est\u00e1n pr\u00f3fugos, pero ser\u00e1n juzgados en ausencia.<\/p>\n<p>Un tribunal especializado en crimen organizado lleva adelante el modelo de macroaudiencia por \u201cm\u00e1s de 47.000 delitos\u201d cometidos entre 2012 y 2022, seg\u00fan la Fiscal\u00eda General, entre ellos, ordenar 86 asesinatos entre el 25 y 27 de marzo de 2022. Es un modelo de juicio establecido tras varias reformas aprobadas en 2023 al C\u00f3digo Penal de El Salvador, en el contexto de la implementaci\u00f3n de un r\u00e9gimen de excepci\u00f3n que sigue vigente desde hace cuatro a\u00f1os y que suspende garant\u00edas constitucionales.<\/p>\n<p>En estos procesos, los detenidos suelen contar con un defensor p\u00fablico. CNN intenta averiguar con qu\u00e9 tipo de acompa\u00f1amiento legal cuentan las personas que est\u00e1n siendo juzgadas y c\u00f3mo es el acceso a la defensa en este caso.<\/p>\n<p>El Salvador comenz\u00f3 2022 con un promedio de 2,8 asesinatos diarios, una cifra que iba en aumento desde los \u00faltimos meses de 2021. El viernes 25 de marzo, las autoridades registraron 14 homicidios, lo que condujo a una reuni\u00f3n de emergencia del Gabinete de Seguridad, pero la escalada de violencia continu\u00f3 el s\u00e1bado. La Polic\u00eda confirm\u00f3 62 asesinatos en esa jornada y 11 m\u00e1s el domingo.<\/p>\n<p>Con esos n\u00fameros, es considerado el fin de semana m\u00e1s violento en el pa\u00eds desde la Guerra Civil de los a\u00f1os 80.<\/p>\n<p>En medio de esa ola de sangre, Bukele <a href=\"https:\/\/x.com\/nayibbukele\/status\/1507901269138194433\">pidi\u00f3<\/a> por redes sociales a la Asamblea que declarara inmediatamente el r\u00e9gimen de excepci\u00f3n. El Congreso, de mayor\u00eda oficialista, convoc\u00f3 a una sesi\u00f3n extraordinaria y alcanz\u00f3 el 75 % necesario para aprobarlo.<\/p>\n<p>Por ese entonces, el Gobierno de Estados Unidos ya hab\u00eda <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/12\/09\/ee-uu-sanciona-funcionarios-el-salvador-acuerdo-pandillas-trax\">sancionado a dos funcionarios<\/a> de El Salvador por supuestas negociaciones secretas con la MS-13. Bukele siempre rechaz\u00f3 las versiones de una presunta \u201ctregua\u201d con las pandillas.<\/p>\n<p>El estado de excepci\u00f3n aprobado por la Asamblea se convirti\u00f3 en la principal apuesta del Gobierno contra las pandillas. Desde ese momento, las autoridades afirman haber capturado a 91.300 personas acusadas de pertenecer supuestamente a las pandillas o tener v\u00ednculos con esos grupos criminales. Bukele, que mantiene altos niveles de popularidad, dijo que 8.000 personas que eran inocentes han sido liberadas, mientras que organizaciones de derechos humanos han documentado la muerte de al menos 488 personas bajo custodia de las autoridades.<\/p>\n<p>El lunes, cuando comenz\u00f3 la primera audiencia del juicio, no se autoriz\u00f3 el acceso a los medios de comunicaci\u00f3n. La Fiscal\u00eda inform\u00f3 por la noche que los acusados est\u00e1n imputados por \u201ccr\u00edmenes que marcaron al pa\u00eds\u201d: homicidios, femicidios, extorsi\u00f3n, narcotr\u00e1fico, desapariciones y tr\u00e1fico de armas, as\u00ed como rebeli\u00f3n \u201cal intentar mantener el control territorial para establecer un Estado paralelo\u201d.<\/p>\n<p>Los fiscales, que no han detallado cu\u00e1nto durar\u00e1 el proceso, han presentado autopsias, an\u00e1lisis bal\u00edsticos y testimonios, y solicitaron al juez que imponga la pena m\u00e1xima por cada crimen. Un acusado podr\u00eda recibir hasta 245 a\u00f1os de condena si es hallado culpable de m\u00faltiples cargos.<\/p>\n<p>El martes, cuando s\u00ed se permiti\u00f3 el acceso a los medios, la FGR dijo que present\u00f3 las declaraciones de testigos que se\u00f1alan a 22 imputados como \u201cranfleros\u201d (la m\u00e1xima jerarqu\u00eda de las pandillas) como responsables de ordenar m\u00e1s de 9.000 cr\u00edmenes. Los acusados \u201cdaban autorizaci\u00f3n de asesinar a contrincantes, miembros de la corporaci\u00f3n policial, elementos de la Fuerza Armada y cualquier persona que se opusiera a sus exigencias\u201d, dijo la Fiscal\u00eda.<\/p>\n<p>Las reformas a la ley de crimen organizado no individualizan la responsabilidad penal de los acusados y eliminaron la audiencia de valoraci\u00f3n de pruebas.<\/p>\n<p>No es la primera vez que decenas de acusados son juzgados colectivamente y grupos defensores de derechos han reclamado por las condiciones de estos procesos.<\/p>\n<p>Estos megajuicios \u201cplantean serias dudas sobre el cumplimiento de las garant\u00edas del debido proceso, incluido el derecho a una defensa individualizada, la presunci\u00f3n de inocencia y el acceso a una representaci\u00f3n legal adecuada\u201d, declar\u00f3 en un comunicado Irene Cu\u00e9llar, investigadora para Centroam\u00e9rica de Amnist\u00eda Internacional (AI). Por su parte, Juan Pappier, subdirector para las Am\u00e9ricas de Human Rights Watch (HRW), dijo a la agencia AP que \u201ccarecen de garant\u00edas b\u00e1sicas del debido proceso y, por lo tanto, aumentan el riesgo de condenar a personas inocentes que no tienen nada que ver con las pandillas que han aterrorizado al pa\u00eds durante d\u00e9cadas\u201d.<\/p>\n<p>En tanto, la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) public\u00f3 este martes un <a href=\"https:\/\/www.oas.org\/es\/CIDH\/jsForm\/?File=\/es\/cidh\/prensa\/comunicados\/2026\/066.asp\">comunicado<\/a> en el que expres\u00f3 \u201cserias preocupaciones por los impactos en los derechos humanos derivados de la prolongaci\u00f3n excesiva e indebida del r\u00e9gimen de excepci\u00f3n en El Salvador\u201d y reiter\u00f3 su pedido al Estado para \u201cponer fin al uso continuado de esta medida como parte de su pol\u00edtica de seguridad\u201d.<\/p>\n<p>De todos modos, el r\u00e9gimen contin\u00faa teniendo un amplio respaldo popular y fue clave para que Bukele asegurara una reelecci\u00f3n, a pesar de que lo prohib\u00eda la Constituci\u00f3n. El Salvador cerr\u00f3 2025 con 82 homicidios, un 28 % menos que en 2024 y, seg\u00fan el Ministerio de Seguridad, es la primera vez que el pa\u00eds registra una cifra anual de dos d\u00edgitos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los asesinatos del sangriento \u00faltimo fin de semana de marzo de 2022, episodio que marc\u00f3 un punto de inflexi\u00f3n en la pol\u00edtica de seguridad del presidente Nayib Bukele, llegaron a un juicio masivo que comenz\u00f3 esta semana contra 486 presuntos miembros de la pandilla MS-13, un proceso bajo un nuevo modelo penal que es criticado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473407","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los asesinatos del sangriento \u00faltimo fin de semana de marzo de 2022, episodio que marc\u00f3 un punto de inflexi\u00f3n en la pol\u00edtica de seguridad del presidente Nayib Bukele, llegaron a un juicio masivo que comenz\u00f3 esta semana contra 486 presuntos miembros de la pandilla MS-13, un proceso bajo un nuevo modelo penal que es criticado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T20:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022\",\"datePublished\":\"2026-04-22T20:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\"},\"wordCount\":1018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\",\"name\":\"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-22T20:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias","og_description":"Los asesinatos del sangriento \u00faltimo fin de semana de marzo de 2022, episodio que marc\u00f3 un punto de inflexi\u00f3n en la pol\u00edtica de seguridad del presidente Nayib Bukele, llegaron a un juicio masivo que comenz\u00f3 esta semana contra 486 presuntos miembros de la pandilla MS-13, un proceso bajo un nuevo modelo penal que es criticado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-22T20:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/"},"author":{"name":"","@id":""},"headline":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022","datePublished":"2026-04-22T20:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/"},"wordCount":1018,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","name":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-22T20:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\u00f3mo fue ese violento fin de semana de 2022","url":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/washington-dc\/2026\/04\/22\/pandilleros-megajuicio-asesinatos-el-salvador-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-22T20:03:57Z","datePublished":"2026-04-22T20:03:57Z","dateModified":"2026-04-22T20:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Casi 500 pandilleros van a un megajuicio por 86 asesinatos en El Salvador: c\\u00f3mo fue ese violento fin de semana de 2022\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/22\\\/pandilleros-megajuicio-asesinatos-el-salvador-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/washington-dc\\\/2026\\\/04\\\/22\\\/pandilleros-megajuicio-asesinatos-el-salvador-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-22T20:03:57Z\",\"datePublished\":\"2026-04-22T20:03:57Z\",\"dateModified\":\"2026-04-22T20:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473474,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/04\/24\/bukele-juicios-masivos-lideres-pandilleros-nuremberg-orix\/","url_meta":{"origin":1473407,"position":0},"title":"Bukele defiende los juicios masivos a l\u00edderes pandilleros y los compara con los procesos contra los nazis en N\u00faremberg","author":"","date":"abril 24, 2026","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, hizo un paralelismo de los juicios masivos que comenzaron esta semana en el pa\u00eds \u2014donde son juzgados 486 presuntos miembros de la pandilla MS-13\u2014 con los juicios de N\u00faremberg, en Alemania, en los que se juzg\u00f3 a m\u00e1s de una veintena de oficiales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460023,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/17\/cecot-megaprision-carcel-el-salvador-bukele-orix\/","url_meta":{"origin":1473407,"position":1},"title":"As\u00ed es el CECOT, la megaprisi\u00f3n de El Salvador que construy\u00f3 Nayib Bukele para encerrar a pandilleros","author":"","date":"marzo 17, 2025","format":false,"excerpt":"En 2023, el Gobierno de El Salvador present\u00f3 el Centro de Confinamiento del Terrorismo (CECOT), una megac\u00e1rcel cuya principal funci\u00f3n ser\u00eda la de alojar a miles de miembros de pandillas, luego de una ola de asesinatos que puso al pa\u00eds en un prolongado estado de excepci\u00f3n en seguridad.El presidente Nayib\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458084,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/01\/31\/rubio-bukele-el-salvador-tren-de-aragua-trax\/","url_meta":{"origin":1473407,"position":2},"title":"Rubio y Bukele discutir\u00e1n el env\u00edo a El Salvador de presuntos pandilleros del Tren de Aragua","author":"","date":"enero 31, 2025","format":false,"excerpt":"El secretario de Estado de Estados Unidos, Marco Rubio, discutir\u00e1 la posibilidad de deportar a El Salvador a presuntos pandilleros del Tren de Aragua, en una reuni\u00f3n a celebrarse con el presidente de El Salvador, Nayib Bukele, seg\u00fan el enviado especial del Departamento de Estado para Am\u00e9rica Latina, Mauricio Claver-Carone.\u201cEstamos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460155,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/03\/19\/maduro-pide-bukele-entregue-venezolanos-deportados-orix\/","url_meta":{"origin":1473407,"position":3},"title":"Maduro pide a Bukele que entregue a los venezolanos deportados de EE.UU.","author":"","date":"marzo 19, 2025","format":false,"excerpt":"El presidente de Venezuela, Nicol\u00e1s Maduro, pidi\u00f3 este mi\u00e9rcoles a su hom\u00f3logo de El Salvador, Nayib Bukele, que entregue a su pa\u00eds a los 238 migrantes venezolanos que el fin de semana fueron deportados por Estados Unidos e ingresados al Centro de Confinamiento del Terrorismo (CECOT), en territorio salvadore\u00f1o.Maduro hizo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461165,"url":"https:\/\/noticiasya.com\/washington-dc\/2025\/04\/14\/trump-bukele-el-salvador-deportaciones-trax\/","url_meta":{"origin":1473407,"position":4},"title":"Trump recibir\u00e1 en la Casa Blanca a Bukele, que juega un papel clave en la agenda sobre inmigraci\u00f3n del Gobierno de EE.UU.","author":"","date":"abril 14, 2025","format":false,"excerpt":"En una \u00e9poca en la que las alianzas estadounidenses se han visto sometidas a una tensi\u00f3n extrema por las guerras arancelarias y las disputas sobre el gasto militar, un l\u00edder se ha ganado firmemente el favor del presidente Donald Trump: Nayib Bukele, de El Salvador, quien visitar\u00e1 la Casa Blanca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473705,"url":"https:\/\/noticiasya.com\/washington-dc\/2026\/05\/01\/derechos-seguridad-salvador-bukele-orix\/","url_meta":{"origin":1473407,"position":5},"title":"Hasta d\u00f3nde est\u00e1n dispuestos los salvadore\u00f1os a aceptar medidas extremas de Bukele con tal de vivir en calma","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Para los defensores de los derechos humanos, la mejora en los niveles de seguridad en El Salvador tiene un alto precio: el deterioro de la democracia y el respeto a la ley. Sin embargo, reconocen que el Gobierno del presidente Nayib Bukele cuenta con respaldo ciudadano.Medidas como el r\u00e9gimen de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/washington-dc\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=1473407"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/posts\/1473407\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=1473407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=1473407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=1473407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}